{"id":10009,"date":"2026-06-03T20:15:39","date_gmt":"2026-06-03T17:15:39","guid":{"rendered":"https:\/\/imgist.ru\/novyj-serial-zvyozdnye-vrata-byl-zakryt-kompaniej-amazon\/"},"modified":"2026-06-03T20:15:39","modified_gmt":"2026-06-03T17:15:39","slug":"die-neue-stargate-serie-wurde-von-amazon-abgesetzt","status":"publish","type":"post","link":"https:\/\/imgist.ru\/de\/novyj-serial-zvyozdnye-vrata-byl-zakryt-kompaniej-amazon\/","title":{"rendered":"Die neue Stargate-Serie wurde von Amazon abgesetzt."},"content":{"rendered":"<p>Nachdem Fans jahrelang beharrlich eine R\u00fcckkehr ins Stargate-Universum gefordert hatten, sah sich die lang ersehnte Wiederbelebung der Serie pl\u00f6tzlich un\u00fcberwindlichen Hindernissen gegen\u00fcber.<\/p>\n<p> Berichten zufolge wird Amazon die neue Stargate-Serie nicht produzieren.<\/p>\n<p> Im November 2025 bestellte Amazon die Serie, bei der Martin Gero als Autor, Showrunner und ausf\u00fchrender Produzent fungiert. Gero, ein Stargate-Veteran, hat zuvor \u00fcber 40 Episoden des Franchise geschrieben oder mitentwickelt, darunter mehrere Episoden. <em>\u00abStargate SG-1\u00bb<\/em> (1997-2007) und <em>\u00abStargate Atlantis\u00bb<\/em> (2004-2009) zu Beginn seiner Karriere.<\/p>\n<h3> Warum das Projekt ins Stocken geraten ist und was die Zukunft bringt<\/h3>\n<p> Laut einer mit der Situation vertrauten Quelle waren die Amazon-Manager besorgt, dass eine Version der Serie mit Gero au\u00dferhalb der bestehenden Stargate-Fangemeinde nicht viele Menschen ansprechen w\u00fcrde.<\/p>\n<p> Der Technologiekonzern scheint jedoch entschlossen, die Filmreihe am Leben zu erhalten. Seit der \u00dcbernahme der MGM Studios im Jahr 2022 hat das Unternehmen Interesse an der Entwicklung neuer Projekte gezeigt und pr\u00fcft trotz der Absetzung der Gero-Serie weiterhin andere M\u00f6glichkeiten zur Fortsetzung der Reihe.<\/p>\n<p> Es ist erw\u00e4hnenswert, dass Gero im Rahmen seines Gesamtvertrags mit Amazon MGM Studios weiterhin bei dem Unternehmen unter Vertrag steht und dort auch weiterhin an anderen Projekten arbeiten wird.<\/p>\n<p> Es wurden noch keine Details zur Handlung von Geros Version der Serie ver\u00f6ffentlicht. An dem Projekt war ein recht gro\u00dfes Produktionsteam beteiligt, darunter Joby Harold und Tory Tunnell. <em>Bilder vom Safehouse<\/em> , Neben Dean Devlin und Roland Emmerich, die das Drehbuch zum Originalfilm von 1994 gemeinsam schrieben und Regie f\u00fchrten, wirkten auch die langj\u00e4hrigen Franchise-Veteranen Brad Wright und Joe Mallozzi als beratende Produzenten mit.<\/p>\n<p> <em>Die Stargate-Serie\u00ab<\/em> Es begann 1994 mit einem Spielfilm mit James Spader (als Daniel Jackson) und Kurt Russell (als Jack O&#039;Neill). Sp\u00e4ter entstand daraus eine langj\u00e4hrige Fernsehserie. <em>\u00abStargate SG-1\u00bb<\/em> , die zehn Staffeln lang ausgestrahlt wurde, und <em>\u00abStargate Atlantis\u00bb<\/em> , Die Serie lief f\u00fcnf Staffeln lang.<\/p>\n<p> Im Laufe der Jahre gab es au\u00dferdem mehrere Direct-to-Video-Filme und diverse andere Serien, die j\u00fcngste davon ist eine Prequel-Webserie. <em>\u00abStargate Origins\u00bb<\/em> (2018).<\/p>\n<p> Auch wenn Heros Version niemals das Licht der Welt erblicken wird, kann man mit Sicherheit davon ausgehen, dass Amazons anhaltendes Interesse darauf hindeutet, dass die legend\u00e4re Science-Fiction-Saga in einer anderen Form zur\u00fcckkehren k\u00f6nnte.<\/p>\n<p> <em>Quellen:<\/em> Amazonas <em>,<\/em> Variety, Prime Video, Deadline<\/p>\n<p> Lesen Sie den Originalartikel auf GEEKSPIN. Affiliate-Links auf GEEKSPIN k\u00f6nnen uns und unseren Partnern Provisionen einbringen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nach jahrelangen, hartn\u00e4ckigen Fanw\u00fcnschen nach einer R\u00fcckkehr ins Stargate-Universum ist die lang ersehnte Wiederbelebung der Serie pl\u00f6tzlich auf un\u00fcberwindbare Hindernisse gesto\u00dfen. Berichten zufolge\u2026<\/p>","protected":false},"author":1,"featured_media":10010,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10009","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/10009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/comments?post=10009"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/10009\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media\/10010"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media?parent=10009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/categories?post=10009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/tags?post=10009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}