{"id":17024,"date":"2026-06-07T19:59:52","date_gmt":"2026-06-07T16:59:52","guid":{"rendered":"https:\/\/imgist.ru\/teleskop-ne-ponadobitsya-na-etoj-nedele-yupiter-i-venera-budut-kazatsya-pochti-soprikasayushhimisya\/"},"modified":"2026-06-07T19:59:52","modified_gmt":"2026-06-07T16:59:52","slug":"sie-werden-diese-woche-kein-teleskop-benotigen-jupiter-und-venus-werden-sich-fast-beruhren","status":"publish","type":"post","link":"https:\/\/imgist.ru\/de\/teleskop-ne-ponadobitsya-na-etoj-nedele-yupiter-i-venera-budut-kazatsya-pochti-soprikasayushhimisya\/","title":{"rendered":"Kein Teleskop n\u00f6tig: Jupiter und Venus werden diese Woche fast in Ber\u00fchrung kommen."},"content":{"rendered":"<p>(NEXSTAR) \u2013 Diese Woche bietet eine der besten Gelegenheiten im Juni, ein besonderes Himmelsereignis zu beobachten \u2013 die Konjunktion der Planeten Venus und Jupiter.<\/p>\n<p> Am 9. Juni werden die beiden Planeten aus unserer Perspektive unglaublich nah beieinander erscheinen, doch dies ist in Wirklichkeit eine optische T\u00e4uschung, da sie im Weltraum immer noch Millionen von Kilometern voneinander entfernt sein werden.<\/p>\n<p> Laut dem Magazin Sky and Telescope besteht eine der Hauptattraktionen dieses Spektakels darin, dass die Planeten so hell erscheinen, dass keine spezielle Ausr\u00fcstung ben\u00f6tigt wird, um sie zu genie\u00dfen.<\/p>\n<p> Warum die Sozialversicherungsleistungen bis 2032 um 500 Dollar pro Monat gek\u00fcrzt werden k\u00f6nnten<\/p>\n<p> Um die \u00abangrenzenden Planeten\u00bb zu sehen, empfiehlt die Webseite, 45 Minuten bis 2 Stunden nach Sonnenuntergang in Richtung Westnordwest zu schauen.<\/p>\n<p> Merkur vervollst\u00e4ndigt dieses Planetenspektakel und gesellt sich zwei Tage sp\u00e4ter zu den beiden anderen Planeten am Himmel. Da Merkur n\u00e4her am Horizont steht, ben\u00f6tigt man f\u00fcr seine Beobachtung eine freie Sicht nach Westen.<\/p>\n<p> Laut NASA werden einige Gl\u00fcckliche die Venus kurzzeitig &quot;verschwinden&quot; sehen k\u00f6nnen, wenn der Mond vor ihr vorbeizieht.<\/p>\n<p> Die kosmische Aufregung setzt sich am 21. Juni fort, der Sommersonnenwende, die den Beginn des astronomischen Sommers markiert, sowie mit dem Meteorstrom der Bootyiden am 27. Juni und dem mikroskopisch kleinen Erdbeermond am 29. Juni.<\/p>\n<p> \u00a9 2026 Nexstar Media, Inc. Alle Rechte vorbehalten. Dieses Material darf nicht ver\u00f6ffentlicht, gesendet, umgeschrieben oder weiterverbreitet werden.<\/p>\n<p> Aktuelle Nachrichten, Wetterberichte, Sportergebnisse und Live-Videos finden Sie auf The Hill.<\/p>","protected":false},"excerpt":{"rendered":"<p>(NEXSTAR) \u2013 Diese Woche bietet eine der besten Gelegenheiten im Juni, ein besonderes Himmelsereignis zu beobachten \u2013 die Konjunktion der Planeten Venus und Jupiter. Am 9. Juni\u2026<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-17024","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/17024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/comments?post=17024"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/17024\/revisions"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media?parent=17024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/categories?post=17024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/tags?post=17024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}