{"id":4930,"date":"2026-06-01T16:10:19","date_gmt":"2026-06-01T13:10:19","guid":{"rendered":"https:\/\/imgist.ru\/avan-dzhogia-s-neterpeniem-zhdyot-kogda-holzi-sygraet-glavnuyu-rol-v-ego-sleduyushhem-rezhissyorskom-proekte-replacer\/"},"modified":"2026-06-01T16:10:19","modified_gmt":"2026-06-01T13:10:19","slug":"avan-dzhogias-neterpeniem-zhdyot-kogda-holzi-sgotet-die-hauptrolle-in-seinem-nachsten-regieprojekt","status":"publish","type":"post","link":"https:\/\/imgist.ru\/de\/avan-dzhogia-s-neterpeniem-zhdyot-kogda-holzi-sygraet-glavnuyu-rol-v-ego-sleduyushhem-rezhissyorskom-proekte-replacer\/","title":{"rendered":"Avan Jogia freut sich darauf, dass Halsey in seinem n\u00e4chsten Regieprojekt Replacer die Hauptrolle spielen wird."},"content":{"rendered":"<p>Avan Jogia freut sich darauf, seine Verlobte und Co-Autorin Halsey in ihrer ersten Hauptrolle in ihrem neuen Film \u00abReplacer\u00bb zu sehen. Anfang des Monats wurde bekannt gegeben, dass die S\u00e4ngerin, bekannt f\u00fcr ihren Hit \u00abWithout Me\u00bb, ihre erste Hauptrolle in dem psychosexuellen Horrorfilm ergattert hat, an dem sie gemeinsam das Drehbuch geschrieben haben.<\/p>\n<p> Im Gespr\u00e4ch mit dem Hollywood Reporter erkl\u00e4rte Jogia, der bei dem Projekt Regie f\u00fchren wird, dass er sich darauf freue, Halsey nach Jahrzehnten als S\u00e4ngerin auch als Schauspielerin unter Beweis stellen zu sehen.<\/p>\n<p> \u00abIch bin einfach nur am Zuschauen interessiert\u201e, sagte er. \u201cIch m\u00f6chte, dass die Schauspieler die Person und die Figur verk\u00f6rpern. Und ihr dabei zuzusehen \u2013 ich habe das Drehbuch mit dem Verst\u00e4ndnis geschrieben, dass sie in ihren Zwanzigern unglaublichen Erfolg in einem sehr, sehr schwierigen Bereich feierte. Deshalb hatte sie keine Zeit f\u00fcr Filme wie diesen. Und ich dachte: \u00bbDu solltest in einem Film wie diesem mitspielen, also lass mich das machen.\u2018\u201c.<\/p>\n<p> Der ehemalige Nickelodeon-Star f\u00fcgte hinzu: \u00abJemanden zu lieben bedeutet auch, all die verschiedenen Versionen dieser Person sehen zu k\u00f6nnen, die h\u00e4tten sein k\u00f6nnen oder die vielleicht noch sein werden.\u00bb.<\/p>\n<p> Halsey, deren b\u00fcrgerlicher Name Ashley Frangipane lautet, war zuvor in Filmen wie A Star Is Born, Sing 2, Americana und MaXXXine zu sehen, und Replacer ist ihre erste Hauptrolle.<\/p>\n<p> Sie spielt die problembeladene DJ Proxy, die sich mit einer Gruppe von Leuten anfreundet, die einen Underground-Radiosender betreiben. Als die Sendung des Senders durch ein mysteri\u00f6ses Signal gest\u00f6rt wird, muss Proxy fliehen, bevor der Schall sie \u00abin etwas Urw\u00fcchsiges, Primitives und Unkenntliches\u00bb verwandelt.<\/p>\n<p> Jogia merkte an, dass der Schreibprozess \u00absehr einfach\u00bb gewesen sei, da er und Halsey, die seit 2024 verlobt sind, \u00abeinen \u00e4hnlichen Schreibstil\u00bb h\u00e4tten.<\/p>\n<p> \u00abEine der gr\u00f6\u00dften Freuden meines Lebens ist die M\u00f6glichkeit, mit jemandem zusammenzuleben und zusammenzuarbeiten, der meiner Meinung nach in jedem Bereich, den sie bekleidet, unglaublich talentiert ist. Und wir arbeiten wirklich gut zusammen\u00bb, lobte er.<\/p>\n<p> Der Star aus Zombieland: Double Tap f\u00fchrte zuvor Regie bei den Kurzfilmen Alex und Of Dogs and Men, bei Episoden der Fernsehserie Teen Apocalypse Survivors aus dem Jahr 2016 und gab 2022 mit Doormouse sein Spielfilmdeb\u00fct als Regisseur.<\/p>","protected":false},"excerpt":{"rendered":"<p>Avan Jogia freut sich darauf, seine Verlobte und Co-Autorin Halsey in ihrer ersten Hauptrolle in ihrem neuen Film \u00abReplacer\u00bb zu sehen. Zuvor\u2026<\/p>","protected":false},"author":1,"featured_media":4931,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-4930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/4930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/comments?post=4930"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/4930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media\/4931"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media?parent=4930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/categories?post=4930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/tags?post=4930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}