{"id":5525,"date":"2026-06-01T20:16:00","date_gmt":"2026-06-01T17:16:00","guid":{"rendered":"https:\/\/imgist.ru\/v-programme-the-view-privetstvovali-reshenie-trampa-ubrat-svoe-imya-s-nazvaniya-kennedi-czentra-dajte-mne-lestniczu\/"},"modified":"2026-06-01T20:16:00","modified_gmt":"2026-06-01T17:16:00","slug":"v-programm-die-ansicht-privetstvovovali-reshenie-trampa-%d1%83%d0%b1%d1%80%d0%b0%d1%82-svoe-imya-s-nazvaniya-kennedi-czentra-%d0%b4%d0%b0%d0%b9%d1%82%d0%b5%d0%bc%d0%bd%d0%b5-lestniczu","status":"publish","type":"post","link":"https:\/\/imgist.ru\/de\/v-programme-the-view-privetstvovali-reshenie-trampa-ubrat-svoe-imya-s-nazvaniya-kennedi-czentra-dajte-mne-lestniczu\/","title":{"rendered":"In der Sendung \u00abThe View\u00bb wurde Trumps Entscheidung, seinen Namen vom Kennedy Center entfernen zu lassen, begr\u00fc\u00dft: \u00abGebt mir die Treppe!\u00bb"},"content":{"rendered":"<p>In der Montagsausgabe von \u00abThe View\u00bb vergoss Whoopi Goldberg ein paar Tr\u00e4nen, als sie den Zuschauern mitteilte, dass ein Richter Pr\u00e4sident Trump am Wochenende angewiesen hatte, seinen Namen vom Kennedy Center zu entfernen. Nat\u00fcrlich waren ihre Tr\u00e4nen gespielt, denn die ABC-Moderatorin und ihre Kolleginnen sowie das Publikum jubelten der Nachricht einhellig zu.<\/p>\n<p> Zum Auftakt der Diskussion bemerkte Goldberg, der Pr\u00e4sident habe \u00aban diesem Wochenende noch einige R\u00fcckschl\u00e4ge hinnehmen m\u00fcssen\u00bb und begann, sichtlich ger\u00fchrt, diese aufzuz\u00e4hlen. Zuerst erw\u00e4hnte sie die Entscheidung zur Verleihung der Kennedy Center Honors, die beim Publikum von \u00abThe View\u00bb tosenden Applaus ausl\u00f6ste (so sehr, dass Goldberg sogar eingreifen musste, um die Situation zu beruhigen).<\/p>\n<p> \u00abM\u00e4dchen, wenn sie mir eine Leiter geben, mache ich das kostenlos\u00bb, scherzte Moderatorin Ana Navarro.<\/p>\n<p> Moderatorin Sunny Hostin bezeichnete die Entscheidung als kleinen, aber \u00absehr erfreulichen\u00bb Sieg. Goldberg sah das allerdings etwas anders.<\/p>\n<p> \u00abEin riesiger Sieg!\u00bb, korrigierte sie.<\/p>\n<p> Die Frauen am\u00fcsierten sich besonders \u00fcber das 93-seitige Urteil des Richters und scherzten, er habe sich wohl \u00abeinige Gedanken dazu gemacht\u00bb. F\u00fcr Hostin war der gr\u00f6\u00dfere Erfolg jedoch, dass auch Trumps 1,7 Milliarden Dollar schwerer Fonds f\u00fcr seine Verb\u00fcndeten blockiert wurde. Die Moderatorin merkte an, sie habe lange bef\u00fcrchtet, das System der Gewaltenteilung sei verschwunden, und lobte die Justiz daf\u00fcr, dass sie diesmal Trumps Handlungen unter Kontrolle gebracht habe.<\/p>\n<p> \u00abHabe ich euch nicht gesagt, dass sie es sein w\u00fcrden?\u00bb, jubelte Goldberg.<\/p>\n<p> Frauen haben sich lautstark kritisch \u00fcber Trumps Stiftung ge\u00e4u\u00dfert. Alyssa Farah Griffin sagte zuvor: \u00abDas Schmutzigste, was ich mir vorstellen kann, ist ein geheimer Fonds f\u00fcr seine Verb\u00fcndeten.\u00bb.<\/p>\n<p> <em>Die Sendung \u00abThe View\u00bb wird wochentags um 11:00 Uhr ET auf ABC ausgestrahlt.<\/em><\/p>\n<p> Der Artikel \u00ab\u2018The View\u2019 feiert Trumps erzwungene Namens\u00e4nderung vom Kennedy Center: \u2018Gebt mir eine Leiter'\u00bb erschien zuerst auf TheWrap.<\/p>","protected":false},"excerpt":{"rendered":"<p>In der Sendung \u00abThe View\u00bb am Montag wurde Whoopi Goldberg etwas emotional, als sie den Zuschauern erz\u00e4hlte, wie ein Richter Pr\u00e4sident Trump angewiesen hatte, seine...<\/p>","protected":false},"author":1,"featured_media":5526,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-5525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/5525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/comments?post=5525"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/5525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media\/5526"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media?parent=5525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/categories?post=5525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/tags?post=5525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}