{"id":6813,"date":"2026-06-02T11:10:35","date_gmt":"2026-06-02T08:10:35","guid":{"rendered":"http:\/\/imgist.ru\/nezavisimyj-film-2010-goda-o-chasto-zabyvaemoj-pank-gruppe-priznannyj-luchshim-rok-filmom-vseh-vremen\/"},"modified":"2026-06-02T11:10:35","modified_gmt":"2026-06-02T08:10:35","slug":"ein-2010-erschienener-independentfilm-uber-eine-oft-vergessene-punkband-der-zum-besten-rockfilm-aller-zeiten-gewahlt-wurde","status":"publish","type":"post","link":"https:\/\/imgist.ru\/de\/nezavisimyj-film-2010-goda-o-chasto-zabyvaemoj-pank-gruppe-priznannyj-luchshim-rok-filmom-vseh-vremen\/","title":{"rendered":"Ein 2010 erschienener Independentfilm \u00fcber eine oft vergessene Punkband, der als \u00abder beste Rockfilm aller Zeiten\u00bb gefeiert wurde."},"content":{"rendered":"<p>Filme, die die Geschichten unserer Lieblingsbands erz\u00e4hlen, geh\u00f6ren zu den fesselndsten im Kino. Manchmal ist es jedoch nicht so sehr die Band, die einen guten Film ausmacht, sondern die, die viele vergessen. Der Film aus dem Jahr 2010 <strong>Dakota Fanning<\/strong> \u0438 <strong>Kristen Stewart<\/strong> mit <strong>Cherie Currie<\/strong> \u0438 <strong>Joan Jett<\/strong> Demnach wird die Geschichte vom Aufstieg und Fall der Gruppe erz\u00e4hlt. <em><strong>Die Ausrei\u00dfer,<\/strong><\/em> \u2014 Genau so ein Film ist er. Obwohl er eher ein Kultklassiker ist, ergab eine Leserumfrage des Magazins <em>Rolling Stone<\/em> Das Gegenteil wurde bewiesen, und der Film landete auf Platz eins der Liste der \u00abBesten Rockfilme aller Zeiten\u00bb.<\/p>\n<p> Die Drehbuchautorin und Regisseurin Floria Sigismondi (die mit diesem Film ihr Spielfilmdeb\u00fct gibt) lie\u00df sich von der Geschichte der Punkband inspirieren und wollte einen Coming-of-Age-Film anstelle einer traditionellen Biografie drehen. \u00dcber ihre Geschichte sagte sie:<\/p>\n<p> <em>\u00abWas ich an den Runaways so toll fand, war, dass sie Dinge taten, die M\u00e4dchen eigentlich nicht tun sollten, vor allem nicht mit 15. Ich wollte einfangen, wie es war, noch sehr jung zu sein und sich in dieser Rock&#039;n&#039;Roll-Welt wiederzufinden, zu einer Zeit, in der M\u00e4dchen gerade erst versuchten, ihren K\u00f6rper zu entdecken und ihre Identit\u00e4t zu finden.\u00bb.<\/em><\/p>\n<p> Aktion <em>Film &quot;The Runaways&quot;\u00ab<\/em> \u201eThe Runaways\u201c beginnt 1975, als Joan Jett (gespielt von Stewart) mit Cherie Currie (gespielt von Fanning) die Band The Runaways gr\u00fcndet. Unter der Leitung von Produzent Kim Fowley k\u00e4mpft die rein weibliche Punkband mit Ruhm, Beziehungen und dem turbulenten Rock-&#039;n&#039;-Roll-Lifestyle. Der Film beleuchtet Themen wie psychische Gesundheit und die Musikindustrie und dokumentiert vier Jahre der Karriere von The Runaways.<\/p>\n<p> <em>Die Ausrei\u00dfer\u00ab<\/em> Der Film erhielt \u00fcberwiegend positive Kritiken, wobei die schauspielerischen Leistungen besonders gelobt wurden. Auch wenn es keine gro\u00dfe, filmische Geschichte ist, <em>\u00abDie Ausrei\u00dfer\u00bb<\/em> Es erf\u00fcllt seinen Zweck voll und ganz. Es f\u00e4ngt die Atmosph\u00e4re der Jugend und der Punk-Szene der 1970er Jahre ein und erz\u00e4hlt gleichzeitig die Geschichte der Band auf fesselnde und dynamische Weise.<\/p>\n<p> <strong>\ud83c\udfac <strong>Abonnieren Sie den t\u00e4glichen Newsletter von Parade, um die neuesten Popkultur-News und Promi-Interviews direkt in Ihren Posteingang zu erhalten.<\/strong> \ud83c\udfac<\/strong><\/p>\n<p> <strong>Siehe auch: Das Bourbon &amp; Beyond Festival 2026 bringt die Foo Fighters, Chris Stapleton und weitere K\u00fcnstler nach Louisville.<\/strong><\/p>\n<p> Dieser Artikel wurde urspr\u00fcnglich am 2. Juni 2026 von Parade im Nachrichtenteil ver\u00f6ffentlicht. F\u00fcgen Sie Parade Ihrer Liste empfohlener Quellen hinzu, indem Sie hier klicken.<\/p>","protected":false},"excerpt":{"rendered":"<p>Filme, die die Geschichten unserer Lieblingsbands erz\u00e4hlen, geh\u00f6ren zu den fesselndsten im Kino. Manchmal ist es jedoch weniger die Band selbst, die einen Film gro\u00dfartig macht, sondern\u2026<\/p>","protected":false},"author":1,"featured_media":6814,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-6813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/6813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/comments?post=6813"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/6813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media\/6814"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media?parent=6813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/categories?post=6813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/tags?post=6813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}