{"id":9688,"date":"2026-06-03T18:10:27","date_gmt":"2026-06-03T15:10:27","guid":{"rendered":"https:\/\/imgist.ru\/syn-klinta-istvuda-rasskazal-vazhnuyu-novost-o-svoem-96-letnem-otcze\/"},"modified":"2026-06-03T18:10:27","modified_gmt":"2026-06-03T15:10:27","slug":"clint-eastwoods-sohn-teilte-wichtige-neuigkeiten-uber-seinen-96-jahrigen-vater-mit","status":"publish","type":"post","link":"https:\/\/imgist.ru\/de\/syn-klinta-istvuda-rasskazal-vazhnuyu-novost-o-svoem-96-letnem-otcze\/","title":{"rendered":"Clint Eastwoods Sohn teilte wichtige Neuigkeiten \u00fcber seinen 96-j\u00e4hrigen Vater mit."},"content":{"rendered":"<p>Clint Eastwoods Sohn, Kyle Eastwood, hat eine gro\u00dfe Neuigkeit \u00fcber seinen Vater verk\u00fcndet: Der legend\u00e4re Schauspieler und Regisseur ist offiziell in den Ruhestand getreten.<\/p>\n<p> \u00abIch habe viele sch\u00f6ne Erinnerungen an die Zusammenarbeit mit ihm. Er ist jetzt im Ruhestand, 95 Jahre alt\u00bb, sagte Kyle im November gegen\u00fcber dem franz\u00f6sischen Sender France 3, wie The Independent berichtete.<\/p>\n<p> Clint, der am 31. Mai 96 Jahre alt wurde, arbeitete bei Filmen mit seinem Sohn zusammen. <em>\u00abMillion Dollar Baby\u00bb<\/em> (2004), <em>\u00abBriefe von Iwo Jima\u00bb<\/em> (2006), <em>\u00abGran Torino\u00bb<\/em> (2008) und <em>\u00ab&quot;Unbesiegbar&quot;\u00bb<\/em> (2009).<\/p>\n<p> \u00abIch hatte das gro\u00dfe Gl\u00fcck, mit ihm an mehreren Filmen zusammenarbeiten zu d\u00fcrfen\u00bb, f\u00fcgte Kyle, 58, Filmkomponist und Jazzmusiker, hinzu. \u00abEs war eine wunderbare Erfahrung f\u00fcr mich.\u00bb.<\/p>\n<p> Clints letzter Auftritt vor der Kamera war in <em>im Film &quot;Cry Macho&quot;\u00ab<\/em> 2021, und seine letzte Arbeit als Regisseur war der Film <em>\u00abGeschworener Nr. 2<\/em> \u00bb 2024 mit Nicholas Hoult und Toni Collette in den Hauptrollen.<\/p>\n<p> Clint Eastwoods Schauspielkarriere war vor allem f\u00fcr Sergio Leones Spaghetti-Western bekannt, darunter die Dollar-Trilogie. In den Filmen spielte er den Mann ohne Namen.\u00ab <em>F\u00fcr eine Handvoll Dollar\u00bb<\/em> (1964), <em>\u00ab&quot;F\u00fcr ein paar Dollar mehr&quot;\u00bb<\/em> (1965) und <em>\u00abGut, B\u00f6se und H\u00e4sslich\u00bb<\/em> (1966) Clint spielte dann Inspektor Harry Callahan in dem Film <em>\u00abDirty Harry\u00bb<\/em> (1971) und dessen Fortsetzungen. Er ist auch f\u00fcr seine Rollen in den Filmen bekannt. <em>\u00abFlucht von Alcatraz\u00bb<\/em> (1979), <em>\u00abDie Br\u00fccken von Madison County\u00bb<\/em> (1995), <em>\u00abMillion Dollar Baby\u00bb<\/em> und viele andere.<\/p>\n<p> Clint gewann zwei Oscars f\u00fcr die Regie (Beste Regie und Bester Film) f\u00fcr <em>Million Dollar Baby-Filme\u00ab<\/em> \u0438 <em>\u00abUnvergeben\u00bb<\/em> (1992). Zu seinen weiteren bemerkenswerten Regiearbeiten geh\u00f6ren: <em>\u00ab&quot;High Plains Rogue<\/em> \u00bb (1973), <em>\u00abDer Gesetzlose Josey Wales\u00bb<\/em> (1976), <em>\u00abMystic River\u00bb<\/em> (2003), <em>\u00abAmerikanischer Scharfsch\u00fctze\u00bb<\/em> (2014) und <em>\u00ab&quot;Ausfall&quot;\u00bb<\/em> (2016).<\/p>\n<p> Neben Kyle hat Clint sieben Kinder: die T\u00f6chter Lori, Kimber, Katherine, Morgan, Alison Eastwood (Schauspielerin, Regisseurin und Produzentin), Francesca Eastwood (ebenfalls Schauspielerin) und den Sohn, den Schauspieler Scott Eastwood.<\/p>\n<p> Lesen Sie die aktuellsten Nachrichten aus der Welt der Unterhaltung auf TV Insider.<\/p>","protected":false},"excerpt":{"rendered":"<p>Clint Eastwoods Sohn, Kyle Eastwood, verk\u00fcndete eine wichtige Neuigkeit \u00fcber seinen Vater: Der legend\u00e4re Schauspieler und Regisseur ist offiziell in den Ruhestand getreten. \u00abIch habe viele sch\u00f6ne Erinnerungen \u2026\u201c<\/p>","protected":false},"author":1,"featured_media":9689,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/9688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/comments?post=9688"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/9688\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media\/9689"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media?parent=9688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/categories?post=9688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/tags?post=9688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}