{"id":9973,"date":"2026-06-03T20:10:58","date_gmt":"2026-06-03T17:10:58","guid":{"rendered":"https:\/\/imgist.ru\/dzhonatan-groff-prisoedinilsya-k-denielu-redkliffu-v-trillere-o-vojne-vo-vetname-doversya-cheloveku\/"},"modified":"2026-06-03T20:10:58","modified_gmt":"2026-06-03T17:10:58","slug":"jonathan-groff-spielte-neben-daniel-radcliffe-in-einem-thriller-uber-den-krieg-im-namen-des-mannes","status":"publish","type":"post","link":"https:\/\/imgist.ru\/de\/dzhonatan-groff-prisoedinilsya-k-denielu-redkliffu-v-trillere-o-vojne-vo-vetname-doversya-cheloveku\/","title":{"rendered":"Jonathan Groff spielt neben Daniel Radcliffe in dem Vietnamkriegsthriller Trust the Man."},"content":{"rendered":"<p><strong>EXKLUSIV:<\/strong> Der Tony- und Grammy-Preistr\u00e4ger Jonathan Groff hat einen Vertrag zur Zusammenarbeit mit Daniel Radcliffe an einem Film unterzeichnet. <em>\u00abVertraue dem Mann<\/em> , ein Vietnamkriegsthriller, der im Februar letzten Jahres im Vorfeld des Europ\u00e4ischen Musikfestivals angek\u00fcndigt wurde.<\/p>\n<p> Das von Will Graham geschriebene und inszenierte Projekt bringt das Duo nach ihrer Zusammenarbeit an der mit dem Tony Award ausgezeichneten Produktion von Stephen Sondheims Musical wieder zusammen. <em>\u00abFr\u00f6hlich rollen wir weiter\u00bb<\/em> , das im Laufe seiner Laufzeit im Hudson Theatre mehrfach Besucherrekorde aufstellte.<\/p>\n<p> <strong>Weitere Neuigkeiten von Deadline<\/strong><\/p>\n<ul>\n<li>\n<p> Village Roadshow gibt seine Anteile an \u00abMatrix: Resurrection\u00bb im Rahmen einer 57-Millionen-Dollar-Einigung mit Warner Bros. auf.<\/p>\n<\/li>\n<li>\n<p> Nikki Glaser, Zoe Saldanha, Jonathan Groff und Ethan Hawke geh\u00f6ren zu den Pers\u00f6nlichkeiten aus der Unterhaltungsbranche, die vom Time Magazine in die Liste der 100 einflussreichsten Personen aufgenommen wurden.<\/p>\n<\/li>\n<li>\n<p> Jonathan Groff, Rachel Zegler, Sheryl Lee Ralph und weitere Schauspieler haben sich Lin-Manuel Mirandas Musikfilm \u00abOctet\u00bb angeschlossen.<\/p>\n<\/li>\n<\/ul>\n<p> Die Dreharbeiten finden diesen Sommer in New Jersey statt. <em>\u00ab&quot;Vertraue dem Mann.&quot;.<\/em> Die Handlung dreht sich um einen ehrgeizigen Offizier des Milit\u00e4rgeheimdienstes, der den Fall eines hochdekorierten Soldaten mit einer mysteri\u00f6sen Vergangenheit im Vietnamkrieg untersuchen soll. Mit zunehmender \u00dcberwachung und intensiven Verh\u00f6ren verschwimmt die Grenze zwischen Loyalit\u00e4t und Besessenheit, was die beiden M\u00e4nner in eine gef\u00e4hrliche und unkontrollierbare Beziehung f\u00fchrt.<\/p>\n<p> \u00dcber Groffs Rolle ist noch nichts bekannt. Lucas Hedges sollte urspr\u00fcnglich an der Seite von Radcliffe spielen, sagte aber aufgrund von Terminkonflikten ab.<\/p>\n<p> Zu den Produzenten des Films geh\u00f6ren <em>\u00abVertraue dem Mann\u00bb<\/em> Zum Produktionsteam geh\u00f6ren Graham, Tonia Davis und Max Lynskey von Invitation Media, Luke Rogers und Alex Scott. Jeffrey Soros und Hayley Wierengo fungieren als Executive Producer, Jess Hackel als Co-Produzentin. UTA vertritt die US-Rechte, Neon International die internationalen Rechte.<\/p>\n<p> Sowohl Groff als auch Radcliffe konnten in letzter Zeit Erfolge am Broadway feiern. Im Fr\u00fchjahr dieses Jahres beendete Groff seine f\u00fcr den Tony Award nominierte Performance als Bobby Darin im Musical <em>\u00abJust-in-Time\u00bb<\/em> , das er ebenfalls produzierte. Inzwischen hatte Radcliffe gerade seine f\u00fcr den Tony Award nominierte Performance in dem Ein-Mann-St\u00fcck beendet. <em>\u00abJede brillante Sache\u00bb<\/em> . Beide Serien haben ihre Positionen vollst\u00e4ndig wiedererlangt, und <em>\u00abJust-in-Time\u00bb<\/em> wurde das erste neue Musical der Saison 2024-2025, dem dies gelang.<\/p>\n<p> Groff arbeitet derzeit an einer Verfilmung des Musicals. <em>\u00ab&quot;Oktett&quot;\u00bb<\/em> Sie wird von Lin-Manuel Miranda inszeniert und wird demn\u00e4chst ihr Deb\u00fct bei der Royal Shakespeare Company als Rosalind in der Produktion von geben.\u00ab <em>\u00bbGanz nach Ihrem Geschmack.\u201c<\/em> Ein Film mit ausschlie\u00dflich m\u00e4nnlichen Darstellern unter der Regie von Daniel Evans, der von CAA vertreten wird.<\/p>\n<p> <strong>Das Beste von Deadline<\/strong><\/p>\n<ul>\n<li>\n<p> Alles, was wir bisher \u00fcber die Adaption von \u00abDer Gott des Waldes\u00bb durch Sony Television und Netflix wissen.<\/p>\n<\/li>\n<li>\n<p> Fotogalerie der abgesetzten Fernsehserien 2026: Serien, die in diesem Jahr und dar\u00fcber hinaus enden.<\/p>\n<\/li>\n<li>\n<p> Premierentermine f\u00fcr neue und wiederkehrende Serien auf Fernseh-, Streaming- und Kabelkan\u00e4len im Jahr 2026<\/p>\n<\/li>\n<\/ul>\n<p> Abonnieren Sie den Deadline-Newsletter. F\u00fcr aktuelle Neuigkeiten folgen Sie uns auf Facebook, Twitter und Instagram.<\/p>","protected":false},"excerpt":{"rendered":"<p>EXKLUSIV: Tony- und Grammy-Preistr\u00e4ger Jonathan Groff hat einen Vertrag f\u00fcr die Hauptrolle an der Seite von Daniel Radcliffe in dem Thriller \u00abTrust the Man\u00bb unterzeichnet\u2026<\/p>","protected":false},"author":1,"featured_media":9974,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/9973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/comments?post=9973"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/posts\/9973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media\/9974"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/media?parent=9973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/categories?post=9973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/de\/wp-json\/wp\/v2\/tags?post=9973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}