{"id":12810,"date":"2026-06-05T00:13:51","date_gmt":"2026-06-04T21:13:51","guid":{"rendered":"https:\/\/imgist.ru\/lia-mishel-i-kristin-chenouet-poyavyatsya-na-czeremonii-vrucheniya-premii-toni-v-2026-godu-posle-togo-kak-ih-ne-nominirovali-na-premiyu\/"},"modified":"2026-08-29T12:10:34","modified_gmt":"2026-08-29T09:10:34","slug":"lia-michelle-y-kristin-chenouet-apareceran-en-los-premios-tony-2026-despues-de-haber-sido-declaradas-no-elegibles-para-los-premios","status":"publish","type":"post","link":"https:\/\/imgist.ru\/es\/lia-mishel-i-kristin-chenouet-poyavyatsya-na-czeremonii-vrucheniya-premii-toni-v-2026-godu-posle-togo-kak-ih-ne-nominirovali-na-premiyu\/","title":{"rendered":"Lea Michele y Kristin Chenoweth aparecer\u00e1n en los Premios Tony 2026 despu\u00e9s de haber sido ignoradas para los galardones."},"content":{"rendered":"<h3>LO QUE NECESITA SABER<\/h3>\n<p> <strong>Principales conclusiones<\/strong><\/p>\n<ul>\n<li>\n<p> Lea Michele actuar\u00e1 en el n\u00famero de apertura repleto de estrellas, que contar\u00e1 con la participaci\u00f3n de m\u00e1s de 170 estrellas de Broadway y la presentadora Pink.<\/p>\n<\/li>\n<li>\n<p> Kristin Chenoweth se unir\u00e1 a un elenco de presentadores que tambi\u00e9n incluye a Ariana DeBose, Neil Patrick Harris, Megan Thee Stallion y otros.<\/p>\n<\/li>\n<li>\n<p> La ceremonia contar\u00e1 con n\u00fameros especiales dedicados a musicales emblem\u00e1ticos como Rent, Chicago y The Book of Mormon.<\/p>\n<\/li>\n<\/ul>\n<p> Puede que Lea Michele y Kristin Chenoweth no est\u00e9n nominadas a los premios Tony este a\u00f1o, pero aun as\u00ed subir\u00e1n al escenario del evento m\u00e1s importante de Broadway.<\/p>\n<p> Se ha anunciado la impresionante lista de artistas y presentadores que participar\u00e1n en la 79.\u00aa edici\u00f3n de los Premios Tony, que tendr\u00e1 lugar el domingo 7 de junio. Michelle y Chenoweth figuran entre las estrellas que se espera que asistan.<\/p>\n<p> Ambas actrices estuvieron notablemente ausentes de las nominaciones a los premios Tony de este a\u00f1o. Michelle era considerada una de las candidatas por su actuaci\u00f3n en la obra. <em>\u00ab&quot;Ajedrez&quot;\u00bb<\/em> , Chenoweth recibi\u00f3 grandes elogios de la cr\u00edtica por su actuaci\u00f3n en la obra. <em>\u00abLa Reina de Versalles\u00bb<\/em> .<\/p>\n<p> <strong>No te pierdas ninguna noticia: suscr\u00edbete a<\/strong> <strong>Bolet\u00edn informativo diario gratuito PEOPLE<\/strong> <strong>, Para estar al d\u00eda de lo mejor que ofrece PEOPLE, desde noticias de famosos hasta conmovedoras historias humanas.<\/strong> <\/p>\n<p> Pink en el estreno de &quot;All of You&quot; el 17 de septiembre de 2025. Foto: Dia Dipasupil\/Getty.<\/p>\n<p> Michelle actuar\u00e1 como parte del n\u00famero de apertura de este a\u00f1o, que contar\u00e1 con m\u00e1s de 170 estrellas de Broadway, muchas de ellas de los musicales m\u00e1s exitosos de este a\u00f1o, cantando junto a la presentadora Pink.<\/p>\n<p> El tema musical de apertura ser\u00e1 escrito por los ganadores del premio EGOT Benj Pasek y Justin Paul ( <em>Querido Evan Hansen (pel\u00edculas)\u00ab<\/em> , <em>\u00abEl gran showman\u00bb<\/em> ), as\u00ed como el ganador del Oscar y del Grammy, Mark Sonnenblick ( <em>Serie de K-pop &quot;Cazadores de demonios&quot;\u00ab<\/em> La coreograf\u00eda de la pieza estar\u00e1 a cargo de Sarah O&#039;Gleby, con Tim Murray e Isaac Josephtal como asesores creativos.<\/p>\n<p> Mientras tanto, Chenoweth se une a la lista de presentadores junto a Adrien Brody, Annette Bening, Ariana DeBose, Ben Platt, Bernadette Peters, Billy Crystal, Brian Stokes Mitchell, Carrie Coon, Cole Escola, Darren Criss, Jack O&#039;Brien, Jeremy Pope, John Leguizamo, Julia Louis-Dreyfus, Cara Young, Kelli O&#039;Hara, Law Roach, Lena Waithe, Lily Rabe, Maya Rudolph, Megan Thee Stallion, Neil Patrick Harris, Nicole Scherzinger, Patrick Wilson, Paul Rudd, Ruben Santiago-Hudson, Sarah Paulson y Sting. <\/p>\n<p> El elenco del musical de Broadway &quot;Titanic&quot;. Foto: Evan Zimmerman para MurphyMade.<\/p>\n<p> Los premios Tony, creados por la Asociaci\u00f3n Americana de Teatro y la Liga de Broadway, son considerados el galard\u00f3n m\u00e1s prestigioso del teatro y reconocen los logros m\u00e1s destacados en actuaci\u00f3n, direcci\u00f3n, escenograf\u00eda y otras disciplinas. Adem\u00e1s, forman la &quot;T&quot; del acr\u00f3nimo &quot;EGOT&quot;, junto con los premios Emmy (televisi\u00f3n), los premios Grammy (m\u00fasica) y los premios \u00d3scar (cine).<\/p>\n<p> Este espect\u00e1culo es conocido por mostrar lo mejor del talento teatral en las artes creativas.<\/p>\n<p> Por lo general, el programa incluye actuaciones nominadas a Mejor Musical y Mejor Reposici\u00f3n de un Musical, y este a\u00f1o no es una excepci\u00f3n. <em>\u00abLos Ni\u00f1os Perdidos\u00bb<\/em> , <em>\u00ab&quot;\u00a1Schmigadun!&quot;\u00bb<\/em> , <em>\u00abTit\u00e1nico\u00bb<\/em> , <em>\u00abDos extra\u00f1os (Llevando un pastel por Nueva York)\u00bb<\/em> , <em>\u00abGatos: El baile Jellicle\u00bb<\/em> , <em>\u00ab&quot;Rag-time&quot;\u00bb<\/em> \u0438 <em>\u00abEl show de terror de Rocky de Richard O&#039;Brien<\/em> Se interpretar\u00e1n fragmentos de sus producciones. <\/p>\n<p> El elenco del musical &quot;Cats: The Jellicle Ball&quot; en Broadway. Foto: Matthew Murphy y Evan Zimmerman para MurphyMade.<\/p>\n<p> La ceremonia tambi\u00e9n conmemorar\u00e1 los aniversarios de los estrenos de los musicales. <em>\u00abEl Libro de Morm\u00f3n\u00bb<\/em> , <em>\u00abAlquiler, Chicago\u00bb<\/em> \u0438 <em>\u00ab&quot;Cuerpo de baile&quot;.<\/em><\/p>\n<p> En honor al 15\u00ba aniversario de la producci\u00f3n de Broadway, el elenco original del musical <em>\u00abEl Libro de Morm\u00f3n\u00bb<\/em> El elenco, que incluye a Josh Gad, Andrew Rannells, Rory O&#039;Malley y Nikki M. James, se reunir\u00e1 en el escenario para un n\u00famero musical. Los ganadores del premio Tony, Trey Parker, Matt Stone y Robert Lopez, presentar\u00e1n la obra.<\/p>\n<p> <em>En Chicago<\/em> Celebrar\u00e1 su 30 aniversario en Broadway con un elenco estelar que incluye a Pink, Jesse Tyler Ferguson, Alex Newell, Adrienne Warren, Cedric &quot;The Entertainer&quot;, Julianne Hough, Whitney Leavitt, Dylan Mulvaney y Queen Latifah (esta \u00faltima fue nominada a un Oscar por su papel de Matron Mama Morton en la adaptaci\u00f3n cinematogr\u00e1fica).<\/p>\n<p> Rachel Zegler, que regresar\u00e1 a Broadway la pr\u00f3xima temporada en <em>el musical &quot;Evita&quot;\u00ab<\/em> , interpretar\u00e1 un n\u00famero en honor al 50 aniversario del musical. <em>\u00abUna l\u00ednea coral\u00bb<\/em> , y Leslie Odom Jr. honrar\u00e1 la memoria de los artistas de Broadway que han fallecido en el \u00faltimo a\u00f1o interpretando &quot;Without You&quot; de <em>musical &quot;Rent&quot;<\/em> \u00bb&quot;En reconocimiento al 30 aniversario de este innovador musical.&quot;.<\/p>\n<p> La 79.\u00aa edici\u00f3n de los Premios Tony se transmitir\u00e1 en vivo desde el Radio City Music Hall de Nueva York el domingo 7 de junio (a partir de las 20:00 ET\/17:00 PT) por CBS y se podr\u00e1 ver en l\u00ednea a trav\u00e9s de Paramount+. Laura Benanti y Tituss Burgess presentar\u00e1n un programa previo a la transmisi\u00f3n. <em>\u00abPremios Tony: Acto uno\u00ab<\/em> , que se transmitir\u00e1 en vivo por Pluto TV.<\/p>\n<p> Lee el art\u00edculo original en People.<\/p>","protected":false},"excerpt":{"rendered":"<p>LO QUE DEBES SABER Puntos clave: Lea Michele actuar\u00e1 en el n\u00famero de apertura repleto de estrellas, con m\u00e1s de 170 estrellas de Broadway y la presentadora Pink. Kristin Chenoweth se unir\u00e1\u2026<\/p>","protected":false},"author":1,"featured_media":12811,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-12810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/12810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/comments?post=12810"}],"version-history":[{"count":3,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/12810\/revisions"}],"predecessor-version":[{"id":156268,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/12810\/revisions\/156268"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media\/12811"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media?parent=12810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/categories?post=12810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/tags?post=12810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}