{"id":22480,"date":"2022-06-09T11:52:16","date_gmt":"2022-06-09T09:52:16","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/?p=22480"},"modified":"2022-06-09T11:52:16","modified_gmt":"2022-06-09T09:52:16","slug":"10-casos-de-armas-anacronicas-utilizadas-en-la-guerra","status":"publish","type":"post","link":"https:\/\/imgist.ru\/es\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne\/","title":{"rendered":"10 casos de armas anacr\u00f3nicas utilizadas en la guerra"},"content":{"rendered":"<p>A pesar de su enfoque territorial lento y retr\u00f3grado, las fuerzas armadas mundiales est\u00e1n bajo constante presi\u00f3n para mantenerse a la vanguardia. De lo contrario, pierden guerras. Al menos en teor\u00eda. En la pr\u00e1ctica, no siempre es as\u00ed. Estas diez armas del pasado remoto se utilizan en campos de batalla modernos, a veces incluso con \u00e9xito.<\/p>\n<h2>10. Club (1918)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-83168\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_6489892d03757.jpeg\" alt=\"\" width=\"893\" height=\"644\" \/><\/p>\n<p><a href=\"https:\/\/imgist.ru\/es\/10-nerazgadannyx-tajn-pervoj-mirovoj-vojny\/\">Primera Guerra Mundial<\/a>, La llamada &quot;Gran Guerra&quot; introdujo todo tipo de armas para el combate a larga distancia: desde tanques y submarinos hasta ametralladoras y gas nervioso. Sin embargo, en la pr\u00e1ctica, en la cruda realidad de la guerra de trincheras, los soldados de ambos bandos improvisaron armas blancas. Convirtieron estacas en cuchillos de empuje, herramientas de atrincheramiento en hachas de guerra y cualquier objeto que pudiera pasarse entre s\u00ed en garrotes.<\/p>\n<p>Los garrotes eran particularmente brutales. Algunos eran simples trozos de madera, mientras que otros eran mucho m\u00e1s elaborados; por ejemplo, la maza alemana, con correas de mu\u00f1eca improvisadas y p\u00faas mortales en la cabeza. La versi\u00f3n francesa, que tambi\u00e9n serv\u00eda como bast\u00f3n, estaba hecha de madera nudosa natural, mango de cuero, pesas de plomo y p\u00faas de hierro. Por otro lado, los garrotes brit\u00e1nicos sol\u00edan ser m\u00e1s sencillos. El golpeador, por ejemplo, era el mango de una pala de trinchera est\u00e1ndar con una cabeza de metal moleteado.<\/p>\n<p>La eficacia de esta arma para las incursiones en trincheras pronto condujo a su estandarizaci\u00f3n y producci\u00f3n en masa para el uso oficial del ej\u00e9rcito.<\/p>\n<h2>9. Lance (1939)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-83173 aligncenter\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_64898934381cc.jpeg\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Un retorno simb\u00f3lico a la era de la caballer\u00eda, duelos entre caballeros a caballo, la lanza se us\u00f3 hasta <a href=\"https:\/\/imgist.ru\/es\/10-nerazgadannyx-tajn-vtoroj-mirovoj-vojny\/\">Segunda Guerra Mundial<\/a> \u2014 al menos seg\u00fan la leyenda. El 1 de septiembre de 1939, seg\u00fan cuenta la historia, el veterano coronel polaco Kazimierz Mastalerz y su caballer\u00eda avistaron una gran cantidad de fuerzas alemanas \u2014mucho mayores que las suyas y apoyadas por tanques\u2014 y comprendieron que necesitar\u00edan el factor sorpresa. Mastalerz decidi\u00f3 cargar. Y a pesar de ser diezmados por las ametralladoras, los lanceros a caballo lograron dispersar al enemigo.<\/p>\n<p>En realidad, esta dram\u00e1tica historia fue difundida por propagandistas italianos y alemanes. Mastalerz y su caballer\u00eda s\u00ed atacaron al enemigo, pero no con la ingenuidad que recordaban, y probablemente no con lanzas.<\/p>\n<p>Sin embargo, aunque la caballer\u00eda polaca despu\u00e9s de 1937 sol\u00eda usar fusiles antitanque, las lanzas segu\u00edan formando parte de su arsenal. El atractivo de la lanza, utilizada a discreci\u00f3n del comandante, radicaba en su impacto psicol\u00f3gico sobre el enemigo.<\/p>\n<h2>8. Pu\u00f1os americanos (1945)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-83169\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_6489892e1d844.jpeg\" alt=\"\" width=\"1920\" height=\"1471\" \/><\/p>\n<p>Los nudillos de lat\u00f3n probablemente se usaron por primera vez en el siglo XII en la India, donde se encontraron objetos puntiagudos. <i>vajra-mushti<\/i>, El pu\u00f1o, o &quot;pu\u00f1o trueno&quot;, era un sello distintivo de la lucha libre. Antes de esto, el aumento del pu\u00f1o con accesorios met\u00e1licos generalmente tomaba la forma de un guante, como un cestus, que <i>visti\u00f3<\/i> gladiadores romanos.<\/p>\n<p>M\u00e1s tarde, se utilizaron nudillos de lat\u00f3n durante la Guerra Civil Estadounidense. De hecho, <a href=\"https:\/\/imgist.ru\/es\/10-iconos-historicos-que-todo-el-mundo-malinterpreta\/\">Abraham Lincoln<\/a> Se sab\u00eda que tanto ellos como sus guardaespaldas portaban esta arma.<\/p>\n<p>M\u00e1s recientemente, se utilizaron en la Primera y la Segunda Guerra Mundial. Esto se debi\u00f3 a varios motivos. Adem\u00e1s de su utilidad en los asaltos a trincheras en combate cuerpo a cuerpo, tambi\u00e9n eran econ\u00f3micas de adquirir o f\u00e1ciles de fabricar fundiendo balas de plomo y molde\u00e1ndolas. Otra ventaja era la libertad de uso de los dedos al transportarlas, lo que permit\u00eda a los soldados recargar sus armas.<\/p>\n<h2>7. La cerbatana (1945)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-83170\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_6489893084c79.jpeg\" alt=\"\" width=\"837\" height=\"630\" \/><\/p>\n<p>Las pistolas de aire comprimido son silenciosas y letales. En el instante en que la v\u00edctima oye el dardo, muere al instante (o peor, seg\u00fan el veneno). En 1964, fueron utilizadas por la guerrilla en el Congo, asesinando al jefe del Estado Mayor del ej\u00e9rcito congole\u00f1o, a un misionero estadounidense y a otras personas.<\/p>\n<p>Estas no son las armas que uno asociar\u00eda con la guerra moderna. Sin embargo, parece que contribuyeron a la victoria de los Aliados en la Segunda Guerra Mundial. Durante la campa\u00f1a de Borneo, se anim\u00f3 a los cazadores de cabezas dayak locales a usar sus cerbatanas contra los japoneses. Incluso tropas estadounidenses se unieron a ellos. Tras estrellarse su bombardero B-24 Liberator, un soldado estadounidense salt\u00f3 en paraca\u00eddas sobre la isla, fue rescatado por dayaks y entrenado en el uso de cerbatanas. Dos d\u00e9cadas despu\u00e9s, la situaci\u00f3n se invirti\u00f3 y las tropas estadounidenses invasoras se encontraron bajo el fuego del Viet Cong en Vietnam.<\/p>\n<p>En 2022, soldados estadounidenses estacionados en Haw\u00e1i utilizaron dardos contra gatos callejeros en Oahu, lo que provoc\u00f3 indignaci\u00f3n entre los residentes locales.<\/p>\n<h2>6. Arco y flecha (1945)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-66930 aligncenter\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_64898931cbcc9.jpeg\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Seg\u00fan el diario de la 4.\u00aa Brigada de Infanter\u00eda brit\u00e1nica durante la Segunda Guerra Mundial, \u00abver al capit\u00e1n Churchill caminando por la playa con arco y flechas\u00bb fue uno de los momentos m\u00e1s alentadores al desembarcar en Dunkerque. \u00abEl Loco\u00bb Jack Churchill era conocido por su afici\u00f3n a las armas antiguas, llegando a declarar que \u00abcualquier oficial que vaya a la batalla sin espada va mal vestido\u00bb. Pero tambi\u00e9n cre\u00eda en el arco largo. Tras la batalla de Epinette, en Francia, cuando su compa\u00f1\u00eda qued\u00f3 acorralada por los nazis, mat\u00f3 al primer soldado enemigo con su arco largo antes de recurrir a las ametralladoras.<\/p>\n<p>Incluso hoy en d\u00eda, algunas personas se preguntan por qu\u00e9 el tiro con arco ha ca\u00eddo en desuso. El propio Ej\u00e9rcito de los EE. UU. ha demostrado su superioridad t\u00e1ctica, al menos en algunas situaciones. En 2015, por ejemplo, las Fuerzas Especiales dispararon a una caja llena de tierra utilizando una variedad de armas (la autom\u00e1tica M1911A1 .45, la carabina .30 M1, el rifle .30 M1 y <a href=\"https:\/\/pro2020god.ru\/kak-vybrat-blochnyj-luk\/\" target=\"_blank\" rel=\"noopener\">arco moderno<\/a>), y solo el arco y la flecha disparados desde el otro lado. Otra ventaja, por supuesto, es que son f\u00e1ciles de hacer en el campo.<\/p>\n<h2>5. Ballesta (1999)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-83171 aligncenter\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_64898932a5a89.png\" alt=\"\" width=\"640\" height=\"432\" \/><\/p>\n<p>Las ballestas, inventadas hace dos mil quinientos a\u00f1os, se utilizaron en la guerra de Vietnam el siglo pasado. Pero all\u00ed, eran el arma tradicional de los ind\u00edgenas de las tierras altas, o &quot;monta\u00f1eses&quot;.<\/p>\n<p>Menos tradicional fue su uso por parte de los serbios contra el Ej\u00e9rcito de Liberaci\u00f3n de Kosovo (ELK) en la d\u00e9cada de 1990. Sorprendentemente, no se limitaron a usar cualquier arma que tuvieran a mano. Se seleccionaron e importaron ballestas espec\u00edficamente de Inglaterra como arma predilecta para contrarrestar a los francotiradores. No solo son silenciosas, dijo un periodista en aquel entonces, sino que tambi\u00e9n &quot;tienen un efecto psicol\u00f3gico&quot;. Tambi\u00e9n recordaron al criminal de guerra serbio Arkan, quien a principios de la d\u00e9cada de 1990 us\u00f3 ballestas y &quot;otras armas ex\u00f3ticas&quot; para infundir terror en los corazones de sus enemigos.<\/p>\n<p>Pero exist\u00eda otra raz\u00f3n, m\u00e1s pr\u00e1ctica. Dado que los brit\u00e1nicos las clasificaban como equipo deportivo, las ballestas no estaban sujetas a las mismas restricciones de exportaci\u00f3n que otras armas letales. Por lo tanto, al menos hasta que el gobierno brit\u00e1nico se enter\u00f3, pod\u00edan importarse libremente a la zona de guerra. Los pa\u00edses m\u00e1s cercanos al conflicto, como Eslovenia y Croacia, no eran tan permisivos, como descubri\u00f3 el ELK cuando intent\u00f3 comprarles algunas armas.<\/p>\n<h2>4. Bayoneta (2004)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-78860 aligncenter\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_6489892ca1ad5.png\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Las bayonetas no se han usado con regularidad desde la Guerra de Vietnam. Basadas en lanzas, est\u00e1n dise\u00f1adas para perforar al enemigo, lo cual, dado que se montan en fusiles, era mucho m\u00e1s importante antes de la recarga autom\u00e1tica, como durante la Guerra de Independencia y la Guerra Civil estadounidense. Solo se usaron en Vietnam porque la jungla hac\u00eda inevitable el combate cuerpo a cuerpo. .<\/p>\n<p>Sin embargo, en 2004, un cabo brit\u00e1nico lider\u00f3 una carga a la bayoneta contra los talibanes en Helmand. Bajo el intenso fuego de soldados cercanos, su patrulla se repleg\u00f3 a una zanja y se percat\u00f3 de que estaban acorralados. Mientras dos hombres les proporcionaban fuego de cobertura, el cabo y otros tres saltaron y cargaron. Los soldados talibanes, aparentemente tan desorientados, se retiraron, y cuando reaparecieron, ya hab\u00edan llegado los refuerzos.<\/p>\n<p>Las lanzas se usaban incluso antes que las bayonetas, pero no por los ej\u00e9rcitos modernos avanzados. En diciembre de 2019, antes de adquirir armas de fuego, los masalitas de Darfur todav\u00eda se defend\u00edan con lanzas, as\u00ed como con <a href=\"https:\/\/imgist.ru\/es\/los-10-cuchillos-y-dagas-mas-caros-del-mundo\/\">cuchillos y dagas<\/a>.<\/p>\n<h2>3. Trebuchet (2014)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-83172 aligncenter\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_648989339574a.jpeg\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Otra arma procedente de China, siglo IV a. C., <a href=\"https:\/\/imgist.ru\/es\/10-increibles-estructuras-defensivas-de-castillos-antiguos\/\">trabuquete<\/a> Cayeron en desuso durante la Edad Media. Su \u00faltimo uso hist\u00f3rico tuvo lugar durante el asedio de Tenochtitl\u00e1n en 1521. Desde entonces, han sido reemplazados por la artiller\u00eda.<\/p>\n<p>Sin embargo, en 2014, los rebeldes sirios construyeron trabuquetes para combatir a Assad. Su ventaja sobre las armas modernas (falta de sonido, luz, calor, etc.) fue pura coincidencia; los rebeldes usaron lo que ten\u00edan a mano. Por ejemplo, fabricaron sus propios lanzagranadas con bolas decorativas y cartuchos de escopeta. Tambi\u00e9n adaptaron mandos de videojuegos para disparar morteros y construyeron sus propios &quot;tanques&quot;: veh\u00edculos recubiertos de chapa ondulada.<\/p>\n<h2>2. Espada (2020)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-73189 aligncenter\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_6489892b9319f.jpeg\" alt=\"\" width=\"640\" height=\"422\" \/><\/p>\n<p>En Yemen, es frecuente ver hombres con espadas, muchas de las cuales fueron forjadas con fragmentos de la calle durante la guerra civil. Aunque el Yemen <i>jambiya<\/i> tradicionalmente simb\u00f3lico (como el sijismo) <i>kirpan<\/i>Los hut\u00edes lo utilizaron para oprimir continuamente a la poblaci\u00f3n. En un incidente particularmente brutal, apu\u00f1alaron a un joven hasta la muerte tras golpearlo con alambre, supuestamente por haber descubierto casos de corrupci\u00f3n.<\/p>\n<p>Pero la \u00faltima vez que se entregaron espadas a las tropas fue durante la Primera Guerra Mundial. A pesar de todas las nuevas armas que debutaron en ese conflicto, el sable de caballer\u00eda se mantuvo en uso. Para los soldados brit\u00e1nicos y de la Commonwealth, se trataba del modelo de 1908, al que se le atribuye la primera derrota de Gran Breta\u00f1a en la guerra; el capit\u00e1n Hornby, del 4.\u00ba Regimiento de Dragones de la Guardia, mat\u00f3 a un alem\u00e1n del 4.\u00ba Regimiento de Coraceros. Dise\u00f1ado para montar a caballo, el dise\u00f1o (aprobado a rega\u00f1adientes por el rey Eduardo VII, quien lo calific\u00f3 de \u00ababominable\u00bb) estaba pensado para correr y matar al enemigo. En otras palabras, era para apu\u00f1alar, no para cortar.<\/p>\n<p>Aunque los soldados japoneses trajeron espadas cortantes (<i>katanas<\/i>Durante la Segunda Guerra Mundial, no estaban destinadas a ser usadas como armas. Eran preciadas reliquias familiares, entregadas a los soldados como amuleto de buena suerte. Se esperaba que ambos regresaran a casa sanos y salvos. Sin embargo, Estados Unidos, a\u00fan conmocionado por la matanza de medio mill\u00f3n de civiles, oblig\u00f3 a Jap\u00f3n a entregarlas todas, sabiendo que una espada samur\u00e1i entregada perder\u00eda su valor.<\/p>\n<h2>1. \u00abMaxim Machine Gun\u00bb (2022)<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-83166 aligncenter\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/06\/10-sluchaev-primeneniya-anahronichnogo-oruzhiya-na-vojne_6489892c0e68f.jpeg\" alt=\"\" width=\"640\" height=\"429\" \/><\/p>\n<p>La versi\u00f3n rusa de la primera ametralladora autom\u00e1tica se denomin\u00f3 &quot;Maxim 1910&quot;, o M1910 para abreviar. La Maxim original, de fabricaci\u00f3n brit\u00e1nica, introducida dos d\u00e9cadas y media antes, en 1884, hab\u00eda impresionado tanto a Rusia durante la guerra contra Jap\u00f3n (1904-1905) que emprendieron su desarrollo. Unos a\u00f1os m\u00e1s tarde, fue utilizada por el Ej\u00e9rcito Imperial Ruso en la Primera Guerra Mundial, dando origen al apodo de aquel conflicto: la guerra de ametralladoras. Tambi\u00e9n fue utilizada por el Ej\u00e9rcito Rojo en la Guerra Civil Rusa y en la Segunda Guerra Mundial.<\/p>\n<p>El a\u00f1o pasado, Ucrania la utiliz\u00f3 contra Rusia. Aunque los medios los ridiculizaron, ten\u00edan una buena raz\u00f3n. A diferencia de las ametralladoras modernas, esta voluminosa reliquia de disparo r\u00e1pido, fija y de principios del siglo XX, cuenta con un sistema de refrigeraci\u00f3n l\u00edquida: una camisa de agua de lat\u00f3n alrededor del ca\u00f1\u00f3n. Las ametralladoras modernas disparan en r\u00e1fagas para evitar el sobrecalentamiento, la deformaci\u00f3n del ca\u00f1\u00f3n y la detonaci\u00f3n prematura de la munici\u00f3n. En cambio, la M1910 puede disparar de forma continua durante varios minutos.<\/p>\n<p>Esta no fue la \u00fanica antig\u00fcedad que utilizaron. Los ucranianos tambi\u00e9n emplearon un ob\u00fas M101 de fabricaci\u00f3n estadounidense y una pieza de artiller\u00eda D-44 de principios de la d\u00e9cada de 1940.<\/p>","protected":false},"excerpt":{"rendered":"<p>A pesar de su enfoque territorial lento y retr\u00f3grado, las maquinarias militares del mundo est\u00e1n bajo constante presi\u00f3n para mantenerse a la vanguardia. Si no lo hacen\u2026<\/p>","protected":false},"author":1,"featured_media":22481,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-22480","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/22480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/comments?post=22480"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/22480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media\/22481"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media?parent=22480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/categories?post=22480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/tags?post=22480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}