{"id":3451,"date":"2026-05-31T17:44:07","date_gmt":"2026-05-31T14:44:07","guid":{"rendered":"https:\/\/imgist.ru\/tehasskie-rogatye-yashhericzy-ischezali-a-teper-proczvetayut\/"},"modified":"2026-08-29T11:30:26","modified_gmt":"2026-08-29T08:30:26","slug":"los-gusanos-cornudos-del-fresno-de-texas-desaparecieron-y-ahora-proliferan","status":"publish","type":"post","link":"https:\/\/imgist.ru\/es\/tehasskie-rogatye-yashhericzy-ischezali-a-teper-proczvetayut\/","title":{"rendered":"Los lagartos cornudos de Texas estaban extintos, pero ahora est\u00e1n prosperando."},"content":{"rendered":"<p>El art\u00edculo &quot;Los lagartos cornudos de Texas estaban desapareciendo, ahora est\u00e1n prosperando&quot; apareci\u00f3 originalmente en AZ Animals.<\/p>\n<p> El lagarto cornudo de Texas ha desempe\u00f1ado un papel importante en la historia y la cultura de Texas durante siglos. Anta\u00f1o un elemento b\u00e1sico de los h\u00e1bitats de todo el estado, su poblaci\u00f3n ha disminuido en los \u00faltimos 30 o 40 a\u00f1os. Sin embargo, gracias a los esfuerzos del Zool\u00f3gico de San Antonio, se espera que la poblaci\u00f3n de lagartos cornudos de Texas regrese a su h\u00e1bitat natural.<\/p>\n<h2> Los lagartos cornudos de Texas nacidos en cautividad est\u00e1n prosperando en estado salvaje.<\/h2>\n<p> El lagarto cornudo de Texas ha estado asociado con Texas durante generaciones. Gracias a su apariencia distintiva y a sus v\u00ednculos culturales e hist\u00f3ricos con el estado, reconocer a este reptil como el s\u00edmbolo oficial de Texas fue una tarea sencilla.<\/p>\n<p> Lamentablemente, en las d\u00e9cadas transcurridas desde que esta criatura fue declarada reptil oficial del estado, la poblaci\u00f3n de lagartos cornudos de Texas ha seguido disminuyendo. Aunque no existen censos oficiales, estos lagartos se han extinguido en algunas regiones del estado.<\/p>\n<p> Afortunadamente, el Centro de Conservaci\u00f3n e Investigaci\u00f3n del Zool\u00f3gico de San Antonio intervino para solucionar este problema. Gracias a sus esfuerzos, el lagarto cornudo de Texas podr\u00eda tener una oportunidad de sobrevivir. <\/p>\n<p> Los lagartos cornudos de Texas nacidos en cautividad est\u00e1n prosperando en las zonas de Texas donde fueron liberados.<\/p>\n<p> \u00a9Martens Coyotes\/Shutterstock.com<\/p>\n<p> Esta semana, el zool\u00f3gico de San Antonio anunci\u00f3 el rotundo \u00e9xito de su programa de liberaci\u00f3n de lagartos cornudos en Texas. Las observaciones de campo confirmaron que los lagartos nacidos en el zool\u00f3gico en 2024 y 2025 y liberados en las praderas de la zona central del estado siguen vivos. Seg\u00fan el Dr. Dante Fenoglio, vicepresidente del Centro para la Conservaci\u00f3n e Investigaci\u00f3n, no solo est\u00e1n vivos, sino que se encuentran en excelente estado de salud.<\/p>\n<p> \u00abEs en momentos como estos cuando hacemos este trabajo\u00bb, explic\u00f3 el Dr. Fenoglio a la cadena de televisi\u00f3n. <em>WOAI San Antonio<\/em> . &quot;Una cosa es liberar animales en la naturaleza, y otra muy distinta es verlos prosperar en ella, creciendo y dispers\u00e1ndose de forma natural. Esa s\u00ed es una verdadera contribuci\u00f3n a la conservaci\u00f3n.&quot;.<\/p>\n<p> Los investigadores esperaban pasar muchas horas buscando a los esquivos lagartos cornudos. Pero, como descubri\u00f3 Becky Musher-Hodges, directora del Centro para la Conservaci\u00f3n e Investigaci\u00f3n, encontrar a los lagartos result\u00f3 ser menos dif\u00edcil de lo previsto.<\/p>\n<p> \u00ab&quot;Dej\u00e9 el recipiente para excrementos y de repente vi parte de un lagarto cornudo justo a mi lado&quot;, declar\u00f3 Musher-Hodges al medio de comunicaci\u00f3n. &quot;Fue incre\u00edble. Siempre esperamos encontrarlos, pero momentos como este nunca dejan de emocionarnos&quot;.<\/p>\n<p> Se confirm\u00f3 que el lagarto hallado por Musher-Hodges hab\u00eda nacido en el zool\u00f3gico de San Antonio en 2025. Ese mismo d\u00eda, se avist\u00f3 otro lagarto a medio kil\u00f3metro del lugar de liberaci\u00f3n inicial. Se determin\u00f3 que este lagarto cornudo de Texas hab\u00eda nacido en el zool\u00f3gico en 2024.<\/p>\n<p> A\u00fan m\u00e1s incre\u00edble es que el tercer lagarto descubierto por los investigadores no era el que fue liberado del zool\u00f3gico. Se cree que es uno de los primeros lagartos nacidos en libertad como parte del programa de reintroducci\u00f3n. Los estudios gen\u00e9ticos a\u00fan no lo han confirmado. De ser cierto, el Centro de Conservaci\u00f3n e Investigaci\u00f3n habr\u00eda contribuido al aumento de la poblaci\u00f3n de lagartos cornudos de Texas en regiones donde muchos pensaban que nunca m\u00e1s se volver\u00edan a ver.<\/p>\n<h2> \u00bfQu\u00e9 provoc\u00f3 el dr\u00e1stico descenso de la poblaci\u00f3n de lagartos cornudos de Texas?<\/h2>\n<p> Quienes han vivido en Texas durante generaciones probablemente recuerden una \u00e9poca en la que el lagarto cornudo de Texas era bastante com\u00fan. Ya no es as\u00ed. De hecho, en regiones donde antes abundaban, ahora no hay lagartos. La disminuci\u00f3n de las poblaciones de lagartos no se debe a un solo factor, sino a una multitud de factores que han agravado el problema. <\/p>\n<p> Numerosos factores, entre ellos la p\u00e9rdida y la fragmentaci\u00f3n del h\u00e1bitat, han provocado la extinci\u00f3n del lagarto cornudo de Texas en algunas zonas de Texas.<\/p>\n<p> \u00a9Matt Jeppson\/Shutterstock.com<\/p>\n<p> Las razones por las que la poblaci\u00f3n de lagartos cornudos en Texas ha disminuido a una fracci\u00f3n de sus niveles anteriores son las siguientes:<\/p>\n<ul>\n<li>\n<p> P\u00e9rdida de h\u00e1bitat<\/p>\n<\/li>\n<li>\n<p> fragmentaci\u00f3n del h\u00e1bitat<\/p>\n<\/li>\n<li>\n<p> Reducci\u00f3n de la poblaci\u00f3n de hormigas recolectoras<\/p>\n<\/li>\n<li>\n<p> Uso de plaguicidas<\/p>\n<\/li>\n<li>\n<p> Especies de plagas invasoras, como las hormigas rojas no aut\u00f3ctonas.<\/p>\n<\/li>\n<li>\n<p> cambio clim\u00e1tico<\/p>\n<\/li>\n<li>\n<p> comercio de animales<\/p>\n<\/li>\n<\/ul>\n<p> Actualmente, el lagarto cornudo de Texas est\u00e1 pr\u00e1cticamente extinto en el este y centro del estado. A\u00fan se pueden encontrar poblaciones en el sur y el oeste. Sin embargo, sin una intervenci\u00f3n efectiva y sin abordar los factores que causaron su declive general, la probabilidad de que estas poblaciones sobrevivan a largo plazo es baja.<\/p>\n<h2> Sin los lagartos cornudos de Texas, los ecosistemas colapsar\u00edan.<\/h2>\n<p> Aunque parezca incre\u00edble, incluso las criaturas m\u00e1s peque\u00f1as pueden ser especies clave en su h\u00e1bitat, y el lagarto cornudo de Texas es un ejemplo de ello. Si se extinguiera, su ecosistema colapsar\u00eda. <\/p>\n<p> Ecosistemas enteros colapsar\u00edan sin los lagartos cornudos de Texas, dado que son una especie clave.<\/p>\n<p> \u00a9Lauren Suryanata\/Shutterstock.com<\/p>\n<p> Los lagartos cornudos de Texas son expertos cazadores de insectos. Sienten una especial predilecci\u00f3n por las hormigas cosechadoras, que tambi\u00e9n son importantes para su h\u00e1bitat, ya que airean eficazmente el suelo. Sin embargo, sin los lagartos cornudos de Texas, la poblaci\u00f3n de hormigas cosechadoras se disparar\u00eda. Esto propiciar\u00eda el florecimiento de algunas especies de flora y fauna, mientras que otras acabar\u00edan desapareciendo.<\/p>\n<p> Los lagartos cornudos de Texas contribuyen a la salud del ecosistema. Ya sean pastizales, praderas, afloramientos rocosos, estribaciones o desiertos, ninguno de estos ecosistemas funcionar\u00eda con la misma eficacia sin estos lagartos. Ayudan a mantener el equilibrio, raz\u00f3n por la cual los esfuerzos de conservaci\u00f3n se han intensificado significativamente a lo largo de los a\u00f1os.<\/p>\n<h2> \u00bfQu\u00e9 se est\u00e1 haciendo para conservar los lagartos cornudos de Texas?<\/h2>\n<p> El Proyecto de Reintroducci\u00f3n del Lagarto Cornudo de Texas ha desempe\u00f1ado un papel fundamental en el aumento de la poblaci\u00f3n de esta especie en el estado. Sin embargo, esta no es la \u00fanica manera de recuperarla. Se han tomado otras medidas para asegurar su reintroducci\u00f3n en regiones donde se hab\u00edan extinguido. <\/p>\n<p> Las medidas de conservaci\u00f3n, como la eliminaci\u00f3n de plantas e insectos invasores, est\u00e1n ayudando a que la poblaci\u00f3n de lagartos cornudos se recupere en Texas.<\/p>\n<p> \u00a9Milan Zygmunt\/Shutterstock.com<\/p>\n<p> Algunas de las maneras en que los conservacionistas est\u00e1n trabajando para salvar a los lagartos cornudos de Texas incluyen:<\/p>\n<ul>\n<li>\n<p> Restaurar la vegetaci\u00f3n natural, incluidas las hormigas recolectoras, para sustentar la poblaci\u00f3n de esta especie.<\/p>\n<\/li>\n<li>\n<p> Eliminaci\u00f3n de especies de pastos invasoras<\/p>\n<\/li>\n<li>\n<p> Reducci\u00f3n de la poblaci\u00f3n de hormigas rojas<\/p>\n<\/li>\n<li>\n<p> Se realizaron estudios para analizar la salud de los lagartos cornudos de Texas liberados.<\/p>\n<\/li>\n<li>\n<p> Educar a los residentes locales sobre m\u00e9todos de control de insectos distintos a los pesticidas.<\/p>\n<\/li>\n<\/ul>\n<p> La cr\u00eda de lagartos cornudos de Texas en condiciones controladas hasta que alcancen la edad adecuada para su liberaci\u00f3n en la naturaleza permitir\u00e1, con suerte, la recuperaci\u00f3n de su poblaci\u00f3n. Solo mediante el apoyo continuo a estos esfuerzos, el lagarto tendr\u00e1 la posibilidad de ser retirado de la lista de especies en peligro de extinci\u00f3n de Texas. La alternativa es la extinci\u00f3n definitiva y la p\u00e9rdida irreparable del querido lagarto del estado.<\/p>\n<p> El art\u00edculo &quot;Los lagartos cornudos de Texas estaban desapareciendo, ahora est\u00e1n prosperando&quot; apareci\u00f3 originalmente en AZ Animals.<\/p>","protected":false},"excerpt":{"rendered":"<p>El art\u00edculo \u00abLos lagartos cornudos de Texas estaban desapareciendo, ahora prosperan\u00bb apareci\u00f3 por primera vez en el sitio web AZ Animals. El lagarto cornudo de Texas ha desempe\u00f1ado un papel importante en la historia de\u2026<\/p>","protected":false},"author":1,"featured_media":3452,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-3451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/3451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/comments?post=3451"}],"version-history":[{"count":4,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/3451\/revisions"}],"predecessor-version":[{"id":146588,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/3451\/revisions\/146588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media\/3452"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media?parent=3451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/categories?post=3451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/tags?post=3451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}