{"id":4921,"date":"2026-06-01T16:03:58","date_gmt":"2026-06-01T13:03:58","guid":{"rendered":"https:\/\/imgist.ru\/81-letnij-rod-styuart-otmenil-dva-konczerta-iz-za-problem-so-zdorovem\/"},"modified":"2026-06-01T16:03:58","modified_gmt":"2026-06-01T13:03:58","slug":"rod-stewart-de-81-anos-cancelo-dos-conciertos-debido-a-problemas-de-salud","status":"publish","type":"post","link":"https:\/\/imgist.ru\/es\/81-letnij-rod-styuart-otmenil-dva-konczerta-iz-za-problem-so-zdorovem\/","title":{"rendered":"Rod Stewart, de 81 a\u00f1os, ha cancelado dos conciertos debido a problemas de salud."},"content":{"rendered":"<p><strong>Rod Stewart<\/strong> Se vio obligado a cancelar dos conciertos en Las Vegas debido a problemas de salud.<\/p>\n<p> En una declaraci\u00f3n al peri\u00f3dico <em>Revista-Diario de Las Vegas<\/em> Un representante del legendario m\u00fasico de rock ingl\u00e9s declar\u00f3: &quot;Siguiendo las recomendaciones m\u00e9dicas, Rod Stewart lamentablemente ha cancelado sus conciertos en The Colosseum del Caesars Palace de Las Vegas los d\u00edas 29 y 30 de mayo, pero planea regresar con nuevos conciertos a partir del 2 de junio&quot;.<\/p>\n<p> En una entrevista con la publicaci\u00f3n, el propio m\u00fasico de 81 a\u00f1os dijo: &quot;Mis disculpas a mis fans. Estoy descansando vocalmente mientras me recupero de una infecci\u00f3n sinusal. Espero verlos en un futuro concierto en el Caesars Palace o en mi gira de verano&quot;.<\/p>\n<p> Los poseedores de entradas tienen derecho a un reembolso.<\/p>\n<p> Afortunadamente, se trata solo de un breve descanso para la estrella, que volver\u00e1 a los escenarios a principios de junio, seg\u00fan ha comunicado su representante.<\/p>\n<p> Seg\u00fan los datos <em>Revista de revisi\u00f3n<\/em> , Stewart ha ofrecido m\u00e1s de 200 espect\u00e1culos en Las Vegas a lo largo de su carrera. Esta semana, tiene previsto actuar en el Coliseo el martes 2 de junio, el jueves 4 de junio y el s\u00e1bado 6 de junio. Posteriormente, se dirigir\u00e1 a Phoenix, Arizona.<\/p>\n<p> El l\u00edder de Faces, que es Caballero del Imperio Brit\u00e1nico y por lo tanto es tratado como Sir, recientemente fue noticia por un momento bastante inc\u00f3modo durante su \u00faltima interacci\u00f3n p\u00fablica con <strong>Rey Carlos III<\/strong> .<\/p>\n<p> El 11 de mayo, durante la celebraci\u00f3n del 50 aniversario de la organizaci\u00f3n ben\u00e9fica The King&#039;s Trust en el Royal Albert Hall de Londres, Stewart salud\u00f3 al monarca, que acababa de regresar de una visita al presidente. <strong>A Donald Trump<\/strong> En Estados Unidos, con las palabras: &quot;D\u00e9jame decirte que hiciste un gran trabajo en Estados Unidos. Estuviste magn\u00edfico. Absolutamente magn\u00edfico. Pusiste a ese bastardo en su lugar&quot;.<\/p>\n<p> Un avergonzado Carlos no respondi\u00f3 directamente al comentario, ya que se espera que los miembros de la familia real brit\u00e1nica mantengan una postura pol\u00edticamente neutral y eviten comentar asuntos que puedan considerarse una injerencia en los asuntos de gobierno.<\/p>\n<p> Aunque Stewart y Trump fueron amigos en el pasado, el comediante se ha convertido desde entonces en uno de los cr\u00edticos m\u00e1s ac\u00e9rrimos del presidente, expresando con frecuencia sus opiniones negativas sobre el comandante en jefe.<\/p>\n<p> Sus cr\u00edticas abiertas a Trump tambi\u00e9n se extendieron a las redes sociales, donde muchos usuarios bombardearon sus publicaciones con comentarios que atacaban sus puntos de vista pol\u00edticos.<\/p>\n<p> La reacci\u00f3n en contra de las opiniones anti-Trump de Stewart fue particularmente notoria porque, a diferencia de muchos de sus cr\u00edticos famosos m\u00e1s francos, el m\u00fasico ha estado asociado durante mucho tiempo con la pol\u00edtica conservadora. Sin embargo, seg\u00fan <em>Sky News<\/em> , Sus puntos de vista parecen haber cambiado en los \u00faltimos a\u00f1os, influenciados en parte por sus opiniones sobre l\u00edderes individuales como Trump y el ex primer ministro brit\u00e1nico. <strong>Boris Johnson<\/strong> .<\/p>","protected":false},"excerpt":{"rendered":"<p>Rod Stewart se vio obligado a cancelar dos conciertos en Las Vegas debido a problemas de salud. En un comunicado al Las Vegas Review-Journal, un representante del legendario m\u00fasico de rock ingl\u00e9s declar\u00f3:\u2026<\/p>","protected":false},"author":1,"featured_media":4922,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-4921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muzyka","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/4921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/comments?post=4921"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/4921\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media\/4922"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media?parent=4921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/categories?post=4921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/tags?post=4921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}