{"id":97181,"date":"2024-07-24T00:00:00","date_gmt":"2024-07-23T21:00:00","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj\/"},"modified":"2024-07-24T00:00:00","modified_gmt":"2024-07-23T21:00:00","slug":"la-amada-ciudad-de-los-emperadores-romanos-la-ciudad-sumergida-de-bagni-que-habia-estado-bajo-el-agua-durante-siglos","status":"publish","type":"post","link":"https:\/\/imgist.ru\/es\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj\/","title":{"rendered":"La ciudad favorita de los emperadores romanos: la ciudad sumergida de Baiae, que permaneci\u00f3 bajo el agua durante siglos."},"content":{"rendered":"<div readability=\"128.23891625616\">\n<p>Baiae es una antigua ciudad romana situada al noroeste de N\u00e1poles. Lo que la distingue de otras ciudades romanas antiguas es que fue hogar de numerosos emperadores, entre ellos Julio C\u00e9sar. La ciudad, sumergida por fumarolas volc\u00e1nicas, fue descubierta en 1940 por Raimondo Boucher, piloto de la Fuerza A\u00e9rea Italiana. \u00a1Exploremos las antiguas ruinas romanas en Baiae y sus alrededores, un lugar que en su d\u00eda fue un destino predilecto de la \u00e9lite romana!<\/p>\n<h2 class=\"wp-block-heading\"> La historia de la ciudad sumergida de Baiae <\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1833\" height=\"1227\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2025\/04\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj_67eb34150604e.jpeg\" alt=\"la ciudad sumergida de Baiae\" class=\"wp-image-675568\"><\/figure>\n<\/h2>\n<p> El primer asentamiento en Baiae data del a\u00f1o 3000 a. C. Si bien la ciudad fue fundada alrededor del siglo II, alcanz\u00f3 su m\u00e1ximo esplendor durante el reinado del emperador Augusto. Augusto conect\u00f3 todas las lujosas villas de la zona mediante una carretera, y las casas fueron equipadas con grandes ba\u00f1os termales. Los sucesores de Augusto \u2014Ner\u00f3n, Adriano y Alejandro Severo\u2014 continuaron expandiendo y desarrollando la ciudad de Baiae, construyendo vastas villas y centros de entretenimiento a lo largo de los a\u00f1os.<\/p>\n<p> Como se puede apreciar, Baiae se convirti\u00f3 en una ciudad donde resid\u00eda la \u00e9lite romana y donde se celebraban fiestas sin fin. Situada sobre fumarolas volc\u00e1nicas naturales, la ciudad era especialmente famosa por sus aguas termales terap\u00e9uticas. Se sabe que figuras c\u00e9lebres de la Antig\u00fcedad, como Ner\u00f3n, Cicer\u00f3n y C\u00e9sar, visitaban Baiae con frecuencia, e incluso muchos de ellos construyeron all\u00ed villas de verano.<\/p>\n<p> Esta vida glamurosa en Baiae, tambi\u00e9n conocida como la &quot;Ciudad de C\u00e9sar&quot; y considerada el equivalente romano antiguo de Las Vegas, lleg\u00f3 a su fin con el saqueo de la ciudad en el siglo VIII. Hacia 1500, la ciudad fue abandonada gradualmente debido a su vulnerabilidad a las erupciones volc\u00e1nicas y las epidemias de malaria. Poco despu\u00e9s de su abandono, el nivel del agua subi\u00f3 lentamente debido a las fumarolas volc\u00e1nicas, y Baiae desapareci\u00f3 en las aguas poco profundas de la bah\u00eda.<\/p>\n<h2 class=\"wp-block-heading\"> La ciudad sumergida fue avistada por primera vez por un piloto italiano que volaba a baja altitud. <\/h2>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"717\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2025\/04\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj_67eb34153b1e6.webp\" alt=\"\" class=\"wp-image-675570\"><\/figure>\n<p> En el siglo XIX, se descubrieron ocasionalmente ruinas romanas antiguas en la zona. En la d\u00e9cada de 1920, durante las operaciones de dragado frente a la costa de Pozzuoli, el hallazgo de estatuas de m\u00e1rmol atrajo la atenci\u00f3n del entonces l\u00edder italiano Benito Mussolini, quien exigi\u00f3 la evacuaci\u00f3n de la zona. El descubrimiento de la ciudad tuvo lugar en 1940. Volando a baja altura sobre el puerto de Portus Julius, el piloto de la Fuerza A\u00e9rea Italiana Raimondo Boucher descubri\u00f3 Baiae, que describi\u00f3 como una &quot;extra\u00f1a ciudad fantasma&quot;.<\/p>\n<p> Las fotograf\u00edas a\u00e9reas tomadas por Boucher, quien tambi\u00e9n practica apnea, mostraron el pantano con una claridad extraordinaria. El hecho de que la profundidad del agua ese d\u00eda fuera de 1,5 metros y el mar tan transparente revel\u00f3 un mundo hasta entonces desconocido.<\/p>\n<p> Aunque las excavaciones de la ciudad sumergida de Baiae y sus alrededores comenzaron en 1959, los trabajos principales se completaron a principios de la d\u00e9cada de 1980. Durante estas excavaciones se descubri\u00f3 el Ninfeo, una c\u00e1mara construida por el emperador Claudio y repleta de estatuas de m\u00e1rmol. Desde entonces, los arque\u00f3logos han descubierto decenas de artefactos hist\u00f3ricos.<\/p>\n<p> Ba\u00f1os, fuentes, casas lujosas, mosaicos y estatuas, por mencionar solo algunos\u2026 Sin embargo, entre los artefactos descubiertos se encuentra una valiosa inscripci\u00f3n: L. Pisonis\u2026 Esta inscripci\u00f3n afirma que Piso plane\u00f3 asesinar a su amigo \u00edntimo, el emperador Ner\u00f3n, en su villa de verano en Baiae. Aunque Piso cre\u00eda que as\u00ed se convertir\u00eda en emperador, Ner\u00f3n cancel\u00f3 su visita a Baiae al enterarse del plan de asesinato.<\/p>\n<h2 class=\"wp-block-heading\"> Baiae se convirti\u00f3 en un importante destino tur\u00edstico tras las excavaciones arqueol\u00f3gicas. <\/h2>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"929\" height=\"622\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2025\/04\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj_67eb341567130.jpeg\" alt=\"\" class=\"wp-image-675571\"><\/figure>\n<p> Situada en el golfo de N\u00e1poles, Baiae se ha convertido en un importante destino tur\u00edstico tras las excavaciones arqueol\u00f3gicas. Miles de turistas visitan la zona cada a\u00f1o para contemplar la ciudad sumergida de Baiae. Se ofrecen excursiones en barco con fondo de cristal, y la m\u00e1gica ciudad submarina puede explorarse con la ayuda de empresas de buceo.<\/p>\n<p> Algunos visitantes exploran la ciudad sumergida practicando snorkel. Estas excursiones permiten descubrir villas de familias nobles romanas, termas, mosaicos, estatuas y muchas otras obras de arte. Aunque los muros de algunos edificios se han derrumbado, las habitaciones a\u00fan son visibles. Los suelos de mosaico de muchas habitaciones se conservan hasta nuestros d\u00edas.<\/p>\n<h2 class=\"wp-block-heading\"> Lugares para visitar alrededor de la ciudad sumergida de Baiae \ud83d\udc47 <\/h2>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2025\/04\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj_67eb34158bb14.webp\" alt=\"\" class=\"wp-image-675573\"><\/figure>\n<p> Adem\u00e1s del parque arqueol\u00f3gico subacu\u00e1tico de Baiae, se pueden visitar numerosas ruinas romanas. Las m\u00e1s populares son:<\/p>\n<h3 class=\"wp-block-heading\"> Templo de Mercurio <\/h3>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2025\/04\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj_67eb3415bb93d.jpeg\" alt=\"la ciudad sumergida de Baiae\" class=\"wp-image-675575\"><\/figure>\n<p> Antes de la construcci\u00f3n del Pante\u00f3n, el Templo de Mercurio ostentaba la c\u00fapula m\u00e1s grande del mundo: 21,5 metros. El templo, con la c\u00fapula de hormig\u00f3n m\u00e1s antigua que se conoce, data del a\u00f1o 3000 a. C. Fue construido en el siglo I con bloques de toba volc\u00e1nica.<\/p>\n<h3 class=\"wp-block-heading\"> Templo de Diana <\/h3>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2025\/04\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj_67eb3415e8a14.jpeg\" alt=\"la ciudad sumergida de Baiae\" class=\"wp-image-675576\"><\/figure>\n<p> El Templo de Diana, con su enorme c\u00fapula, ahora parcialmente derruida, se utilizaba como balneario termal en la antigua Roma. Las paredes del templo est\u00e1n decoradas con frisos que representan escenas de caza.<\/p>\n<h3 class=\"wp-block-heading\"> Templo de Venus <\/h3>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"947\" height=\"700\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2025\/04\/lyubimyj-gorod-rimskih-imperatorov-zatonuvshij-gorod-baji-vekami-nahodivshijsya-pod-vodoj_67eb341621cf6.jpeg\" alt=\"la ciudad sumergida de Baiae\" class=\"wp-image-675578\"><\/figure>\n<p> Templo de Venus, siglo III a. C. Fue construido en el a\u00f1o 46 a. C. por Julio C\u00e9sar en honor a la diosa romana Venus. El edificio, gravemente da\u00f1ado por un incendio en el a\u00f1o 80 d. C., fue reconstruido por Domiciano y restaurado por Trajano en el a\u00f1o 113 d. C. Tres columnas, que a\u00fan se conservan, incluyen fragmentos de esta \u00faltima restauraci\u00f3n.<\/p>\n<p> Tambi\u00e9n te puede interesar este contenido:<\/p>\n<p> Cinco ciudades sumergidas en Turqu\u00eda con una belleza incre\u00edble.<\/p>\n<p> \u00a1Comparte tu opini\u00f3n en los comentarios! <a href=\"https:\/\/en.wikipedia.org\/wiki\/Baiae\" target=\"_blank\" rel=\"external nofollow noopener\">Wikipedia<\/a><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Baiae es una antigua ciudad romana situada al noroeste de N\u00e1poles. Lo que distingue a este lugar de otras antiguas ciudades romanas es que alberg\u00f3 a muchos\u2026<\/p>","protected":false},"author":1,"featured_media":97182,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-97181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-puteshestviya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/97181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/comments?post=97181"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/97181\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/97182"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media?parent=97181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/categories?post=97181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/tags?post=97181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}