{"id":9739,"date":"2026-06-03T18:15:29","date_gmt":"2026-06-03T15:15:29","guid":{"rendered":"http:\/\/imgist.ru\/rejchel-meddou-rezko-kritikuet-uvolnenie-skotta-pelli-i-oligarhicheskij-zahvat-cbs-v-vengerskom-stile-video\/"},"modified":"2026-06-03T18:15:29","modified_gmt":"2026-06-03T15:15:29","slug":"rachel-meddou-critica-duramente-el-despido-de-scott-pelli-y-la-toma-de-control-oligarquica-de-cbs-en-un-video-al-estilo-hungaro","status":"publish","type":"post","link":"https:\/\/imgist.ru\/es\/rejchel-meddou-rezko-kritikuet-uvolnenie-skotta-pelli-i-oligarhicheskij-zahvat-cbs-v-vengerskom-stile-video\/","title":{"rendered":"Rachel Maddow critica duramente el despido de Scott Pelley y la &quot;toma de control olig\u00e1rquica al estilo h\u00fangaro de CBS&quot; | Video"},"content":{"rendered":"<p>Rachel Maddow est\u00e1 sumamente disgustada con el despido del veterano presentador de &quot;60 Minutes&quot;, Scott Pelley, esta semana, y no lo ocult\u00f3 el martes por la noche. La presentadora de MS NOW denunci\u00f3 en directo la &quot;toma de control olig\u00e1rquica, al estilo h\u00fangaro, de la CBS&quot;.<\/p>\n<p> Al comentar la noticia, Maddow afirm\u00f3 que el nuevo productor ejecutivo de 60 Minutes, Nick Bilton, fue &quot;nombrado&quot; para el puesto como parte de una descarada toma de control olig\u00e1rquica al estilo h\u00fangaro de la organizaci\u00f3n de noticias, y expres\u00f3 su sorpresa por la carta en la que desped\u00eda a Pelley.<\/p>\n<p> \u00abLo digo en parte en broma, pero tambi\u00e9n en parte en serio\u00bb, afirm\u00f3 Maddow. \u00abNadie comprende mejor el valor de la libertad de prensa que quienes intentan arrebat\u00e1rsela. Y cuando el presidente declara abiertamente: &quot;Voy a usar el poder del Estado para conseguir los medios que quiero&quot;, y recluta a sus amigos de la \u00e9lite olig\u00e1rquica para lograrlo\u2026 de nuevo, no hay disimulo alguno\u201e.<\/p>\n<p> \u00ab&quot;No hay forma de decir que esto est\u00e9 sucediendo por otra raz\u00f3n&quot;, continu\u00f3 Maddow. &quot;En CBS News no sucede nada m\u00e1s all\u00e1 de lo que vemos&quot;.<\/p>\n<p> Maddow a\u00f1adi\u00f3 que no tiene ni idea de d\u00f3nde acabar\u00e1 Pelley despu\u00e9s de CBS, pero expres\u00f3 su esperanza de que sea en MS NOW. Sin embargo, independientemente de ad\u00f3nde vaya Pelley, Maddow solo quiere que siga trabajando en televisi\u00f3n.<\/p>\n<p> \u00ab&quot;Espero que ma\u00f1ana salga en televisi\u00f3n, y espero que todos los periodistas y todos los que valoran la libertad de prensa encuentren la manera de burlar a quienes intentan arrebat\u00e1rnosla&quot;, dijo. &quot;Pero en este momento, reina el caos&quot;.<\/p>\n<p> Alicia Men\u00e9ndez asinti\u00f3 de inmediato y a\u00f1adi\u00f3 que cre\u00eda en la palabra de Cecilia Vega, otra corresponsal de 60 Minutes despedida recientemente tras criticar el ambiente actual del programa y de la cadena.<\/p>\n<p> \u00abAs\u00ed que estoy de acuerdo contigo en 100% en que no hay nada que discutir aqu\u00ed\u00bb, dijo Men\u00e9ndez. \u00abEst\u00e1 perfectamente claro lo que est\u00e1n haciendo. El trabajo de Bari Weiss no es producir periodismo impecable, ni elaborar una pol\u00edtica editorial, ni convertirlo en un nuevo producto. No, su trabajo es sobornar a sus jefes corporativos y, seamos honestos, a celebridades de todo tipo para lograr ese objetivo\u00bb.<\/p>\n<p> La grabaci\u00f3n completa de la conversaci\u00f3n con MS NOW puede verse en el v\u00eddeo de arriba.<\/p>\n<p> El art\u00edculo &quot;Rachel Maddow critica duramente el despido de Scott Pelley y la &#039;adquisici\u00f3n olig\u00e1rquica al estilo h\u00fangaro de CBS&#039; | V\u00eddeo&quot; apareci\u00f3 originalmente en TheWrap.<\/p>","protected":false},"excerpt":{"rendered":"<p>Rachel Maddow est\u00e1 sumamente disgustada con el despido esta semana del veterano presentador de &quot;60 Minutes&quot;, Scott Pelley, y no ocult\u00f3 su opini\u00f3n el martes por la noche...<\/p>","protected":false},"author":1,"featured_media":9740,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/9739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/comments?post=9739"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/9739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media\/9740"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media?parent=9739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/categories?post=9739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/tags?post=9739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}