{"id":99159,"date":"2022-06-03T00:00:00","date_gmt":"2022-06-02T21:00:00","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/10-chelovek-kotorye-sdelali-sebe-operaciyu\/"},"modified":"2022-06-03T00:00:00","modified_gmt":"2022-06-02T21:00:00","slug":"10-personas-que-se-operaron-a-si-mismas","status":"publish","type":"post","link":"https:\/\/imgist.ru\/es\/10-chelovek-kotorye-sdelali-sebe-operaciyu\/","title":{"rendered":"10 personas que se sometieron a cirug\u00eda en s\u00ed mismas"},"content":{"rendered":"<div readability=\"254.69448269531\">\n<p><span>Encontramos evidencia de que las personas se somet\u00edan a cirug\u00edas incluso<\/span> <span>Hace 12.000 a\u00f1os<\/span> <span>. Estos procedimientos indican que nuestros ancestros practicaban la trepanaci\u00f3n quir\u00fargica, que consist\u00eda en perforar un agujero en el cr\u00e1neo para exponer el cerebro. Por lo tanto, era evidente que pod\u00edan recurrir a este m\u00e9todo si el paciente sobreviv\u00eda.<\/span><\/p>\n<p> <span>Hoy<\/span> <span>se celebra anualmente<\/span> cerca <span>310 millones de transacciones<\/span> . <span>Hemos avanzado mucho. Pero a pesar de nuestros progresos, algunas cirug\u00edas parecen eludir las normas y los procedimientos que consideramos seguros, especialmente cuando se trata de procedimientos realizados en las propias personas.<\/span><\/p>\n<h2> <span>10. Werner Forssmann<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81834\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b8183526.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>Si no has o\u00eddo hablar de Werner Forssmann, es probable que sea porque naci\u00f3 en 1904 y se adelant\u00f3 mucho a su tiempo. Sus contribuciones a la ciencia m\u00e9dica fueron tan significativas que en 1956 recibi\u00f3 el Premio Nobel de Fisiolog\u00eda o Medicina. Todo esto se debe a su investigaci\u00f3n en el campo de la<\/span> <span>cateterismo card\u00edaco<\/span> <span>, un procedimiento que todav\u00eda se utiliza hoy en d\u00eda para tratar y diagnosticar numerosas afecciones card\u00edacas.<\/span><\/p>\n<p> <span>Forssmann cre\u00eda que al insertar un cat\u00e9ter en una vena del brazo, podr\u00eda introducirlo en el coraz\u00f3n del paciente. Esto tiene sentido hoy en d\u00eda, pero cuando lo ide\u00f3 en 1929, la comunidad m\u00e9dica pens\u00f3 que era un idiota o un loco. As\u00ed que, para demostrar su punto, tuvo que...<\/span> <span>Hazte esto a ti mismo<\/span> <span>. Para que quede claro, ten\u00eda expresamente prohibido hacerlo. As\u00ed que actu\u00f3 a escondidas de sus superiores y solo consigui\u00f3 que una persona se uniera al equipo: una enfermera de quir\u00f3fano, Gerda Dietzen. Sin su ayuda, ni siquiera pod\u00eda acceder a los instrumentos necesarios para realizar el procedimiento.<\/span><\/p>\n<p> <span>Forssmann convenci\u00f3 a Dietzen de que su procedimiento era correcto. La convenci\u00f3 tanto que ella se ofreci\u00f3 como paciente. Entonces la sujet\u00f3 a la mesa de operaciones con arneses de seguridad y luego extrajo el interruptor viejo, haciendo lo mismo consigo mismo mientras ella estaba atada e incapaz de detenerlo.<\/span><\/p>\n<p> <span>Logr\u00f3 defenderse de otro m\u00e9dico que le extrajo el cat\u00e9ter del brazo y luego se hizo una radiograf\u00eda para demostrar que hab\u00eda funcionado. Posteriormente, realiz\u00f3 el procedimiento en un paciente terminal, public\u00f3 los resultados y fue despedido inmediatamente del hospital donde trabajaba por violar las normas.<\/span><\/p>\n<h2> <span>9. Leonid Rogozov se practic\u00f3 su propia apendicectom\u00eda en la Ant\u00e1rtida.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-71253\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b82b78cf.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>La mayor\u00eda de nosotros nunca viajaremos a la Ant\u00e1rtida, y con raz\u00f3n. En 2021, la temperatura promedio de abril a septiembre<\/span> <span>la temperatura era de -61 grados Celsius.<\/span> <span>, lo que equivale a -78 grados Fahrenheit. B\u00e1sicamente, es la muerte en forma de fiebre.<\/span> <span>Anticongelante<\/span> <span>Se congela antes incluso de enfriarse. Por lo tanto, cuando la gente viaja al Polo Sur, suele permanecer confinada en una base de investigaci\u00f3n durante largos periodos de tiempo con un peque\u00f1o grupo de colegas y sin contacto oportuno con el mundo exterior.<\/span><\/p>\n<p> <span>En 1961, Leonid Rogozov era el \u00fanico m\u00e9dico de la estaci\u00f3n ant\u00e1rtica Novolazarevskaya. En abril, Rogozov se sinti\u00f3 muy enfermo, y el barco que los llevar\u00eda de regreso a Rusia no llegar\u00eda hasta dentro de un a\u00f1o. A pesar de ello, el viaje dur\u00f3 36 d\u00edas y necesitaba ayuda urgente. Necesitaba...<\/span> <span>quitar el ap\u00e9ndice,<\/span> <span>y \u00e9l era la \u00fanica persona que ten\u00eda derecho a hacerlo.<\/span><\/p>\n<p> <span>Rogozov ten\u00eda dos opciones: morir o operarse \u00e9l mismo. Varios de sus colegas le prestaron asistencia como enfermeros, y a uno de ellos le asignaron la tarea de sostener un espejo para que pudiera ver lo que hac\u00eda. Le administraron anestesia local para adormecer la piel del abdomen, pero una vez dentro, no podr\u00eda usar analg\u00e9sicos.<\/span><\/p>\n<p> <span>El espejo result\u00f3 demasiado dif\u00edcil de manejar, as\u00ed que realiz\u00f3 la operaci\u00f3n a ciegas, gui\u00e1ndose por el tacto. Estuvo a punto de desmayarse varias veces, pero tras dos horas trabajando dentro de su propio intestino, lograron extraer el \u00f3rgano, que se esperaba que explotara en un d\u00eda. Regres\u00f3 al trabajo dos semanas despu\u00e9s.<\/span><\/p>\n<h2> <span>8. In\u00e9s Ram\u00edrez se practic\u00f3 ella misma la ces\u00e1rea.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-66159\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b839fe4b.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>Si te preguntas cu\u00e1n fuerte puede ser una madre, piensa en In\u00e9s Ram\u00edrez. A los cuarenta a\u00f1os, Ram\u00edrez ya ten\u00eda seis hijos, y unos a\u00f1os antes hab\u00eda perdido al s\u00e9ptimo al nacer. Le encantaba vivir en una finca a 80 kil\u00f3metros de la ciudad m\u00e1s cercana, en una zona muy rural de M\u00e9xico. No hab\u00eda tel\u00e9fono en su casa, y su esposo hab\u00eda ido al comedor. Solo Ram\u00edrez y sus hijos estaban en casa.<\/span><\/p>\n<p> <span>Tras experimentar el familiar dolor abdominal durante 12 horas, Ram\u00edrez se dio cuenta de que algo andaba mal con el beb\u00e9 y que, si no buscaba ayuda, corr\u00eda el riesgo de perderlo, tal como hab\u00eda perdido al anterior. Pero no hab\u00eda forma de conseguir ayuda. As\u00ed que decidi\u00f3 tomar cartas en el asunto.<\/span><\/p>\n<p> <span>Ram\u00edrez bebi\u00f3 varias botellas<\/span> <span>alcohol<\/span> <span>y cogi\u00f3 un cuchillo de la cocina. Ten\u00eda experiencia despiezando animales, pero ninguna formaci\u00f3n m\u00e9dica. A pesar de ello, logr\u00f3 hacer cortes precisos que le impidieron herir al beb\u00e9 o cualquier \u00f3rgano interno. Sac\u00f3 al beb\u00e9, cort\u00f3 el cord\u00f3n umbilical con unas tijeras y perdi\u00f3 el conocimiento.<\/span><\/p>\n<p> <span>El hijo de seis a\u00f1os de Ram\u00edrez corri\u00f3 al pueblo y regres\u00f3 con ayuda. Un trabajador m\u00e9dico regres\u00f3 y le sutur\u00f3 la herida a Ram\u00edrez con aguja e hilo comunes. Los m\u00e9dicos que la examinaron despu\u00e9s,<\/span> <span>estaban convencidos<\/span> <span>, Que la historia ocurri\u00f3 tal como la cont\u00f3 Ram\u00edrez, y quedaron impresionados con el trabajo que hab\u00eda realizado.<\/span><\/p>\n<h2> <span>7. Boston Corbett mat\u00f3 a John Wilkes Booth y se castr\u00f3 a s\u00ed mismo.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81838\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b83ef3cb.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>En 1865, tras el asesinato de Abraham Lincoln por John Wilkes Booth, este escap\u00f3 a caballo. Se movilizaron tropas para dar con el asesino, y el 16.\u00ba Regimiento de Caballer\u00eda de Nueva York lo localiz\u00f3. Lo encontraron en un granero, donde Boston Corbett le dispar\u00f3 con su rev\u00f3lver, hiri\u00e9ndolo.<\/span> <span>Wilkes en el cuello<\/span> <span>.<\/span><\/p>\n<p> <span>Aunque esta fue la principal raz\u00f3n por la que Corbett se hizo famoso, el hombre llev\u00f3 una vida interesante y curiosa. Tambi\u00e9n desapareci\u00f3, sin que se volviera a saber de \u00e9l despu\u00e9s de 1894. Pero en vida, su excentricidad fue m\u00e1s notoria en la operaci\u00f3n que se realiz\u00f3 a s\u00ed mismo. En 1858,<\/span> <span>se castr\u00f3 a s\u00ed mismo<\/span> <span>, para controlar su deseo de estar con prostitutas. En lugar de buscar ayuda m\u00e9dica, sali\u00f3 a cenar despu\u00e9s del acto.<\/span><\/p>\n<p> <span>A\u00f1os despu\u00e9s, los historiadores concluyeron que Corbett, que trabaj\u00f3 durante un tiempo como sombrerero, absorbi\u00f3 una gran cantidad de sustancias qu\u00edmicas t\u00f3xicas que afectaron su estado mental.<\/span><\/p>\n<h2> <span>6. Un m\u00e9dico se repara a s\u00ed mismo un ligamento desgarrado.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-54752\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b854de6f.jpeg\" alt=\"\" width=\"640\" height=\"384\"><\/p>\n<p> <span>En Cincinnati, el Dr. Mohab Foad lleva a\u00f1os operando manos. Realiza m\u00e1s de una docena de intervenciones al d\u00eda y lleva m\u00e1s de una d\u00e9cada haci\u00e9ndolo. Si necesita un experto en cirug\u00eda de mano, \u00e9l es la persona indicada. Por eso, resulta obvio que cuando necesit\u00f3 operarse la mano, acudi\u00f3 a \u00e9l.<\/span> <span>la hizo<\/span> <span>.<\/span><\/p>\n<p> <span>Tras sufrir una lesi\u00f3n jugando al paintball, Foud se dio cuenta de que se hab\u00eda roto varios ligamentos. Aunque recibi\u00f3 ayuda de un compa\u00f1ero por insistencia de su esposa, \u00e9l mismo realiz\u00f3 la mayor parte de la cirug\u00eda, lo que le permiti\u00f3 comprender mejor lo que sufr\u00edan sus pacientes.<\/span><\/p>\n<h2> <span>5. Un australiano se extirpa \u00e9l mismo un quiste tras dos a\u00f1os de espera.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-81186\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b867d2d5.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Tom Petty cant\u00f3 una vez que la espera es lo m\u00e1s dif\u00edcil, pero un electricista australiano al que le extirparon un quiste tras dos a\u00f1os de espera podr\u00eda opinar diferente. Us\u00f3 un c\u00fater com\u00fan para extirparlo.<\/span> <span>un quiste del tama\u00f1o de una uva<\/span> <span>de su propia mano.<\/span><\/p>\n<p> <span>El per\u00edodo de espera supuestamente est\u00e1 limitado a un a\u00f1o, y el quiste le imped\u00eda trabajar. Despu\u00e9s de dos a\u00f1os, no pudo esperar m\u00e1s, as\u00ed que calent\u00f3 un cuchillo, extirp\u00f3 el quiste, sec\u00f3 la mucosidad del interior, desinfect\u00f3 la herida y le aplic\u00f3 un vendaje.<\/span><\/p>\n<p> <span>Los m\u00e9dicos destacaron la suerte que tuvo de que nada hubiera empeorado, al tiempo que reconocieron que, efectivamente, el tiempo de espera podr\u00eda ser excesivo.<\/span><\/p>\n<h2> <span>4. Una mujer intent\u00f3 aumentar el tama\u00f1o de sus senos por su cuenta.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-78772\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b8705bba.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Es dif\u00edcil decir que exista un momento adecuado para operarse uno mismo. A veces se hace por necesidad, y otras veces simplemente porque el cirujano sabe c\u00f3mo hacerlo. Pero cuando una persona com\u00fan y corriente intenta operarse, puede ser se\u00f1al de un problema de salud mental mucho m\u00e1s grave, o simplemente de una terrible incomprensi\u00f3n de las posibles consecuencias.<\/span><\/p>\n<p> <span>En 2014, una mujer de Argentina intent\u00f3 aumentar el tama\u00f1o de sus senos. Lo logr\u00f3.,<\/span> al ingresar <span>en mi pecho<\/span> <span>vaselina<\/span> . <span>Poco despu\u00e9s del procedimiento, surgieron complicaciones y comenz\u00f3 a tener dificultades para respirar. Al principio, neg\u00f3 saber nada de lo sucedido y se neg\u00f3 a contarles a los m\u00e9dicos lo que hab\u00eda hecho. M\u00e1s tarde confes\u00f3, pero ya era demasiado tarde. Hab\u00eda sufrido un co\u00e1gulo de sangre fatal.<\/span><\/p>\n<h2> <span>3. Cirug\u00eda de hernia con cuchillo de mantequilla<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81836\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b885dc59.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>Contrariamente a lo que mucha gente cree,<\/span> <span>tiempo de espera<\/span> <span>Las cirug\u00edas en Estados Unidos suelen ser mucho m\u00e1s caras que en pa\u00edses con sanidad universal. La espera puede ser de dos, tres, cuatro meses o incluso m\u00e1s, dependiendo de la urgencia de la intervenci\u00f3n. Cirug\u00edas como la de hernia pueden requerir una espera considerable.<\/span><\/p>\n<p> <span>En 2011, un hombre de California decidi\u00f3 operarse \u00e9l mismo de una hernia. No est\u00e1 claro si fue por falta de tiempo, dinero o incluso una enfermedad mental. Pero se sabe que intent\u00f3 la operaci\u00f3n con un cuchillo de mantequilla. Cuando llegaron los param\u00e9dicos, el cuchillo a\u00fan sobresal\u00eda del abdomen del hombre. Lo extrajo y<\/span> <span>poner un cigarrillo,<\/span> <span>que se fumaba, introduci\u00e9ndolo en la herida, tal vez para cauterizarla o simplemente para parecer una estrella de acci\u00f3n de los a\u00f1os 80.<\/span><\/p>\n<h2> <span>2. Tatsuya Ichihashi se someti\u00f3 a una cirug\u00eda pl\u00e1stica para escapar de la polic\u00eda.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-80447\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b893dc7e.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Casi todas las autooperaciones quir\u00fargicas de las que se oye hablar se realizan por motivos m\u00e9dicos. Tatsuya Ichihashi se oper\u00f3 para evitar ser procesado por asesinato. Cambi\u00f3 su apariencia.,<\/span> <span>usando tijeras<\/span> <span>, Para reducir el tama\u00f1o de sus labios, utiliz\u00f3 un c\u00fater para eliminar lunares y us\u00f3 hilo para coserse la nariz en un intento de hacerla m\u00e1s peque\u00f1a.<\/span><\/p>\n<p> <span>En alg\u00fan momento acudi\u00f3 a un cirujano pl\u00e1stico de verdad para que se lo hiciera.<\/span> <span>cirug\u00eda de nariz<\/span> <span>, ya que sus propios esfuerzos hab\u00edan dado pocos resultados, pero el cirujano not\u00f3 m\u00e1s tarde que su aspecto hab\u00eda permanecido pr\u00e1cticamente inalterado.<\/span><\/p>\n<p> <span>Ichihashi llevaba pr\u00f3fugo en Jap\u00f3n desde el asesinato de Lindsay Hawker en 2007. Transcurrieron m\u00e1s de dos a\u00f1os antes de que finalmente fuera capturado.<\/span><\/p>\n<h2> <span>1. Evan O&#039;Neal Kane ha sido sometido a 3 cirug\u00edas.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81837\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-chelovek-kotorye-sdelali-sebe-operaciyu_64107b8a2d553.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>El Dr. Evan O&#039;Neil Kane era un tipo peculiar, en parte debido a las circunstancias y en parte debido a su excentricidad general. Por ejemplo, una vez sugiri\u00f3 que las madres y los reci\u00e9n nacidos se hicieran tatuajes iguales para evitar que los beb\u00e9s se perdieran. Tambi\u00e9n<\/span> <span>tatu\u00f3 a sus pacientes<\/span> <span>en tinta despu\u00e9s de las operaciones con su inicial en c\u00f3digo Morse.<\/span><\/p>\n<p> <span>Un paciente al que nunca tatu\u00f3 fue a s\u00ed mismo, y no por falta de oportunidad. Se hab\u00eda realizado tres procedimientos en s\u00ed mismo a lo largo de los a\u00f1os. El primero fue<\/span> <span>amputaci\u00f3n<\/span> <span>Tras sufrir una grave infecci\u00f3n en el dedo, no crey\u00f3 que fuera necesaria la anestesia general para la operaci\u00f3n.<\/span><\/p>\n<p> <span>Dos a\u00f1os despu\u00e9s de que le amputaran el dedo, Kane necesit\u00f3 que le extirparan el ap\u00e9ndice. Una vez m\u00e1s, simplemente us\u00f3 anestesia local para la intervenci\u00f3n. No tuvo que hacerlo \u00e9l mismo; otro cirujano estaba presente para cerrar la incisi\u00f3n despu\u00e9s. Simplemente quer\u00eda que se lo hicieran.<\/span><\/p>\n<p> <span>A\u00f1os despu\u00e9s, a los setenta a\u00f1os, Kane tambi\u00e9n se someti\u00f3 a una cirug\u00eda de hernia. La operaci\u00f3n fue un \u00e9xito, pero falleci\u00f3 pocos meses despu\u00e9s.<\/span><\/p>\n<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>Hemos encontrado evidencia de que los humanos se somet\u00edan a cirug\u00edas hace 12.000 a\u00f1os. Estos procedimientos indican que nuestros ancestros antiguos realizaban intervenciones quir\u00fargicas\u2026<\/p>","protected":false},"author":1,"featured_media":13430,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-99159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/99159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/comments?post=99159"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/99159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media\/13430"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media?parent=99159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/categories?post=99159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/tags?post=99159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}