{"id":99160,"date":"2022-06-02T00:00:00","date_gmt":"2022-06-01T21:00:00","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/samye-neobychnye-izotopy-na-zemle\/"},"modified":"2026-08-24T13:32:07","modified_gmt":"2026-08-24T10:32:07","slug":"los-isotopos-mas-inusuales-de-la-tierra","status":"publish","type":"post","link":"https:\/\/imgist.ru\/es\/samye-neobychnye-izotopy-na-zemle\/","title":{"rendered":"Los is\u00f3topos m\u00e1s inusuales de la Tierra"},"content":{"rendered":"<div readability=\"246.19069684548\">\n<p><span>Cada elemento tiene un n\u00famero at\u00f3mico distintivo. El n\u00famero at\u00f3mico representa la cantidad de protones en el n\u00facleo. Los is\u00f3topos tienen la misma cantidad de protones, es decir, son el mismo elemento, pero con diferente n\u00famero de neutrones. El carbono, por ejemplo, tiene tres is\u00f3topos: carbono-12, carbono-13 y carbono-14. Cada uno tiene seis protones, pero tienen seis, siete y ocho neutrones, respectivamente. En cuanto a los is\u00f3topos, son bastante aburridos, aunque algunos poseen propiedades notables.<\/span><\/p>\n<h2> <span>10. El telurio-128 tiene una vida media incre\u00edblemente larga.<\/span> <\/h2>\n<\/p>\n<p> <span>El telurio es el elemento n\u00famero 52 de la tabla peri\u00f3dica y es un metaloide plateado. Tambi\u00e9n es ligeramente t\u00f3xico, as\u00ed que procura no jugar con \u00e9l. Tiene ocho is\u00f3topos, y uno de ellos, el telurio-128, ha obtenido su propio reconocimiento.<\/span> <span>R\u00e9cord Mundial Guinness<\/span> <span>debido a que tiene una vida media incre\u00edblemente larga.<\/span><\/p>\n<p> <span>El n\u00famero se calcul\u00f3 como 2,2 x (10 elevado a la potencia de 24) a\u00f1os. Este es un n\u00famero oscuro para la mayor\u00eda de nosotros, as\u00ed que puedes expresarlo de otra manera. Esto<\/span> <span>160 billones de veces<\/span> <span>m\u00e1s larga que la edad del universo mismo. El universo tiene casi 14 mil millones de a\u00f1os, por lo que la vida media del telurio-128 es lo m\u00e1s cercano a la eternidad que se puede encontrar en la naturaleza.<\/span><\/p>\n<h2> <span>9. La desintegraci\u00f3n de los is\u00f3topos de astato en un abrir y cerrar de ojos.<\/span> <\/h2>\n<\/p>\n<p> <span>En el extremo opuesto del espectro del telurio, el astato no tiene una vida media larga en absoluto. Clasificado en el puesto 85 de la tabla peri\u00f3dica, tambi\u00e9n es el m\u00e1s<\/span> <span>elemento raro en la Tierra:<\/span> <span>En cualquier momento dado, solo hay unos 25 gramos en el planeta. \u00bfPor qu\u00e9 es tan raro? De nuevo, por su corta vida media.<\/span><\/p>\n<p> <span>El is\u00f3topo de astato de mayor duraci\u00f3n es el astato-210, con una vida media de 8,1 horas. Existen 32 is\u00f3topos, y ninguno de ellos es estable. El de menor duraci\u00f3n es el astato-213, con una vida media de<\/span> <span>125 nanosegundos<\/span> <span>. Tambi\u00e9n se ha dicho que la radiactividad del astato es tan fuerte que en realidad se autodestruye.<\/span><\/p>\n<p> <span>Todos los is\u00f3topos son radiactivos y pueden formarse a partir de bismuto en el laboratorio. A veces se utilizan como trazadores radiactivos, pero aparte de eso, tienen poca aplicaci\u00f3n cient\u00edfica.<\/span><\/p>\n<h2> <span>8. El oro tiene 41 is\u00f3topos, pero solo uno de ellos es estable.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-66998\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/samye-neobychnye-izotopy-na-zemle_64107b984a364.jpeg\" alt=\"\" width=\"640\" height=\"424\"><\/p>\n<p> <span>El oro es un elemento muy conocido, y a la mayor\u00eda nos encantar\u00eda encontrarlo en la naturaleza. Es muy valioso y no se corroe como muchos otros metales. Lo que es menos conocido es que existen 41 is\u00f3topos conocidos de este metal. El que conocemos y anhelamos es el oro-197, y es el \u00fanico.<\/span> <span>is\u00f3topo estable,<\/span> <span>que est\u00e1 presente en el oro. Los 40 restantes son radiactivos.<\/span><\/p>\n<p> <span>Es interesante que el oro-197<\/span> <span>observacionalmente estable<\/span> <span>. Esto significa que la ciencia predice que deber\u00eda ser radiactivo, pero las observaciones no confirman esa predicci\u00f3n. As\u00ed que, aunque se espere que sea radiactivo, no lo es. En general, esto ha sido beneficioso para casi todas las econom\u00edas a lo largo de la historia.<\/span><\/p>\n<h2> <span>7. El germanio-72 experimenta una transici\u00f3n de fase inusual.<\/span> <\/h2>\n<\/p>\n<p> <span>El germanio es el trig\u00e9simo segundo elemento de la tabla peri\u00f3dica y otro metaloide que se sit\u00faa entre los metales y los no metales. Consta de cinco is\u00f3topos estables, y el germanio-76 es el de mayor vida media, aproximadamente 130 mil millones de veces la edad del universo. Sin embargo, no es el is\u00f3topo m\u00e1s interesante. En cuanto al germanio, es el is\u00f3topo 72 el que presenta un comportamiento muy inusual al calentarse.<\/span><\/p>\n<p> <span>Entendemos que ciertos fen\u00f3menos ocurren en los \u00e1tomos cuando se aplica calor a una sustancia. Al igual que con el agua, el calor excita los \u00e1tomos y hace que se muevan m\u00e1s r\u00e1pido. Pero, \u00bfqu\u00e9 sucede en el interior de los propios \u00e1tomos?<\/span> <span>Germanio-72<\/span> <span>Esto demuestra que no es tan obvio como crees.<\/span><\/p>\n<p> <span>El germanio tiene 32 protones, mientras que el germanio tiene 72,40 neutrones. Estos protones forman pares fuertes que se debilitan a medida que el \u00e1tomo se calienta. Esto tiene sentido en nuestro ejemplo del agua. El problema es que en alg\u00fan momento ocurre algo inusual. Cuando la temperatura alcanza un nivel suficientemente alto, los enlaces entre los pares de protones<\/span> <span>se est\u00e1 volviendo m\u00e1s fuerte de nuevo<\/span> <span>. Esto se debe a un fen\u00f3meno llamado transici\u00f3n de fase. La estabilizaci\u00f3n se produce al inicio de la transici\u00f3n, antes de debilitarse nuevamente a medida que la temperatura contin\u00faa aumentando.<\/span><\/p>\n<h2> <span>6. Se encontr\u00f3 hierro-60 en la nieve ant\u00e1rtica.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-71251\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/samye-neobychnye-izotopy-na-zemle_64107b99485f7.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Todo el mundo conoce el hierro, uno de los elementos m\u00e1s comunes del planeta, tan importante que un siglo entero lleva su nombre. Sin hierro, todos nuestros imanes se caer\u00edan al suelo, por no hablar de nuestra incapacidad para fabricar casi todos los productos met\u00e1licos del mundo.<\/span> Seg\u00fan las estimaciones <span>, en el mundo<\/span> <span>hay aproximadamente<\/span> <span>800 mil millones de toneladas<\/span> El mineral de hierro sin refinar contiene 230 mil millones de toneladas de hierro, as\u00ed que tenemos trabajo por hacer.<\/p>\n<p> <span>Existen cuatro is\u00f3topos estables de hierro y 24 is\u00f3topos radiactivos. Uno de ellos, el hierro-60, es el m\u00e1s estable, con una vida media de aproximadamente 2,6 millones de a\u00f1os. Tampoco es algo que aparezca por casualidad en cualquier lugar. Si quieres obtener hierro-60, tendr\u00e1s que buscarlo, porque se crea durante las explosiones estelares: las supernovas. Cuando una estrella explota, el hierro-60 es expulsado al universo, y peque\u00f1as cantidades caen ocasionalmente a la Tierra. Incluso se han detectado algunos en<\/span> <span>nieves ant\u00e1rticas<\/span> <span>. A partir de 500 kilogramos de nieve pura recolectada para la muestra, los cient\u00edficos descubrieron cinco \u00e1tomos de hierro-60. Este is\u00f3topo fue detectado por primera vez en la Tierra hace apenas 23 a\u00f1os en sedimentos de suelos de aguas profundas.<\/span><\/p>\n<h2> <span>5. Se encontr\u00f3 plutonio-244 en el fondo del oc\u00e9ano.<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-73679\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/samye-neobychnye-izotopy-na-zemle_64107b9a4d2ee.jpeg\" alt=\"\" width=\"640\" height=\"402\"><\/p>\n<p> <span>Al igual que el hierro-60, el plutonio-244 no es un is\u00f3topo que aparezca de la nada. A diferencia del hierro, no hay is\u00f3topos de plutonio a los que convenga acercarse demasiado. Existen 20 de ellos, todos radiactivos, pero el plutonio-244 es el m\u00e1s estable.<\/span><\/p>\n<p> <span>Se encontraron rastros de plutonio-244 en<\/span> <span>fondo oce\u00e1nico<\/span> <span>en 2021, y se cree que ha viajado un largo camino para llegar hasta aqu\u00ed. El plutonio-244 se produce en condiciones bastante complejas. En este caso, el plutonio se form\u00f3 durante<\/span> <span>colisi\u00f3n de dos estrellas<\/span> <span>, lo que provoc\u00f3 una potente explosi\u00f3n. Es probable que tambi\u00e9n se forme en supernovas junto con el hierro-60.<\/span><\/p>\n<p> <span>El plutonio-244 no es un is\u00f3topo que podamos crear f\u00e1cilmente en la Tierra. Los reactores nucleares producen diversos is\u00f3topos, pero cuando el plutonio-242 se desintegra en 243, su vida media es de tan solo unas horas y no puede desintegrarse en 244. Se ha teorizado que una explosi\u00f3n de un arma nuclear podr\u00eda producir 244, pero esto sigue siendo puramente te\u00f3rico y no se ha observado.<\/span><\/p>\n<h2> <span>4. El magnesio-18 se descompone para formar<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-76024\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/samye-neobychnye-izotopy-na-zemle_64107b975f0b9.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Hemos visto que el astato tiene una vida media muy corta, pero los cient\u00edficos han creado un is\u00f3topo de magnesio tan inestable que resulta pr\u00e1cticamente imposible de observar. Normalmente, el magnesio tiene tres is\u00f3topos estables y 19 inestables.<\/span><\/p>\n<p> <span>De los elementos inestables, el magnesio-18 y el magnesio-19 son particularmente interesantes debido a sus vidas medias incre\u00edblemente cortas. El magnesio-19 tiene una vida media de<\/span> <span>5 picosegundos<\/span> <span>. Eso equivale a cinco billon\u00e9simas de segundo. Si les parece un periodo de tiempo muy corto, y lo es, entonces prep\u00e1rense para el magnesio-18.<\/span><\/p>\n<p> <span>El magnesio-18 no se ha medido adecuadamente porque su vida \u00fatil es aproximadamente de uno.<\/span> <span>sextill\u00f3n\u00e9sima de segundo<\/span> <span>. Se desintegra tan r\u00e1pidamente que los electrones ni siquiera pueden reorganizarse a su alrededor para formar un \u00e1tomo verdadero. Es solo un n\u00facleo, y luego se desintegra. Esto significa que los cient\u00edficos no pueden estudiarlo directamente, sino simplemente observar lo que hizo durante su corta existencia.<\/span><\/p>\n<h2> <span>3. Solo existen 500 g de prometio natural en el mundo.<\/span> <\/h2>\n<\/p>\n<p> <span>El prometio es un elemento excepcionalmente raro que carece de is\u00f3topos estables, aunque posee 38 is\u00f3topos inestables. Emite rayos X y es extraordinariamente escaso. Actualmente, solo se encuentra presente en el 100% del planeta.<\/span> <span>aproximadamente una libra<\/span> <span>Prometio natural. Sin embargo, tambi\u00e9n podemos producirlo en el laboratorio bombardeando uranio-235 y neodimio-147 con neutrones.<\/span><\/p>\n<p> <span>En 1902, un qu\u00edmico checo llamado Bohuslav Braun sugiri\u00f3 que el prometio deb\u00eda existir junto con otros seis elementos no descubiertos, y su presentimiento fue confirmado unos a\u00f1os m\u00e1s tarde cuando Henry Moseley confirm\u00f3 que algo entre el neodimio y el samario deb\u00eda existir en la tabla peri\u00f3dica con<\/span> <span>at\u00f3mico<\/span> <span>con un peso de 61. Fueron necesarios otros 20 a\u00f1os de b\u00fasqueda antes de que se determinara que, cualquiera que fuera el elemento 61, no tendr\u00eda is\u00f3topos estables.<\/span><\/p>\n<p> <span>Tras a\u00f1os de b\u00fasqueda, el prometio fue finalmente descubierto no en la naturaleza, sino en el laboratorio, cuando los cient\u00edficos se dieron cuenta de que pod\u00edan crear elementos y sus is\u00f3topos.<\/span><\/p>\n<p> <span>Siendo una sustancia tan rara y radiactiva, uno podr\u00eda pensar que tendr\u00eda aplicaciones importantes a nivel mundial, pero estar\u00eda equivocado. En realidad, se utiliza principalmente para cosas como pintura luminiscente y bater\u00edas nucleares.<\/span><\/p>\n<h2> <span>2. El estroncio-90 se procesa en el cuerpo de forma similar al calcio.<\/span> <\/h2>\n<\/p>\n<p> <span>El estroncio es un metal alcalinot\u00e9rreo y ocupa el puesto 38 en la tabla peri\u00f3dica. Posee cuatro is\u00f3topos estables naturales y 32 inestables. De estos is\u00f3topos, el estroncio-90 es el que requiere especial atenci\u00f3n, ya que su comportamiento es algo complejo.<\/span><\/p>\n<p> <span>El estroncio-90 es altamente reactivo y puede producir calor. Esta reacci\u00f3n lo hace \u00fatil como<\/span> <span>fuente de energ\u00eda<\/span> <span>, Se utiliza en estaciones meteorol\u00f3gicas remotas e incluso en naves espaciales, as\u00ed como en la industria m\u00e9dica. Si bien no es un is\u00f3topo estable que se encuentre en la naturaleza, es un subproducto de la fisi\u00f3n nuclear, de la cual proviene la mayor parte del suministro mundial, aunque tambi\u00e9n se produjo como resultado de las pruebas de armas nucleares en la d\u00e9cada de 1950.<\/span><\/p>\n<p> <span>Obviamente, hay que evitar el estroncio-90 debido a su radiactividad, pero tiene una forma insidiosa de provocar enfermedades si se entra en contacto con \u00e9l.<\/span> <span>puede ser inhalado<\/span> <span>, Sin embargo, tambi\u00e9n puede ingresar al cuerpo a trav\u00e9s de alimentos y agua contaminados. Una vez dentro, el cuerpo lo procesa de la misma manera que procesa el calcio. Esto significa que el estroncio radiactivo penetrar\u00e1 en los dientes y los huesos. Una vez incorporado al organismo, puede provocar c\u00e1ncer de hueso, c\u00e1ncer de m\u00e9dula \u00f3sea y c\u00e1ncer de tejidos blandos en las \u00e1reas circundantes a las part\u00edculas radiactivas.<\/span><\/p>\n<h2> <span>1. El tritio es una de las cosas m\u00e1s caras de la Tierra.<\/span> <\/h2>\n<\/p>\n<p> <span>El hidr\u00f3geno es el elemento m\u00e1s abundante del universo, con siete is\u00f3topos, aunque solo tres se dan de forma natural. El \u00faltimo, el hidr\u00f3geno-3, es lo que llamamos tritio, y es tan raro como valioso. Puede formarse de forma natural en la atm\u00f3sfera cuando<\/span> <span>Los rayos c\u00f3smicos impactan el nitr\u00f3geno.<\/span> <span>, pero solo se producen cantidades \u00ednfimas. Tambi\u00e9n se produce durante las explosiones nucleares y como subproducto de los reactores nucleares.<\/span><\/p>\n<p> <span>El tritio se utiliza en la producci\u00f3n de armas nucleares y tambi\u00e9n para la producci\u00f3n de<\/span> <span>esferas luminosas<\/span> <span>y para diversos fines cient\u00edficos y de investigaci\u00f3n. Libra por libra, tambi\u00e9n es una de las sustancias m\u00e1s valiosas de la Tierra. Por ejemplo, un gramo de oro puro puede costar alrededor de $70, dependiendo de varios factores. Un gramo de platino puede costar alrededor de $40. Un gramo de coca\u00edna puede costar alrededor de $120, dependiendo de d\u00f3nde lo compres. \u00bfY un gramo de tritio? Eso te costar\u00e1...<\/span> <span>aproximadamente $25,000<\/span> <span>.<\/span><\/p>\n<p> <span>Aproximadamente cuatro gramos de tritio se utilizan en armas nucleares para<\/span> <span>mejorar la eficiencia<\/span> <span>y hacer que el arma sea m\u00e1s destructiva, pero al mismo tiempo m\u00e1s ligera.<\/span><\/p>\n<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>Cada elemento tiene un n\u00famero at\u00f3mico distintivo. El n\u00famero at\u00f3mico representa la cantidad de protones en el n\u00facleo. Los is\u00f3topos tienen la misma cantidad de protones, lo que significa que son iguales\u2026<\/p>","protected":false},"author":1,"featured_media":13443,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-99160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/99160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/comments?post=99160"}],"version-history":[{"count":6,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/99160\/revisions"}],"predecessor-version":[{"id":138641,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/posts\/99160\/revisions\/138641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media\/13443"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/media?parent=99160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/categories?post=99160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/es\/wp-json\/wp\/v2\/tags?post=99160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}