{"id":10641,"date":"2026-06-04T01:14:01","date_gmt":"2026-06-03T22:14:01","guid":{"rendered":"https:\/\/imgist.ru\/supriya-ganesh-zayavila-chto-reshenie-ob-uhode-pitta-prinimali-noa-uajl-i-prodyusery-luchshe-sprosit-u-nih-otvety\/"},"modified":"2026-06-04T01:14:01","modified_gmt":"2026-06-03T22:14:01","slug":"suprya-ganesh-a-declare-que-la-decision-de-quitter-pitta-avait-ete-prise-par-noah-wajl-et-que-les-producteurs-feraient-mieux-de-leur-demander-des-explications","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/supriya-ganesh-zayavila-chto-reshenie-ob-uhode-pitta-prinimali-noa-uajl-i-prodyusery-luchshe-sprosit-u-nih-otvety\/","title":{"rendered":"Supriya Ganesh a d\u00e9clar\u00e9 que la d\u00e9cision de se s\u00e9parer de Pitt avait \u00e9t\u00e9 prise par Noah Wyle et les producteurs : \u00ab Il vaut mieux leur demander des explications. \u00bb."},"content":{"rendered":"<p>Si les fans de Pitt veulent savoir pourquoi le personnage de Supriya Ganesh a \u00e9t\u00e9 retir\u00e9 de l&#039;histoire apr\u00e8s la deuxi\u00e8me saison, l&#039;actrice affirme que Noah Wyle et les producteurs de la s\u00e9rie sont les mieux plac\u00e9s pour r\u00e9pondre \u00e0 cette question.<\/p>\n<p> Dans une interview accord\u00e9e au Los Angeles Times, Ganesh s&#039;est exprim\u00e9 plus ouvertement sur son d\u00e9part de la s\u00e9rie. L&#039;annonce du d\u00e9part du Dr Sameera Mohan lors de la troisi\u00e8me saison avait, \u00e0 juste titre, suscit\u00e9 la col\u00e8re des fans. Ganesh a alors point\u00e9 du doigt les producteurs ex\u00e9cutifs R. Scott Gemmill, Wyle et John Wells.<\/p>\n<p> \u00ab Ils travaillent tellement dur sur la s\u00e9rie et prennent chaque d\u00e9cision pour cette raison pr\u00e9cise, alors je pense qu&#039;il vaut mieux leur demander des r\u00e9ponses \u00bb, a d\u00e9clar\u00e9 Ganesh. \u00ab Je garderai pr\u00e9cieusement tous les souvenirs de mon travail avec ces deux-l\u00e0 et tous les autres. C&#039;\u00e9tait merveilleux de recevoir autant d&#039;amour de la part des fans. Je suis d\u00e9sol\u00e9 pour eux aussi qu&#039;ils ne puissent pas voir ce personnage. \u00bb.<\/p>\n<p> \u00ab La fa\u00e7on dont tu t&#039;es repr\u00e9sent\u00e9e dans la s\u00e9rie est tout simplement magnifique \u00bb, a ajout\u00e9 Isa Briones. \u00ab Voir les fans te soutenir autant et dire : &quot;C&#039;est la premi\u00e8re fois que je me sens repr\u00e9sent\u00e9e \u00e0 l&#039;\u00e9cran&quot;, c&#039;est vraiment formidable de voir tout le monde se mobiliser, s&#039;enthousiasmer et te c\u00e9l\u00e9brer. \u201e.<\/p>\n<p> Selon une source proche du dossier, la d\u00e9cision d&#039;\u00e9vincer Ganesh s&#039;inspirait de l&#039;intrigue de la s\u00e9rie \u00ab Pitt \u00bb, qui d\u00e9crit le roulement du personnel m\u00e9dical, infirmier et \u00e9tudiant dans un h\u00f4pital universitaire.<\/p>\n<p> \u00ab\u00a0Des d\u00e9parts sont in\u00e9vitables, et c\u2019est ce qui rend la s\u00e9rie r\u00e9aliste pour les t\u00e9l\u00e9spectateurs\u00a0\u00bb, avait d\u00e9clar\u00e9 John Wells \u00e0 TheWrap. \u00ab\u00a0\u00c0 l\u2019avenir, ces changements influenceront \u00e9galement la mani\u00e8re dont nous les g\u00e9rerons.\u00a0\u00bb.<\/p>\n<p> Le docteur Mohan, interpr\u00e9t\u00e9 par Ganesh, est le deuxi\u00e8me personnage en deux saisons \u00e0 quitter l&#039;h\u00f4pital entre deux gardes. Le docteur Collins, interpr\u00e9t\u00e9e par Tracy Ifeachor, a quitt\u00e9 la s\u00e9rie apr\u00e8s la premi\u00e8re saison, malgr\u00e9 plusieurs intrigues en suspens, notamment une relation pass\u00e9e avec le docteur Robbie.<\/p>\n<p> L&#039;article \u00ab Supriya Ganesh affirme que le d\u00e9part de Pitt \u00e9tait \u00e0 la discr\u00e9tion de Noah Wyle et des producteurs : mieux vaut leur demander des r\u00e9ponses \u00bb est paru initialement sur TheWrap.<\/p>","protected":false},"excerpt":{"rendered":"<p>Si les fans de Pitt veulent savoir pourquoi Supriya Ganesh a \u00e9t\u00e9 retir\u00e9e de l&#039;histoire apr\u00e8s la deuxi\u00e8me saison, l&#039;actrice affirme que Noah Wyle est le mieux plac\u00e9 pour r\u00e9pondre \u00e0 cette question\u2026<\/p>","protected":false},"author":1,"featured_media":10642,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-10641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/10641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=10641"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/10641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/10642"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=10641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=10641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=10641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}