{"id":14180,"date":"2026-06-05T18:15:57","date_gmt":"2026-06-05T15:15:57","guid":{"rendered":"https:\/\/imgist.ru\/off-campus-eto-serial-kotorogo-zhdali-i-zasluzhivayut-millenialy\/"},"modified":"2026-08-29T12:13:05","modified_gmt":"2026-08-29T09:13:05","slug":"off-campus-est-la-serie-que-les-millennials-attendaient-et-meritaient","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/off-campus-eto-serial-kotorogo-zhdali-i-zasluzhivayut-millenialy\/","title":{"rendered":"\u00abOff Campus est l&#039;\u00e9mission que les millennials attendaient et m\u00e9ritent."},"content":{"rendered":"<p>Si vous n&#039;avez pas eu la chance de d\u00e9couvrir le cin\u00e9ma et la t\u00e9l\u00e9vision dans les ann\u00e9es 90, laissez-moi vous dire tout de suite : c&#039;\u00e9tait une \u00e9poque \u00e9trange.<\/p>\n<p> Oui, il y avait de v\u00e9ritables perles parmi elles : <em>\u00abBuffy contre les vampires\u00bb<\/em> , <em>\u00abD\u00e9sempar\u00e9s\u00bb<\/em> , <em>\u00abMagie pratique\u00bb<\/em> (Dieu merci, la suite tant attendue arrive bient\u00f4t) et bien d&#039;autres s\u00e9ries cultes pour adolescents.<\/p>\n<p> Mais la s\u00e9rie v\u00e9hiculait aussi de terribles st\u00e9r\u00e9otypes qui la rendent difficile \u00e0 revoir\u00a0: une diversit\u00e9 minimale, des amiti\u00e9s toxiques, des crit\u00e8res de beaut\u00e9 irr\u00e9alistes, une conception douteuse du consentement\u2026 et ce, avant m\u00eame d\u2019\u00e9voquer les abus en coulisses, d\u00e9sormais reconnus comme \u00e9tant monnaie courante dans le milieu. Bref, grandir \u00e0 cette \u00e9poque a \u00e9t\u00e9 une p\u00e9riode tr\u00e8s d\u00e9routante.<\/p>\n<p> La consolation, c&#039;est que dans cette t\u00e9l\u00e9-poubelle (c&#039;est-\u00e0-dire l&#039;incroyablement populaire) <em>S\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab\u00a0Off Campus\u00a0\u00bb<\/em> \u00bb&quot;) pr\u00e9sente une bonne dose d&#039;absurdit\u00e9 pure (par exemple, le personnage principal, une jeune femme d&#039;environ 19 ans, se demande si elle tombera un jour amoureuse) combin\u00e9e \u00e0 des sc\u00e8nes explicites et \u00e0 des moments \u00e9tonnamment touchants. Ah, et du hockey. C&#039;est en gros, <em>\u00abRivalit\u00e9 exacerb\u00e9e\u00bb<\/em> pour les h\u00e9t\u00e9rosexuels.<\/p>\n<p> Les adolescents regardent-ils cette \u00e9mission\u00a0? Honn\u00eatement, je ne peux pas en \u00eatre s\u00fbre, mais c\u2019est un v\u00e9ritable succ\u00e8s aupr\u00e8s des jeunes femmes de la g\u00e9n\u00e9ration Y qui ont grandi avec des intrigues absurdes, des relookings, de faux rendez-vous sans raison apparente et, surtout, un final qui implique une comp\u00e9tition \u00e0 enjeux \u00e9lev\u00e9s.<\/p>\n<p> Les enfants, si vous lisez ceci, sachez que la vie ne fonctionne pas ainsi. Si quelqu&#039;un vous sugg\u00e8re de faire semblant de sortir avec quelqu&#039;un pour le rendre jaloux avant un concert important, la r\u00e9ponse doit toujours \u00eatre \u00ab non \u00bb.<\/p>\n<p> Pour ceux qui ne connaissent pas l&#039;histoire, l&#039;adaptation cin\u00e9matographique des romans \u00e0 succ\u00e8s d&#039;Ellie Kennedy raconte l&#039;histoire d&#039;Hannah Wells (Ella Bright), \u00e9tudiante en musique, follement amoureuse d&#039;un gar\u00e7on qui ignore jusqu&#039;\u00e0 son existence. \u00ab Ce n&#039;est pas parce qu&#039;il sait jouer de la guitare et qu&#039;il a des petits tatouages qu&#039;il est une sorte d&#039;idole du rock inaccessible \u00bb, lui lance sa meilleure amie Ellie (Mika Abdallah). \u00ab O\u00f9 \u00e9tais-tu quand j&#039;avais vingt ans, Ellie ? \u00bb<\/p>\n<p> \u00c0 ce stade, il convient de s&#039;int\u00e9resser un peu \u00e0 Ellie, sans conteste le meilleur personnage de la s\u00e9rie, qui prodigue de sages conseils, met fin \u00e0 des relations ennuyeuses pour vivre pleinement sa vie (notamment une romance avec le joueur de hockey Dean, dont l&#039;intrigue deviendra essentielle \u00e0 la deuxi\u00e8me saison), et s&#039;habille comme une ic\u00f4ne, \u00e0 l&#039;instar de J.Lo. <\/p>\n<p> L&#039;acteur Mika Abdallah joue Allie Haze dans <em>dans le film &quot;Off Campus&quot;\u00ab<\/em> . (Chris Pizzello\/Invision\/AP)<\/p>\n<p> Revenons \u00e0 Hannah qui, en plus de souffrir d&#039;un amour non partag\u00e9, doit \u00e9crire une chanson pour un concours pop afin de conserver sa bourse (un concours classique de drame adolescent \u00e0 enjeux \u00e9lev\u00e9s).<\/p>\n<p> Voici Garrett (Belmont Cameli), star du hockey et colosse muscl\u00e9, qui pr\u00e9tend ne JAMAIS avoir de copine (mdr). Il accepte de faire semblant de sortir avec Hannah pour rendre le musicien jaloux, en \u00e9change de quoi elle deviendra sa tutrice de philo (bon retour \u00e0 l&#039;intrigue de 1999, elle nous avait manqu\u00e9 !). Attention spoiler : les faux rendez-vous se transforment en vrais rendez-vous, et une romance passionn\u00e9e s&#039;ensuit. Ah oui, et beaucoup de sc\u00e8nes explicites.<\/p>\n<p> Note : Si la philosophie vous int\u00e9resse, il y a une sc\u00e8ne \u00e9trange sur Kierkegaard qui est ins\u00e9r\u00e9e dans le film, mais sinon vous serez d\u00e9\u00e7u.<\/p>\n<p> En ce qui concerne les s\u00e9ries dramatiques pour adolescents, <em>\u00abHors campus\u00bb<\/em> Elle coche toutes les cases : un casting incroyablement s\u00e9duisant, une bande originale g\u00e9niale, du suspense, de la romance, des amiti\u00e9s f\u00e9minines toxiques (typique des sitcoms des ann\u00e9es 90), des athl\u00e8tes vraiment dou\u00e9s et une histoire personnelle riche.<\/p>\n<p> La fa\u00e7on dont le film aborde le sexe, le consentement et les agressions sexuelles est radicale, et me fait comprendre la g\u00e9n\u00e9ration Y qui a grandi en regardant des films o\u00f9 le viol \u00e9tait banalis\u00e9. Ici, on voit des hommes qui prennent en compte les craintes des femmes de se faire droguer, des hommes qui attendent qu&#039;elles se sentent \u00e0 l&#039;aise avant d&#039;avoir des relations sexuelles, des hommes qui expriment ouvertement leurs sentiments. \u00ab On voit bien que ces personnages ont \u00e9t\u00e9 \u00e9crits par une femme \u00bb, a fait remarquer un ami. Si c&#039;est le cas, messieurs, il est temps de vous ressaisir.<\/p>\n<p> L&#039;influence de la s\u00e9rie <em>\u00ab Hors campus \u00bb est tellement vaste,<\/em> Mon fil Instagram est d\u00e9sormais inond\u00e9 de publications de femmes d&#039;un certain \u00e2ge (hum) qui se rappellent : \u00ab Je suis adulte, j&#039;ai deux enfants et je ne peux pas tomber amoureuse de joueurs de hockey fictifs. \u00bb Mesdames, allez-y, tombez amoureuses ! Vous avez assez souffert pour ces personnages masculins toxiques et mal \u00e9crits ; maintenant, c&#039;est votre tour.<\/p>","protected":false},"excerpt":{"rendered":"<p>Si vous n&#039;avez pas eu la chance de d\u00e9couvrir le cin\u00e9ma et la t\u00e9l\u00e9vision dans les ann\u00e9es 90, laissez-moi vous dire\u00a0: c&#039;\u00e9tait une \u00e9poque \u00e9trange. Oui, parmi eux\u2026<\/p>","protected":false},"author":1,"featured_media":14181,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-14180","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/14180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=14180"}],"version-history":[{"count":1,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/14180\/revisions"}],"predecessor-version":[{"id":157474,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/14180\/revisions\/157474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/14181"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=14180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=14180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=14180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}