{"id":162795,"date":"2026-09-01T10:12:00","date_gmt":"2026-09-01T07:12:00","guid":{"rendered":"https:\/\/imgist.ru\/dejstvitelno-li-geneticheski-modificzirovannye-produkty-opasny\/"},"modified":"2026-09-01T10:12:06","modified_gmt":"2026-09-01T07:12:06","slug":"les-aliments-genetiquement-modifies-sont-ils-vraiment-dangereux","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/dejstvitelno-li-geneticheski-modificzirovannye-produkty-opasny\/","title":{"rendered":"Les aliments g\u00e9n\u00e9tiquement modifi\u00e9s sont-ils vraiment dangereux ?"},"content":{"rendered":"<p>Partager sur WhatsApp, Reddit, Email, Tweeter, \u00c9pingler 0 partages<\/p>\n<p> Entrez dans un supermarch\u00e9 aujourd&#039;hui et vous verrez d&#039;innombrables produits \u00e9tiquet\u00e9s \u00ab sans OGM \u00bb en rayon. Cette mention se trouve g\u00e9n\u00e9ralement \u00e0 c\u00f4t\u00e9 des \u00e9tiquettes \u00ab sans gluten \u00bb ou \u00ab sans mati\u00e8res grasses \u00bb. Bien qu&#039;elle ne mentionne pas explicitement les OGM, cette \u00e9tiquette vise clairement \u00e0 vous rassurer, vous, le consommateur. Elle garantit que l&#039;aliment que vous vous appr\u00eatez \u00e0 consommer est sain car il ne contient pas d&#039;ingr\u00e9dients g\u00e9n\u00e9tiquement modifi\u00e9s !<\/p>\n<p> Il existe une organisation enti\u00e8re, le Non-GMO Project, cr\u00e9\u00e9e avec un logo repr\u00e9sentant un petit papillon orange, pour vous aider \u00e0 identifier les aliments non g\u00e9n\u00e9tiquement modifi\u00e9s. Cela laisse clairement entendre que les OGM sont nocifs, voire dangereux, mais est-ce vraiment le cas\u00a0? Selon le Non-GMO Project, les organismes g\u00e9n\u00e9tiquement modifi\u00e9s sont compos\u00e9s d&#039;une combinaison de g\u00e8nes v\u00e9g\u00e9taux, animaux, bact\u00e9riens et viraux qu&#039;on ne trouve jamais \u00e0 l&#039;\u00e9tat naturel, et aucune \u00e9tude \u00e0 long terme n&#039;a permis d&#039;\u00e9tablir leur innocuit\u00e9.<\/p>\n<p> Alors, que disent les donn\u00e9es scientifiques\u00a0? Plus de 901\u00a0% des tonnes de coton, de soja et de ma\u00efs cultiv\u00e9es aux \u00c9tats-Unis d\u2019ici 2024 seront g\u00e9n\u00e9tiquement modifi\u00e9es. Y a-t-il des risques, et lesquels\u00a0? Le riz produit selon les bonnes pratiques de fabrication (BPF) est-il sans danger pour la sant\u00e9, ou risquez-vous de devenir un mutant alimentaire\u00a0?<\/p>\n<h2> dangers<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/dejstvitelno-li-geneticheski-modificzirovannye-produkty-opasny_6a967ac1798c4.jpeg\" alt=\"\" width=\"640\" height=\"437\"><\/p>\n<p> Commen\u00e7ons par les dangers potentiels des OGM, tels que d\u00e9taill\u00e9s par le Projet sans OGM. Leur site web met en lumi\u00e8re deux points souvent n\u00e9glig\u00e9s. Premi\u00e8rement, les semences OGM peuvent repr\u00e9senter un fardeau pour les agriculteurs et m\u00eame compromettre leurs moyens de subsistance. Des pr\u00e9cautions doivent \u00eatre prises pour \u00e9viter la contamination des cultures OGM par des cultures non OGM, et inversement. Imaginez la difficult\u00e9 d&#039;emp\u00eacher la pollinisation crois\u00e9e entre les cultures, qui pourrait mener au d\u00e9veloppement de nouvelles cultures potentiellement OGM. Cela pourrait avoir de graves cons\u00e9quences sur la mani\u00e8re dont les produits alimentaires sont cultiv\u00e9s, \u00e9tiquet\u00e9s et commercialis\u00e9s.<\/p>\n<p> De plus, les semences OGM sont brevet\u00e9es par les entreprises qui les produisent. Cela signifie que les agriculteurs ne peuvent ni stocker ni produire leurs propres semences, et que s&#039;ils tentent de semer des semences issues de leurs propres cultures, des entreprises comme Monsanto peuvent les poursuivre pour contrefa\u00e7on.<\/p>\n<p> Les cultures g\u00e9n\u00e9tiquement modifi\u00e9es peuvent \u00e9galement \u00eatre extr\u00eamement nocives pour l&#039;environnement. L&#039;une des modifications que subissent de nombreuses cultures est la r\u00e9sistance aux herbicides. Bien qu&#039;il soit souhaitable que les cultures soient r\u00e9sistantes et difficiles \u00e0 \u00e9liminer, cela semble une bonne id\u00e9e au premier abord. Cependant, la r\u00e9sistance aux herbicides entra\u00eene une forte augmentation de leur utilisation. Au Canada seulement, les ventes d&#039;herbicides comme le Roundup, associ\u00e9 au cancer depuis des ann\u00e9es, ont augment\u00e9 de pr\u00e8s de 2\u00a0000\u00a0\u00a3.<\/p>\n<p> Il a \u00e9galement \u00e9t\u00e9 sugg\u00e9r\u00e9 que l&#039;utilisation accrue d&#039;herbicides a entra\u00een\u00e9 un d\u00e9clin des esp\u00e8ces v\u00e9g\u00e9tales indig\u00e8nes tout en favorisant la prolif\u00e9ration des mauvaises herbes r\u00e9sistantes aux herbicides.<\/p>\n<h2> Aucun risque et am\u00e9liorations potentielles<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/dejstvitelno-li-geneticheski-modificzirovannye-produkty-opasny_6a967ac26408e.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> Bien que certains facteurs environnementaux doivent \u00eatre pris en compte, ils pr\u00e9sentent \u00e9galement certains avantages. L&#039;utilisation de certains herbicides a augment\u00e9, mais certaines \u00e9tudes sugg\u00e8rent que l&#039;utilisation mondiale de pesticides et autres produits chimiques a diminu\u00e9 de 371 %, tandis que les rendements agricoles ont augment\u00e9 de 221 % et les b\u00e9n\u00e9fices des exploitations agricoles de 641 %.<\/p>\n<p> Gr\u00e2ce aux cultures g\u00e9n\u00e9tiquement modifi\u00e9es, l&#039;utilisation de pesticides \u00e9tant moins fr\u00e9quente, les \u00e9missions de gaz \u00e0 effet de serre ont \u00e9galement diminu\u00e9. En 2018, cela \u00e9quivalait \u00e0 retirer 15 millions de voitures de la circulation.<\/p>\n<p> Dans les pays moins d\u00e9velopp\u00e9s que les \u00c9tats-Unis et les autres nations occidentales, l&#039;agriculture a traditionnellement \u00e9t\u00e9 beaucoup plus rude et dangereuse. Les cultures g\u00e9n\u00e9tiquement modifi\u00e9es ont consid\u00e9rablement r\u00e9duit les cas d&#039;intoxication aux pesticides dans les pays en d\u00e9veloppement. L&#039;Afrique du Sud a enregistr\u00e9 une baisse significative du nombre d&#039;agriculteurs souffrant d&#039;intoxication li\u00e9e \u00e0 l&#039;utilisation de pesticides. En Chine, un tiers des agriculteurs n&#039;utilisant pas de coton g\u00e9n\u00e9tiquement modifi\u00e9 ont d\u00e9clar\u00e9 avoir \u00e9t\u00e9 intoxiqu\u00e9s, contre 91 % pour ceux qui l&#039;utilisent. En Inde, on a d\u00e9nombr\u00e9 au moins 38 millions de cas d&#039;intoxication en moins entre 2003 et 2019, mais ce chiffre pourrait \u00eatre bien plus \u00e9lev\u00e9.<\/p>\n<p> La premi\u00e8re culture g\u00e9n\u00e9tiquement modifi\u00e9e aux \u00c9tats-Unis fut la tomate Flavr Savr, introduite en 1994. Elle fut modifi\u00e9e pour ralentir sa maturation et \u00e9viter qu&#039;elle ne se g\u00e2te rapidement, contrairement aux autres vari\u00e9t\u00e9s de tomates. Les chercheurs de l&#039;Institut pour une technologie responsable (IRT) condamn\u00e8rent rapidement les OGM. Leurs \u00e9tudes affirmaient que les effets toxiques sur les rats \u00e9taient quasi imm\u00e9diats. Aucun autre scientifique n&#039;a r\u00e9ussi \u00e0 reproduire ces r\u00e9sultats en laboratoire.<\/p>\n<p> De nombreuses \u00e9tudes men\u00e9es par diff\u00e9rents groupes dans divers pays n&#039;ont r\u00e9v\u00e9l\u00e9 aucun effet n\u00e9faste sur la sant\u00e9 des personnes consommant des aliments g\u00e9n\u00e9tiquement modifi\u00e9s. M\u00eame au niveau microscopique, aucun effet sp\u00e9cifique associ\u00e9 aux OGM n&#039;a \u00e9t\u00e9 d\u00e9tect\u00e9.<\/p>\n<p> Des \u00e9tudes ont \u00e9galement \u00e9t\u00e9 men\u00e9es sur des rats nourris au ma\u00efs g\u00e9n\u00e9tiquement modifi\u00e9 afin de d\u00e9terminer si d&#039;\u00e9ventuels d\u00e9fauts pouvaient se transmettre de g\u00e9n\u00e9ration en g\u00e9n\u00e9ration. M\u00eame apr\u00e8s quatre g\u00e9n\u00e9rations, les rats ne pr\u00e9sentaient aucun effet n\u00e9gatif sur les tissus ou organes qui auraient d\u00fb \u00eatre affect\u00e9s en cas d&#039;h\u00e9r\u00e9dit\u00e9.<\/p>\n<p> Les cultures g\u00e9n\u00e9tiquement modifi\u00e9es ne sont pas modifi\u00e9es de mani\u00e8re \u00e0 causer des probl\u00e8mes de sant\u00e9 chez l&#039;homme ou les animaux qui les consomment. Ce domaine est soumis \u00e0 une r\u00e9glementation extr\u00eamement stricte afin de garantir une parfaite connaissance des g\u00e8nes utilis\u00e9s pour modifier ces organismes, et cette r\u00e9glementation est bien plus rigoureuse que celle applicable aux aliments non g\u00e9n\u00e9tiquement modifi\u00e9s.<\/p>\n<p> Loin d&#039;\u00eatre un projet de science-fiction dangereux et irrationnel, le g\u00e8ne de la tomate Flavr Savr qui emp\u00eache sa d\u00e9t\u00e9rioration \u00e9tait d\u00e9j\u00e0 pr\u00e9sent dans la tomate elle-m\u00eame. Les scientifiques ont copi\u00e9 ce g\u00e8ne et l&#039;ont ins\u00e9r\u00e9 dans une cellule bact\u00e9rienne d\u00e9pourvue de substances nocives, l&#039;utilisant comme simple enveloppe pour l&#039;h\u00e9berger. Une fois introduit dans la tomate, le g\u00e8ne inhibe la production d&#039;une enzyme qui acc\u00e9l\u00e8re la d\u00e9t\u00e9rioration, permettant ainsi \u00e0 la tomate de rester fra\u00eeche plus longtemps. Aucun \u00e9l\u00e9ment nocif n&#039;a \u00e9t\u00e9 introduit et rien ne peut provoquer d&#039;allergies, de cancers, de mutations ou tout autre probl\u00e8me de sant\u00e9. Croire que cela est possible repose uniquement sur une mauvaise compr\u00e9hension des sciences, voire sur des mensonges purs et simples.<\/p>\n<p> Les groupes de recherche sur le cancer soulignent \u00e9galement que les inqui\u00e9tudes concernant un lien entre le cancer et les aliments OGM sont infond\u00e9es, car leur fonctionnement est tout simplement erron\u00e9. Rien ne prouve qu&#039;ils aient caus\u00e9 des cancers par le pass\u00e9, et aucune explication scientifiquement valable ne permet de comprendre comment cela pourrait se produire. Depuis l&#039;introduction des OGM aux \u00c9tats-Unis, aucune augmentation significative du nombre de cas de cancer n&#039;a \u00e9t\u00e9 constat\u00e9e.<\/p>\n<h2> Les aliments OGM sauvent des vies<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/dejstvitelno-li-geneticheski-modificzirovannye-produkty-opasny_6a967ac35f9cb.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> Dans le monde occidental, il est plus difficile de saisir pleinement l&#039;importance des cultures g\u00e9n\u00e9tiquement modifi\u00e9es. Pour nous, une tomate qui se conserve plus longtemps peut sembler anodine. Pourtant, dans les r\u00e9gions du monde o\u00f9 la famine est une menace r\u00e9elle et o\u00f9 des personnes meurent chaque jour, les cultures g\u00e9n\u00e9tiquement modifi\u00e9es auraient permis de sauver des milliards de vies. Gr\u00e2ce \u00e0 des rendements plus \u00e9lev\u00e9s, une meilleure r\u00e9sistance aux insectes et \u00e0 la s\u00e9cheresse, des populations qui, autrement, mourraient de faim, peuvent d\u00e9sormais se nourrir.<\/p>\n<p> Les pommes g\u00e9n\u00e9tiquement modifi\u00e9es, qui s&#039;oxydent et brunissent moins vite, contribuent \u00e0 r\u00e9duire le gaspillage alimentaire, et le soja g\u00e9n\u00e9tiquement modifi\u00e9 permet de produire une huile plus saine. Si la nouveaut\u00e9 de vari\u00e9t\u00e9s comme les pommes Arctic illustre comment les OGM peuvent transformer notre alimentation, le v\u00e9ritable enjeu est de garantir un approvisionnement alimentaire suffisant et de qualit\u00e9 nutritionnelle.<\/p>\n<p> Le riz g\u00e9n\u00e9tiquement modifi\u00e9, con\u00e7u pour augmenter sa teneur en b\u00eata-carot\u00e8ne, \u00e9tait cens\u00e9 sauver des millions de vies. Se transformant en vitamine A apr\u00e8s ingestion, il aurait \u00e9t\u00e9 d&#039;une valeur inestimable dans les r\u00e9gions du monde o\u00f9 la carence en vitamine A cause un million de d\u00e9c\u00e8s par an et deux fois moins de cas de c\u00e9cit\u00e9. Malheureusement, malgr\u00e9 l&#039;absence de preuves de dangerosit\u00e9, le \u00ab\u00a0riz dor\u00e9\u00a0\u00bb n&#039;a jamais \u00e9t\u00e9 cultiv\u00e9 ni commercialis\u00e9, car des groupes anti-OGM, dont Greenpeace, s&#039;y sont oppos\u00e9s et ont convaincu les gouvernements de l&#039;interdire. Il n&#039;a toujours pas \u00e9t\u00e9 cultiv\u00e9 \u00e0 grande \u00e9chelle, malgr\u00e9 des \u00e9tudes montrant qu&#039;il contient plus de vitamine A que les \u00e9pinards.<\/p>\n<p> Pr\u00e8s de 800 millions de personnes sur Terre souffrent r\u00e9guli\u00e8rement de la faim. Environ 9 millions d&#039;entre elles en meurent chaque ann\u00e9e. Les cultures g\u00e9n\u00e9tiquement modifi\u00e9es ne suffisent pas \u00e0 elles seules \u00e0 r\u00e9soudre ce probl\u00e8me \u2013 elles existent depuis des d\u00e9cennies et la faim persiste \u2013 mais elles peuvent contribuer \u00e0 r\u00e9duire ces chiffres. Des rendements plus \u00e9lev\u00e9s, une valeur nutritionnelle am\u00e9lior\u00e9e et une plus grande durabilit\u00e9 permettront \u00e0 un plus grand nombre de personnes de se nourrir.<\/p>\n<h2> Quels sont les OGM existants ?<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/dejstvitelno-li-geneticheski-modificzirovannye-produkty-opasny_6a967ac45856a.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> Nous avons d\u00e9j\u00e0 abord\u00e9 la question des nombreux aliments g\u00e9n\u00e9tiquement modifi\u00e9s pr\u00e9sents dans le monde. Des pommes au ma\u00efs en passant par le riz, les possibilit\u00e9s sont infinies. Il y a fort \u00e0 parier que vous avez d\u00e9j\u00e0 consomm\u00e9 des c\u00e9r\u00e9ales, des produits \u00e0 base de soja, du sucre et toutes sortes d&#039;autres aliments g\u00e9n\u00e9tiquement modifi\u00e9s, peut-\u00eatre m\u00eame sans le savoir. Et il existe encore de nouveaux produits sur le march\u00e9.<\/p>\n<p> Le saumon AquAdvantage est un saumon g\u00e9n\u00e9tiquement modifi\u00e9 qui atteint sa taille commerciale deux fois plus vite. C&#039;est l&#039;un des premiers OGM vivants, et le public semble se m\u00e9fier davantage de ce poisson que des plantes, malgr\u00e9 l&#039;absence de toute preuve de dangerosit\u00e9. Les m\u00e9dias ont commenc\u00e9 \u00e0 le surnommer \u00ab\u00a0Frankenfish\u00a0\u00bb.<\/p>\n<p> Au Canada, des porcs connus pour produire d&#039;importantes quantit\u00e9s de fumier potentiellement toxique en raison de leur forte teneur en phosphore ont \u00e9galement \u00e9t\u00e9 g\u00e9n\u00e9tiquement modifi\u00e9s. La nouvelle race EnviroPig a \u00e9t\u00e9 s\u00e9lectionn\u00e9e pour produire naturellement une enzyme, couramment ajout\u00e9e \u00e0 leur alimentation par les \u00e9leveurs, qui contribue \u00e0 r\u00e9duire les niveaux dangereux de phosphore. Certaines vaches \u00e9mettent \u00e9galement moins de gaz et de rots, ce qui se traduit par une diminution des \u00e9missions de m\u00e9thane.<\/p>\n<p> L&#039;une des inventions les plus impressionnantes du g\u00e9nie g\u00e9n\u00e9tique est la cr\u00e9ation de ch\u00e8vres produisant de la soie d&#039;araign\u00e9e. Les g\u00e8nes responsables de la production de soie ont \u00e9t\u00e9 modifi\u00e9s au niveau des glandes mammaires des ch\u00e8vres, de sorte que la traite permet la production de soie d&#039;araign\u00e9e. Ces exp\u00e9riences se poursuivent car la soie d&#039;araign\u00e9e pr\u00e9sente de nombreuses applications potentielles \u00e0 travers le monde\u00a0; son obtention par les m\u00e9thodes conventionnelles est toutefois extr\u00eamement difficile en raison de la taille \u00e9tonnamment petite et du comportement impr\u00e9visible des araign\u00e9es.<\/p>\n<p> Des scientifiques travaillent actuellement \u00e0 la cr\u00e9ation d&#039;un chou v\u00e9n\u00e9neux. Des g\u00e8nes de scorpion sont utilis\u00e9s pour permettre au chou de produire un poison dans ses feuilles. Ce poison sera modifi\u00e9 pour \u00eatre inoffensif pour l&#039;homme, mais constituera \u00e9galement un puissant r\u00e9pulsif contre les ravageurs tels que les chenilles. En tant que pesticide naturel, ce proc\u00e9d\u00e9 pourrait r\u00e9duire consid\u00e9rablement l&#039;utilisation de produits chimiques tout en prot\u00e9geant l&#039;environnement.<\/p>\n<p> \u00c0 premi\u00e8re vue, tout cela para\u00eet \u00e9trange, et il est facile de pr\u00e9senter ces id\u00e9es comme dangereuses. Cependant, le but \u00e9vident de ces modifications et leurs avantages deviennent \u00e9galement tr\u00e8s clairs lorsqu&#039;on prend le temps d&#039;\u00e9tudier la question. C&#039;est d&#039;ailleurs l&#039;objectif de tout OGM\u00a0: am\u00e9liorer la situation.<\/p>\n<h2> Contradictions<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"\" alt=\"\" width=\"640\" height=\"480\"><\/p>\n<p> Si la science affirme que les cultures OGM ne pr\u00e9sentent aucun danger, pourquoi tant de personnes, d&#039;organisations et m\u00eame de gouvernements s&#039;y opposent-ils\u00a0? Un groupe de biotechnologistes belges a publi\u00e9 un article expliquant que l&#039;une des raisons de cette forte opposition aux OGM est tout simplement qu&#039;elle nous para\u00eet logique. Notre esprit comprend ais\u00e9ment pourquoi ils sont n\u00e9fastes, et nous finissons par le croire.<\/p>\n<p> En r\u00e9alit\u00e9, la plupart des opposants aux OGM sont moins bien inform\u00e9s qu&#039;ils ne le pensent. Les \u00e9tudes montrent que ceux qui s&#039;y opposent le plus et se consid\u00e8rent comme des experts sont en fait ceux qui en savent le moins. Et l&#039;ignorance n&#039;est pas un d\u00e9faut\u00a0; presque aucun d&#039;entre nous ne connaissait les OGM avant de go\u00fbter sa premi\u00e8re tomate, alors il est bon de s&#039;informer avant de porter un jugement.<\/p>\n<p> Pour certains, comme les chefs cuisiniers, la question des OGM rel\u00e8ve moins de la science que du contr\u00f4le exerc\u00e9 par les entreprises sur l&#039;approvisionnement alimentaire. Il s&#039;agit d&#039;un probl\u00e8me bien plus grave que les risques potentiels pour la sant\u00e9.<\/p>\n<h2> Une militante anti-OGM qui s&#039;est tourn\u00e9e vers d&#039;autres technologies.<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/dejstvitelno-li-geneticheski-modificzirovannye-produkty-opasny_6a967ac5c1bca.jpeg\" alt=\"\" width=\"640\" height=\"400\"><\/p>\n<p> D&#039;ailleurs, certaines personnes \u00e9taient initialement oppos\u00e9es aux OGM, mais ont chang\u00e9 d&#039;avis apr\u00e8s s&#039;\u00eatre mieux inform\u00e9es. Le militant \u00e9cologiste Mark Lynas a m\u00eame d\u00e9truit des cultures OGM. Il estimait que la science interf\u00e9rait avec certains \u00e9l\u00e9ments fondamentaux de la nature et que, non seulement il ne pouvait cautionner cela, mais qu&#039;il devait le combattre activement.<\/p>\n<p> Au fil des ans, son int\u00e9r\u00eat croissant pour les questions environnementales telles que le changement climatique l&#039;a amen\u00e9 \u00e0 approfondir ses connaissances scientifiques et \u00e0 r\u00e9aliser que sa position initiale \u00e9tait profond\u00e9ment anti-scientifique. Apr\u00e8s avoir \u00e9tudi\u00e9 les processus de production des OGM, il a chang\u00e9 d&#039;avis et a exhort\u00e9 ceux qui partageaient ses convictions \u00e0 faire de m\u00eame et \u00e0 ne pas entraver les progr\u00e8s susceptibles de nourrir les populations affam\u00e9es.<\/p>\n<p> Comme pour tout le reste, la cl\u00e9 de la compr\u00e9hension r\u00e9side dans l&#039;\u00e9tude du sujet et la prise de d\u00e9cisions en ayant toutes les informations, et non seulement une partie.<\/p>\n<p> Autres articles susceptibles de vous int\u00e9resser<\/p>","protected":false},"excerpt":{"rendered":"<p>Entrez dans un supermarch\u00e9 aujourd&#039;hui et vous verrez d&#039;innombrables produits \u00e9tiquet\u00e9s \u00ab sans OGM \u00bb sur les rayons. Cette \u00e9tiquette se trouve g\u00e9n\u00e9ralement \u00e0 c\u00f4t\u00e9 des\u2026<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-162795","post","type-post","status-publish","format-standard","hentry","category-interesnye-fakty"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/162795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=162795"}],"version-history":[{"count":1,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/162795\/revisions"}],"predecessor-version":[{"id":162801,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/162795\/revisions\/162801"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=162795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=162795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=162795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}