{"id":163490,"date":"2026-09-01T17:30:40","date_gmt":"2026-09-01T14:30:40","guid":{"rendered":"https:\/\/imgist.ru\/86-interesnyh-faktov-o-futbole\/"},"modified":"2026-09-01T17:30:50","modified_gmt":"2026-09-01T14:30:50","slug":"86-faits-interessants-sur-le-football","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/86-interesnyh-faktov-o-futbole\/","title":{"rendered":"86 faits int\u00e9ressants sur le football"},"content":{"rendered":"<p>Derni\u00e8re mise \u00e0 jour : 24 juin 2023, r\u00e9daction.<\/p>\n<p> <strong>Football<\/strong> Le football est un sport d&#039;\u00e9quipe qui se joue entre des \u00e9quipes de 11 joueurs. Il se pratique avec un ballon sph\u00e9rique. Environ 250 millions de personnes jouent au football dans plus de 200 pays, ce qui en fait le sport le plus populaire au monde. D\u00e9couvrons-en plus sur le football gr\u00e2ce \u00e0 ces informations sur les joueurs, les ballons, les chaussures, les terrains, l&#039;histoire, les arbitres, les clubs et bien plus encore.<\/p>\n<p> L&#039;article comprend \u00e9galement des tableaux r\u00e9capitulant les gains de la Coupe du Monde de la FIFA depuis 1982, les meilleurs buteurs de la comp\u00e9tition, le nombre de titres remport\u00e9s par pays et les ann\u00e9es de ces victoires, ainsi que les joueurs ayant inscrit le plus de buts de l&#039;histoire. Lire l&#039;article complet.<\/p>\n<h2> Faits int\u00e9ressants sur le football<\/h2>\n<p> <strong>1.<\/strong> Le plus t\u00f4t <strong>un jeu historique qui rappelle le football,<\/strong> Le cujiu est un jeu chinois. L&#039;histoire de ce sport remonte \u00e0 la dynastie Han (206 av. J.-C. \u2013 220 apr. J.-C.). On y jouait en envoyant une balle de cuir entre deux poteaux de bambou plac\u00e9s \u00e0 30-40 centim\u00e8tres de distance.<\/p>\n<p> <strong>2.<\/strong> T\u00f4t <strong>alternatives au football<\/strong> Les boules contenaient des peaux d&#039;animaux, des cr\u00e2nes, des vessies de porc et bien d&#039;autres choses encore.<\/p>\n<p> <strong>3.<\/strong> <strong>Le plus ancien club de football professionnel encore en activit\u00e9<\/strong> Le meilleur club du monde est Sheffield FC. C&#039;\u00e9tait <strong>fond\u00e9e en 1857<\/strong> et a \u00e9volu\u00e9 tout au long de son histoire dans diff\u00e9rentes ligues anglaises.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"L&#039;\u00e9quipe nationale argentine \u00e0 Saint-P\u00e9tersbourg. Quelques faits int\u00e9ressants sur le football.\" width=\"799\" height=\"533\"><figcaption> L&#039;\u00e9quipe nationale argentine \u00e0 Saint-P\u00e9tersbourg. Source de l&#039;image\u00a0: archives photographiques de la GPA.<\/figcaption><\/figure>\n<p> <strong>4.<\/strong> <strong>Le Groenland n&#039;a jamais eu d&#039;\u00e9quipe reconnue par la FIFA.<\/strong> C&#039;est parce qu&#039;ils n&#039;y font pas pousser de gazon pour cr\u00e9er des terrains de football.<\/p>\n<p> <strong>5.<\/strong> Au total, 22 Coupes du Monde de la FIFA ont eu lieu entre 1930 et 2022. La Coupe du Monde se d\u00e9roule tous les quatre ans, \u00e0 l&#039;exception de <strong>1942 et 1946, ann\u00e9e o\u00f9 elle fut annul\u00e9e en raison de la Seconde Guerre mondiale.<\/strong><\/p>\n<p> <strong>6.<\/strong> La premi\u00e8re Coupe du monde de la FIFA a eu lieu en Uruguay en <strong>En 1930<\/strong> . Ce match opposait l&#039;Uruguay \u00e0 l&#039;Argentine, et l&#039;Uruguay remporta une victoire impressionnante sur le score de 4-2.<\/p>\n<p> <strong>7.<\/strong> <strong>Jusqu&#039;en 1881, aucun arbitre n&#039;\u00e9tait utilis\u00e9 lors des matchs de football officiels.<\/strong> Jusqu&#039;\u00e0 pr\u00e9sent, les joueurs \u00e9taient responsables de la prise de d\u00e9cisions.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"L&#039;arbitre adresse un avertissement \u00e0 Eric Stevenson. Infos footballistiques.\" width=\"800\" height=\"532\"><figcaption> L&#039;arbitre avertit Erik Stevenson. Image courtoisie de Hayden Schiff. <strong>.<\/strong><\/figcaption><\/figure>\n<p> <strong>8.<\/strong> En 1964, apr\u00e8s qu&#039;un arbitre eut refus\u00e9 un but p\u00e9ruvien lors d&#039;un match de qualification olympique entre l&#039;Argentine et le P\u00e9rou, des \u00e9meutes ont \u00e9clat\u00e9, faisant plus de 300 morts et 500 bless\u00e9s parmi les spectateurs.<\/p>\n<p> <strong>9.<\/strong> En f\u00e9vrier 2011, l&#039;arbitre d&#039;un match du championnat argentin de 5e division entre Victoriano Arenas et Claypole a distribu\u00e9 36 cartons rouges, expulsant du terrain tous les joueurs, rempla\u00e7ants et entra\u00eeneurs.<\/p>\n<p> <strong>10.<\/strong> La popularit\u00e9 du football a augment\u00e9 de fa\u00e7on spectaculaire avec l&#039;av\u00e8nement du colonialisme, <strong>Les Britanniques ont r\u00e9pandu ce jeu dans le monde entier.<\/strong><\/p>\n<p> <strong>11.<\/strong> L&#039;Italie est devenue la premi\u00e8re \u00e9quipe europ\u00e9enne \u00e0 remporter la Coupe du monde de la FIFA. <strong>En 1934<\/strong> , lorsqu&#039;elle a battu les \u00c9tats-Unis 7-1.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"Des petits enfants jouent au football\" width=\"800\" height=\"533\"><figcaption> Photo \u00a9 Stef22<\/figcaption><\/figure>\n<p> <strong>12.<\/strong> Le footballeur italien Giuseppe Meazza a connu un petit incident vestimentaire lorsque son short est tomb\u00e9 lors d&#039;un penalty contre le Br\u00e9sil, son rival, pendant la Coupe du monde. <strong>1938<\/strong> . Il a transform\u00e9 le tir, au grand dam du gardien adverse, assurant ainsi \u00e0 l&#039;Italie une place en finale.<\/p>\n<p> <strong>13.<\/strong> La Coupe du Monde de la FIFA a \u00e9t\u00e9 diffus\u00e9e en direct dans les foyers du monde entier pour la premi\u00e8re fois en <strong>En 1954.<\/strong><\/p>\n<p> <strong>14.<\/strong> Championnat du monde <strong>Le championnat de football a \u00e9t\u00e9 con\u00e7u pour mettre en valeur les meilleurs joueurs de football professionnels du monde.<\/strong> \u00c0 l&#039;\u00e9poque, les Jeux olympiques \u00e9taient r\u00e9serv\u00e9s aux athl\u00e8tes amateurs. Aujourd&#039;hui, la plupart des pays envoient leurs jeunes athl\u00e8tes aux Jeux olympiques tous les quatre ans.<\/p>\n<p> <strong>15.<\/strong> <strong>La premi\u00e8re Coupe du Monde de la FIFA<\/strong> Le tournoi de 1930 fut difficile pour les pays europ\u00e9ens. Il se d\u00e9roula en Uruguay et seuls la France, la Roumanie, la Belgique et la Yougoslavie y particip\u00e8rent.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"Supporters uruguayens lors d&#039;un match de football\" width=\"800\" height=\"519\"><figcaption> Supporters uruguayens lors d&#039;un match de football. Source de l&#039;image\u00a0: Global Panorama.<\/figcaption><\/figure>\n<p> <strong>16.<\/strong> L&#039;Uruguay est le seul <strong>un champion du monde qui n&#039;a pas tent\u00e9 de d\u00e9fendre son titre quatre ans plus tard.<\/strong> Ils refus\u00e8rent de participer \u00e0 la Coupe du monde de 1934, organis\u00e9e en Italie. Ce refus fut per\u00e7u comme un acte de snobisme et une vengeance contre l&#039;Italie, car ils avaient refus\u00e9 de se rendre en Uruguay quatre ans auparavant.<\/p>\n<p> <strong>17.<\/strong> L&#039;Uruguay n&#039;a remport\u00e9 de m\u00e9dailles d&#039;or olympiques en football qu&#039;en 1924 et 1928 \u2013 elle n&#039;en a plus remport\u00e9 depuis.<\/p>\n<p> <strong>18.<\/strong> Un match au Congo en 1998 s&#039;est termin\u00e9 en trag\u00e9die : <strong>La foudre a an\u00e9anti toute l&#039;\u00e9quipe.<\/strong> Les adversaires sont rest\u00e9s indemnes.<\/p>\n<p> <strong>19.<\/strong> \u00abLa \u00bb Guerre des Cent Heures \u00ab, ou \u00bb Guerre du Football \u00bb, de 1969, fut un conflit \u00e9clair entre le Honduras et le Salvador. Les combats \u00e9clat\u00e8rent apr\u00e8s la victoire du Honduras sur le Salvador lors d&#039;un match de qualification pour la Coupe du monde au Mexique.<\/p>\n<p> <strong>20.<\/strong> Football <strong>Il a fait ses d\u00e9buts \u00e0 la t\u00e9l\u00e9vision en 1937.,<\/strong> lorsqu&#039;un match impliquant Arsenal a eu lieu en Angleterre. Il s&#039;agissait d&#039;un match d&#039;entra\u00eenement des joueurs du club.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"stade de football\" width=\"800\" height=\"532\"><figcaption> Photo \u00a9 La Fabrika Pixel Sl<\/figcaption><\/figure>\n<p> <strong>21.<\/strong> <strong>Le record du nombre de supporters assistant \u00e0 un seul match de football a \u00e9t\u00e9 \u00e9tabli en 1950.<\/strong> \u00c0 Rio de Janeiro, 199 854 personnes ont assist\u00e9 au match Br\u00e9sil-Uruguay de la Coupe du monde.<\/p>\n<p> <strong>22.<\/strong> Plus de 81 millions de Islandais se sont rendus en France pour assister au match de leur \u00e9quipe nationale en quarts de finale du Championnat d&#039;Europe de football 2016.<\/p>\n<p> <strong>23.<\/strong> <strong>En 1958<\/strong> Trois nouvelles \u00e9quipes se sont qualifi\u00e9es pour la Coupe du Monde de la FIFA\u00a0: le Pays de Galles, l\u2019Irlande du Nord et l\u2019Union sovi\u00e9tique. C\u2019\u00e9tait la premi\u00e8re (et unique) fois que les quatre nations de Grande-Bretagne (Angleterre, Irlande, \u00c9cosse et Pays de Galles) se qualifiaient pour la Coupe du Monde.<\/p>\n<p> <strong>24.<\/strong> Coupe du Monde de la FIFA <strong>1962<\/strong> Le match fut rapidement surnomm\u00e9 la \u00ab Bataille de Santiago \u00bb suite \u00e0 un incident entre le Chili, pays h\u00f4te, et l&#039;Italie. Apr\u00e8s l&#039;expulsion de deux joueurs, des violences ont \u00e9clat\u00e9 sur le terrain. En cons\u00e9quence, les cartons jaunes et rouges ont \u00e9t\u00e9 introduits.<\/p>\n<p> <strong>25.<\/strong> La Coupe du Monde de la FIFA \u00e9tait <strong>vol\u00e9<\/strong> \u0432 <strong>En 1966,<\/strong> Quelques jours avant la finale, il a \u00e9t\u00e9 retrouv\u00e9 par un chien nomm\u00e9 Pickles et ramen\u00e9 \u00e0 l&#039;exposition du Westminster Central Hall.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"joueurs de football\" width=\"800\" height=\"499\"><figcaption> Photo \u00a9 Galina Barskaya<\/figcaption><\/figure>\n<p> <strong>26.<\/strong> Lee Todd est officiellement le propri\u00e9taire <strong>Record du carton rouge le plus rapide de l&#039;histoire du football.<\/strong> Il jouait pour Cross Park Farm Celtic lorsqu&#039;il a prof\u00e9r\u00e9 un juron deux secondes apr\u00e8s le coup d&#039;envoi. Il a re\u00e7u un carton rouge pour avoir dit\u00a0: \u00ab\u00a0Putain, c&#039;\u00e9tait bruyant\u00a0!\u00a0\u00bb apr\u00e8s le coup de sifflet final.<\/p>\n<p> <strong>27.<\/strong> La Norv\u00e8ge n&#039;est peut-\u00eatre pas consid\u00e9r\u00e9e comme le meilleur pays pour r\u00e9ussir dans le football, mais elle l&#039;est. <strong>la seule \u00e9quipe de football qui n&#039;a jamais perdu<\/strong> Le Br\u00e9sil en comp\u00e9titions internationales. Ils comptent deux victoires et deux nuls face \u00e0 cette solide \u00e9quipe.<\/p>\n<p> <strong>28.<\/strong> La FIFA regroupe 211 pays, r\u00e9gions et \u00c9tats membres r\u00e9partis sur six continents\u00a0: Europe, Afrique, Asie, Am\u00e9rique du Sud, Am\u00e9rique du Nord, Australie et Oc\u00e9anie. L\u2019ONU, quant \u00e0 elle, n\u2019en reconna\u00eet actuellement que 203.<\/p>\n<p> <strong>29.<\/strong> En 2014, l&#039;Allemagne a remport\u00e9 la Coupe du monde de la FIFA en tant que pays unifi\u00e9 pour la premi\u00e8re fois. L&#039;Allemagne de l&#039;Ouest avait remport\u00e9 les trois titres pr\u00e9c\u00e9dents.<\/p>\n<p> <strong>30.<\/strong> Autre fait \u00e9tonnant concernant le football\u00a0: environ neuf mois apr\u00e8s la Coupe du monde 2006 organis\u00e9e en Allemagne, <strong>un baby-boom d&#039;environ 30%.<\/strong> De nombreux autres pays ont \u00e9galement constat\u00e9 une hausse de leur taux de natalit\u00e9 apr\u00e8s avoir accueilli (et remport\u00e9) la Coupe du monde, mais pas de mani\u00e8re aussi significative qu&#039;en Allemagne.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"Des enfants qui sourient ensemble. Des faits int\u00e9ressants sur le football.\" width=\"800\" height=\"601\"><figcaption> Image reproduite avec l&#039;aimable autorisation de jess2284. Faits int\u00e9ressants sur le football.<\/figcaption><\/figure>\n<p> <strong>31.<\/strong> <strong>Le syst\u00e8me de football anglais compte plus de 5 000 \u00e9quipes.,<\/strong> Le championnat est divis\u00e9 en diff\u00e9rentes divisions selon le niveau de jeu. Toute \u00e9quipe peut acc\u00e9der \u00e0 la premi\u00e8re division, la Premier League, en remportant des matchs et en montant de division.<\/p>\n<p> <strong>32.<\/strong> Champ <strong>Les joueurs parcourent entre 8 et 16 kilom\u00e8tres par match.<\/strong> La plus grande diff\u00e9rence de distance d\u00e9pend de la vitesse du jeu et du poste occup\u00e9 par le joueur.<\/p>\n<p> <strong>33.<\/strong> Une \u00e9quipe de football compte 11 joueurs\u00a0: un attaquant, un avant-centre, un ailier, des milieux de terrain (offensif, d\u00e9fensif et central), un lat\u00e9ral, un d\u00e9fenseur central, un lib\u00e9ro et un gardien de but.<\/p>\n<p> <strong>34.<\/strong> Les gardiens de but ont commenc\u00e9 \u00e0 les porter pour la premi\u00e8re fois. <strong>T-shirts multicolores en 1913,<\/strong> pour aider les arbitres \u00e0 prendre les bonnes d\u00e9cisions pendant le match.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"Maillots de football. Informations sur le football.\" width=\"800\" height=\"450\"><figcaption> Maillots de football. Source de l&#039;image\u00a0: a 1 ucard<\/figcaption><\/figure>\n<p> <strong>35.<\/strong> Andr\u00e9s Escobar a marqu\u00e9 un but contre son camp pour la Colombie lors de la Coupe du monde de 1994. <strong>Il fut tu\u00e9 dix jours plus tard.<\/strong> Un supporter en col\u00e8re \u00e0 cause de son erreur, ce qui en fait l&#039;un des plus grands scandales de l&#039;histoire de la Coupe du monde.<\/p>\n<p> <strong>36.<\/strong> Au cours des derniers championnats du monde, environ <strong>La moiti\u00e9 de la population mondiale a regard\u00e9 le match ou \u00e9cout\u00e9 sa retransmission.<\/strong><\/p>\n<p> <strong>37.<\/strong> <strong>Le joueur le plus \u00e2g\u00e9 de l&#039;histoire de la Coupe du monde est le gardien de but \u00e9gyptien Essam El Hadary.<\/strong> . Il n&#039;a jou\u00e9 pour le club que sporadiquement pendant la phase de groupes.<\/p>\n<p> <strong>38.<\/strong> Lors de la Coupe du monde de la FIFA 1982, le capitaine et gardien de but italien Dino Zoff est devenu le capitaine le plus \u00e2g\u00e9 \u00e0 remporter la Coupe du monde de la FIFA, \u00e0 l&#039;\u00e2ge de 40 ans.<\/p>\n<p> <strong>39.<\/strong> Oleg Salenko, originaire de Russie, est <strong>D\u00e9tenteur du record du nombre de buts marqu\u00e9s lors d&#039;un seul match de Coupe du monde.<\/strong> Lors du match contre le Cameroun, il a marqu\u00e9 5 buts.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"Un gardien de but de football arr\u00eate le ballon. Informations sur le football.\" width=\"800\" height=\"557\"><figcaption> Photo \u00a9 Cosmin Iftode<\/figcaption><\/figure>\n<h3> Meilleurs buteurs de la Coupe du Monde de la FIFA<\/h3>\n<table>\n<tbody>\n<thead>\n<tr>\n<th> Nom du joueur<\/th>\n<th> Pays<\/th>\n<th> Nombre de t\u00eates<\/th>\n<th> Matchs jou\u00e9s<\/th>\n<\/tr>\n<\/thead>\n<\/tbody>\n<tbody>\n<tr>\n<td> Miroslav Klose<\/td>\n<td> Allemagne<\/td>\n<td> 16<\/td>\n<td> 24<\/td>\n<\/tr>\n<tr>\n<td> Ronaldo<\/td>\n<td> Br\u00e9sil<\/td>\n<td> 15<\/td>\n<td> 19<\/td>\n<\/tr>\n<tr>\n<td> Gerd M\u00fcller<\/td>\n<td> Allemagne de l&#039;Ouest<\/td>\n<td> 14<\/td>\n<td> 13<\/td>\n<\/tr>\n<tr>\n<td> Lionel Messi<\/td>\n<td> Argentine<\/td>\n<td> 13<\/td>\n<td> 26<\/td>\n<\/tr>\n<tr>\n<td> Just Fontaine<\/td>\n<td> France<\/td>\n<td> 13<\/td>\n<td> 6<\/td>\n<\/tr>\n<tr>\n<td> Pel\u00e9<\/td>\n<td> Br\u00e9sil<\/td>\n<td> 12<\/td>\n<td> 14<\/td>\n<\/tr>\n<tr>\n<td> Le tableau a \u00e9t\u00e9 mis \u00e0 jour pour la derni\u00e8re fois.<\/td>\n<td> 12.06.2023<\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p> <strong>40.<\/strong> Les prolongations ont longtemps \u00e9t\u00e9 un indicateur de temps controvers\u00e9 et myst\u00e9rieux dans les matchs de football. <strong>C&#039;est le juge qui en d\u00e9cide.,<\/strong> Elle dure g\u00e9n\u00e9ralement de 1 \u00e0 5 minutes. La dur\u00e9e exacte des prolongations n&#039;est jamais annonc\u00e9e officiellement, car elle d\u00e9pend de la d\u00e9cision de l&#039;arbitre.<\/p>\n<p> <strong>41.<\/strong> Cristiano Ronaldo, qui joue pour l&#039;\u00e9quipe nationale portugaise, d\u00e9tient le record du plus grand nombre de buts marqu\u00e9s en matchs internationaux de football, avec 122 buts en 198 matchs.<\/p>\n<p> <strong>42.<\/strong> Cristiano Ronaldo est <strong>Le seul footballeur connu de l&#039;histoire du football professionnel \u00e0 avoir marqu\u00e9 un but \u00e0 chaque minute d&#039;un match.<\/strong> \u00c0 un moment de sa carri\u00e8re, il marquait des buts de la premi\u00e8re \u00e0 la 90e minute.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"La Coupe du Monde de la FIFA et le ballon de football Adidas. Informations sur le football.\" width=\"800\" height=\"533\"><figcaption> La Coupe du Monde de la FIFA et un ballon de football Adidas. Photo : Maria Butd.<\/figcaption><\/figure>\n<p> <strong>43.<\/strong> Mexico et Rio de Janeiro - <strong>les deux seules villes \u00e0 avoir accueilli plusieurs fois la finale de la Coupe du monde de la FIFA.<\/strong><\/p>\n<p> <strong>44.<\/strong> \u00c9quipe des \u00c9tats-Unis <strong>domine la Coupe du monde f\u00e9minine<\/strong> Depuis sa cr\u00e9ation en 1991, ce tournoi a vu s&#039;ajouter huit \u00e9ditions\u00a0: quatre titres remport\u00e9s et une deuxi\u00e8me place obtenue.<\/p>\n<p> <strong>45.<\/strong> <strong>Le transfert le plus cher de l&#039;histoire du football<\/strong> cela s&#039;est produit lorsque le Paris Saint-Germain a pay\u00e9 263 millions de dollars \u00e0 Barcelone pour Neymar Jr.<\/p>\n<p> <strong>46.<\/strong> Lionel Messi - <strong>Le footballeur le mieux pay\u00e9 de tous les temps.<\/strong> Gr\u00e2ce \u00e0 son contrat lucratif avec Barcelone et \u00e0 ses nombreux contrats publicitaires, il gagne r\u00e9guli\u00e8rement plus de 100 millions de dollars par an.<\/p>\n<p> <strong>47.<\/strong> Le record du plus grand nombre de buts marqu\u00e9s par une seule \u00e9quipe lors d&#039;un match de Coupe du Monde de la FIFA est de 10, et ce record appartient \u00e0 la Hongrie. Il a \u00e9t\u00e9 \u00e9tabli lors du match de 1982 opposant la Hongrie au Salvador en Espagne.<\/p>\n<p> <strong>48.<\/strong> Le plus <strong>l\u00e9sion majeure enregistr\u00e9e<\/strong> Le record de buts contre son camp dans l&#039;histoire du football \u00e9tait de 149:0, et tous ont \u00e9t\u00e9 marqu\u00e9s en signe de protestation.<\/p>\n<p> <strong>49.<\/strong> Ricardo Olivera, d&#039;Uruguay, est le d\u00e9tenteur <strong>record du but le plus rapide marqu\u00e9 dans l&#039;histoire du football.<\/strong> En 1998, il est parvenu \u00e0 marquer un but apr\u00e8s seulement 2,8 secondes de jeu.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"Le maillot num\u00e9ro 10 de Leo Messi. Anecdotes footballistiques.\" width=\"769\" height=\"800\"><figcaption> Photo \u00a9 Natursports<\/figcaption><\/figure>\n<p> <strong>50.<\/strong> <strong>Le chiffre 10<\/strong> officieusement consid\u00e9r\u00e9 comme le num\u00e9ro de maillot du meilleur joueur de l&#039;\u00e9quipe.<\/p>\n<p> <strong>51.<\/strong> On pense que <strong>football moderne<\/strong> Tout a commenc\u00e9 avec l&#039;adoption des r\u00e8gles de Cambridge en 1848. Ces r\u00e8gles furent les premi\u00e8res \u00e0 \u00eatre standardis\u00e9es et cr\u00e9\u00e8rent une mani\u00e8re plus uniforme de pratiquer ce sport.<\/p>\n<p> <strong>52.<\/strong> Charles Goodyear a cr\u00e9\u00e9 <strong>Le premier ballon de football fabriqu\u00e9 en caoutchouc vulcanis\u00e9 date de 1855.<\/strong> Au cours des deux d\u00e9cennies suivantes, il a \u00e9t\u00e9 standardis\u00e9, recevant une vessie en caoutchouc gonflable, ainsi que des dimensions et des poids officiels.<\/p>\n<p> <strong>53.<\/strong> L&#039;un des troph\u00e9es les plus convoit\u00e9s de tous les sports, <strong>La Coupe du monde \u00e9tait en papier m\u00e2ch\u00e9 jusqu&#039;en 1950.<\/strong> Les fortes pluies ont n\u00e9cessit\u00e9 la cr\u00e9ation d&#039;un troph\u00e9e plus r\u00e9sistant.<\/p>\n<p> <strong>54.<\/strong> Le joueur le plus \u00e2g\u00e9 de la Coupe du monde de 1950 \u00e9tait Stanley Matthews, un Anglais de 35 ans. Fait remarquable, il continua \u00e0 jouer pour l&#039;Angleterre pendant sept ans avant de prendre sa retraite, devenant ainsi le joueur le plus \u00e2g\u00e9 \u00e0 avoir repr\u00e9sent\u00e9 l&#039;Angleterre.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"Un gar\u00e7on donne un coup de pied dans un ballon de football sur un terrain de sport.\" width=\"800\" height=\"543\"><figcaption> Photo \u00a9 Dusan Kostic<\/figcaption><\/figure>\n<p> <strong>55.<\/strong> <strong>Il n&#039;existe pas de dimensions uniformes pour un terrain de football.<\/strong> Selon le r\u00e8glement de la FIFA, la longueur peut varier de 100 \u00e0 110 m\u00e8tres, et la largeur de 64 \u00e0 75 m\u00e8tres. Certaines ligues \u00e0 travers le monde appliquent des dimensions encore plus strictes.<\/p>\n<p> <strong>56.<\/strong> Les matchs de football internationaux et professionnels durent 105 minutes \u2013 45 minutes par mi-temps avec une pause de 15 minutes entre les deux.<\/p>\n<p> <strong>57.<\/strong> <strong>Le terrain de football est appel\u00e9 \u00ab pitch \u00bb en raison de la pente que pr\u00e9sentent la plupart des terrains.<\/strong> Un terrain de football peut pr\u00e9senter une pente allant jusqu&#039;\u00e0 5\u00b0 d&#039;un bout \u00e0 l&#039;autre, les \u00e9quipes changent donc de place \u00e0 la mi-temps.<\/p>\n<p> <strong>58.<\/strong> Pel\u00e9, l&#039;une des nombreuses superstars br\u00e9siliennes \u00e0 avoir re\u00e7u des surnoms d&#039;un seul mot, <strong>Il a re\u00e7u son surnom parce qu&#039;il avait six orteils \u00e0 chaque pied \u00e0 sa naissance<\/strong> . Le mot \u00ab Pel\u00e9 \u00bb signifie \u00ab six jambes \u00bb en portugais br\u00e9silien.<\/p>\n<p> <strong>59.<\/strong> Le Br\u00e9silien Pel\u00e9 a \u00e9tabli trois records lors de la Coupe du monde de 1958. Il d\u00e9tient les records du plus jeune buteur, du plus jeune auteur d&#039;un tripl\u00e9 et du plus jeune auteur d&#039;un tripl\u00e9 en finale de Coupe du monde \u2013 il n&#039;avait que 17 ans \u00e0 l&#039;\u00e9poque.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"\" alt=\"Pel\u00e9\" width=\"640\" height=\"800\"><figcaption> Pel\u00e9. Photo \u00a9 Jerry Coley<\/figcaption><\/figure>\n<p> <strong>60.<\/strong> Pel\u00e9 - <strong>Le seul joueur \u00e0 avoir soulev\u00e9 la Coupe du monde \u00e0 trois reprises.<\/strong> Il a remport\u00e9 des titres en 1958, 1962 et 1970 avec l&#039;\u00e9quipe nationale br\u00e9silienne.<\/p>\n<p> <strong>61.<\/strong> Le c\u00e9l\u00e8bre joueur de cricket Sir Viv Richard est devenu la seule personne \u00e0 avoir particip\u00e9 \u00e0 la fois \u00e0 la Coupe du monde de cricket et \u00e0 la Coupe du monde de la FIFA, puisqu&#039;il a jou\u00e9 pour Antigua lors de la Coupe du monde de la FIFA de 1974.<\/p>\n<p> <strong>62.<\/strong> \u0412 <strong>En 1978<\/strong> Khemais Labidi n&#039;a jou\u00e9 que deux minutes pour la Tunisie contre le Mexique, devenant ainsi le joueur ayant la carri\u00e8re la plus courte en Coupe du monde. <strong>au football<\/strong> .<\/p>\n<p> <strong>63.<\/strong> Le footballeur nord-irlandais Norman Whiteside est entr\u00e9 dans l&#039;histoire en devenant le plus jeune joueur de l&#039;histoire de la Coupe du monde. <strong>Football FIFA<\/strong> , lorsque son \u00e9quipe a jou\u00e9 contre la Yougoslavie en <strong>En 1982<\/strong> . \u00c0 l&#039;\u00e9poque, Whiteside n&#039;avait que 17 ans.<\/p>\n<p> <strong>\u2026la suite se trouve \u00e0 la page suivante<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Derni\u00e8re mise \u00e0 jour\u00a0: 24 juin 2023, r\u00e9daction. Le football est un sport d\u2019\u00e9quipe o\u00f9 s\u2019affrontent des \u00e9quipes de 11 joueurs. Dans ce sport\u2026<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-163490","post","type-post","status-publish","format-standard","hentry","category-interesnye-fakty"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/163490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=163490"}],"version-history":[{"count":1,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/163490\/revisions"}],"predecessor-version":[{"id":163491,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/163490\/revisions\/163491"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=163490"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=163490"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=163490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}