{"id":17002,"date":"2026-06-07T19:19:25","date_gmt":"2026-06-07T16:19:25","guid":{"rendered":"https:\/\/imgist.ru\/harriet-sperling-narushila-tradicziyu-vybrav-tiaru-dlya-svadby-s-piterom-fillipsom-na-korolevskoj-svadbe-leta\/"},"modified":"2026-08-29T12:18:59","modified_gmt":"2026-08-29T09:18:59","slug":"harriet-sperling-a-rompu-avec-la-tradition-en-choisissant-une-tiare-pour-son-mariage-avec-peter-phillips-lors-du-mariage-royal-cet-ete","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/harriet-sperling-narushila-tradicziyu-vybrav-tiaru-dlya-svadby-s-piterom-fillipsom-na-korolevskoj-svadbe-leta\/","title":{"rendered":"Harriet Spurling a rompu avec la tradition en choisissant un diad\u00e8me pour son mariage avec Peter Phillips lors du mariage royal de cet \u00e9t\u00e9."},"content":{"rendered":"<h3>L&#039;essence<\/h3>\n<ul>\n<li>\n<p> Le 6 juin, des membres de la famille royale sont venus soutenir le fils de la princesse Anne, Peter Phillips, et Harriet Spurling lors de leur mariage \u00e0 l&#039;\u00e9glise All Saints de Kemble.<\/p>\n<\/li>\n<li>\n<p> La mari\u00e9e a rompu avec la tradition en portant le diad\u00e8me de la famille Pragnell, celui-l\u00e0 m\u00eame que le joaillier avait cr\u00e9\u00e9 pour sa magnifique bague de fian\u00e7ailles.<\/p>\n<\/li>\n<li>\n<p> Comme il s&#039;agit du deuxi\u00e8me mariage de Sperling, sa d\u00e9cision de porter un diad\u00e8me a surpris, tout comme le fait qu&#039;elle n&#039;ait pas choisi une pi\u00e8ce de la collection de sa belle-m\u00e8re, la princesse Anne.<\/p>\n<\/li>\n<\/ul>\n<p> Le plus grand mariage royal de l&#039;\u00e9t\u00e9 a eu lieu ce week-end, et la mari\u00e9e, Harriet Spurling, a rompu avec la tradition en portant un diad\u00e8me lors de son mariage avec Peter Phillips, le fils de la princesse Anne. <\/p>\n<p> Harriet Spurling portant le diad\u00e8me de la famille Pragnell. Photo\u00a0: Getty<\/p>\n<p> Non seulement Sperling n&#039;a port\u00e9 aucune tiare de la collection de la princesse Anne lors de son entr\u00e9e dans l&#039;\u00e9glise le 6 juin, mais le fait qu&#039;elle en ait port\u00e9 une est en soi remarquable. Suivant l&#039;exemple de la reine Camilla (alors Camilla Parker Bowles) lors de son mariage avec le roi Charles (alors prince Charles) en 2005, Camilla a choisi de se passer de tiare \u2013 m\u00eame si elle \u00e9pousait le futur roi \u2013 pr\u00e9f\u00e9rant un chapeau blanc pour la c\u00e9r\u00e9monie civile et une coiffe de plumes dor\u00e9es sign\u00e9e Philip Treacy pour la b\u00e9n\u00e9diction religieuse. S&#039;agissant de son second mariage, Camilla a renonc\u00e9 \u00e0 la tiare\u00a0; c&#039;\u00e9tait \u00e9galement le second mariage pour Philip et Sperling.<\/p>\n<p> Lorsqu&#039;Anne \u00e9pousa son second mari, le vice-amiral Sir Timothy Lawrence, en 1992, elle renon\u00e7a \u00e9galement \u00e0 la tiare, comme elle l&#039;avait fait avec sa premi\u00e8re \u00e9pouse, Mark Phillips, en 1973. \u00c0 la place, elle porta des fleurs dans les cheveux pour son second mariage. <\/p>\n<p> Harriet Sperling quitte le lieu de son mariage le 6 juin 2026. Photo : Getty.<\/p>\n<p> Samedi, une c\u00e9r\u00e9monie de mariage priv\u00e9e a eu lieu \u00e0 l&#039;\u00e9glise All Saints de Kemble. Sperling portait le diad\u00e8me familial de Pragnell, le joaillier qui avait cr\u00e9\u00e9 sa bague de fian\u00e7ailles (et qui, de fa\u00e7on touchante, avait \u00e9galement r\u00e9alis\u00e9 celle de la grand-m\u00e8re de Phillips, la reine Elizabeth). Elle portait aussi des boucles d&#039;oreilles Pragnell, une magnifique robe de mari\u00e9e en dentelle sign\u00e9e Emilia Wickstead, des chaussures Jimmy Choo et ses cheveux blonds \u00e9taient coiff\u00e9s en un chignon bas. <\/p>\n<p> Peter Phillips et Harriet Spurling le jour de leur mariage royal, le 6 juin 2026. Photo\u00a0: Getty<\/p>\n<p> Dans la description de la robe fournie \u00e0 la publication <em>InStyle<\/em> , Un repr\u00e9sentant du couple a d\u00e9crit la robe de mari\u00e9e de Sperling comme une \u00ab robe fourreau majestueuse \u00bb avec une tra\u00eene spectaculaire de trois m\u00e8tres, confectionn\u00e9e en cr\u00eape italien et orn\u00e9e de dentelle fran\u00e7aise. Cette robe dos nu \u00e0 encolure carr\u00e9e \u00e9tait dot\u00e9e d&#039;un corsage amovible en dentelle transparente, \u00e0 col montant et manches transparentes. La dentelle, provenant des archives fran\u00e7aises de Sophie Hallett, date du d\u00e9but du XXe si\u00e8cle et est orn\u00e9e de motifs floraux romantiques et de finitions d\u00e9licates.<\/p>\n<p> \u00ab Nous nous sommes mis d&#039;accord sur ce qui devait \u00eatre \u00e0 la fois authentique, traditionnel et moderne \u00bb, a d\u00e9clar\u00e9 le cr\u00e9ateur. <em>Vogue britannique<\/em> . <\/p>\n<p> Harriet Sperling et ses demoiselles d&#039;honneur. Photo : Getty<\/p>\n<p> Emilia Wickstead est la cr\u00e9atrice pr\u00e9f\u00e9r\u00e9e de la princesse de Galles, qui a assist\u00e9 hier au mariage avec son \u00e9poux, le prince William. Parmi les autres membres de la famille royale pr\u00e9sents \u00e0 la c\u00e9r\u00e9monie figuraient le roi et la reine, les princesses B\u00e9atrice, Eug\u00e9nie et Anne, ainsi que la s\u0153ur du mari\u00e9, Zara Tindall, et son \u00e9poux, Mike Tindall.<\/p>\n<p> Sperling, dont le p\u00e8re, Rupert Sanders, est d\u00e9c\u00e9d\u00e9 en 2023, a remont\u00e9 l&#039;all\u00e9e au bras de son fr\u00e8re, Nicholas. Ses demoiselles d&#039;honneur, \u00e9galement v\u00eatues de robes Emilia Wickstead, \u00e9taient sa fille, Georgina Sperling, et les filles de Phillips, Savannah Phillips et Isla Phillips. Toutes trois portaient des boucles d&#039;oreilles Aspinal of London. <\/p>\n<p> Peter Phillips et Harriet Spurling quittent le lieu de leur mariage. Photo\u00a0: Getty<\/p>\n<p> Le choix de Sperling de porter le diad\u00e8me a surpris, selon les informations. <em>Tatler<\/em> , Non seulement parce qu&#039;il s&#039;agit de son second mariage, mais aussi en raison de la nature discr\u00e8te de la mari\u00e9e, selon la publication. Le diad\u00e8me de perles et de diamants ressemble \u00e0 celui qui appartenait \u00e0 Anne et qui figurait sur la photo officielle c\u00e9l\u00e9brant son cinquanti\u00e8me anniversaire en 2000. Le diad\u00e8me Pragnell, bien que ne faisant pas partie de la collection royale, <em>a<\/em> Histoire royale \u2013 elle \u00e9tait pr\u00e9sente aux couronnements du roi George VI et de la reine Elizabeth.<\/p>\n<p> Comme indiqu\u00e9 <em>Le journal The Times<\/em> , Sperling arriva \u00e0 l&#039;\u00e9glise juste avant 13 heures, et la pluie qui avait commenc\u00e9 ce jour-l\u00e0 cessa bri\u00e8vement pour lui permettre d&#039;entrer. Une foule de sympathisants s&#039;\u00e9tait mass\u00e9e devant l&#039;\u00e9glise \u2013 environ 300 personnes, selon les informations disponibles. <em>Le Daily Mail,<\/em> \u00ab Hourra ! \u00bb s\u2019\u00e9cria-t-elle en saluant Sperling, sa fille et ses deux belles-filles qui entraient dans l\u2019\u00e9glise. <\/p>\n<p> Harriet Sperling, 6 juin 2026. Photo : Getty.<\/p>\n<p> Alors que les jeunes mari\u00e9s quittaient l&#039;\u00e9glise pour rejoindre leur voiture, une \u00ab garde d&#039;honneur improvis\u00e9e de parapluies \u00bb s&#039;est form\u00e9e (selon un rapport). <em>Le Daily Mail<\/em> \u00ab\u00a0Ainsi, les mari\u00e9s pourraient sortir relativement au sec pour la s\u00e9ance photo en ext\u00e9rieur\u00a0\u00bb, \u00e9crivait le magazine. Apr\u00e8s avoir pos\u00e9 sous un grand parasol blanc, Phillips et Sperling ont salu\u00e9 la foule avant de descendre dans une Rolls-Royce d&#039;\u00e9poque et de se rendre \u00e0 la r\u00e9ception de mariage au domaine de Gatcombe Park, propri\u00e9t\u00e9 de la princesse Anne.<\/p>\n<p> \u00c0 propos de la robe de mari\u00e9e de Sperling, le styliste Orion Robb a d\u00e9clar\u00e9 au magazine <em>Bonjour!:<\/em> \u00ab On observe des parall\u00e8les subtils entre la robe de la princesse de Galles et le choix de la robe d&#039;Emilia Wickstead, ainsi que la recherche d&#039;une \u00e9l\u00e9gance intemporelle. \u00bb.<\/p>\n<p> \u00ab Plut\u00f4t que de suivre les tendances \u00e9ph\u00e9m\u00e8res en mati\u00e8re de mariage, Harriet a opt\u00e9 pour un style empreint de savoir-faire, de raffinement et de tradition \u00bb, a poursuivi Robb. \u00ab L\u2019ajout du diad\u00e8me de la famille Pragnell conf\u00e8re \u00e0 l\u2019ensemble une touche \u00e0 la fois profond\u00e9ment personnelle et d\u2019une \u00e9l\u00e9gance royale. \u00bb. <\/p>\n<p> Peter Phillips et Harriet Spurling s&#039;embrassent le jour de leur mariage royal. Photo\u00a0: Getty<\/p>\n<p> \u00ab Ce qui me frappe le plus, c&#039;est son naturel \u00bb, a ajout\u00e9 Robb. \u00ab La robe est incontestablement magnifique, mais elle la porte avec une telle gr\u00e2ce et une telle aisance que l&#039;ensemble d\u00e9gage une impression intemporelle plut\u00f4t que formelle. C&#039;est un parfait exemple de la fa\u00e7on dont la confiance et l&#039;\u00e9l\u00e9gance vont de pair. Pour moi, le plus beau dans cette tenue, c&#039;est qu&#039;on la remarque avant m\u00eame de voir la robe. La robe, les bijoux et le diad\u00e8me sont exquis, mais ils ne l&#039;\u00e9clipsent jamais. Elle para\u00eet sereine, gracieuse et rayonnante de bonheur, et c&#039;est ce qui, en fin de compte, rend une tenue de mariage inoubliable. \u00bb.<\/p>\n<p> Lisez l&#039;article original sur InStyle.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le 6 juin, des membres de la famille royale sont venus soutenir le fils de la princesse Anne, Peter Phillips, et Harriet Spurling lors de leur mariage \u00e0 l&#039;\u00e9glise All Saints de Kemble\u2026.<\/p>","protected":false},"author":1,"featured_media":17003,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-17002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selebriti","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/17002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=17002"}],"version-history":[{"count":7,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/17002\/revisions"}],"predecessor-version":[{"id":160496,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/17002\/revisions\/160496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/17003"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=17002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=17002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=17002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}