{"id":18049,"date":"2026-06-10T21:14:46","date_gmt":"2026-06-10T18:14:46","guid":{"rendered":"https:\/\/imgist.ru\/kimberli-shlapman-delitsya-dusherazdirayushhej-istoriej-borby-svoej-materi-s-boleznyu-parkinsona\/"},"modified":"2026-08-25T12:05:38","modified_gmt":"2026-08-25T09:05:38","slug":"kimberly-schlapman-partage-lhistoire-dechirante-du-combat-de-sa-mere-contre-la-maladie-de-parkinson","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/kimberli-shlapman-delitsya-dusherazdirayushhej-istoriej-borby-svoej-materi-s-boleznyu-parkinsona\/","title":{"rendered":"Kimberly Schlapman partage l&#039;histoire d\u00e9chirante du combat de sa m\u00e8re contre la maladie de Parkinson."},"content":{"rendered":"<p>Plus de deux d\u00e9cennies <strong>Kimberly Schlapman<\/strong> Voir la maladie de Parkinson transformer peu \u00e0 peu la femme qu&#039;elle a toujours connue comme \u00ab\u00a0Maman\u00a0\u00bb. La chanteuse de Little Big Town, dont la m\u00e8re est malade depuis 21 ans, se confie aujourd&#039;hui sur la r\u00e9alit\u00e9 \u00e9motionnelle de prendre soin d&#039;une personne encore vivante, jonglant entre son r\u00f4le de m\u00e8re, une carri\u00e8re exigeante et le deuil. Dans une interview exclusive accord\u00e9e \u00e0 The Blast, Kimberly Schlapman \u00e9voque la douleur, la culpabilit\u00e9 et la r\u00e9silience qui accompagnent le soutien apport\u00e9 \u00e0 un parent atteint de cette maladie \u00e9volutive, ainsi que sa collaboration avec la campagne \u00ab\u00a0Changer la perception de la maladie de Parkinson\u00a0\u00bb d&#039;AbbVie, visant \u00e0 aider les familles \u00e0 se sentir moins isol\u00e9es.<\/p>\n<p> Kimberly Schlapman affirme que la maladie de Parkinson de sa m\u00e8re a \u00ab compl\u00e8tement pris le dessus \u00bb. <\/p>\n<figure><figcaption> Xavier Collin\/Image Press Agency \/ MEGA<\/figcaption><\/figure>\n<p> Lorsque la m\u00e8re de Shlapman a re\u00e7u un diagnostic de maladie de Parkinson il y a plus de vingt ans, la star de la country a admis que sa famille ignorait presque tout de ce que ce diagnostic impliquait r\u00e9ellement. \u00ab \u00c0 l&#039;\u00e9poque, nous ne connaissions que la maladie de Parkinson \u00bb, a d\u00e9clar\u00e9 Shlapman \u00e0 The Blast, expliquant que les sympt\u00f4mes de sa m\u00e8re \u00e9taient initialement relativement l\u00e9gers.<\/p>\n<p> Pendant de nombreuses ann\u00e9es, la vie a suivi son cours relativement normalement. Mais il y a environ huit ans, tout a commenc\u00e9 \u00e0 changer d&#039;une mani\u00e8re que la famille ne pouvait plus ignorer. \u00ab Nous sommes entr\u00e9s dans une nouvelle phase de la maladie de Parkinson, qui a commenc\u00e9 \u00e0 affecter son quotidien \u00bb, a-t-elle confi\u00e9, ajoutant que la maladie avait d\u00e9sormais envahi toute la famille. \u00ab Nous pensons constamment \u00e0 elle, et elle a besoin de soins permanents. \u00bb.<\/p>\n<p> La chanteuse a expliqu\u00e9 qu&#039;assister \u00e0 la progression de la maladie \u00e9tait terrifiant, d&#039;autant plus que la maladie de Parkinson se manifeste diff\u00e9remment chez chaque personne. Ce qui avait commenc\u00e9 par des tremblements occasionnels a fini par \u00e9voluer en une affection qui affecte presque tous les aspects de la vie de sa m\u00e8re.<\/p>\n<h2> La star de Little Big Town jongle entre la garde d&#039;enfants, la maternit\u00e9 et sa carri\u00e8re.<\/h2>\n<figure><figcaption> Ozzie B\/imageSPACE \/ MEGA<\/figcaption><\/figure>\n<p> Bien que Shlapman soit connue pour ses prestations sc\u00e9niques internationales avec le groupe Little Big Town, elle doit en coulisses jongler avec des responsabilit\u00e9s que beaucoup de femmes connaissent bien. \u00c9pouse, m\u00e8re, artiste et fille aidant un parent \u00e2g\u00e9, Shlapman confie que trouver cet \u00e9quilibre rel\u00e8ve souvent de la survie.<\/p>\n<p> \u00ab Ma famille est tr\u00e8s unie \u00bb, a-t-elle expliqu\u00e9, pr\u00e9cisant que ses deux fr\u00e8res et s\u0153urs participent activement aux soins de leur m\u00e8re. \u00ab Nous sommes tous tr\u00e8s impliqu\u00e9s dans ses soins. \u00bb.<\/p>\n<p> Maintenir ce soutien tout en \u00e9tant en tourn\u00e9e n&#039;est pas chose facile. \u00ab Je voyage beaucoup \u00bb, explique Shlapman. \u00ab Quand je suis chez moi, j&#039;essaie de rendre visite \u00e0 ma m\u00e8re pour l&#039;aider \u00e0 prendre soin d&#039;elle. \u00bb Elle ajoute qu&#039;elle emm\u00e8ne souvent ses enfants en voyage, et que son mari se joint parfois \u00e0 elle, soulignant que l&#039;\u00e9quilibre entre vie professionnelle et vie personnelle est une n\u00e9cessit\u00e9 que beaucoup de m\u00e8res actives connaissent bien.<\/p>\n<p> \u00ab Comme toutes les mamans et les femmes qui travaillent dur, nous essayons simplement de faire notre travail \u00bb, a-t-elle poursuivi.<\/p>\n<h2> Kimberly Schlapman exhorte les aidants \u00e0 cesser de souffrir en silence.<\/h2>\n<figure><figcaption> MBS\/MEGA<\/figcaption><\/figure>\n<p> Selon Shlapman, l&#039;une des principales raisons pour lesquelles elle souhaitait parler publiquement de la maladie de Parkinson est que les aidants sont rarement inclus dans le d\u00e9bat public \u00e0 ce sujet. \u00ab\u00a0Lorsque nous avons entam\u00e9 cette phase de prise en charge de ma m\u00e8re, je n&#039;avais jamais entendu personne en parler\u00a0\u00bb, a-t-elle confi\u00e9. \u00ab\u00a0Et cela me d\u00e9sole, car c&#039;est tellement difficile et cela demande \u00e9norm\u00e9ment d&#039;\u00e9nergie et d&#039;\u00e9motions.\u00a0\u00bb.<\/p>\n<p> Shlapman se souvient avoir vu sa propre m\u00e8re prendre soin de sa grand-m\u00e8re en silence pendant son combat contre le cancer du sein, sans jamais \u00e9voquer ouvertement le poids \u00e9motionnel de cette \u00e9preuve. Aujourd&#039;hui, elle esp\u00e8re que sa g\u00e9n\u00e9ration changera cela.<\/p>\n<p> \u00ab Je pense qu&#039;il est vraiment important de garder le contact et de partager ce que nous vivons \u00bb, a-t-elle d\u00e9clar\u00e9, encourageant les aidants \u00e0 ne pas h\u00e9siter \u00e0 demander du soutien aux autres dans les moments difficiles. \u00ab C&#039;est difficile, c&#039;est triste, et cela suscite tellement d&#039;\u00e9motions. \u00bb.<\/p>\n<p> Elle a \u00e9galement soulign\u00e9 l&#039;importance pour les aidants d&#039;avoir une personne de confiance absolue. \u00ab\u00a0Il est primordial d&#039;avoir quelqu&#039;un en qui l&#039;on peut avoir une confiance totale et \u00e0 qui se confier\u00a0\u00bb, a expliqu\u00e9 Shlapman. \u00ab\u00a0Quelqu&#039;un \u00e0 qui l&#039;on peut se confier sans h\u00e9siter\u2026 car cela permet de prendre soin de soi pour pouvoir prendre soin de la personne aim\u00e9e.\u00a0\u00bb.<\/p>\n<h2> Pourquoi Schlapman s&#039;est associ\u00e9 \u00e0 la campagne d&#039;AbbVie contre la maladie de Parkinson<\/h2>\n<blockquote><p> Publication partag\u00e9e par Kimberly Schlapman (@ohgussie)<\/p><\/blockquote>\n<p> Shlapman a confi\u00e9 que sa participation \u00e0 la campagne \u00ab\u00a0Changer les mentalit\u00e9s face \u00e0 la maladie de Parkinson\u00a0\u00bb d&#039;AbbVie lui tenait particuli\u00e8rement \u00e0 c\u0153ur, car elle encourage les familles \u00e0 plaider en faveur de traitements personnalis\u00e9s. Elle a soulign\u00e9 que les sympt\u00f4mes de la maladie de Parkinson peuvent varier consid\u00e9rablement d&#039;une personne \u00e0 l&#039;autre, rendant ainsi une communication ouverte avec les m\u00e9decins essentielle. \u00ab\u00a0Aucun sympt\u00f4me n&#039;est trop insignifiant pour \u00eatre ignor\u00e9\u00a0\u00bb, a-t-elle d\u00e9clar\u00e9 \u00e0 The Blast. \u00ab\u00a0M\u00eame si vous pensez que ce n&#039;est absolument pas li\u00e9 \u00e0 la maladie de Parkinson, cela pourrait tr\u00e8s bien l&#039;\u00eatre.\u00a0\u00bb.<\/p>\n<p> Avec le recul, Shlapman regrette que sa famille ne se soit pas renseign\u00e9e plus t\u00f4t sur la maladie, apr\u00e8s le diagnostic de sa m\u00e8re. Elle encourage \u00e9galement les familles r\u00e9cemment diagnostiqu\u00e9es \u00e0 envisager sans tarder des changements de mode de vie susceptibles d&#039;am\u00e9liorer leur qualit\u00e9 de vie, notamment l&#039;exercice physique et les activit\u00e9s cardiovasculaires. Bien que le parcours de chaque personne atteinte de la maladie de Parkinson soit unique, Shlapman affirme qu&#039;une meilleure compr\u00e9hension de la maladie au d\u00e9but permet aux familles d&#039;\u00eatre mieux pr\u00e9par\u00e9es \u00e0 l&#039;avenir.<\/p>\n<h2> Kimberly Schlapman confie que la musique a \u00e9t\u00e9 une source de r\u00e9confort pour elle, mais que le deuil a \u00e9t\u00e9 la chose la plus difficile qu&#039;elle ait eu \u00e0 endurer.<\/h2>\n<figure><figcaption> Xavier Collin\/Image Press Agency \/ MEGA<\/figcaption><\/figure>\n<p> Musicienne de profession, Shlapman conna\u00eet bien le pouvoir apaisant de la musique et confie qu&#039;elle est devenue un outil pr\u00e9cieux pour sa famille lors des moments difficiles. \u00ab Si elle passe une mauvaise journ\u00e9e, on l&#039;installe dans un fauteuil et on \u00e9coute de la musique douce pour la calmer \u00bb, explique Shlapman \u00e0 propos de sa m\u00e8re. \u00ab \u00c7a la d\u00e9tend. \u00bb.<\/p>\n<p> Sa s\u0153ur, musicoth\u00e9rapeute, l&#039;a \u00e9galement aid\u00e9e \u00e0 mettre en place des techniques pour r\u00e9conforter sa m\u00e8re dans les moments difficiles. Mais malgr\u00e9 ce soutien, Shlapman a reconnu qu&#039;il existe une r\u00e9alit\u00e9 douloureuse de la maladie de Parkinson \u00e0 laquelle personne ne l&#039;avait vraiment pr\u00e9par\u00e9e\u00a0: le deuil. \u00ab\u00a0Je savais que je devrais vivre sans mes parents un jour\u00a0\u00bb, a-t-elle d\u00e9clar\u00e9. \u00ab\u00a0Mais faire le deuil de ma m\u00e8re, de celle qu&#039;elle a toujours \u00e9t\u00e9, et de ce que cette maladie lui a fait subir\u2026\u00a0\u00bb<\/p>\n<p> Pour Shlapman, s&#039;accorder le temps d&#039;assimiler cette douleur \u00e9motionnelle est devenu essentiel dans son r\u00f4le d&#039;aidante. \u00ab Je pense que me permettre de faire mon deuil \u00e9tait vraiment important \u00bb, a-t-elle confi\u00e9, rappelant que parfois, la perte commence bien avant les adieux.<\/p>","protected":false},"excerpt":{"rendered":"<p>Depuis plus de vingt ans, Kimberly Schlapman voit la maladie de Parkinson transformer peu \u00e0 peu la femme qu&#039;elle a toujours connue comme \u00ab\u00a0Maman\u00a0\u00bb. La chanteuse de Little Big Town, dont\u2026<\/p>","protected":false},"author":1,"featured_media":18050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-18049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selebriti","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/18049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=18049"}],"version-history":[{"count":4,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/18049\/revisions"}],"predecessor-version":[{"id":142424,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/18049\/revisions\/142424"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/18050"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=18049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=18049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=18049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}