{"id":26705,"date":"2019-10-17T00:00:00","date_gmt":"2019-10-16T22:00:00","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira\/"},"modified":"2019-10-17T00:00:00","modified_gmt":"2019-10-16T22:00:00","slug":"les-10-musees-et-chateaux-les-plus-effrayants-du-monde","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira\/","title":{"rendered":"10 des mus\u00e9es et ch\u00e2teaux les plus effrayants du monde"},"content":{"rendered":"<div>\n<p>L&#039;histoire de l&#039;humanit\u00e9, h\u00e9las, est jalonn\u00e9e d&#039;actes de cruaut\u00e9 fr\u00f4lant la barbarie. Et malgr\u00e9 tous nos discours sur l&#039;humanit\u00e9 et la justice, des actes de violence sont commis sur Terre \u00e0 chaque instant.<\/p>\n<p>On peut \u00e9tablir d&#039;innombrables listes et classements sur les manifestations de la cruaut\u00e9 humaine. L&#039;un de ces classements est le top 10 des plus terrifiantes. <a href=\"https:\/\/imgist.ru\/fr\/10-villes-antiques-et-musees-a-visiter-la-nuit-en-ete\/\">mus\u00e9es<\/a> \u0438 <a href=\"https:\/\/imgist.ru\/fr\/42-samyx-drevnix-et-prekrasnyx-zamkov-contre-mire\/\">ch\u00e2teaux du monde<\/a>.<br \/>\n<span id=\"more-132\"><\/span><\/p>\n<h2><span id=\"10_%D0%97%D0%B0%D0%BC%D0%BE%D0%BA_%D0%A3%D0%B6%D0%B0%D1%81%D0%BE%D0%B2_%D0%9B%D0%BE%D0%BD%D0%B4%D0%BE%D0%BD%D1%81%D0%BA%D0%B0%D1%8F_%D1%82%D0%B5%D0%BC%D0%BD%D0%B8%D1%86%D0%B0_%D0%B2_%D0%90%D0%BD%D0%B3%D0%BB%D0%B8%D0%B8\" class=\"ez-toc-section\"><\/span>10. Castle Horror (London Dungeon) en Angleterre<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"q1yzun2o\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f7820de876c.jpeg\" alt=\"q1yzun2o\" width=\"700\" height=\"480\" border=\"0\" \/><\/p>\n<p><strong>Londres, Angleterre<\/strong><\/p>\n<p>On y trouve un peu de tout\u00a0: une reconstitution de l\u2019incendie de Londres, des chambres et instruments de torture m\u00e9di\u00e9vaux, et divers spectacles \u00e0 vous glacer le sang. Le ch\u00e2teau est construit de fa\u00e7on tr\u00e8s r\u00e9aliste et \u00e9quip\u00e9 des technologies les plus r\u00e9centes, permettant par exemple de sentir les odeurs.<\/p>\n<p>La billetterie du mus\u00e9e est ouverte tous les jours de 10h00 (11h00 le jeudi) \u00e0 16h00 (17h00 le samedi), sauf les jours f\u00e9ri\u00e9s o\u00f9 les horaires peuvent \u00eatre modifi\u00e9s. Le prix des billets varie selon la date d&#039;achat et des r\u00e9ductions sont propos\u00e9es aux \u00e9coliers.<\/p>\n<h2><span id=\"9_%D0%9C%D1%83%D0%B7%D0%B5%D0%B9_%D0%93%D0%B8%D0%B3%D0%B8%D0%B5%D0%BD%D1%8B_%D0%B2_%D0%A0%D0%BE%D1%81%D1%81%D0%B8%D0%B8\" class=\"ez-toc-section\"><\/span>9. Mus\u00e9e de l&#039;hygi\u00e8ne en Russie<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"isvru2kj\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f7820e5cd43.jpeg\" alt=\"isvru2kj\" width=\"700\" height=\"467\" border=\"0\" \/><\/p>\n<p><strong>Saint-P\u00e9tersbourg, F\u00e9d\u00e9ration de Russie<\/strong><\/p>\n<p>Les expositions du mus\u00e9e ne suivent pas un th\u00e8me unique\u00a0: on y trouve le chien de Pavlov, des syst\u00e8mes circulatoires dysfonctionnels, un fauteuil de dentiste d&#039;\u00e9poque, et m\u00eame des sp\u00e9cimens de parties g\u00e9nitales illustrant le d\u00e9veloppement progressif des maladies v\u00e9n\u00e9riennes. Chacune, prise individuellement, est d\u00e9plaisante, mais elles forment un spectacle singulier et r\u00e9pugnant.<\/p>\n<p>Horaires d&#039;ouverture du mus\u00e9e\u00a0: tous les jours sauf le dimanche. Entr\u00e9e payante.<\/p>\n<h2><span id=\"8_%D0%9C%D1%83%D0%B7%D0%B5%D0%B9_%D0%BF%D0%B0%D1%82%D0%BE%D0%BB%D0%BE%D0%B3%D0%BE%D0%B0%D0%BD%D0%B0%D1%82%D0%BE%D0%BC%D0%B8%D0%B8_%D0%91%D0%B0%D1%88%D0%BD%D1%8F_%D0%91%D0%B5%D0%B7%D1%83%D0%BC%D0%BD%D1%8B%D1%85_%D0%B2_%D0%90%D0%B2%D1%81%D1%82%D1%80%D0%B8%D0%B8\" class=\"ez-toc-section\"><\/span>8. Le Mus\u00e9e d&#039;anatomie pathologique (Tour des fous) en Autriche<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"bytupins\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f7820edd519.jpeg\" alt=\"bytupins\" width=\"700\" height=\"394\" border=\"0\" \/><\/p>\n<p><strong>Vienne, Autriche<\/strong><\/p>\n<p>Au Moyen \u00c2ge, ce b\u00e2timent servait d&#039;asile d&#039;ali\u00e9n\u00e9s, d&#039;o\u00f9 son surnom de \u00ab\u00a0Tour des Fous\u00a0\u00bb. Les expositions regorgent d&#039;organes et de parties de corps humains, ainsi que de sp\u00e9cimens illustrant des malformations et des maladies v\u00e9n\u00e9riennes. Tout y est pr\u00e9sent\u00e9 comme naturel, ce qui rend le tout extr\u00eamement repoussant.<\/p>\n<p>La tour est ouverte aux visiteurs trois jours par semaine\u00a0: mercredi de 10h00 \u00e0 18h00, jeudi de 10h00 \u00e0 13h00 et samedi de 10h00 \u00e0 13h00. L\u2019entr\u00e9e est payante.<\/p>\n<h2><span id=\"7_%D0%9C%D1%83%D0%B7%D0%B5%D0%B9_%D0%BF%D1%8B%D1%82%D0%BE%D0%BA_%D0%BD%D0%B0_%D0%9C%D0%B0%D0%BB%D1%8C%D1%82%D0%B5\" class=\"ez-toc-section\"><\/span>7. Mus\u00e9e de la torture \u00e0 Malte<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"ffn5bp05\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f7820f6c4eb.jpeg\" alt=\"ffn5bp05\" width=\"700\" height=\"467\" border=\"0\" \/><\/p>\n<p><strong>Mdina, Malte<\/strong><\/p>\n<p>Le mus\u00e9e abrite d&#039;innombrables instruments de torture m\u00e9di\u00e9vaux originaux et des figures de cire qui recr\u00e9ent des sc\u00e8nes r\u00e9alistes des atrocit\u00e9s brutales de l&#039;Inquisition.<\/p>\n<p>Fait int\u00e9ressant, les visiteurs seront accompagn\u00e9s d&#039;un gardien qui fait \u00e9galement partie de l&#039;exposition pendant leur visite de la collection.<\/p>\n<p>Le mus\u00e9e est ouvert tous les jours\u00a0: dim. 9h30\u201316h30, lun.\u2013sam. 10h00\u201316h00. L\u2019entr\u00e9e est payante\u00a0; les \u00e9tudiants b\u00e9n\u00e9ficient d\u2019une r\u00e9duction.<\/p>\n<h2><span id=\"6_%D0%97%D0%B0%D0%BC%D0%BE%D0%BA_%D0%94%D1%80%D0%B0%D0%BA%D1%83%D0%BB%D1%8B_%D0%91%D1%80%D0%B0%D0%BD_%D0%B2_%D0%A0%D1%83%D0%BC%D1%8B%D0%BD%D0%B8%D0%B8\" class=\"ez-toc-section\"><\/span>6. Le ch\u00e2teau de Dracula (Bran) en Roumanie<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"b3v0rmii\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f7820fe8221.jpeg\" alt=\"b3v0rmii\" width=\"700\" height=\"469\" border=\"0\" \/><\/p>\n<p><strong>Transylvanie, Carpates, Roumanie<\/strong><\/p>\n<p>Le ch\u00e2teau, b\u00e2ti au bord d&#039;un pr\u00e9cipice, offre un spectacle terrifiant de style gothique. L&#039;une de ses nombreuses pi\u00e8ces abrite un immense lit o\u00f9, selon la l\u00e9gende, Dracula su\u00e7ait le sang de ses victimes. En r\u00e9alit\u00e9, le comte n&#039;\u00e9tait pas un vampire\u00a0; la l\u00e9gende est n\u00e9e de sa soif de sang envers ses serviteurs. On raconte qu&#039;il empalait les personnes ind\u00e9sirables sur le chemin du ch\u00e2teau, ce qui lui valut le surnom d&#039;\u00ab\u00a0Empaleur\u00a0\u00bb.<\/p>\n<p>Vous pouvez visiter le ch\u00e2teau librement ou avec un guide. Les horaires d&#039;ouverture varient selon la saison, mais il est g\u00e9n\u00e9ralement ouvert tous les jours.<\/p>\n<h2><span id=\"5_%D0%9C%D1%83%D0%B7%D0%B5%D0%B9_%D1%83%D1%81%D0%BE%D0%BF%D1%88%D0%B8%D1%85_%D0%B4%D1%83%D1%88_%D0%98%D1%82%D0%B0%D0%BB%D0%B8%D1%8F\" class=\"ez-toc-section\"><\/span>5. Mus\u00e9e des \u00e2mes d\u00e9funtes, Italie<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"to51mlie\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f782105a9b3.jpeg\" alt=\"to51mlie\" width=\"700\" height=\"477\" border=\"0\" \/><\/p>\n<p><strong>\u00c9glise du Sacr\u00e9-C\u0153ur, Rome, Italie<\/strong><\/p>\n<p>Le mus\u00e9e le plus myst\u00e9rieux du monde se trouve \u00e0 Rome. L&#039;entr\u00e9e est gratuite, mais une autorisation d&#039;un pr\u00eatre est n\u00e9cessaire pour le visiter. Le mus\u00e9e regorge d&#039;objets li\u00e9s aux fant\u00f4mes et pr\u00e9tendant prouver la pr\u00e9sence d&#039;\u00e2mes errantes sur Terre. La photographie est autoris\u00e9e, mais personne n&#039;a encore r\u00e9ussi \u00e0 imprimer les clich\u00e9s.<\/p>\n<p>Vous pouvez visiter l&#039;exposition pendant les heures d&#039;ouverture de l&#039;\u00e9glise, tous les jours de 9h00 \u00e0 12h00 et de 17h00 \u00e0 19h00.<\/p>\n<h2><span id=\"4_%D0%9C%D1%83%D0%B7%D0%B5%D0%B9_%D0%9F%D1%8B%D1%82%D0%BE%D0%BA_%D0%92%D1%80%D0%B0%D1%82%D0%B0_%D0%90%D1%80%D0%B5%D1%81%D1%82%D0%B0%D0%BD%D1%82%D0%BE%D0%B2_%D0%B2_%D0%9D%D0%B8%D0%B4%D0%B5%D1%80%D0%BB%D0%B0%D0%BD%D0%B4%D0%B0%D1%85\" class=\"ez-toc-section\"><\/span>4. Mus\u00e9e de la torture (Porte des prisonniers) aux Pays-Bas<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"xdqpclrz\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f78210db767.jpeg\" alt=\"xdqpclrz\" width=\"700\" height=\"467\" border=\"0\" \/><\/p>\n<p><strong>Bau Tenhof, La Haye, Pays-Bas<\/strong><\/p>\n<p>Ce mus\u00e9e du XIIIe si\u00e8cle, qui servit \u00e0 la fois de prison et de chambre de torture, abrite une collection d&#039;instruments de bourreau absolument terrifiante. Les sc\u00e8nes les plus sanglantes et les tortures les plus brutales y sont expos\u00e9es, et un guide passionn\u00e9 r\u00e9pondra avec \u00e9motion et pr\u00e9cision \u00e0 toutes vos questions sur l&#039;utilisation et le but de ces instruments. L&#039;atmosph\u00e8re du mus\u00e9e est si immersive et r\u00e9aliste que certains touristes s&#039;\u00e9vanouissent.<\/p>\n<p>Il se trouve sur la place principale, pr\u00e8s du c\u00e9l\u00e8bre tribunal international. L&#039;entr\u00e9e est payante et les salles d&#039;audience sont ouvertes jusqu&#039;\u00e0 23h.<\/p>\n<h2><span id=\"3_%D0%97%D0%B0%D0%BC%D0%BE%D0%BA_%D0%AD%D0%BB%D1%8C%D0%BC%D0%B8%D0%BD%D0%B0\" class=\"ez-toc-section\"><\/span>3. Ch\u00e2teau d&#039;Elmina<\/h2>\n<p><strong>Cape Coast (Cabo Corso), Ghana<\/strong><\/p>\n<p>En troisi\u00e8me position se trouve un monument symbolisant la culpabilit\u00e9 de l&#039;homme blanc envers les Noirs\u00a0: le Ghana fut jadis l&#039;un des premiers centres de la traite n\u00e9gri\u00e8re. Une pi\u00e8ce exigu\u00eb, avec une minuscule fen\u00eatre sous le plafond, des cha\u00eenes et un \u00e9troit passage dans le mur \u2013 un passage servant \u00e0 embarquer les esclaves. Et le spectacle le plus gla\u00e7ant\u00a0: un puits o\u00f9 des personnes restaient assises pendant des mois, attendant leur sort.<\/p>\n<p>L&#039;une des ailes du fort abrite un mus\u00e9e pr\u00e9sentant les marchandises que les chefs noirs obtenaient en \u00e9change de leurs hommes\u00a0: armes, bouteilles d&#039;alcool et perles. Le ch\u00e2teau est aujourd&#039;hui inscrit au patrimoine mondial de l&#039;UNESCO.<\/p>\n<p>Le ch\u00e2teau de Cape Coast est ouvert tous les jours de 9h00 \u00e0 16h30 et l&#039;entr\u00e9e est payante.<\/p>\n<h2><span id=\"2_%D0%9C%D1%83%D0%B7%D0%B5%D0%B9_%D0%A7%D0%B5%D1%80%D1%82%D0%B5%D0%B9_%D0%B2_%D0%9B%D0%B8%D1%82%D0%B2%D0%B5\" class=\"ez-toc-section\"><\/span>2. Le mus\u00e9e du diable en Lituanie<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"sdnczkk5\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f782116d4fe.jpeg\" alt=\"sdnczkk5\" width=\"700\" height=\"495\" border=\"0\" \/><\/p>\n<p><strong>Kaunas, Lituanie<\/strong><\/p>\n<p>La deuxi\u00e8me place est revenue au mus\u00e9e, qui abrite pr\u00e8s de 2\u00a0000 repr\u00e9sentations du diable, r\u00e9alis\u00e9es avec un r\u00e9alisme saisissant \u00e0 partir de cuir, de bois, de c\u00e9ramique et d&#039;autres mat\u00e9riaux. Cette collection, la plus importante du genre, comprend la collection personnelle du c\u00e9l\u00e8bre artiste Antanas \u017dmuidzinavi\u010dius. Les pi\u00e8ces sont pr\u00e9sent\u00e9es par th\u00e8mes, selon les m\u00e9thodes de s\u00e9duction du diable. La collection s&#039;agrandit constamment et occupe d\u00e9j\u00e0 trois \u00e9tages.<\/p>\n<p>L&#039;exposition est ouverte\u00a0: du mardi au mercredi, vendredi et dimanche de 11\u00a0h \u00e0 17\u00a0h, le jeudi de 11\u00a0h \u00e0 19\u00a0h, ferm\u00e9e le lundi et le samedi. L&#039;entr\u00e9e est payante, mais gratuite pour les enfants de moins de 7\u00a0ans.<\/p>\n<h2><span id=\"1_%D0%A7%D0%B5%D1%88%D1%81%D0%BA%D0%B8%D0%B9_%D0%BC%D1%83%D0%B7%D0%B5%D0%B9-%D0%BA%D0%BE%D1%81%D1%82%D0%B5%D1%85%D1%80%D0%B0%D0%BD%D0%B8%D0%BB%D0%B8%D1%89%D0%B5_%D0%9A%D0%BE%D1%81%D1%82%D0%BD%D0%B8%D1%86%D0%B5\" class=\"ez-toc-section\"><\/span>1. Mus\u00e9e ossuaire tch\u00e8que de Kostnice<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" title=\"jkj2re1d\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/09\/top-10-samyh-strashnyh-muzeev-i-zamkov-mira_64f78211f1790.jpeg\" alt=\"jkj2re1d\" width=\"700\" height=\"350\" border=\"0\" \/><\/p>\n<p><strong>Sedlec, Kutna Hora, R\u00e9publique tch\u00e8que.<\/strong><\/p>\n<p>Autrefois, le site de ce mus\u00e9e abritait un cimeti\u00e8re et une \u00e9glise. Ce vaste site de 3,5 hectares accueillait principalement les victimes de l&#039;\u00e9pid\u00e9mie de peste du XIVe si\u00e8cle et de la guerre hussite. Apr\u00e8s la fermeture du cimeti\u00e8re, devenu satur\u00e9, tous les squelettes des d\u00e9funts furent entrepos\u00e9s dans la cave de la chapelle plut\u00f4t que d\u00e9truits, dans un souci de r\u00e9tablir l&#039;ordre. Deux si\u00e8cles plus tard, un moine, voulant nettoyer la chapelle, entassa tous les ossements en six pyramides. Trois si\u00e8cles plus tard, le nouveau propri\u00e9taire de la chapelle chargea le ma\u00eetre sculpteur sur bois F. Rint de la d\u00e9corer. Il travailla tous les squelettes et cr\u00e9a un int\u00e9rieur saisissant compos\u00e9 d&#039;ossements humains, soit environ 40\u00a0000 pi\u00e8ces.<\/p>\n<p>L&#039;\u00e9glise-chapelle est ouverte aux visiteurs tous les jours, du matin au soir.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>L&#039;histoire de l&#039;humanit\u00e9, h\u00e9las, est riche en exemples de cruaut\u00e9 fr\u00f4lant la barbarie. Et peu importe combien nous proclamons l&#039;humanit\u00e9 et la justice, chaque instant sur Terre\u2026<\/p>","protected":false},"author":1,"featured_media":26706,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-26705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/26705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=26705"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/26705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/26706"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=26705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=26705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=26705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}