{"id":302,"date":"2026-05-29T17:31:46","date_gmt":"2026-05-29T14:31:46","guid":{"rendered":"https:\/\/imgist.ru\/19-serialov-kotorye-nachinalis-mnogoobeshhayushhe-no-potom-stali-sovershenno-nesmotribelnymi\/"},"modified":"2026-08-24T14:23:33","modified_gmt":"2026-08-24T11:23:33","slug":"19-series-televisees-qui-avaient-commence-de-maniere-prometteuse-mais-qui-sont-ensuite-devenues-totalement-insupportables-a-regarder","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/19-serialov-kotorye-nachinalis-mnogoobeshhayushhe-no-potom-stali-sovershenno-nesmotribelnymi\/","title":{"rendered":"19 s\u00e9ries t\u00e9l\u00e9vis\u00e9es qui avaient commenc\u00e9 de fa\u00e7on prometteuse mais qui sont devenues par la suite totalement insupportables."},"content":{"rendered":"<p>Avertissement : Ce texte mentionne le viol et les agressions sexuelles.<\/p>\n<h2> En mati\u00e8re de culture pop, rien n&#039;est plus jouissif que de d\u00e9couvrir une nouvelle s\u00e9rie g\u00e9niale. Et rien n&#039;est plus d\u00e9cevant que de voir cette s\u00e9rie perdre compl\u00e8tement le fil et sa qualit\u00e9 chuter drastiquement. Voici quelques s\u00e9ries qui \u00e9taient vraiment excellentes\u2026 jusqu&#039;\u00e0 ce qu&#039;elles ne le soient plus\u2026<\/h2>\n<h2> 1. \u00ab Euphoria \u00bb. Lors de sa premi\u00e8re diffusion, on avait l&#039;impression de regarder une s\u00e9rie pour adolescents comme on n&#039;en avait jamais vue auparavant. <\/h2>\n<p> HBO<\/p>\n<h2> Mais in\u00e9vitablement, le m\u00eame probl\u00e8me que pour toutes les autres s\u00e9ries de ce genre s&#039;est pos\u00e9\u00a0: une perte de fil conducteur une fois que les personnages quittent enfin le lyc\u00e9e. La derni\u00e8re saison est assez p\u00e9nible et difficile \u00e0 regarder. <\/h2>\n<p> HBO<\/p>\n<h2> 2. Game of Thrones. \u00c0 ses moments de gloire, c&#039;\u00e9tait l&#039;une des meilleures s\u00e9ries de l&#039;histoire de la t\u00e9l\u00e9vision. Et \u00e0 ses moments de faiblesse, c&#039;\u00e9tait plus douloureux que les Noces Pourpres elles-m\u00eames. <\/h2>\n<p> HBO<\/p>\n<h2> \u00c0 partir de la saison 5, la s\u00e9rie a commenc\u00e9 \u00e0 d\u00e9cliner, m\u00eame si les saisons suivantes ont offert quelques moments forts. Malheureusement, durant la majeure partie de la derni\u00e8re saison, ce qui faisait son charme a compl\u00e8tement disparu. <\/h2>\n<p> HBO <\/p>\n<p> <strong>Voir aussi\u00a0: Choisissez l\u2019un de ces personnages fictifs susceptibles de vous int\u00e9resser et nous \u00e9valuerons votre \u00ab\u00a0niveau d\u2019\u00e9tranget\u00e9\u00a0\u00bb sur une \u00e9chelle de 1 \u00e0 10.<\/strong><\/p>\n<h2> 3. Riverdale. La premi\u00e8re saison \u00e9tait un peu na\u00efve, mais coh\u00e9rente. Les personnages et leurs relations \u00e9taient caricaturaux et dignes d&#039;un feuilleton, sans pour autant \u00eatre totalement irr\u00e9alistes, et l&#039;intrigue polici\u00e8re offrait un rebondissement captivant. <\/h2>\n<p> CW<\/p>\n<h2> \u2026Et puis c\u2019est devenu une version en prises de vues r\u00e9elles de \u00ab\u00a0Mad Tales\u00a0\u00bb, et chaque saison devenait de plus en plus absurde. Quoi\u00a0? Archie se bat contre un ours\u00a0? Il y a une secte\u00a0? Tout le monde a des super-pouvoirs\u00a0? On est dans les ann\u00e9es 50\u00a0?! <\/h2>\n<p> CW<\/p>\n<h2> 4. \u00ab Pretty Little Liars \u00bb. Au premier abord, la s\u00e9rie semblait \u00eatre une enqu\u00eate polici\u00e8re complexe et minutieusement construite. C&#039;\u00e9tait passionnant de rechercher des indices et d&#039;\u00e9laborer diverses th\u00e9ories. <\/h2>\n<p> Famille ABC<\/p>\n<h2> Au final, il est devenu \u00e9vident que le public s&#039;\u00e9tait davantage investi dans l&#039;intrigue que les sc\u00e9naristes eux-m\u00eames. <\/h2>\n<p> Famille ABC <\/p>\n<h2> 5. Dexter. Les premi\u00e8res saisons \u00e9taient captivantes, d&#039;un humour noir et terrifiantes, dans le bon sens du terme. <\/h2>\n<p> Afficher l&#039;heure<\/p>\n<h2> La qualit\u00e9 des saisons suivantes a d\u00e9clin\u00e9 de plus en plus jusqu&#039;\u00e0 ce que l&#039;on arrive au point o\u00f9 Deb a avou\u00e9 son amour \u00e0 son fr\u00e8re \u2013 et apr\u00e8s cela, il n&#039;y avait plus de retour en arri\u00e8re possible. <\/h2>\n<p> Afficher l&#039;heure<\/p>\n<h2> 6. \u00ab Heroes \u00bb. \u00c0 sa sortie, \u00ab Heroes \u00bb paraissait unique, captivante, avec une intrigue bien ficel\u00e9e et un rythme dynamique. La r\u00e9plique \u00ab Sauvez la pom-pom girl, sauvez le monde \u00bb est rest\u00e9e culte. <\/h2>\n<p> NBK<\/p>\n<h2> Malheureusement, la qualit\u00e9 a chut\u00e9 assez rapidement d\u00e8s la deuxi\u00e8me saison et n&#039;a fait qu&#039;empirer depuis. Quel g\u00e2chis de talent et de potentiel !. <\/h2>\n<p> NBK <\/p>\n<h2> 7. Westworld. La premi\u00e8re saison repr\u00e9sente le summum des s\u00e9ries t\u00e9l\u00e9vis\u00e9es de prestige. Magnifique et profonde, elle b\u00e9n\u00e9ficie d&#039;une distribution exceptionnelle et de rebondissements inattendus mais justifi\u00e9s. <\/h2>\n<p> HBO<\/p>\n<p> <strong>Voir aussi\u00a0: 23 sc\u00e9narios de s\u00e9ries t\u00e9l\u00e9vis\u00e9es tellement mauvais que leurs auteurs devraient avoir honte.<\/strong><\/p>\n<h2> Les saisons suivantes sont devenues de plus en plus insupportables \u00e0 regarder, donnant finalement \u00e0 Westworld l&#039;apparence d&#039;une s\u00e9rie compl\u00e8tement diff\u00e9rente, avec une fin confuse, sombre et insatisfaisante. <\/h2>\n<p> HBO<\/p>\n<h2> 8. The Walking Dead. Pour une s\u00e9rie de zombies, The Walking Dead a toujours mis l&#039;accent sur l&#039;humanit\u00e9\u00a0; non seulement sur ce qu&#039;il faut pour survivre, mais aussi sur ce que cela signifie. C&#039;\u00e9tait une s\u00e9rie riche, avec une multitude de personnages auxquels on s&#039;attache. <\/h2>\n<p> AMS<\/p>\n<h2> Au fil du r\u00e9cit, la violence et l&#039;atmosph\u00e8re se sont intensifi\u00e9es, et des personnages auxquels on s&#039;\u00e9tait attach\u00e9 ont p\u00e9ri ou ont connu un destin tragique. Le sort de Glenn a \u00e9t\u00e9 la goutte d&#039;eau qui a fait d\u00e9border le vase pour de nombreux spectateurs. <\/h2>\n<p> AMS <\/p>\n<h2> 9. \u00ab\u00a0The Losers\u00a0\u00bb. Les deux premi\u00e8res saisons de \u00ab\u00a0The Losers\u00a0\u00bb \u00e9taient originales, dr\u00f4les et captivantes. La troisi\u00e8me saison, un peu moins charmante suite au d\u00e9part de Robert Sheehan (Nathan), restait n\u00e9anmoins une excellente s\u00e9rie. <\/h2>\n<p> E4<\/p>\n<h2> Puis, \u00e0 la fin de la saison 3, la plupart des acteurs restants ont quitt\u00e9 la s\u00e9rie, et les deux saisons suivantes ont donn\u00e9 l&#039;impression d&#039;\u00eatre de p\u00e2les imitations des pr\u00e9c\u00e9dentes. <\/h2>\n<p> E4<\/p>\n<h2> 10. True Blood. \u00c0 l&#039;instar des livres dont la s\u00e9rie est tir\u00e9e, True Blood a connu son plus grand succ\u00e8s \u00e0 ses d\u00e9buts, lorsqu&#039;il s&#039;agissait simplement d&#039;une histoire gothique et sensuelle sur des vampires du Sud. <\/h2>\n<p> HBO<\/p>\n<h2> Plus les cr\u00e9atures surnaturelles apparaissaient, moins la s\u00e9rie devenait int\u00e9ressante, et la vie personnelle compliqu\u00e9e de Sookie a cess\u00e9 d&#039;\u00eatre amusante. La derni\u00e8re saison \u00e9tait particuli\u00e8rement \u00e9prouvante. <\/h2>\n<p> HBO <\/p>\n<p> <strong>Voir aussi\u00a0: Les fans occasionnels de Disney ne r\u00e9ussiront pas ce quiz Disney de type \u00ab\u00a0Jeopardy\u00a0\u00bb, alors si vous \u00eates un vrai fan, il est temps de le prouver (et cinq autres quiz Disney)<\/strong><\/p>\n<h2> 11. Younger. Le postulat de Younger a toujours \u00e9t\u00e9 un peu tir\u00e9 par les cheveux, mais c&#039;\u00e9tait suffisamment dr\u00f4le pour que l&#039;attente en vaille la peine. <\/h2>\n<p> TV Land<\/p>\n<h2> Au fil des \u00e9pisodes, cela est devenu de plus en plus difficile, car le secret de Lisa \u2014 et le fait que beaucoup ignoraient ou soup\u00e7onnaient la v\u00e9rit\u00e9 \u2014 est devenu moins captivant, et les personnages eux-m\u00eames sont devenus moins complexes et plus irritants. <\/h2>\n<p> TV Land<\/p>\n<h2> 12. \u00ab Il \u00e9tait une fois \u00bb. Au d\u00e9but, la s\u00e9rie semblait originale et captivante, int\u00e9grant habilement et avec humour des contes de f\u00e9es \u00e0 son intrigue principale. <\/h2>\n<p> ABS<\/p>\n<h2> Au cours des derni\u00e8res saisons, la plupart des personnages originaux restants commen\u00e7aient \u00e0 s&#039;essouffler, les nouveaux n&#039;\u00e9taient pas attachants, et l&#039;ensemble paraissait un peu trop fade. <\/h2>\n<p> ABS <\/p>\n<h2> 13. \u00ab 100 \u00bb. Un concept g\u00e9nial, initialement tr\u00e8s bien ex\u00e9cut\u00e9 et captivant, avec des personnages complexes et imparfaits, mais qui donnaient envie de les soutenir. <\/h2>\n<p> CW<\/p>\n<h2> L&#039;\u00e9quipe cr\u00e9ative et le showrunner ont ensuite pris une s\u00e9rie de d\u00e9cisions qui semblaient sp\u00e9cifiquement con\u00e7ues pour mettre les fans en col\u00e8re, et la derni\u00e8re saison \u00e9tait, franchement, le portrait crach\u00e9 de tous ceux qui \u00e9taient rest\u00e9s fid\u00e8les \u00e0 la s\u00e9rie. <\/h2>\n<p> CW<\/p>\n<h2> 14. Outlander. Des paysages \u00e9poustouflants, une cin\u00e9matographie \u00e9poustouflante, des acteurs captivants et talentueux, des costumes magnifiques et une romance intrigante sur fond de voyage dans le temps ont rendu cette s\u00e9rie incroyablement prenante. <\/h2>\n<p> Starz<\/p>\n<h2> Malheureusement, les sc\u00e8nes de viol r\u00e9p\u00e9titives, explicites et gratuites ont rendu la s\u00e9rie totalement insupportable, d\u00e8s la fin de la premi\u00e8re saison et tout au long de la s\u00e9rie, si tant est que vous ayez r\u00e9ussi \u00e0 la regarder jusqu&#039;au bout. <\/h2>\n<p> Starz <\/p>\n<h2> 15. Stranger Things. La premi\u00e8re saison \u00e9tait une aventure parfaite, dans le style Amblin, recr\u00e9ant l&#039;ambiance des ann\u00e9es 80. C&#039;est discutable, mais la s\u00e9rie aurait d\u00fb rester une mini-s\u00e9rie. <\/h2>\n<p> Netflix<\/p>\n<h2> Bien que les saisons suivantes aient comport\u00e9 de nombreux moments forts, le d\u00e9veloppement de l&#039;intrigue \u00e9tait maladroit, et la derni\u00e8re saison en particulier fut un v\u00e9ritable fiasco qui a sap\u00e9 tout ce qui avait pr\u00e9c\u00e9d\u00e9. <\/h2>\n<p> Netflix<\/p>\n<p> <strong>Voir aussi\u00a0: Pouvez-vous nommer ces personnages embl\u00e9matiques de Peanuts\u00a0?<\/strong><\/p>\n<h2> 16. \u00ab Yellow Wasps \u00bb. La premi\u00e8re saison \u00e9tait captivante, originale, divertissante et d&#039;une noirceur implacable. Gr\u00e2ce \u00e0 une distribution exceptionnelle et \u00e0 deux \u00e9poques distinctes, la s\u00e9rie a tenu les spectateurs en haleine et leur a offert des rebondissements inattendus. <\/h2>\n<p> Afficher l&#039;heure<\/p>\n<h2> Cependant, au fil des saisons, l&#039;intrigue s&#039;est transform\u00e9e, passant d&#039;une toile complexe \u00e0 un n\u0153ud inextricable. Si la distribution reste excellente, les histoires sont devenues plus fastidieuses et moins captivantes. <\/h2>\n<p> Afficher l&#039;heure <\/p>\n<h2> 17. The Umbrella Academy. La premi\u00e8re saison \u00e9tait une aventure de super-h\u00e9ros unique et rafra\u00eechissante, avec des personnages imparfaits qu&#039;on ne pouvait s&#039;emp\u00eacher d&#039;aimer. La deuxi\u00e8me saison \u00e9tait \u00e9galement r\u00e9ussie et g\u00e9n\u00e9ralement dr\u00f4le. <\/h2>\n<p> Netflix<\/p>\n<h2> Si la troisi\u00e8me saison \u00e9tait moins r\u00e9ussie, elle valait tout de m\u00eame le coup d&#039;\u0153il. En revanche, la quatri\u00e8me et derni\u00e8re saison s&#039;est \u00e9ternis\u00e9e (surtout la fin), aplatissant tellement les personnages et l&#039;univers qu&#039;ils en sont devenus m\u00e9connaissables. <\/h2>\n<p> Netflix<\/p>\n<h2> 18. \u00ab Glee \u00bb. Lors de sa premi\u00e8re diffusion, aucune autre \u00e9mission ne ressemblait \u00e0 \u00ab Glee \u00bb. C&#039;\u00e9tait original, kitsch, absurde, hilarant et rempli de tubes. <\/h2>\n<p> Renard<\/p>\n<h2> Glee a toujours eu ses d\u00e9fauts, mais au fil des \u00e9pisodes, ils sont devenus de plus en plus flagrants, au point que la s\u00e9rie a fini par devenir ridicule et totalement inint\u00e9ressante. Bien s\u00fbr, elle comptait tout de m\u00eame quelques bonnes chansons. <\/h2>\n<p> Renard <\/p>\n<h2> 19. Et enfin, X-Files. Les premi\u00e8res saisons de X-Files sont consid\u00e9r\u00e9es comme des classiques \u00e0 juste titre\u00a0: une s\u00e9rie parfaite avec un monstre diff\u00e9rent chaque semaine, une alchimie captivante entre Mulder et Scully, une intrigue pleine de suspense (\u00ab\u00a0vont-ils finir ensemble ou non\u00a0?\u00a0\u00bb) et un myst\u00e8re int\u00e9ressant qui n\u2019\u00e9clipse pas toute la s\u00e9rie. <\/h2>\n<p> Renard<\/p>\n<h2> Dans les derni\u00e8res saisons, la s\u00e9rie est devenue une caricature d&#039;elle-m\u00eame\u00a0: Mulder et Scully \u00e9taient sous-repr\u00e9sent\u00e9s, et les intrigues li\u00e9es au complot extraterrestre \u00e9taient surexploit\u00e9es. Une grande partie de la s\u00e9rie \u00e9tait d\u00e9nu\u00e9e de sens et d\u00e9cevante. <\/h2>\n<p> Renard<\/p>\n<h2> Quelle s\u00e9rie t\u00e9l\u00e9vis\u00e9e, apr\u00e8s un excellent d\u00e9but, est devenue insupportable\u00a0? Partagez votre avis dans les commentaires ou anonymement ci-dessous\u00a0!<\/h2>\n<p> Si vous ou une personne de votre entourage avez \u00e9t\u00e9 victime d&#039;agression sexuelle, vous pouvez appeler la ligne d&#039;\u00e9coute nationale contre les agressions sexuelles au 1-800-656-HOPE, qui vous orientera vers le centre d&#039;aide aux victimes d&#039;agressions sexuelles le plus proche. Vous trouverez \u00e9galement des informations sur un centre pr\u00e8s de chez vous ici. .<\/p>\n<p> <strong>Votre entra\u00eenement c\u00e9r\u00e9bral quotidien\u00a0: La plupart des gens ne parviendront pas \u00e0 terminer la cha\u00eene de mots g\u00e9ante ce week-end \u2014 et vous\u00a0?<\/strong><\/p>\n<p> <strong>Toujours dans la section TV et Films\u00a0: Malheureusement, je doute fort qu\u2019un adulte d\u2019aujourd\u2019hui puisse nommer les 14 personnages de PBS.<\/strong><\/p>\n<p> <strong>\u00c9galement sur TVAndMovies\u00a0: Seuls les vrais fans de Disney ont vu au moins 40 de ces 60 films d\u2019animation.<\/strong><\/p>\n<p> <strong>Lisez l&#039;article sur BuzzFeed.com<\/strong><\/p>","protected":false},"excerpt":{"rendered":"<p>Avertissement\u00a0: ce texte mentionne le viol et les agressions sexuelles. En mati\u00e8re de culture populaire, rien de mieux que de d\u00e9couvrir une nouvelle s\u00e9rie t\u00e9l\u00e9vis\u00e9e captivante. Et il n\u2019y a rien\u2026<\/p>","protected":false},"author":1,"featured_media":303,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=302"}],"version-history":[{"count":38,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/302\/revisions"}],"predecessor-version":[{"id":141001,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/302\/revisions\/141001"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/303"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=302"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}