{"id":4186,"date":"2026-06-01T03:04:22","date_gmt":"2026-06-01T00:04:22","guid":{"rendered":"https:\/\/imgist.ru\/vse-hity-drejka-zanyavshie-pervoe-mesto-v-chartah-v-poryadke-ubyvaniya-populyarnosti\/"},"modified":"2026-06-01T03:04:22","modified_gmt":"2026-06-01T00:04:22","slug":"tous-les-tubes-numero-un-de-drake-classes-par-ordre-decroissant-de-popularite","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/vse-hity-drejka-zanyavshie-pervoe-mesto-v-chartah-v-poryadke-ubyvaniya-populyarnosti\/","title":{"rendered":"Tous les tubes de Drake class\u00e9s num\u00e9ro un dans les charts, par ordre d\u00e9croissant de popularit\u00e9."},"content":{"rendered":"<p>Nom <strong>Canard<\/strong> est devenu synonyme de succ\u00e8s fulgurant.<\/p>\n<p> Tout au long de sa carri\u00e8re, le leader d&#039;OVO a domin\u00e9 les classements Billboard, nous offrant des tubes inoubliables. Le 26 mai, l&#039;artiste canadien a franchi une nouvelle \u00e9tape en d\u00e9passant Michael Jackson et en atteignant la premi\u00e8re place du classement Billboard Hot 100 avec un impressionnant total de 14 titres.<\/p>\n<p> M\u00eame si les critiques peuvent d\u00e9battre du r\u00f4le du streaming par rapport aux ventes d&#039;albums physiques, la r\u00e9ussite de Drake est incontestablement remarquable.<\/p>\n<p> De son plus r\u00e9cent tube num\u00e9ro 1, \u00ab First Person Shooter \u00bb, \u00e0 sa collaboration de 2010 avec Rihanna, \u00ab What&#039;s My Name \u00bb, voici le classement d\u00e9finitif des plus grands succ\u00e8s de Drake.<\/p>\n<p> BOUTIQUE UNIQUE : Retrouvez vos marques pr\u00e9f\u00e9r\u00e9es o\u00f9 et quand vous voulez. D\u00e9couvrez les nouveaut\u00e9s. Achetez. Collectionnez. Profitez.<\/p>\n<\/p>\n<h2> 14.<\/h2>\n<p> \u00abToboggan Toosie (2020)<\/p>\n<p> <strong>Producteur:<\/strong> OZ<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1<\/p>\n<p> Le morceau \u201c Toosie Slide \u201d est arriv\u00e9 \u00e0 point nomm\u00e9. Il est sorti en avril 2020, un mois seulement apr\u00e8s que la pand\u00e9mie de Covid-19 a paralys\u00e9 le monde entier.<\/p>\n<p> \u00c0 l&#039;\u00e9poque, les fans ne recherchaient pas une musique abordant des sujets s\u00e9rieux comme la crise sanitaire mondiale ou l&#039;escalade des tensions sociales ; ils voulaient simplement s&#039;amuser ou se d\u00e9tendre, et \u00ab Toosie Slide \u00bb a r\u00e9pondu \u00e0 leurs attentes.<\/p>\n<p> Gr\u00e2ce \u00e0 son rythme entra\u00eenant, ses paroles simples et la voix suave de Drake, le morceau a atteint le sommet du classement Billboard Hot 100.<\/p>\n<p> La chanson a \u00e9galement conquis le c\u0153ur des auditeurs gr\u00e2ce \u00e0 son rythme entra\u00eenant, caract\u00e9ris\u00e9 par des pas l\u00e9gers. \u00ab Toosie Slide \u00bb est loin d&#039;\u00eatre son meilleur single, mais il a atteint son objectif, prouvant que Drake sait ce que les gens veulent et ce dont ils ont besoin.<\/p>\n<h2> 13.<\/h2>\n<p> Drake avec SZA, \u00ab Slime You Out \u00bb (2023)<\/p>\n<p> <strong>Producteurs :<\/strong> 40, BNYX\u00ae, Noel Cadastre, D10 et Grant Lapointe<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1<\/p>\n<p> Malgr\u00e9 la controverse initiale concernant l&#039;utilisation non autoris\u00e9e de l&#039;image de l&#039;actrice Halle Berry pour la couverture, \u00ab Slime You Out \u00bb met en valeur la ma\u00eetrise du genre R&amp;B par Drake.<\/p>\n<p> Sur une m\u00e9lodie douce et harmonieuse, l&#039;alliance de paroles percutantes et de la voix suave de Drake conf\u00e8re \u00e0 la chanson une profondeur unique. La contribution envo\u00fbtante de SZA harmonise le tout, faisant de \u00ab\u00a0Slime You Out\u00a0\u00bb l&#039;un des r\u00e9cents tubes de Drake, un succ\u00e8s intemporel.<\/p>\n<h2> 12.<\/h2>\n<p> Drake, Future et Young Thug, \u00ab Way 2 Sexy \u00bb (2021)<\/p>\n<p> <strong>Producteurs :<\/strong> TM88 et TooDope<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1<\/p>\n<p> La chanson \u00ab Way 2 Sexy \u00bb est n\u00e9e d&#039;une plaisanterie entre Young Thug et Future, ce dernier ayant remarqu\u00e9 que Thug portait une tenue sexy en studio. Mais le morceau est rapidement devenu l&#039;un des meilleurs singles de l&#039;album de Drake sorti en 2021. <em>Gar\u00e7on amoureux certifi\u00e9<\/em> . Ce morceau, qui fait r\u00e9f\u00e9rence au tube de Right Said Fred de 1991 \u00ab I&#039;m Too Sexy \u00bb, est un v\u00e9ritable succ\u00e8s aupr\u00e8s du public masculin gr\u00e2ce \u00e0 sa m\u00e9lodie entra\u00eenante et ses paroles espi\u00e8gles. Le m\u00e9lange subtil d&#039;humour et d&#039;assurance, associ\u00e9 au refrain m\u00e9morable de Future, rend cette chanson irr\u00e9sistible pour les fans.<\/p>\n<h2> 11.<\/h2>\n<p> Future avec Drake et Gems, \u00ab Wait For U \u00bb (2022)<\/p>\n<p> <strong>Producteurs :<\/strong> ATL Jacob, FNZ, 1SRAEL, Sonic Major et Tejiri.<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1<\/p>\n<p> \u00ab&quot;Wait For U&quot; s&#039;inscrit dans la lign\u00e9e des collaborations m\u00e9morables de Drake et Future.<\/p>\n<p> Le morceau est sorti sur l&#039;album Future, sorti en 2022. <em>Je ne t&#039;ai jamais aim\u00e9<\/em> et a imm\u00e9diatement attir\u00e9 l&#039;attention gr\u00e2ce \u00e0 son sample poignant, ses voix et son th\u00e8me.<\/p>\n<p> Sur ce morceau, Future et Drake affichent une alchimie ind\u00e9niable, mais ce qui propulse v\u00e9ritablement la chanson au sommet des charts, c&#039;est le sample de \u00ab Higher \u00bb de Tems. La voix velout\u00e9e de l&#039;auteure-compositrice-interpr\u00e8te nig\u00e9riane sublime le single, incitant les auditeurs \u00e0 d\u00e9passer les paroles, qui se concentrent principalement sur la toxicit\u00e9 de la relation amoureuse entre Drake et Future. Drake et Future sont surtout connus pour leurs hymnes \u00e9nergiques, mais \u00ab Wait For U \u00bb prouve qu&#039;ils ma\u00eetrisent aussi les rythmes R&amp;B.<\/p>\n<h2> 10.<\/h2>\n<p> \u00abEt apr\u00e8s ? (2021)<\/p>\n<p> <strong>Producteurs :<\/strong> Supa Mario et Manish<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1<\/p>\n<p> \u00ab What&#039;s Next \u00bb de Drake est imm\u00e9diatement reconnaissable \u00e0 son rythme \u00e9nergique et entra\u00eenant. Drake y revient sur son parcours musical, d\u00e9montrant son assurance et sa capacit\u00e9 \u00e0 s&#039;adapter \u00e0 diff\u00e9rents styles. S&#039;il a incontestablement prouv\u00e9 sa ma\u00eetrise des compositions R&amp;B, c&#039;est lorsqu&#039;il se tourne vers le rap qu&#039;il excelle, cr\u00e9ant des morceaux percutants, parfaits pour les clubs et les soir\u00e9es. Son charisme sur ce titre est communicatif et palpable. \u00ab What&#039;s Next \u00bb t\u00e9moigne clairement de la long\u00e9vit\u00e9 de Drake dans l&#039;industrie du rap.<\/p>\n<h2> 9.<\/h2>\n<p> Drake avec J. Cole, \u00ab Jeu de tir \u00e0 la premi\u00e8re personne \u00bb (2023)<\/p>\n<p> <strong>Producteurs :<\/strong> Boi-1da, Tay Keith, Vinylz, OZ, Coleman et FNZ<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1<\/p>\n<p> Sur le morceau \u00ab First Person Shooter \u00bb, Drake s&#039;associe \u00e0 J. Cole, et les deux artistes \u00e9changent des rimes enflamm\u00e9es.<\/p>\n<p> Dans la premi\u00e8re partie du morceau, Drake donne le ton avec ses couplets incisifs et agressifs\u00a0: \u00ab\u00a0Aussi gros que le Super Bowl \/ Mais la diff\u00e9rence, c&#039;est que ce ne sont que deux gars qui jouent ce qu&#039;ils ont compos\u00e9 en studio.\u00a0\u00bb Si le couplet de Drake est suffisamment entra\u00eenant pour \u00eatre \u00e9cout\u00e9 en voiture, le v\u00e9ritable atout du single est la performance de J. Cole, qui livre un couplet remarquable, riche en jeux de mots et en m\u00e9taphores. \u00ab\u00a0Celui qu&#039;on appelle quand rien ne va, j&#039;ai l&#039;impression de travailler dans l&#039;informatique\u00a0\u00bb, rappe Cole.<\/p>\n<p> Bien s\u00fbr, cette chanson est entr\u00e9e dans l&#039;histoire comme le morceau qui a lanc\u00e9 la bataille de rap entre Kendrick Lamar et Drake.<\/p>\n<h2> 8.<\/h2>\n<p> Rihanna en featuring avec Drake, \u00ab What&#039;s My Name \u00bb (2010)<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1<\/p>\n<p> Ce n&#039;est pas un hasard si Drake et Rihanna sont ensemble en t\u00eate des classements.<\/p>\n<p> Leur alchimie musicale est incroyable. \u00ab What&#039;s My Name \u00bb est l&#039;un de leurs plus grands succ\u00e8s, gr\u00e2ce \u00e0 son m\u00e9lange captivant de pop entra\u00eenante et de hip-hop. Ses paroles sensuelles et son refrain irr\u00e9sistible ont contribu\u00e9 \u00e0 sa popularit\u00e9 durable. La chanson a \u00e9galement donn\u00e9 naissance \u00e0 certaines des meilleures r\u00e9pliques de tous les temps, comme : \u00ab Good weed, white wine, oh\/ I come alive at night, yeah \u00bb. Les paroles sensuelles et le refrain entra\u00eenant de Rihanna, combin\u00e9s aux paroles m\u00e9morables de Drake, n&#039;ont fait que renforcer le succ\u00e8s intemporel de la chanson.<\/p>\n<\/p>\n<h2> 7.<\/h2>\n<p> Drake avec 21 Savage, \u00ab Jimmy Cooks \u00bb (2022)<\/p>\n<p> <strong>Producteurs :<\/strong> Tay Keith, Vinylz, Tizzle et CuBeatz<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1<\/p>\n<p> Les plus grands succ\u00e8s de Drake sont souvent connus pour leur orientation pop ou leur attrait radiophonique, mais \u00ab Jimmy Cooks \u00bb sort de ce moule sans rien perdre de son charme ni de son potentiel de r\u00e9\u00e9coute. Ce morceau figure sur l&#039;album de danse exp\u00e9rimental de Drake. <em>Honn\u00eatement, laissez tomber.<\/em> , Sur \u00ab Jimmy Cooks \u00bb, le rappeur collabore avec 21 Savage sur un beat rap brut, inspir\u00e9 par Memphis. Ensemble, ils font r\u00e9f\u00e9rence \u00e0 des moments iconiques du sport et d&#039;Hollywood, notamment la gifle de Will Smith aux Oscars. \u00ab Jimmy Cooks \u00bb se distingue dans la production r\u00e9cente de Drake par son style rap sans compromis, rempla\u00e7ant les habituelles m\u00e9lodies R&amp;B par des paroles agressives et provocatrices.<\/p>\n<h2> 6.<\/h2>\n<p> \u00abDans mes sentiments (2018)<\/p>\n<p> <strong>Producteurs :<\/strong> 40, TrapMoneyBenny et BlaqNmilD<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 10<\/p>\n<p> Certes, \u00ab In My Feelings \u00bb a rapidement connu un succ\u00e8s fulgurant gr\u00e2ce au d\u00e9fi viral, mais il faut reconna\u00eetre \u00e0 Drake le m\u00e9rite d&#039;avoir un titre vraiment entra\u00eenant. Le refrain joyeux, \u00ab Kiki, do you love me ? \u00bb, a donn\u00e9 naissance \u00e0 un v\u00e9ritable ph\u00e9nom\u00e8ne culturel, d\u00e9montrant la capacit\u00e9 de Drake \u00e0 puiser dans ses exp\u00e9riences personnelles avec les femmes pour cr\u00e9er des moments qui transcendent la musique.<\/p>\n<p> Drake a aussi le don de d\u00e9nicher des artistes talentueux, comme il l&#039;a prouv\u00e9 en invitant le duo rap City Girls \u00e0 participer au refrain. Tandis que Drake assure la partie R&amp;B du morceau, City Girls y apportent une touche urbaine et percutante. La chanson est entra\u00eenante, dansante et pleine d&#039;\u00e9nergie, et illustre parfaitement le talent de Drake pour cr\u00e9er des tubes irr\u00e9sistibles qui se hissent au sommet des charts.<\/p>\n<h2> 5.<\/h2>\n<p> \u00abJanice, tais-toi (2026)<\/p>\n<p> <strong>Producteurs :<\/strong> b4u, FNZ et Rog\u00e9t Chahayed<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 1 (pour l&#039;instant)<\/p>\n<p> Qui aurait cru que la chanson la plus entra\u00eenante de l&#039;album de Drake serait celle-ci ? <em>Iceman<\/em> Et sera-t-il aussi l&#039;un des plus cools\u00a0? \u00ab\u00a0Janice STFU\u00a0\u00bb propose certaines des bandes originales les plus audacieuses de Kendrick Lamar\u00a0:<\/p>\n<p> <em>\u00ab<\/em> \u00bb Tu distribues des dindes devant les cam\u00e9ras dans ton quartier, puis tu retournes dans les montagnes \/ Combien de maisons as-tu construites ? Combien d&#039;\u00e2mes as-tu gu\u00e9ries gr\u00e2ce \u00e0 ton travail ? \u00bb, rappe-t-il.<\/p>\n<p> Et il livre tout cela sur un morceau qui vous restera en t\u00eate, utilisant les intonations vocales typiques du rap underground moderne pour appuyer son propos. <em>Dimas Sanfiorenzo<\/em><\/p>\n<h2> 4.<\/h2>\n<p> \u00ab Le plan de Dieu \u00bb (2018)<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 11<\/p>\n<p> \u00ab God&#039;s Plan \u00bb est l&#039;un des plus grands succ\u00e8s de Drake \u00e0 ce jour. Sorti en 2018, il est devenu le deuxi\u00e8me titre de l&#039;histoire du Billboard Hot 100 \u00e0 d\u00e9passer les 100 millions d&#039;\u00e9coutes hebdomadaires.<\/p>\n<p> La chanson est rest\u00e9e 11 semaines dans les charts, devenant ainsi le 24e single \u00e0 r\u00e9aliser cet exploit dans l&#039;histoire du classement. \u00ab\u00a0God&#039;s Plan\u00a0\u00bb est l&#039;un des meilleurs titres de Drake, non seulement gr\u00e2ce \u00e0 son succ\u00e8s commercial, mais aussi gr\u00e2ce \u00e0 son message fort et \u00e0 son clip. La chanson poss\u00e8de un rythme pop entra\u00eenant et aborde les th\u00e8mes de la foi et de la charit\u00e9. Dans le clip, Drake partage \u00e9galement sa fortune avec des familles, des \u00e9tudiants et d&#039;autres groupes d\u00e9favoris\u00e9s de Miami. Le succ\u00e8s de \u00ab\u00a0God&#039;s Plan\u00a0\u00bb s&#039;explique par sa capacit\u00e9 \u00e0 toucher les fans et \u00e0 trouver un \u00e9cho aupr\u00e8s de tous ceux qui ont vu le clip.<\/p>\n<h2> 3.<\/h2>\n<p> Drake avec WizKid et Kyla, \u00ab One Dance \u00bb (2016)<\/p>\n<p> <strong>Producteurs :<\/strong> Les producteurs 40, DJ Maphorisa, Wizkid et Nineteen85<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 9<\/p>\n<p> Drake a r\u00e9gn\u00e9 en ma\u00eetre durant l&#039;\u00e9t\u00e9 2016, et \u00ab One Dance \u00bb a largement contribu\u00e9 \u00e0 son triomphe musical. Ce titre iconique et entra\u00eenant m\u00eale des \u00e9l\u00e9ments de dancehall et de musique afro-carib\u00e9enne. Sur un rythme irr\u00e9sistible, Drake pose un flow suave qui invite le rappeur \u00e0 danser. \u00ab One Dance \u00bb est si captivant car il est \u00e0 la fois taill\u00e9 pour les clubs et\u2026 <em>, et<\/em> Un titre taill\u00e9 pour la radio. Impossible de r\u00e9sister \u00e0 l&#039;envie de danser. Le Drake \u00ab dancehall \u00bb ne fait pas l&#039;unanimit\u00e9, mais \u00ab One Dance \u00bb t\u00e9moigne de la capacit\u00e9 du rappeur \u00e0 exp\u00e9rimenter et \u00e0 explorer de nouveaux genres et sonorit\u00e9s.<\/p>\n<h2> 2.<\/h2>\n<p> Rihanna en featuring avec Drake, &quot;Work&quot; (2016)<\/p>\n<p> <strong>Producteurs :<\/strong> Boy-1da, Seven Thomas, Allen Ritter et Kuk Harrell.<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 9<\/p>\n<p> Le titre \u00ab Work \u00bb de Rihanna, sorti en 2016, met en avant ses racines carib\u00e9ennes gr\u00e2ce \u00e0 un rythme entra\u00eenant et une voix captivante. Si Rihanna est incontestablement la star du morceau, Drake y contribue \u00e9galement, illustrant leur ind\u00e9niable alchimie musicale. Le couplet de Drake dure moins d&#039;une minute, mais il joue un r\u00f4le marquant dans le succ\u00e8s de la chanson, avec des paroles accrocheuses et enjou\u00e9es qui donnent envie de danser. Mis \u00e0 part leurs diff\u00e9rends personnels, il est regrettable que ces deux artistes ne collaborent plus.<\/p>\n<h2> 1.<\/h2>\n<p> \u00abBon pour quoi (2018)<\/p>\n<p> <strong>Producteurs :<\/strong> 40, BlaqNmilD et Murda Beatz<\/p>\n<p> <strong>Nombre de semaines \u00e0 la premi\u00e8re place :<\/strong> 8<\/p>\n<p> \u00ab Nice For What \u00bb de Drake r\u00e9unit tous les ingr\u00e9dients d&#039;un tube : un sample nostalgique, un m\u00e9lange r\u00e9ussi de R&amp;B, de pop et de rap, des paroles m\u00e9morables et un refrain entra\u00eenant. Le morceau fusionne avec brio un sample soul de \u00ab Ex-Factor \u00bb de Lauryn Hill avec un beat hip-hop percutant typique de la Nouvelle-Orl\u00e9ans, cr\u00e9ant ainsi un titre captivant qui s\u00e9duira un large public.<\/p>\n<p> Sur le plan des paroles, le morceau est un hommage au public f\u00e9minin de Drake, c\u00e9l\u00e9brant l&#039;ind\u00e9pendance des femmes et les invitant \u00e0 reprendre le contr\u00f4le de leur temps. Avec des refrains accrocheurs comme \u00ab\u00a0Tu es vraiment \u00e0 fond avec ces gars\/Pourquoi tu dois \u00eatre gentille avec eux\u00a0?\u00a0\u00bb, la chanson est instantan\u00e9ment inoubliable. \u00ab\u00a0Nice For What\u00a0\u00bb t\u00e9moigne du talent musical de Drake et demeure un hymne intemporel, dont l&#039;impact et l&#039;\u00e9nergie communicative restent in\u00e9gal\u00e9s depuis sa sortie.<\/p>\n<h2> Actualit\u00e9s connexes<\/h2>\n<p> Dans son nouveau clip vid\u00e9o, \u00ab White Flag \u00bb, Vince Staples tire avec un fusil d&#039;assaut sur un drapeau am\u00e9ricain.<\/p>\n<p> aespa, Explications : Au c\u0153ur de la musique, des membres et du monde virtuel d&#039;un groupe de K-Pop<\/p>\n<p> BOUTIQUE UNIQUE : Retrouvez vos marques pr\u00e9f\u00e9r\u00e9es o\u00f9 et quand vous voulez. D\u00e9couvrez les nouveaut\u00e9s. Achetez. Collectionnez. Profitez.<\/p>\n<p> Nous donnons vie \u00e0 la culture. Retrouvez ici les derni\u00e8res actualit\u00e9s du monde du divertissement, ainsi que les meilleurs contenus sur la musique, la culture pop, les sneakers, la mode et les s\u00e9ries originales.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le nom de Drake est devenu synonyme de succ\u00e8s fulgurant. Tout au long de sa carri\u00e8re, le leader d&#039;OVO a domin\u00e9 les classements Billboard, nous offrant des tubes inoubliables. 26 mai\u2026<\/p>","protected":false},"author":1,"featured_media":4187,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-4186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muzyka","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/4186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=4186"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/4186\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/4187"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=4186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=4186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=4186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}