{"id":5252,"date":"2026-06-01T18:20:42","date_gmt":"2026-06-01T15:20:42","guid":{"rendered":"https:\/\/imgist.ru\/dzhessi-uilyams-zhdet-rebenka-ot-svoej-zheny-alehandry-onievoj\/"},"modified":"2026-08-29T11:49:49","modified_gmt":"2026-08-29T08:49:49","slug":"jessie-williams-attend-un-enfant-avec-sa-fiancee-alehandra-onievoj","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/dzhessi-uilyams-zhdet-rebenka-ot-svoej-zheny-alehandry-onievoj\/","title":{"rendered":"Jesse Williams et sa femme Alejandra Onieva attendent un b\u00e9b\u00e9."},"content":{"rendered":"<p>Jesse Williams s&#039;appr\u00eate \u00e0 devenir p\u00e8re pour la deuxi\u00e8me fois. L&#039;ancienne star <em>S\u00e9rie t\u00e9l\u00e9vis\u00e9e \u00ab Grey&#039;s Anatomy \u00bb<\/em> et sa nouvelle \u00e9pouse, Alejandra Onieva, attendent leur premier enfant quelques semaines seulement apr\u00e8s que les rumeurs de leur mariage secret aient circul\u00e9.<\/p>\n<p> Comme indiqu\u00e9 par <em>Le New York Post<\/em> , Le couple a \u00e9t\u00e9 photographi\u00e9 \u00e0 Los Angeles lors d&#039;une vir\u00e9e chez Whole Foods, le ventre arrondi d&#039;Onieva \u00e9tant bien visible. Ils ont ensuite d\u00e9jeun\u00e9 avec des amis, tentant de rester discrets malgr\u00e9 l&#039;engouement suscit\u00e9 par leur rencontre. Quelques jours auparavant, Onieva avait elle-m\u00eame confirm\u00e9 sa grossesse sur Instagram, en publiant des photos de son ventre qui s&#039;arrondissait, accompagn\u00e9es de la l\u00e9gende \u00ab\u00a0Vida\u00a0\u00bb (qui signifie \u00ab\u00a0vie\u00a0\u00bb en espagnol), ce qui lui avait rapidement valu de nombreux messages de f\u00e9licitations de la part de ses fans et amis.<\/p>\n<p> BOUTIQUE UNIQUE : Retrouvez vos marques pr\u00e9f\u00e9r\u00e9es o\u00f9 et quand vous voulez. D\u00e9couvrez les nouveaut\u00e9s. Achetez. Collectionnez. Profitez.<\/p>\n<p> Gr\u00e2ce \u00e0 son r\u00f4le de Dr Jackson Avery dans la s\u00e9rie <em>\u00abGrey&#039;s Anatomy\u00bb<\/em> Williams est sous les feux des projecteurs depuis plus d&#039;une d\u00e9cennie.<\/p>\n<p> Williams et Onieva se sont rencontr\u00e9s pour la premi\u00e8re fois en 2025 lors du tournage de la s\u00e9rie Amazon Prime. <em>\u00abH\u00f4tel Kostyera\u00bb<\/em> Sur la c\u00f4te amalfitaine en Italie. Williams y incarnait un ancien marine travaillant dans un h\u00f4tel de luxe, et Onieva \u00e9tait sa partenaire \u00e0 l&#039;\u00e9cran.<\/p>\n<p> Bien que la s\u00e9rie \u00e0 suspense n&#039;ait dur\u00e9 qu&#039;une saison, la relation n\u00e9e pendant le tournage a \u00e9volu\u00e9 rapidement. Fin 2025, ils apparaissaient d\u00e9j\u00e0 ensemble en public \u00e0 Madrid et \u00e0 Rome, ainsi qu&#039;au Festival international du film de San Sebasti\u00e1n, avant que des rumeurs ne circulent, au d\u00e9but du mois, selon lesquelles ils se seraient mari\u00e9s en secret lors d&#039;une c\u00e9r\u00e9monie priv\u00e9e.<\/p>\n<p> Cette nouvelle de grossesse survient des ann\u00e9es apr\u00e8s le divorce tr\u00e8s m\u00e9diatis\u00e9 de Williams et d&#039;Arin Drake-Lee. Ils s&#039;\u00e9taient mari\u00e9s en 2012 apr\u00e8s plusieurs ann\u00e9es de relation et sont parents de deux enfants\u00a0: une fille, Sadie, et un fils, Maceo.<\/p>\n<p> Leur s\u00e9paration en 2017 a d\u00e9g\u00e9n\u00e9r\u00e9 en une longue bataille juridique et une bataille pour la garde des enfants qui se sont poursuivies jusqu&#039;\u00e0 la finalisation du divorce en 2020. Les litiges juridiques concernant les horaires de garde, la pension alimentaire et les modalit\u00e9s de garde ont maintenu l&#039;ancien couple sous les feux des projecteurs m\u00e9diatiques longtemps apr\u00e8s leur s\u00e9paration.<\/p>\n<h3> Actualit\u00e9s connexes <\/h3>\n<p> L&#039;ancien acteur de \u00ab Grey&#039;s Anatomy \u00bb, Jesse Williams, se serait mari\u00e9 avec Alejandra Onieva. L&#039;acteur de \u00ab Grey&#039;s Anatomy \u00bb, A. Russell Andrews, a \u00e9voqu\u00e9 publiquement son combat contre la scl\u00e9rose lat\u00e9rale amyotrophique. L&#039;acteur de \u00ab One Tree Hill \u00bb, James Lafferty, a r\u00e9agi aux comparaisons avec son personnage de \u00ab Grey&#039;s Anatomy \u00bb, McDreamy.<\/p>\n<h2> Actualit\u00e9s connexes<\/h2>\n<p> Zoran Mamdani cr\u00e9e un pr\u00e9c\u00e9dent pour les \u00e9lus en lan\u00e7ant une s\u00e9rie de diffusions en direct sur Twitch.<\/p>\n<p> Dionne Warwick a r\u00e9agi au final de la saison 6 d&#039;Emily in Paris : \u00ab Mon visa de travail a expir\u00e9. \u00bb.<\/p>\n<p> BOUTIQUE UNIQUE : Retrouvez vos marques pr\u00e9f\u00e9r\u00e9es o\u00f9 et quand vous voulez. D\u00e9couvrez les nouveaut\u00e9s. Achetez. Collectionnez. Profitez.<\/p>\n<p> Nous donnons vie \u00e0 la culture. Retrouvez ici les derni\u00e8res actualit\u00e9s du monde du divertissement, ainsi que les meilleurs contenus sur la musique, la culture pop, les sneakers, la mode et les s\u00e9ries originales.<\/p>","protected":false},"excerpt":{"rendered":"<p>Jesse Williams s&#039;appr\u00eate \u00e0 devenir papa pour la deuxi\u00e8me fois. L&#039;ancien acteur de \u00ab Grey&#039;s Anatomy \u00bb et sa nouvelle \u00e9pouse, Alejandra Onieva, attendent leur premier enfant dans quelques semaines.<\/p>","protected":false},"author":1,"featured_media":5253,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-5252","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selebriti","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/5252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=5252"}],"version-history":[{"count":3,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/5252\/revisions"}],"predecessor-version":[{"id":149116,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/5252\/revisions\/149116"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/5253"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=5252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=5252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=5252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}