{"id":7251,"date":"2026-06-02T17:03:42","date_gmt":"2026-06-02T14:03:42","guid":{"rendered":"https:\/\/imgist.ru\/metallica-obedinila-neskolko-albomov-i-u-odnogo-iz-nih-est-povod-dlya-radosti\/"},"modified":"2026-08-29T11:57:06","modified_gmt":"2026-08-29T08:57:06","slug":"metallica-a-compile-plusieurs-albums-et-lun-deux-est-particulierement-rejouissant","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/metallica-obedinila-neskolko-albomov-i-u-odnogo-iz-nih-est-povod-dlya-radosti\/","title":{"rendered":"Metallica a sorti plusieurs albums, et l&#039;un d&#039;eux m\u00e9rite d&#039;\u00eatre c\u00e9l\u00e9br\u00e9."},"content":{"rendered":"<p>Il est extr\u00eamement rare de voir Metallica figurer dans deux classements rock britanniques\u00a0: Official Rock &amp; Metal Albums et Official Rock &amp; Metal Singles. Consid\u00e9r\u00e9 comme le groupe le plus populaire de l&#039;histoire du hard rock, il appara\u00eet r\u00e9guli\u00e8rement dans ces listes, parfois avec un seul titre, parfois avec plusieurs compilations et peut-\u00eatre quelques morceaux pr\u00e9f\u00e9r\u00e9s des fans.<\/p>\n<p> Ce single du groupe laur\u00e9at d&#039;un Grammy Award est un best-seller, mais le groupe a connu un succ\u00e8s bien plus important dans les classements des meilleures ventes d&#039;albums et d&#039;EP. <em>Soci\u00e9t\u00e9 officielle de classement<\/em> Qu&#039;il s&#039;agisse de hard rock, de m\u00e9tal ou simplement de rock, les groupes de rock ont consid\u00e9rablement am\u00e9lior\u00e9 leurs performances par rapport \u00e0 il y a quelques jours seulement, en sortant simultan\u00e9ment deux albums \u00e0 succ\u00e8s.<\/p>\n<h2> Metallica revient avec deux albums pl\u00e9biscit\u00e9s par les fans.<\/h2>\n<p> Cette semaine, deux albums \u00e0 succ\u00e8s de Metallica ont fait leur retour dans le classement officiel des albums rock et m\u00e9tal, et, co\u00efncidence, ils se sont retrouv\u00e9s c\u00f4te \u00e0 c\u00f4te. <em>album Ride the Lightning<\/em> Le groupe a fait son retour dans le classement \u00e0 la 36e place, et son album \u00e9ponyme a de nouveau occup\u00e9 la 37e position. Ces deux projets sont pr\u00e9sent\u00e9s ci-dessous. <em>Ma\u00eetre des marionnettes<\/em> , qui a perdu une place cette semaine, passant de la 24e \u00e0 la 25e place.<\/p>\n<h2> Album de Metallica \u00bb <em>Chevaucher l&#039;\u00e9clair \u00bb<\/em> Cent semaines se sont \u00e9coul\u00e9es.<\/h2>\n<p> Les trois albums de Metallica qui font leur entr\u00e9e cette semaine dans le classement officiel des albums rock et m\u00e9tal sont les plus grands succ\u00e8s du groupe et les trois seuls \u00e0 y \u00eatre rest\u00e9s plus de 100 semaines. <em>album Ride the Lightning<\/em> atteint ce seuil, r\u00e9apparaissant dans le classement pour la centi\u00e8me fois. <em>Ma\u00eetre des marionnettes<\/em> Elle compte d\u00e9sormais 182 entr\u00e9es dans les classements, et l&#039;album porte le m\u00eame nom. <em>Metallica<\/em> nettement en avance sur tous les autres. R\u00e9cemment <em>Metallica<\/em> Il est devenu l&#039;un des rares albums \u00e0 passer plus de 1 000 semaines dans les classements, et compte d\u00e9sormais 1 007 semaines en tant que meilleure vente de rock.<\/p>\n<p> Plusieurs autres compilations de Metallica ont failli entrer dans le club des 100 semaines, comme, <em>\u2026Et justice pour tous<\/em> \u0438 <em>Charger<\/em> , qui figurent sur la liste depuis respectivement 92 et 81 semaines, mais n&#039;ont pas encore r\u00e9ussi \u00e0 atteindre ce chiffre significatif.<\/p>\n<h2> Metallica Trails Only Pink Floyd<\/h2>\n<p> Cette semaine, Metallica occupe la deuxi\u00e8me place du classement officiel des albums rock et metal. Seul Pink Floyd surpasse les hard rockers avec cinq albums sur quarante. Le groupe l\u00e9gendaire continue de dominer le classement. <em>La face cach\u00e9e de la Lune<\/em> , <em>J&#039;aimerais que tu sois ici<\/em> , <em>Le mur<\/em> , <em>Animaux<\/em> \u0438 <em>En direct du Los Angeles Sports Arena<\/em> . <\/p>\n<p> Le groupe pop britannique Pink Floyd, (de gauche \u00e0 droite) Roger Waters, Nick Mason, Syd Barrett et Richard Wright. (Photo \u00a9 Hulton-Deutsch Collection\/CORBIS\/Corbis via Getty Images)<\/p>\n<p> Corbis via Getty Images<\/p>\n<p> Cinq groupes occupent la troisi\u00e8me place du classement des meilleures ventes d&#039;albums, juste derri\u00e8re Metallica, et cinq autres se partagent la premi\u00e8re place. Green Day, Linkin Park, My Chemical Romance, Nirvana et Paramore figurent chacun \u00e0 deux reprises dans ce classement rock.<\/p>\n<h2> Metallica compte 12 titres num\u00e9ro un et plusieurs autres num\u00e9ros un.<\/h2>\n<p> En plus de 30 ans d&#039;existence du classement officiel des albums rock et m\u00e9tal, Metallica a remport\u00e9 une douzaine de titres de champion. Cette liste comprend <em>Ma\u00eetre des marionnettes<\/em> , et <em>Metallica<\/em> . <em>Chevauchez la foudre<\/em> \u2014 l&#039;un des nombreux projets qui ont manqu\u00e9 la premi\u00e8re place d&#039;un seul rang. Avec EP <em>Le sentiment innomm\u00e9<\/em> \u0438 <em>Lulu<\/em> , un projet commun avec Lou Reed, il a atteint la deuxi\u00e8me place du classement.<\/p>\n<p> FORBES | Par Hugh McIntyre. L&#039;album classique de Metallica propulse le groupe vers des sommets in\u00e9gal\u00e9s.<\/p>\n<p> <em>Cet article a \u00e9t\u00e9 initialement publi\u00e9 sur Forbes.com.<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Il est extr\u00eamement rare de voir deux classements d\u00e9di\u00e9s \u00e0 la musique rock au Royaume-Uni \u2013 Official Rock &amp; Metal Albums et Official Rock &amp; Metal Singles \u2013 avec le nom de Metallica dessus\u2026.<\/p>","protected":false},"author":1,"featured_media":7252,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-7251","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-muzyka","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/7251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=7251"}],"version-history":[{"count":1,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/7251\/revisions"}],"predecessor-version":[{"id":151061,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/7251\/revisions\/151061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/7252"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=7251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=7251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=7251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}