{"id":7410,"date":"2026-06-02T18:10:49","date_gmt":"2026-06-02T15:10:49","guid":{"rendered":"http:\/\/imgist.ru\/trejler-filma-natisk-adria-arhona-igraet-snajpera-srazhayushhegosya-liczom-k-liczu-s-chelovecheskim-ekvivalentom-samonavodyashhejsya-rakety-v-novom-filme-adama-vingarda-dlya\/"},"modified":"2026-06-02T18:10:49","modified_gmt":"2026-06-02T15:10:49","slug":"adria-arona-incarne-une-tireuse-delite-qui-affronte-licence-contre-licence-avec-lequivalent-humain-dune-fusee-autopropulsee-dans-le-nouveau-film-dadam-wingard-pour-les-annees-1","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/trejler-filma-natisk-adria-arhona-igraet-snajpera-srazhayushhegosya-liczom-k-liczu-s-chelovecheskim-ekvivalentom-samonavodyashhejsya-rakety-v-novom-filme-adama-vingarda-dlya\/","title":{"rendered":"Bande-annonce d&#039;\u00ab Onslaught \u00bb : Adria Arjona incarne une tireuse d&#039;\u00e9lite qui affronte \u00ab l&#039;\u00e9quivalent humain d&#039;un missile \u00e0 t\u00eate chercheuse \u00bb dans le nouveau film d&#039;Adam Wingard pour A24."},"content":{"rendered":"<p>A24 a d\u00e9voil\u00e9 la premi\u00e8re bande-annonce du film. <em>\u00abAssaut<\/em> , un thriller d&#039;action du r\u00e9alisateur de films <em>\u00ab&quot;\u00c0 ton tour&quot;\u00bb<\/em> \u0438 <em>\u00abGodzilla contre Kong\u00bb<\/em> Adam Wingard, dont la premi\u00e8re en salles est pr\u00e9vue le vendredi 4 septembre.<\/p>\n<p> Dans le film &quot;\u00ab <em>Assaut&quot;\u00bb<\/em> Adria Arjona incarne une tireuse d&#039;\u00e9lite de l&#039;arm\u00e9e et m\u00e8re de famille vivant dans un parc de caravanes en plein d\u00e9sert, qui doit se battre pour prot\u00e9ger sa famille d&#039;une menace inattendue\u00a0: une escouade de supersoldats g\u00e9n\u00e9tiquement modifi\u00e9s l\u00e2ch\u00e9s depuis une base militaire voisine.<\/p>\n<p> <strong>Plus d&#039;actualit\u00e9s de Deadline<\/strong><\/p>\n<ul>\n<li>\n<p> Bande-annonce de \u00ab Je te retrouverai \u00bb : Sam Worthington prend la fuite dans une recherche d\u00e9sesp\u00e9r\u00e9e de son fils.<\/p>\n<\/li>\n<li>\n<p> Comment le film \u00ab Behind the Scenes \u00bb a fait sensation au box-office, engrangeant 118 millions de dollars lors de son premier week-end d&#039;exploitation \u2013 le meilleur score de l&#039;histoire d&#039;A24.<\/p>\n<\/li>\n<li>\n<p> HBO a publi\u00e9 la bande-annonce compl\u00e8te de la saison 3 de House of the Dragon.<\/p>\n<\/li>\n<\/ul>\n<p> La bande-annonce s&#039;ouvre sur Arjona s&#039;installant avec sa fille dans un campement d\u00e9sert, faisant tomber des citrouilles de leurs souches et admettant qu&#039;elle a enfin trouv\u00e9 un endroit o\u00f9 elle se sent en s\u00e9curit\u00e9.<\/p>\n<p> Plus tard, on voit des h\u00e9licopt\u00e8res Black Hawk survoler la zone les uns apr\u00e8s les autres.<\/p>\n<p> \u00ab Ils pr\u00e9parent quelque chose dans le d\u00e9sert au nord d&#039;ici \u00bb, dit Arkhona. \u00ab Une sorte de base secr\u00e8te ou quelque chose comme \u00e7a. \u00bb.<\/p>\n<p> Une voix en arri\u00e8re-plan d\u00e9clare : \u00ab Vous assistez \u00e0 la performance de l&#039;\u00e9quivalent humain d&#039;un missile \u00e0 t\u00eate chercheuse. Le soldat parfait. \u00bb.<\/p>\n<p> On voit plusieurs plans de supersoldats, le visage dissimul\u00e9 par des cagoules, puis le personnage interpr\u00e9t\u00e9 par Rebecca Hall explique : \u00ab Nous avons entrepris de cr\u00e9er le combattant parfait \u00e0 utiliser contre la population locale. Ces gens sont programm\u00e9s pour tuer jusqu&#039;\u00e0 ce qu&#039;on les arr\u00eate. \u00bb.<\/p>\n<p> Dans un autre \u00e9pisode, on voit un personnage aux cheveux d\u00e9color\u00e9s, interpr\u00e9t\u00e9 par Drew Starkey, qui semble avoir \u00e9t\u00e9 envoy\u00e9 pour nettoyer les d\u00e9g\u00e2ts caus\u00e9s par l&#039;arm\u00e9e.<\/p>\n<p> Le film \u00ab Onslaught \u00bb sort simultan\u00e9ment avec le thriller policier de Paramount \u00ab <em>Par tous les moyens n\u00e9cessaires<\/em> \u00bb&quot; avec Mark Wahlberg et Yahya Abdul-Mateen II, ainsi qu&#039;un film d&#039;horreur <em>\u00abCopain\u00bb<\/em> , pr\u00e9sent\u00e9 au Festival du film de Sundance, et le documentaire de Barbara Hammer \u00ab <em>Barbara pour toujours<\/em> \u00bb. <em>Dans le film<\/em> Avec \u00e9galement Dan Stevens, Eric Wareheim, Reginald VelJohnson, Michael Biehn et Alex Pereira.<\/p>\n<p> Wingard a r\u00e9alis\u00e9 le film d&#039;apr\u00e8s un sc\u00e9nario de Simon Barrett, bas\u00e9 sur une histoire qu&#039;ils ont co-cr\u00e9\u00e9e. Parmi les producteurs du projet figuraient Aaron Ryder, Andrew Swett, Wingard, Jeremy Platt, Alexander Black et Barrett.<\/p>\n<p> Visionnez la bande-annonce en cliquant sur le bouton ci-dessus.<\/p>\n<p> <strong>Le meilleur de Deadline<\/strong><\/p>\n<ul>\n<li>\n<p> Tout ce que nous savons jusqu&#039;\u00e0 pr\u00e9sent sur Toy Story 5.<\/p>\n<\/li>\n<li>\n<p> Quels romans d&#039;Emily Henry seront adapt\u00e9s \u00e0 l&#039;\u00e9cran\u00a0? \u00ab\u00a0The Happy Place\u00a0\u00bb, \u00ab\u00a0The Book Lovers\u00a0\u00bb, et d&#039;autres.<\/p>\n<\/li>\n<li>\n<p> Tout ce que nous savons jusqu&#039;\u00e0 pr\u00e9sent sur l&#039;adaptation cin\u00e9matographique du livre de plage d&#039;Emily Henry\u00ab<\/p>\n<\/li>\n<\/ul>\n<p> Abonnez-vous \u00e0 la newsletter Deadline. Pour les derni\u00e8res actualit\u00e9s, suivez-nous sur Facebook, Twitter et Instagram.<\/p>","protected":false},"excerpt":{"rendered":"<p>A24 a d\u00e9voil\u00e9 la premi\u00e8re bande-annonce d&#039;Onslaught, le thriller d&#039;action du r\u00e9alisateur de You&#039;re Next et Godzilla vs. Kong, Adam Wingard, dont la sortie est pr\u00e9vue en\u2026<\/p>","protected":false},"author":1,"featured_media":7411,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-7410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/7410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=7410"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/7410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/7411"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=7410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=7410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=7410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}