{"id":795,"date":"2026-05-29T19:35:35","date_gmt":"2026-05-29T16:35:35","guid":{"rendered":"https:\/\/imgist.ru\/dzhoj-behar-otvetila-na-zamechanie-belogo-doma-o-plohom-zdorove\/"},"modified":"2026-05-29T19:35:35","modified_gmt":"2026-05-29T16:35:35","slug":"joy-behar-a-repondu-au-message-de-la-maison-blanche-concernant-son-etat-de-sante-fragile","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/dzhoj-behar-otvetila-na-zamechanie-belogo-doma-o-plohom-zdorove\/","title":{"rendered":"Joy Behar a r\u00e9agi aux propos de la Maison Blanche concernant sa \u00ab mauvaise sant\u00e9 \u00bb."},"content":{"rendered":"<p>Les pr\u00e9sentatrices de l&#039;\u00e9mission The View ont r\u00e9agi aux critiques de la Maison Blanche concernant <strong>Joy Behar<\/strong> , Elle a ensuite clarifi\u00e9 ses propos. Une publication r\u00e9cente de Rapid Response 47 sur X pr\u00e9sentait une image de Behar, les yeux ferm\u00e9s, encadr\u00e9e par la l\u00e9gende\u00a0: \u00ab\u00a0Waouh\u00a0! Mauvaise sant\u00e9\u00a0?\u00a0\u00bb<\/p>\n<h2> Joy Behar a r\u00e9agi aux attaques de la Maison Blanche concernant sa \u00ab mauvaise sant\u00e9 \u00bb lors d&#039;un r\u00e9cent \u00e9pisode de l&#039;\u00e9mission \u00ab The View \u00bb. <\/h2>\n<p> Dans le podcast \u00ab Behind the Table \u00bb de l&#039;\u00e9mission The View, diffus\u00e9 le 27 mai, l&#039;animatrice Whoopi Goldberg a critiqu\u00e9 Donald Trump qui, selon la Maison Blanche, s&#039;\u00e9tait r\u00e9cemment rendu au centre m\u00e9dical militaire national Walter Reed pour des examens m\u00e9dicaux et dentaires de routine.<\/p>\n<p> La laur\u00e9ate des EGOT a d\u00e9clar\u00e9 : \u00ab La Maison Blanche maintient que Celui-Dont-On-Ne-Doit-Pas-Prononcer-Le-Nom est en excellente sant\u00e9. Ils se sont aussi d\u00e9cha\u00een\u00e9s sur les r\u00e9seaux sociaux, publiant des captures d&#039;\u00e9cran de journalistes les yeux ferm\u00e9s avec des l\u00e9gendes affirmant qu&#039;ils dormaient et devaient \u00eatre malades. \u00bb Elle a ajout\u00e9 : \u00ab Ils t&#039;ont aussi post\u00e9e, Joy. \u00bb Behar, qui s&#039;absente temporairement de la pr\u00e9sentation de \u00ab The View \u00bb, a rapidement r\u00e9pondu : \u00ab Ils devaient diffuser une de ses vid\u00e9os \u00bb, avant de se d\u00e9fendre : \u00ab Ce n&#039;est pas parce que tes paupi\u00e8res sont lourdes que tu dors. \u00bb. <\/p>\n<p> Selon le Hollywood Reporter, en juillet 2025, la Maison-Blanche a critiqu\u00e9 Joy Behar apr\u00e8s qu&#039;elle a affirm\u00e9 que Trump \u00e9tait \u00ab jaloux \u00bb de l&#039;ancien pr\u00e9sident Barack Obama. La porte-parole de la Maison-Blanche, Taylor Rogers, a alors r\u00e9pondu : \u00ab Joy Behar est une rat\u00e9e sans valeur, atteinte d&#039;une haine visc\u00e9rale envers Trump. Pas \u00e9tonnant que les audiences de The View aient chut\u00e9 \u00e0 des niveaux records l&#039;an dernier. Elle ferait bien de r\u00e9fl\u00e9chir \u00e0 sa jalousie envers la popularit\u00e9 historique du pr\u00e9sident Trump avant que son \u00e9mission ne soit la prochaine \u00e0 \u00eatre annul\u00e9e. \u00bb.<\/p>\n<p> <strong>DITES-NOUS CE QUE VOUS PENSEZ DE CETTE R\u00c9PONSE\u00a0?<\/strong><\/p>\n<p> L&#039;article original a \u00e9t\u00e9 publi\u00e9 par Meenakshi Sengupta sur le site web Reality Tea.<\/p>\n<p> L\u2019article \u00ab Joy Behar r\u00e9pond aux propos de la Maison Blanche sur sa \u00ab mauvaise sant\u00e9 \u00bb \u00bb est paru initialement sur Mandatory. .<\/p>","protected":false},"excerpt":{"rendered":"<p>Les animatrices de l&#039;\u00e9mission The View ont r\u00e9agi aux critiques de la Maison-Blanche \u00e0 l&#039;encontre de Joy Behar, et cette derni\u00e8re a clarifi\u00e9 ses propos. Dans une r\u00e9cente s\u00e9quence de r\u00e9ponse rapide (47 minutes)\u2026<\/p>","protected":false},"author":1,"featured_media":796,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=795"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/795\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/796"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}