{"id":98956,"date":"2023-02-05T00:00:00","date_gmt":"2023-02-04T22:00:00","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/10-prostyx-izobretenij-izmenivshix-mir\/"},"modified":"2026-08-24T13:30:52","modified_gmt":"2026-08-24T10:30:52","slug":"10-inventions-simples-qui-ont-change-le-monde","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/10-prostyx-izobretenij-izmenivshix-mir\/","title":{"rendered":"10 inventions simples qui ont chang\u00e9 le monde"},"content":{"rendered":"<div readability=\"231.35660323228\">\n<p><span>On a tendance \u00e0 croire que les innovations majeures, capables de transformer le monde, n\u00e9cessitent une ing\u00e9nierie complexe et d&#039;importants efforts scientifiques, mais ce n&#039;est pas toujours le cas. Parfois, de simples am\u00e9liorations, comme les roulements \u00e0 billes et le fil de fer barbel\u00e9, ont eu un impact profond sur l&#039;histoire de l&#039;humanit\u00e9, menant souvent directement aux prouesses d&#039;ing\u00e9nierie que nous connaissons aujourd&#039;hui.<\/span><\/p>\n<h2> 10. Fil de fer barbel\u00e9 <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-72785\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0c6eff4a.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>L&#039;histoire du fil de fer barbel\u00e9 moderne remonte \u00e0 un homme d&#039;affaires et inventeur am\u00e9ricain.<\/span> <span>Joseph Glidden<\/span> <span>. Son invention \u00e0 deux brins, brevet\u00e9e en 1874, a r\u00e9volutionn\u00e9 la construction de cl\u00f4tures et autres enclos dans le monde entier, notamment en Am\u00e9rique, permettant une couverture plus \u00e9tendue qu&#039;auparavant. Avant son invention, les agriculteurs et les \u00e9leveurs devaient utiliser des cl\u00f4tures en bois ou des murs en pierre pour d\u00e9limiter leurs terres, une solution soit inefficace, soit longue et co\u00fbteuse.<\/span><\/p>\n<p> <span>Le fil de fer barbel\u00e9 a eu un impact profond sur la colonisation de l&#039;Am\u00e9rique, notamment sur la conqu\u00eate de l&#039;Ouest. Il a permis de diviser de vastes \u00e9tendues de terre en unit\u00e9s plus petites et plus faciles \u00e0 g\u00e9rer, permettant ainsi aux colons de mieux prot\u00e9ger leurs r\u00e9coltes et leur b\u00e9tail. Cela a contribu\u00e9 \u00e0 acc\u00e9l\u00e9rer l&#039;expansion de la fronti\u00e8re ouest, facilitant l&#039;\u00e9tablissement de fermes et de ranchs dans des r\u00e9gions recul\u00e9es, ce qui a entra\u00een\u00e9 une expansion \u00e9conomique et territoriale. Il est devenu beaucoup plus facile de d\u00e9finir et d&#039;appliquer les lois relatives \u00e0 la propri\u00e9t\u00e9 et aux cl\u00f4tures, car l&#039;\u00c9tat<\/span> <span>\u00e9tait<\/span> <span>largement incapables de le faire dans les zones frontali\u00e8res plus recul\u00e9es.<\/span><\/p>\n<h2> 9. \u00c9clairs <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-82825\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0c7ad1c9.jpeg\" alt=\"\" width=\"640\" height=\"428\"><\/p>\n<p> <span>Bien que les fus\u00e9es de signalisation soient utilis\u00e9es depuis longtemps pour la navigation et d&#039;autres usages, la fus\u00e9e de signalisation moderne a \u00e9t\u00e9 invent\u00e9e par une femme d&#039;affaires et inventrice nomm\u00e9e Martha Coston. Brevet\u00e9 en 1859, le prototype \u00e9tait bas\u00e9 sur un mod\u00e8le l\u00e9gu\u00e9 par son p\u00e8re.<\/span> <span>mari<\/span> <span>. Les flashs Coston \u00e9taient fabriqu\u00e9s \u00e0 partir de tubes de papier color\u00e9 remplis de produits chimiques qui produisaient un flash lorsqu&#039;ils \u00e9taient d\u00e9clench\u00e9s.<\/span> <span>brillant<\/span> <span>, des flashs color\u00e9s, am\u00e9liorant consid\u00e9rablement leurs pr\u00e9d\u00e9cesseurs en termes de durabilit\u00e9 et de luminosit\u00e9.<\/span><\/p>\n<p> <span>Cette invention joua par la suite un r\u00f4le important dans la guerre de S\u00e9cession am\u00e9ricaine, car elle s&#039;av\u00e9ra tr\u00e8s utile pour la communication entre les navires, le signalement des positions ennemies et une meilleure coordination des strat\u00e9gies de combat \u00e0 longue distance, notamment lors des batailles nocturnes. M\u00eame pendant<\/span> <span>guerres mondiales<\/span> <span>Les fus\u00e9es \u00e9clairantes se sont r\u00e9v\u00e9l\u00e9es \u00eatre un outil important pour tous les camps, offrant un moyen simple mais efficace d&#039;envoyer des messages aux unit\u00e9s alli\u00e9es. Aujourd&#039;hui, elles restent essentielles pour les services d&#039;urgence et<\/span> <span>recherche et sauvetage<\/span> <span>services.<\/span><\/p>\n<h2> 8. Roulement \u00e0 billes <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-82826\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0c87383b.jpeg\" alt=\"\" width=\"640\" height=\"396\"><\/p>\n<p> <span>Les roulements \u00e0 billes sont un type de roulement qui utilise de petites billes sph\u00e9riques pour r\u00e9duire la friction entre les pi\u00e8ces en rotation. Ce concept remonte au moins \u00e0\u2026<\/span> <span>\u00c9gypte antique<\/span> <span>, bien que seulement avec l&#039;invention de Bessemer<\/span> <span>processus<\/span> <span>Au milieu du XIXe si\u00e8cle, le v\u00e9lo pouvait \u00eatre produit en s\u00e9rie et utilis\u00e9 dans de nombreuses applications. Si le proc\u00e9d\u00e9 Bessemer permettait de produire de l&#039;acier de haute qualit\u00e9 de mani\u00e8re plus \u00e9conomique et efficace, le v\u00e9lo est devenu la premi\u00e8re application concr\u00e8te et produite en masse de cette technologie.<\/span><\/p>\n<p> <span>Cette invention a permis aux ing\u00e9nieurs de r\u00e9duire consid\u00e9rablement le frottement et l&#039;usure des pi\u00e8ces rotatives, augmentant ainsi significativement la fiabilit\u00e9 et la durabilit\u00e9 des machines industrielles. Les roulements \u00e0 billes ont \u00e9galement permis la cr\u00e9ation de machines plus petites et plus compactes, car ils occupent moins d&#039;espace et p\u00e8sent moins que les roulements traditionnels. Aujourd&#039;hui, il est impossible de fabriquer une turbine qui reste sur son axe sans des roulements sph\u00e9riques quasi parfaits, car ils sont utilis\u00e9s dans une grande vari\u00e9t\u00e9 d&#039;appareils, des simples appareils m\u00e9nagers aux \u00e9quipements militaires lourds.<\/span><\/p>\n<h2> 7. P\u00e9nicilline <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-82827\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0c6386f7.jpeg\" alt=\"\" width=\"640\" height=\"428\"><\/p>\n<p> <span>28 septembre 1928<\/span> <span>\u00e9cossais<\/span> <span>Le microbiologiste Alexander Fleming a fait l&#039;une des d\u00e9couvertes les plus importantes de l&#039;histoire de la m\u00e9decine. Alors qu&#039;il menait des exp\u00e9riences sur le virus de la grippe, il remarqua que l&#039;une de ses bo\u00eetes de Petri \u00e9tait contamin\u00e9e par une moisissure qui inhibait la croissance des bact\u00e9ries qu&#039;il \u00e9tudiait. C&#039;est ainsi que Fleming d\u00e9couvrit, par hasard, un champignon appel\u00e9 Penicillium.<\/span><\/p>\n<p> <span>\u00c0 partir de l\u00e0, il synth\u00e9tisa l&#039;antibiotique que nous connaissons aujourd&#039;hui sous le nom de p\u00e9nicilline, qui a depuis eu un impact consid\u00e9rable sur la vie moderne, notamment pendant<\/span> <span>guerres<\/span> <span>. De la Seconde Guerre mondiale \u00e0 la r\u00e9cente guerre d&#039;Irak, la p\u00e9nicilline a sauv\u00e9 d&#039;innombrables vies en soignant des blessures qui auraient autrement \u00e9t\u00e9 mortelles. Avant sa d\u00e9couverte, les infections bact\u00e9riennes telles que la pneumonie \u00e9taient souvent fatales et difficiles \u00e0 traiter. Aujourd&#039;hui, c&#039;est l&#039;antibiotique le plus utilis\u00e9 au monde, r\u00e9duisant la mortalit\u00e9 et am\u00e9liorant la qualit\u00e9 de vie de millions de personnes.<\/span><\/p>\n<h2> 6. Lancer des objets <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-82828\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0c96a609.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>Au cours de l&#039;\u00e9volution humaine, le lancer d&#039;objets est apparu il y a environ deux millions d&#039;ann\u00e9es. Cette capacit\u00e9 a conf\u00e9r\u00e9 aux premiers humains un avantage d\u00e9cisif pour leur survie, leur permettant d&#039;acc\u00e9der \u00e0 des sources de nourriture nouvelles et plus abondantes. Les premiers projectiles \u00e9taient probablement des pierres, facilement disponibles et pouvant \u00eatre ramass\u00e9es et lanc\u00e9es avec pr\u00e9cision. L&#039;invention et le perfectionnement de la lance n&#039;\u00e9taient qu&#039;une question de temps, inaugurant une \u00e9tape enti\u00e8rement nouvelle de l&#039;\u00e9volution et du d\u00e9veloppement humains.<\/span><\/p>\n<p> <span>L&#039;\u00e9volution du javelot a directement entra\u00een\u00e9 un certain nombre de changements importants dans le corps humain, notamment dans la taille et la forme de l&#039;homme<\/span> <span>\u00e9paule<\/span> <span>, ce qui a permis de rationaliser le processus et d&#039;accro\u00eetre la vitesse et la pr\u00e9cision des lancers. Cela a eu d&#039;autres cons\u00e9quences sociales et culturelles importantes, comme d\u00e8s le d\u00e9but.<\/span> <span>chasse<\/span> <span>comment l&#039;activit\u00e9 coop\u00e9rative a procur\u00e9 aux premiers humains un sentiment de s\u00e9curit\u00e9 et de contr\u00f4le sur leur environnement, permettant ainsi une expansion et une conqu\u00eate accrues.<\/span><\/p>\n<h2> 5. Transistor <\/h2>\n<\/p>\n<p> <span>Les transistors ont \u00e9t\u00e9 invent\u00e9s en 1947 par John Bardeen, Walter Brattain et William Shockley aux laboratoires Bell Telephone de Murray Hill, dans le New Jersey. Ce fut la premi\u00e8re \u00e9tape majeure de la miniaturisation de l&#039;\u00e9lectronique, les transistors rempla\u00e7ant les composants \u00e9lectroniques volumineux.<\/span> <span>tubes \u00e0 vide<\/span> <span>Des appareils plus petits, plus efficaces et plus fiables.<\/span><\/p>\n<p> <span>Il a r\u00e9volutionn\u00e9 le monde de l&#039;\u00e9lectronique, ouvrant la voie au d\u00e9veloppement des industries modernes de l&#039;informatique et des semi-conducteurs. Les transistors ont permis aux ing\u00e9nieurs de concevoir des dispositifs capables d&#039;accomplir les m\u00eames fonctions que des machines beaucoup plus volumineuses, donnant naissance \u00e0 des appareils \u00e9lectroniques plus petits, plus rapides et bien plus puissants. Aujourd&#039;hui, des versions am\u00e9lior\u00e9es et modernes des transistors\u2026,<\/span> <span>tel que<\/span> <span>Les circuits int\u00e9gr\u00e9s et les microprocesseurs jouent un r\u00f4le fondamental dans la plupart de nos appareils du quotidien.<\/span><\/p>\n<h2> 4. Fusil \u00e0 magasin <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-82829\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0ca5fe67.jpeg\" alt=\"\" width=\"640\" height=\"393\"><\/p>\n<p> <span>\u00c0<\/span> <span>Avant l&#039;invention des fusils \u00e0 r\u00e9p\u00e9tition, les armes \u00e0 feu avaient une cadence de tir limit\u00e9e et n\u00e9cessitaient d&#039;\u00eatre recharg\u00e9es apr\u00e8s chaque coup, ce qui r\u00e9duisait consid\u00e9rablement leur efficacit\u00e9 au combat. L&#039;arriv\u00e9e des premiers prototypes de fusils \u00e0 r\u00e9p\u00e9tition changea la donne, permettant aux soldats de tirer plusieurs coups en succession rapide. Les premiers fusils \u00e0 r\u00e9p\u00e9tition furent invent\u00e9s au milieu du XIXe si\u00e8cle, et le c\u00e9l\u00e8bre<\/span> <span>Fusil Henry<\/span> <span>Il est devenu le premier prototype fonctionnel qui a fait la diff\u00e9rence sur le champ de bataille.<\/span><\/p>\n<p> <span>Les armes \u00e0 r\u00e9p\u00e9tition ont fondamentalement transform\u00e9 la guerre du d\u00e9but de l&#039;\u00e8re moderne, devenant l&#039;arme la plus meurtri\u00e8re qu&#039;un combattant puisse manier. Il \u00e9tait d\u00e9sormais possible d&#039;engager plusieurs ennemis \u00e0 une distance bien plus grande qu&#039;auparavant, ce qui a eu un impact consid\u00e9rable sur les tactiques.<\/span> <span>\u0438<\/span> <span>Strat\u00e9gie de l&#039;\u00e9poque. L&#039;augmentation de la puissance de feu permettait \u00e9galement de gagner les batailles plus rapidement, r\u00e9duisant ainsi les pertes et la dur\u00e9e des combats.<\/span><\/p>\n<h2> 3. Levier <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-82830\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0cb53f39.jpeg\" alt=\"\" width=\"640\" height=\"428\"><\/p>\n<p> <span>En substance, un levier est un m\u00e9canisme simple compos\u00e9 d&#039;une poutre ou d&#039;une tige droite qui pivote autour d&#039;un point fixe appel\u00e9 pivot.<\/span> <span>supports<\/span> <span>. Cela permet d&#039;accro\u00eetre l&#039;effet de levier de diverses mani\u00e8res, autorisant ainsi \u00e0 soulever des objets tr\u00e8s lourds avec un effort consid\u00e9rablement r\u00e9duit. Bien que l&#039;on ignore la date exacte de son invention, le levier a \u00e9t\u00e9 d\u00e9crit math\u00e9matiquement pour la premi\u00e8re fois par Archim\u00e8de. Apparemment, il en fut tellement impressionn\u00e9 que\u2026<\/span> <span>dit<\/span> <span>\u00abDonnez-moi un point d&#039;appui et je soul\u00e8verai le monde avec un levier\u00bb, m\u00eame si c&#039;\u00e9tait peut-\u00eatre un peu exag\u00e9r\u00e9.<\/span><\/p>\n<p> <span>Cependant, il est difficile de surestimer l&#039;importance du simple levier, notamment dans la construction des premi\u00e8res civilisations telles que<\/span> <span>Egypte<\/span> <span>et en Gr\u00e8ce. Cela nous a permis de construire des structures plus grandes et plus complexes, comme les pyramides et les aqueducs, car il est soudainement devenu possible de d\u00e9placer facilement de lourdes pierres et autres mat\u00e9riaux de construction. Aujourd&#039;hui, des syst\u00e8mes de leviers sophistiqu\u00e9s sont utilis\u00e9s dans presque tous les aspects de notre vie, des simples outils m\u00e9nagers comme les ouvre-bo\u00eetes et les pinces aux machines complexes comme les grues et les engins de terrassement.<\/span><\/p>\n<h2> 2. La voile <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-79588\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0cc2d208.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Nous utilisons les voiles comme moyen de transport tout au long du trajet.<\/span> <span>mill\u00e9naires<\/span> <span>, M\u00eame s&#039;il est difficile de d\u00e9terminer avec pr\u00e9cision qui les a invent\u00e9es en premier, les voiles ont permis pour la premi\u00e8re fois aux navires d&#039;exploiter la force du vent, leur permettant ainsi de parcourir des distances bien plus grandes qu&#039;avec les seules rames.<\/span><\/p>\n<p> <span>Bien qu&#039;il ne s&#039;agisse pas d&#039;une machine complexe, cette simple am\u00e9lioration a r\u00e9volutionn\u00e9 la navigation maritime, rendant possible le commerce avec des colonies \u00e9loign\u00e9es. L&#039;utilisation des voiles a \u00e9galement permis aux navires de naviguer contre le vent, ouvrant ainsi la voie \u00e0 des terres enti\u00e8rement nouvelles pour le commerce ou la conqu\u00eate. Gr\u00e2ce \u00e0 la navigation, les premi\u00e8res civilisations ont pu explorer de nouvelles terres et s&#039;\u00e9tablir.<\/span> <span>routes commerciales<\/span> <span>et interagir avec de nouvelles cultures qu&#039;ils n&#039;avaient jamais connues, ce qui a conduit au d\u00e9veloppement d&#039;\u00e9conomies et de cultures plus complexes \u00e0 travers le monde.<\/span><\/p>\n<h2> 1. Billets de banque <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-82105\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-prostyx-izobretenij-izmenivshix-mir_640ba0cd015ed.jpeg\" alt=\"\" width=\"640\" height=\"419\"><\/p>\n<p> <span>Bien que le papier-monnaie ait d\u00e9j\u00e0 \u00e9t\u00e9 utilis\u00e9 dans de nombreuses r\u00e9gions du monde, ce n&#039;est qu&#039;en Europe, pendant les croisades, qu&#039;il devint v\u00e9ritablement monnaie courante.<\/span> <span>randonn\u00e9es<\/span> <span>Ce syst\u00e8me devint r\u00e9alit\u00e9. Les arm\u00e9es et les marchands europ\u00e9ens avaient besoin d&#039;un moyen de transporter d&#039;importantes sommes d&#039;argent sans \u00eatre encombr\u00e9s par le poids des pi\u00e8ces de monnaie, ce qui conduisit \u00e0 l&#039;apparition des premi\u00e8res formes de monnaie papier moderne, appel\u00e9es lettres de change.<\/span><\/p>\n<p> <span>Cette pratique se r\u00e9pandit rapidement en Europe et outre-Atlantique, l&#039;introduction du papier-monnaie jouant un r\u00f4le important dans la colonisation des Am\u00e9riques. \u00c0 l&#039;\u00e9poque, le transport entre l&#039;Europe et l&#039;Am\u00e9rique du Nord \u00e9tait long et fastidieux, engendrant une p\u00e9nurie constante de liquidit\u00e9s parmi les colons et les marchands. Le papier-monnaie leur permit d&#039;acc\u00e9der aux capitaux n\u00e9cessaires au financement de leurs projets sans avoir \u00e0 transporter de grandes quantit\u00e9s de pi\u00e8ces de m\u00e9taux pr\u00e9cieux \u00e0 travers l&#039;Atlantique. Il facilita \u00e9galement les \u00e9changes commerciaux des marchands europ\u00e9ens avec les populations autochtones et les autres colonies europ\u00e9ennes des Am\u00e9riques, car il \u00e9tait beaucoup plus facile \u00e0 transporter et moins susceptible d&#039;\u00eatre perdu ou vol\u00e9 que les formes de monnaie pr\u00e9c\u00e9dentes.<\/span> <span>devises<\/span> <span>.<\/span><\/p>\n<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>On a tendance \u00e0 penser que les innovations majeures, capables de transformer le monde, n\u00e9cessitent une ing\u00e9nierie complexe et d&#039;importants efforts scientifiques, mais ce n&#039;est pas toujours le cas. Parfois, de simples am\u00e9liorations, comme\u2026<\/p>","protected":false},"author":1,"featured_media":7520,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-98956","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/98956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=98956"}],"version-history":[{"count":1,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/98956\/revisions"}],"predecessor-version":[{"id":138307,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/98956\/revisions\/138307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/7520"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=98956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=98956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=98956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}