{"id":99157,"date":"2022-06-05T00:00:00","date_gmt":"2022-06-04T21:00:00","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/10-samyx-malenkix-veshhej-kogda-libo-sozdannyx\/"},"modified":"2026-08-24T13:32:07","modified_gmt":"2026-08-24T10:32:07","slug":"10-samyx-malenkix-veshhej-kogda-libo-sozdannyx","status":"publish","type":"post","link":"https:\/\/imgist.ru\/fr\/10-samyx-malenkix-veshhej-kogda-libo-sozdannyx\/","title":{"rendered":"Les 10 plus petites choses jamais cr\u00e9\u00e9es"},"content":{"rendered":"<div readability=\"247.3168191287\">\n<p><span>Longtemps, la qu\u00eate de grandeur a fascin\u00e9 le monde. C&#039;est encore le cas, \u00e0 bien des \u00e9gards. Il suffit de contempler l&#039;immense gratte-ciel Burj Khalifa \u00e0 Duba\u00ef, culminant \u00e0 828 m\u00e8tres. Le monde est fascin\u00e9 par le gigantisme. Mais l&#039;extr\u00eame miniaturisation fascine tout autant. Plus un objet est petit, plus il devient captivant. Et si, malgr\u00e9 sa taille r\u00e9duite, il fonctionne, au moins en th\u00e9orie, c&#039;est encore plus extraordinaire. De plus, les implications pour des domaines aussi vari\u00e9s que la sant\u00e9, l&#039;\u00e9lectronique et l&#039;informatique sont consid\u00e9rables. Plus les alimentations et les dispositifs de stockage de donn\u00e9es, par exemple, seront miniaturis\u00e9s, plus les ordinateurs du futur seront performants, puissants et rapides. D\u00e9couvrons dix des cr\u00e9ations les plus petites et les plus \u00e9tonnantes jamais r\u00e9alis\u00e9es.<\/span><\/p>\n<h2> <span>Les 10 plus petits avions du monde<\/span> <\/h2>\n<\/p>\n<p> <span>Stratolaunch<\/span> <span>\u2014 le plus grand avion jamais construit<\/span> <span>.<\/span> <span>Con\u00e7u pour lancer des fus\u00e9es, son envergure \u00e9tait de 117 m\u00e8tres. C&#039;est consid\u00e9rable et cela montre qu&#039;il est possible de construire des avions plus grands si l&#039;on ma\u00eetrise les aspects techniques. Alors, quelle est la taille minimale acceptable pour un avion\u00a0?<\/span><\/p>\n<p> <span>En 1952, Ray Stits cr\u00e9a ce qui fut pendant de nombreuses ann\u00e9es le plus petit avion fonctionnel jamais construit. Surnomm\u00e9 le Sky Baby, il avait une envergure de 2,18 m\u00e8tres et une longueur de 3 m\u00e8tres. Il conserva le record du plus petit avion jusqu&#039;en 1984, date \u00e0 laquelle le fils de Ray, Don, lui ravit le titre en cr\u00e9ant\u2026<\/span> <span>B\u00e9b\u00e9 oiseau<\/span> <span>. Son envergure \u00e9tait de 1,90 m\u00e8tre et son poids de plus de 90 kilos. <em>moins<\/em> , que l&#039;avion de son p\u00e8re. Il d\u00e9tient toujours le record du monde du plus petit monoplan.<\/span><\/p>\n<p> <span>Pour ne pas \u00eatre en reste, Robert Starr aida Stits p\u00e8re \u00e0 construire le Sky Baby, mais estimant ne pas recevoir la reconnaissance qu&#039;il m\u00e9ritait, il construisit son propre avion, le Bumblebee. Il fut achev\u00e9 en 1984, juste \u00e0 temps pour que le Baby Bird batte le record du monde. Starr se remit alors \u00e0 la planche \u00e0 dessin et<\/span> <span>Bumblebee II<\/span> <span>.<\/span><\/p>\n<p> <span>Le Bumblebee \u00e9tant un biplan, il d\u00e9tient le record du plus petit avion jamais construit. Son envergure n&#039;\u00e9tait que de 1,68 m\u00e8tre et Starr le pilotait lui-m\u00eame.<\/span><\/p>\n<h2> <span>9. Le plus petit pistolet du monde<\/span> <\/h2>\n<\/p>\n<p> <span>Bien que ce ne soit pas toujours le cas, on suppose g\u00e9n\u00e9ralement que plus une arme est grosse, plus elle est puissante. Il y a certes une certaine marge de man\u0153uvre en termes de munitions, de diam\u00e8tre du canon, etc. Mais un revolver \u00e0 canon court ne fera pas les m\u00eames d\u00e9g\u00e2ts qu&#039;une carabine de chasse de gros calibre. Un pistolet plus petit aura un calibre inf\u00e9rieur, utilisera des balles plus petites et infligera probablement moins de d\u00e9g\u00e2ts. Et \u00e0 un certain point, un pistolet peut devenir si petit qu&#039;on peut se demander comment il peut encore \u00eatre efficace. C&#039;est le cas du<\/span> <span>Minigun suisse C1ST<\/span> <span>.<\/span><\/p>\n<p> <span>Mesurant \u00e0 peine cinq centim\u00e8tres de long et pesant moins de 30 grammes, ce pistolet est parfaitement capable de tirer des munitions de 2,34 mm. Son canon mesure moins de 2,5 centim\u00e8tres et l&#039;arme est de facto interdite aux \u00c9tats-Unis car elle est apparemment trop facile \u00e0 dissimuler.<\/span><\/p>\n<p> <span>L&#039;entreprise produit environ 100 pi\u00e8ces par an, principalement des mod\u00e8les sur mesure, car leur fabrication artisanale, rigoureusement contr\u00f4l\u00e9e, garantit leur bon fonctionnement et leur s\u00e9curit\u00e9. Leur prix d\u00e9passe les 6\u00a0000\u00a0$ (il est possible d&#039;en acqu\u00e9rir un en or 18 carats, pour un prix encore plus \u00e9lev\u00e9).<\/span><\/p>\n<p> <span>Une balle de calibre 9 mm volera \u00e0 une vitesse d&#039;environ<\/span> <span>370 m\u00e8tres par seconde<\/span> <span>. Cela repr\u00e9sente plus de 1\u00a0200 pieds par seconde. Le SwissMiniGun tire \u00e0 environ<\/span> <span>400 pieds par seconde<\/span> <span>, De ce fait, sa puissance globale est, de toute \u00e9vidence, bien moins impressionnante. Son pouvoir de p\u00e9n\u00e9tration est inf\u00e9rieur \u00e0 un pied-livre, et il est peu probable, bien que possible, qu&#039;il puisse m\u00eame percer votre \u0153il.<\/span><\/p>\n<h2> <span>8. Les plus petits disques durs du monde<\/span> <\/h2>\n<\/p>\n<p> <span>L&#039;informatique est un domaine o\u00f9 l&#039;on cherche constamment \u00e0 r\u00e9duire la taille des appareils. Plus de m\u00e9moire, plus de vitesse, moins d&#039;espace\u00a0: c&#039;est ce que tout le monde souhaite. Pour y parvenir efficacement, il nous faut des disques durs toujours plus petits.<\/span> <span>le plus petit de cela<\/span> <span>, Nous avons pu produire des disques durs Toshiba de 2 Go et 4 Go.<\/span> <span>seulement 0,85 pouce<\/span> <span>.<\/span><\/p>\n<p> <span>Il convient de noter que ce disque dur est le plus petit disque dur pratique pouvant \u00eatre utilis\u00e9 et install\u00e9 dans un ordinateur. Cependant, en 2017, IBM a commercialis\u00e9 un disque dur techniquement plus petit. Un seul bit de donn\u00e9es \u00e9tait stock\u00e9 sur une surface magn\u00e9tique mesurant seulement\u2026<\/span> <span>1 atom<\/span> <span>. \u00c0 proprement parler, cela en fait le plus petit disque dur qui sera probablement jamais cr\u00e9\u00e9.<\/span><\/p>\n<h2> <span>7. Lunettes 3D de la taille d&#039;une mante religieuse<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81849\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-samyx-malenkix-veshhej-kogda-libo-sozdannyx_64107b5ac2178.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Savez-vous comment nous percevons le monde en trois dimensions\u00a0? Le m\u00e9canisme exact est difficile \u00e0 expliquer et encore plus difficile \u00e0 reproduire. Par exemple, comment faire voir un robot en trois dimensions\u00a0? Ou cr\u00e9er des yeux artificiels pour les humains capables de percevoir la profondeur\u00a0?<\/span><\/p>\n<p> <span>Des scientifiques \u00e9tudiant le fonctionnement de la vision 3D l&#039;ont \u00e9tudi\u00e9e chez les mantes religieuses. Pour ce faire, ils ont d\u00fb fabriquer de minuscules dispositifs.<\/span> <span>lunettes 3D<\/span> de la taille d&#039;une mante religieuse <span>. Pourquoi les mantes religieuses ? Ce sont les seuls invert\u00e9br\u00e9s connus capables de<\/span> <span>voir les choses en 3D<\/span> <span>. Leur fa\u00e7on de faire diff\u00e8re de la n\u00f4tre. Les mantes religieuses se concentrent uniquement sur le mouvement\u00a0; ce qu\u2019elles voient importe moins que le fait de percevoir le mouvement. Cette d\u00e9couverte pourrait contribuer au d\u00e9veloppement de la vision 3D en robotique et en intelligence artificielle.<\/span><\/p>\n<h2> <span>6. Nano Bible<\/span> <\/h2>\n<\/p>\n<p> <span>Il existe actuellement plusieurs centaines de versions de la Bible dans le monde, mais elles ont toutes en commun d&#039;\u00eatre g\u00e9n\u00e9ralement assez grandes pour \u00eatre lues \u00e0 l&#039;\u0153il nu. Ce n&#039;est pas le cas de<\/span> <span>Nano-Bibles<\/span> <span>. La Bible contient 1,2 million de mots, et les scientifiques sont parvenus \u00e0 les faire tenir tous dans une Bible de la taille de<\/span> <span>0,04 millim\u00e8tre carr\u00e9<\/span> <span>.<\/span><\/p>\n<p> <span>Bien qu&#039;elle ressemble \u00e0 un grain de poussi\u00e8re et se glisse facilement sur un stylo, il s&#039;agit en r\u00e9alit\u00e9 d&#039;une puce de silicium plaqu\u00e9e or. Chaque mot a \u00e9t\u00e9 \u00e9crit \u00e0 l&#039;aide d&#039;un g\u00e9n\u00e9rateur de faisceau d&#039;ions focalis\u00e9, qui a bombard\u00e9 la surface dor\u00e9e d&#039;ions gallium, cr\u00e9ant ainsi la calligraphie la plus fine et la plus minuscule jamais vue. La couche de silicium sur laquelle elle est imprim\u00e9e a une \u00e9paisseur inf\u00e9rieure \u00e0 100 atomes. Pour la lire, le texte doit \u00eatre grossi 10\u00a0000 fois.<\/span><\/p>\n<h2> <span>5. La plus petite batterie du monde<\/span> <\/h2>\n<\/p>\n<p> <span>De nos jours, peu d&#039;objets n\u00e9cessitent des piles D, mais si vous vous souvenez de les avoir utilis\u00e9es, ou si vous poss\u00e9dez encore quelques appareils qui en fonctionnent, vous savez \u00e0 quel point elles \u00e9taient volumineuses et encombrantes. La r\u00e9duction du nombre de piles a permis de rendre les appareils beaucoup plus petits, plus l\u00e9gers et plus portables. Mais ce processus se poursuit, et les piles ont encore une marge de miniaturisation importante. Par exemple, des scientifiques sont parvenus \u00e0 cr\u00e9er une pile fonctionnelle de la taille de\u2026<\/span> <span>grain de sable<\/span> <span>.<\/span><\/p>\n<p> <span>Ces batteries ultra-compactes pourraient alimenter des ordinateurs tout aussi minuscules. Elles seraient id\u00e9ales pour les technologies portables, et notamment pour les dispositifs implantables.<\/span> <span>dispositifs m\u00e9dicaux<\/span> <span>, qui doit \u00eatre aussi petit que possible.<\/span><\/p>\n<p> <span>Fabriqu\u00e9es selon un proc\u00e9d\u00e9 dit \u00ab Swiss-Roll \u00bb qui consiste \u00e0 tordre des couches de film mince, elles sont \u00e9conomiques et peuvent alimenter des ordinateurs de la taille d&#039;un grain de poussi\u00e8re pendant plus de 10 heures.<\/span><\/p>\n<h2> <span>4. Maison de 20 microm\u00e8tres<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81850\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-samyx-malenkix-veshhej-kogda-libo-sozdannyx_64107b59e5106.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>Des chercheurs de l&#039;institut Femto-ST en France ont repouss\u00e9 les limites de la construction \u00e0 petite \u00e9chelle en cr\u00e9ant ce qui pourrait \u00eatre consid\u00e9r\u00e9 comme la plus petite maison jamais construite. Malgr\u00e9 un toit de tuiles, une chemin\u00e9e et sept fen\u00eatres,<\/span> <span>la longueur de la maison n&#039;est que de 20 microns<\/span> <span>. D&#039;un certain point de vue, un cheveu humain mesure g\u00e9n\u00e9ralement environ<\/span> <span>70 microns<\/span> <span>.<\/span><\/p>\n<p> <span>La petite maison a \u00e9t\u00e9 construite \u00e0 l&#039;int\u00e9rieur d&#039;une chambre \u00e0 vide, et il a fallu des nanorobots pour l&#039;assembler \u00e0 partir de membranes de quartz dans un style similaire \u00e0<\/span> <span>faire de l&#039;origami.<\/span> <span>Une maison n&#039;a pas forc\u00e9ment d&#039;utilit\u00e9. Apr\u00e8s tout, il n&#039;y a pas beaucoup de choses assez petites pour y tenir. Mais c&#039;\u00e9tait une d\u00e9monstration convaincante des techniques permettant de cr\u00e9er m\u00eame les plus petites structures.<\/span><\/p>\n<h2> <span>3. La plus petite guitare du monde<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-71341\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-samyx-malenkix-veshhej-kogda-libo-sozdannyx_64107b5baf79b.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Plus un instrument de musique est petit, plus sa note est aigu\u00eb. Le piccolo produit g\u00e9n\u00e9ralement des notes plus aigu\u00ebs que la fl\u00fbte. Le ukul\u00e9l\u00e9, quant \u00e0 lui, n&#039;a tout simplement pas le m\u00eame son qu&#039;une guitare. D\u00e8s lors, on peut ais\u00e9ment imaginer le son de la plus petite guitare du monde si jamais quelqu&#039;un savait en jouer.<\/span><\/p>\n<p> <span>Fabriqu\u00e9e en silicium cristallin, la plus petite guitare du monde a<\/span> <span>longueur de seulement 10 microns<\/span> <span>. Son diam\u00e8tre est environ sept fois inf\u00e9rieur \u00e0 celui d&#039;un cheveu humain, soit l&#039;\u00e9quivalent d&#039;un globule rouge. Il est compos\u00e9 de six brins, chacun<\/span> <span>seulement 50 nanom\u00e8tres<\/span> <span>ou d&#039;une longueur d&#039;environ 100 atomes.<\/span><\/p>\n<p> <span>Des chercheurs de l&#039;universit\u00e9 Cornell ont cr\u00e9\u00e9 une nanoguitare pour d\u00e9montrer une technologie aux implications potentiellement consid\u00e9rables dans des domaines tels que l&#039;\u00e9lectronique et la fibre optique. Le plus remarquable est qu&#039;elle est jouable. Bien s\u00fbr, cela n\u00e9cessiterait l&#039;utilisation d&#039;un microscope \u00e0 force atomique, et le son produit par les cordes serait inaudible, mais cela reste envisageable.<\/span><\/p>\n<h2> <span>2. La plus petite antenne du monde<\/span> <\/h2>\n<\/p>\n<p> <span>Pour \u00e9mettre ou recevoir des signaux radio, il faut une antenne. Autrefois, tous les t\u00e9l\u00e9spectateurs avaient une antenne sur leur toit \u2013 une image qui laisserait sans doute perplexe n&#039;importe quel membre de la g\u00e9n\u00e9ration Z. Mais au fil des ans, les antennes, comme toute autre technologie, sont devenues plus petites, voire ont compl\u00e8tement disparu. La nanoantenne est la plus petite des nanoantennes. Elle est compos\u00e9e d&#039;ADN et, en<\/span><span>20 000 fois plus petit<\/span> <span>Cheveux humains.<\/span><\/p>\n<p> <span>Des chercheurs ont cr\u00e9\u00e9 une antenne de cinq nanom\u00e8tres pour surveiller les prot\u00e9ines plut\u00f4t que les signaux radio ou t\u00e9l\u00e9vis\u00e9s. Sa structure fluorescente lui permet de\u2026<\/span> <span>\u00e9mettre et recevoir des signaux lumineux,<\/span> <span>Voici le principe utilis\u00e9 par les scientifiques qui l&#039;ont cr\u00e9\u00e9. Lorsque les prot\u00e9ines qu&#039;il surveille bougent ou changent, il r\u00e9fl\u00e9chit la lumi\u00e8re d&#039;une couleur diff\u00e9rente, signalant ainsi aux chercheurs qu&#039;un \u00e9v\u00e9nement s&#039;est produit.<\/span><\/p>\n<p> <span>Aussi improbable que cela puisse para\u00eetre, les auteurs de l&#039;\u00e9tude insistent sur le fait que l&#039;utilisation de l&#039;ADN s&#039;explique en partie par sa grande facilit\u00e9 d&#039;utilisation et de programmation. Ils esp\u00e8rent qu&#039;\u00e0 l&#039;avenir, la technologie employ\u00e9e pour d\u00e9velopper cette antenne pourra contribuer \u00e0 de nombreux domaines, allant de la mise au point de nouveaux m\u00e9dicaments aux nanomachines.<\/span><\/p>\n<h2> <span>1. Le plus petit film du monde<\/span> <\/h2>\n<\/p>\n<p> <span>On pense g\u00e9n\u00e9ralement aux films en termes de dur\u00e9e\u00a0: 90 minutes, 3 heures, etc. Un film consid\u00e9r\u00e9 comme long est g\u00e9n\u00e9ralement sorti au format IMAX et optimis\u00e9 pour le grand \u00e9cran. \u00c0 la t\u00e9l\u00e9vision, un message indique parfois que le film a \u00e9t\u00e9 raccourci pour s&#039;adapter \u00e0 l&#039;\u00e9cran. Alors, parmi tous ces crit\u00e8res, qu&#039;est-ce qui d\u00e9finit un film comme le plus court du monde\u00a0?<\/span><\/p>\n<p> <span>Le plus petit film du monde s&#039;appelle<\/span> <em><span>\u00ab&quot;Un gar\u00e7on et son atome&quot;\u00bb<\/span><\/em> <span>. Cr\u00e9\u00e9e par IBM Research, cette animation en stop-motion est r\u00e9alis\u00e9e en manipulant des atomes. Pour la voir, le film doit \u00eatre agrandi plus de 100 millions de fois.<\/span><\/p>\n<p> <span>L&#039;\u00e9quipe a utilis\u00e9 des mol\u00e9cules de monoxyde de carbone, compos\u00e9es chacune de deux atomes, pour raconter, image par image, l&#039;histoire d&#039;un petit gar\u00e7on et de sa mol\u00e9cule servant \u00e0 la fois d&#039;animal de compagnie et de jouet. C&#039;est cette m\u00eame \u00e9quipe qui a cr\u00e9\u00e9 le minuscule dispositif de stockage de donn\u00e9es \u00e0 12 atomes mentionn\u00e9 pr\u00e9c\u00e9demment.<\/span><\/p>\n<p> <span>En fait, vous pouvez constater la diff\u00e9rence entre les atomes de carbone et les atomes d&#039;oxyg\u00e8ne dans chaque mol\u00e9cule en observant comment l&#039;un appara\u00eet comme une sph\u00e8re sombre et l&#039;autre comme une sph\u00e8re claire.<\/span><\/p>\n<p> <span>Bien que ce court m\u00e9trage soit une exploration fascinante du stockage et du traitement des donn\u00e9es \u00e0 l&#039;\u00e9chelle atomique, les spectateurs ne lui ont attribu\u00e9 qu&#039;une note de 6,8.<\/span> <span>sur 10 sur IMDb<\/span> <span>. Certains critiques sont tout simplement impossibles \u00e0 satisfaire.<\/span><\/p>\n<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>Longtemps, la qu\u00eate de la grandeur a obs\u00e9d\u00e9 une grande partie du monde. C&#039;est encore le cas, \u00e0 bien des \u00e9gards. Il suffit de contempler l&#039;immense gratte-ciel Burj Khalifa \u00e0 Duba\u00ef, qui domine\u2026<\/p>","protected":false},"author":1,"featured_media":13416,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-99157","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/99157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/comments?post=99157"}],"version-history":[{"count":7,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/99157\/revisions"}],"predecessor-version":[{"id":138633,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/posts\/99157\/revisions\/138633"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media\/13416"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/media?parent=99157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/categories?post=99157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/fr\/wp-json\/wp\/v2\/tags?post=99157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}