{"id":162750,"date":"2026-09-01T10:09:32","date_gmt":"2026-09-01T07:09:32","guid":{"rendered":"https:\/\/imgist.ru\/chto-proizojdyot-esli-vy-vojdyote-v-chyornuyu-dyru\/"},"modified":"2026-09-01T10:09:37","modified_gmt":"2026-09-01T07:09:37","slug":"o-que-acontece-se-voce-entrar-em-um-buraco-negro","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/chto-proizojdyot-esli-vy-vojdyote-v-chyornuyu-dyru\/","title":{"rendered":"O que acontece se voc\u00ea entrar em um buraco negro?"},"content":{"rendered":"<p>WhatsAppRedditCompartilharEmailTweetFixar0 Compartilhamentos<\/p>\n<p> De todos os lugares do universo que voc\u00ea poderia visitar, um buraco negro provavelmente seria um dos \u00faltimos lugares onde voc\u00ea gostaria de estar. Mesmo que voc\u00ea saiba muito pouco sobre buracos negros, provavelmente pensaria que n\u00e3o \u00e9 um daqueles lugares que voc\u00ea absolutamente precisa visitar. Na verdade, existem muitos motivos pelos quais voc\u00ea gostaria de evitar buracos negros, mas se voc\u00ea quer saber exatamente o que aconteceria se encontrasse um, por que n\u00e3o damos uma olhada?<\/p>\n<h2> O que \u00e9 um buraco negro?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/chto-proizojdyot-esli-vy-vojdyote-v-chyornuyu-dyru_6a967a2d7c906.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> Em termos simples, um buraco negro \u00e9 um lugar no espa\u00e7o onde a gravidade se tornou t\u00e3o forte que nada consegue escapar, nem mesmo a luz. \u00c9 por isso que o chamamos de negro: \u00e9 fisicamente imposs\u00edvel v\u00ea-lo, porque a luz n\u00e3o consegue escapar. Sem luz, n\u00e3o h\u00e1 nada para ver.<\/p>\n<p> Podem existir dois tipos de buracos negros em nosso Universo. O primeiro tipo s\u00e3o os buracos negros primordiais. Acredita-se que eles tenham se formado logo ap\u00f3s o Big Bang. Eles seriam menos densos do que outro tipo de buraco negro, chamado buraco negro estelar.<\/p>\n<p> O buraco negro primordial pode ter se formado antes mesmo do surgimento das estrelas. H\u00e1 uma teoria de que aglomerados densos de mat\u00e9ria podem ter existido no in\u00edcio do universo, quando tudo era muito quente e estava apenas come\u00e7ando a evoluir. Esses aglomerados podem ter colapsado sob sua pr\u00f3pria gravidade, formando uma vers\u00e3o menor do que hoje chamamos de buraco negro.<\/p>\n<p> Um tipo mais comum de buraco negro \u00e9 o buraco negro estelar, que se forma dentro de uma estrela. Quando uma estrela se torna muito massiva no final de sua vida \u2014 se for grande o suficiente, ou seja, cerca de 25 vezes maior que o nosso Sol \u2014 ela colapsa sobre si mesma, tornando-se t\u00e3o densa que um buraco negro se forma.<\/p>\n<p> O Universo tamb\u00e9m cont\u00e9m buracos negros supermassivos que, como o pr\u00f3prio nome indica, s\u00e3o bastante impressionantes. Buracos negros supermassivos s\u00e3o encontrados, por vezes, nos centros das gal\u00e1xias. Acredita-se que tenham sido formados pelo colapso de estrelas massivas h\u00e1 bilh\u00f5es de anos e, desde ent\u00e3o, o buraco negro, como outras estrelas, tem sido capaz de atrair mat\u00e9ria, crescendo cada vez mais. Podem at\u00e9 mesmo ter sido capazes de absorver outros buracos negros.<\/p>\n<h2> Quantos existem no total?<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/chto-proizojdyot-esli-vy-vojdyote-v-chyornuyu-dyru_6a967a2d9ad5e.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> Basicamente, nada consegue escapar de um buraco negro; voc\u00ea n\u00e3o tem torque suficiente para escapar de algo do qual nem mesmo a luz consegue escapar. Isso significa que eles s\u00e3o bem perigosos. Certamente n\u00e3o s\u00e3o t\u00e3o comuns, certo? S\u00e3o como tubar\u00f5es no oceano, voc\u00ea s\u00f3 precisa ficar atento. Mas isso \u00e9 mais dif\u00edcil de avaliar.<\/p>\n<p> Por muito tempo, a resposta mais razo\u00e1vel para a pergunta sobre quantos buracos negros existem no universo era: muitos. Muitos para contar. Imposs\u00edvel estimar. Isso porque detectar fen\u00f4menos c\u00f3smicos j\u00e1 \u00e9 dif\u00edcil, dada a imensid\u00e3o do universo. Detectar algo que n\u00e3o se pode ver \u00e9 ainda mais dif\u00edcil. \u00c9 preciso medir ondas gravitacionais e fen\u00f4menos observ\u00e1veis tipicamente associados \u00e0s estrelas. De certa forma, \u00e9 como contar pedras em um lago pelos respingos.<\/p>\n<p> \u00c9 claro que quaisquer n\u00fameros que encontrarmos ser\u00e3o apenas estimativas; n\u00e3o estamos fornecendo valores exatos. E, por favor, sigam nosso exemplo da mesma forma que estimamos a popula\u00e7\u00e3o da Terra, sem contar literalmente cada pessoa. Mas fizemos progressos nos \u00faltimos anos e temos uma estimativa aproximada do n\u00famero de buracos negros que acreditamos que possam existir. Est\u00e3o preparados? Talvez queiram se sentar, olhar por cima do ombro e garantir que nada esteja prestes a sugar voc\u00eas para o esquecimento.<\/p>\n<p> Trabalhando com grandes volumes de dados complexos, os astrof\u00edsicos calcularam que existem aproximadamente 40 quintilh\u00f5es de buracos negros no universo. Caso voc\u00ea n\u00e3o saiba, um quintilh\u00e3o cont\u00e9m 18 zeros.<\/p>\n<h2> Qual o tamanho que eles atingem?<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/chto-proizojdyot-esli-vy-vojdyote-v-chyornuyu-dyru_6a967a2e96beb.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> No centro da nossa gal\u00e1xia, a Via L\u00e1ctea, encontra-se um buraco negro conhecido como Sagit\u00e1rio A*. N\u00e3o \u00e9 o maior buraco negro que j\u00e1 descobrimos. No entanto, para se ter uma ideia do seu tamanho, ele \u00e9 4 milh\u00f5es de vezes maior que o nosso Sol.<\/p>\n<p> Um buraco negro t\u00edpico pode ser v\u00e1rias vezes maior que o nosso Sol, ou at\u00e9 mesmo centenas de vezes maior. \u00c9 importante lembrar que isso ocorre apenas durante sua forma\u00e7\u00e3o. Como qualquer objeto rec\u00e9m-nascido, ele crescer\u00e1. \u00c0 medida que o buraco negro come\u00e7a a se &quot;alimentar&quot;, absorvendo gases e part\u00edculas do sistema circundante, ele pode come\u00e7ar a devorar outras estrelas, tornando-se cada vez maior. Quanto mais velho ele fica, maior ser\u00e1 o seu tamanho.<\/p>\n<p> Como j\u00e1 mencionamos, Sagit\u00e1rio A* \u00e9 4 milh\u00f5es de vezes maior que o nosso Sol. Voc\u00ea ficar\u00e1 feliz em saber que \u00e9 uma gal\u00e1xia pequena. Existe tamb\u00e9m uma gal\u00e1xia chamada Holmberg 15A, que tem um buraco negro no seu centro. Ela \u00e9 40 bilh\u00f5es de vezes maior que o nosso Sol.<\/p>\n<p> Buracos negros supermassivos, como o da gal\u00e1xia Holmberg 15A, podem ter se formado no primeiro bilh\u00e3o de anos do nosso Universo. \u00c9 prov\u00e1vel que tenham devorado diversas estrelas durante suas vidas e tamb\u00e9m podem ser o resultado da colis\u00e3o entre duas gal\u00e1xias, com um buraco negro consumindo o outro. Al\u00e9m disso, podem acumular mat\u00e9ria escura.<\/p>\n<p> Um contraste interessante aqui s\u00e3o os buracos negros primordiais que discutimos anteriormente. Esses buracos negros s\u00e3o muito menos densos do que os buracos negros estelares e os buracos negros supermassivos. Embora seja apenas te\u00f3rico, acredita-se que alguns deles possam ser 100.000 vezes menores do que um clipe de papel. Portanto, estamos falando de fen\u00f4menos c\u00f3smicos bastante min\u00fasculos e pouco impressionantes em termos de tamanho. Por outro lado, eles podem ser 100.000 vezes mais densos do que o nosso Sol, ent\u00e3o um encontro com eles ainda pode n\u00e3o valer a pena.<\/p>\n<h2> O que acontece dentro de um buraco negro?<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/chto-proizojdyot-esli-vy-vojdyote-v-chyornuyu-dyru_6a967a2f8d3d1.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> Voc\u00ea gosta de espaguete? Vai concordar que \u00e9 bem gostoso. E de todas as op\u00e7\u00f5es de massa, \u00e9 uma das melhores. \u00c9 f\u00e1cil de comer, basta enrol\u00e1-lo no garfo ou sorv\u00ea-lo, nada sofisticado. \u00c9 divertido! A menos, \u00e9 claro, que espaguete seja a sua praia.<\/p>\n<p> Espaguetifica\u00e7\u00e3o \u00e9 um nome ridiculamente engra\u00e7ado para o processo que ocorre quando um objeto cai em um buraco negro com a massa certa. A gravidade do buraco essencialmente o puxar\u00e1 em sua dire\u00e7\u00e3o, como um espaguete. Se voc\u00ea j\u00e1 tentou se enrolar em forma de espaguete, sabe que \u00e9 imposs\u00edvel fazer isso confortavelmente. Vai te matar, e feio.<\/p>\n<p> Mesmo em um objeto t\u00e3o pequeno quanto o \u00f4nibus espacial, as for\u00e7as gravitacionais na parte frontal ser\u00e3o significativamente mais fortes do que na parte traseira. Isso \u00e9 resultado do acentuado gradiente gravitacional que se experimenta ao se aproximar do buraco negro. Imagine uma tigela de gelatina, onde voc\u00ea usa um canudo para sugar a gelatina da parte central superior.<\/p>\n<p> O fundo da tigela n\u00e3o ser\u00e1 danificado por enquanto, mas voc\u00ea destruir\u00e1 tudo o que o canudo tocar. O mesmo acontecer\u00e1 com sua nave. Tudo se acumular\u00e1 naquele canudo, independentemente de ter sido essa a sua fun\u00e7\u00e3o ou n\u00e3o. As for\u00e7as de mar\u00e9 do buraco negro ir\u00e3o estic\u00e1-lo e depois despeda\u00e7\u00e1-lo. Isso \u00e9 espaguetifica\u00e7\u00e3o.<\/p>\n<p> \u00c9 importante lembrar que a espaguetifica\u00e7\u00e3o n\u00e3o \u00e9 poss\u00edvel em todos os buracos negros. Isso depende muito da massa do pr\u00f3prio buraco negro. Buracos negros supermassivos t\u00eam uma for\u00e7a gravitacional t\u00e3o grande que esse gradiente n\u00e3o te afetaria em nada. N\u00e3o seria uma experi\u00eancia agrad\u00e1vel; voc\u00ea simplesmente cairia dentro dele e experimentaria todas as outras coisas terr\u00edveis que v\u00eam com isso.<\/p>\n<p> Por outro lado, embora isso n\u00e3o seja necessariamente positivo, voc\u00ea provavelmente morrer\u00e1 muito antes que isso aconte\u00e7a. Ao redor de um buraco negro existe o que \u00e9 chamado de disco de acre\u00e7\u00e3o, onde todas as part\u00edculas de mat\u00e9ria que ainda n\u00e3o foram absorvidas se acumulam. \u00c9 como um anel c\u00f3smico ao redor de uma banheira, toda essa gosma circundando o centro.<\/p>\n<p> O problema com o anel de acre\u00e7\u00e3o \u00e9 que ele est\u00e1 sujeito \u00e0 for\u00e7a gravitacional do pr\u00f3prio buraco negro. Ele fica t\u00e3o quente que come\u00e7a a emitir radia\u00e7\u00e3o. A gravidade e o atrito se combinam para produzir raios X e raios gama. Portanto, antes que o buraco negro transforme voc\u00ea em marshmallows c\u00f3smicos, o disco de acre\u00e7\u00e3o ir\u00e1 inciner\u00e1-lo.<\/p>\n<p> Mas isso n\u00e3o \u00e9 tudo! Devido ao efeito de dilata\u00e7\u00e3o do tempo inerente a um buraco negro, \u00e0 medida que voc\u00ea se aproxima do horizonte de eventos, para a maior parte do resto do universo voc\u00ea parecer\u00e1 estar desacelerando. Na verdade, voc\u00ea poderia parar completamente e ficar congelado nesse ponto em rela\u00e7\u00e3o ao resto do universo, potencialmente para sempre. Para que isso aconte\u00e7a, precisamos ignorar a espaguetifica\u00e7\u00e3o e a radia\u00e7\u00e3o. Mas, como j\u00e1 mencionado, uma vez que voc\u00ea entra no horizonte de eventos, voc\u00ea nunca mais sair\u00e1.<\/p>\n<h2> Ent\u00e3o, o que \u00e9 um horizonte de eventos?<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/chto-proizojdyot-esli-vy-vojdyote-v-chyornuyu-dyru_6a967a2fb2ef3.jpeg\" alt=\"\" width=\"640\" height=\"417\"><\/p>\n<p> O termo &quot;Horizonte de Eventos&quot; pode ser um pouco dif\u00edcil de entender. Soa grandioso, n\u00e3o \u00e9? Tem a palavra &quot;evento&quot; nele. E &quot;horizonte&quot; \u00e9 o que voc\u00ea v\u00ea \u00e0 dist\u00e2ncia. Ent\u00e3o, parece algo enorme, monumental e distante. Na realidade, \u00e9 simplesmente o limite do buraco negro. Pense nele como uma parede que n\u00e3o \u00e9 f\u00edsica. \u00c9 a parte que separa o buraco negro do espa\u00e7o ao seu redor.<\/p>\n<p> A principal caracter\u00edstica de um buraco negro, o que torna seu horizonte de eventos t\u00e3o crucial, \u00e9 que ele representa o ponto sem retorno. Tecnicamente, \u00e9 o que nos permite ver um buraco negro. Como a luz n\u00e3o consegue escapar al\u00e9m do horizonte de eventos, precisamos observar sua borda para sequer saber que o buraco negro existe. \u00c9 ali que todos os gases, poeira c\u00f3smica, OVNIs e outros objetos se acumulam, aquecendo-se drasticamente antes de cruzar essa fronteira. \u00c9 como um redemoinho c\u00f3smico, chamado de halo porque \u00e9 vis\u00edvel em uma regi\u00e3o incrivelmente escura, inacess\u00edvel a qualquer instrumento terrestre.<\/p>\n<h2> Ser\u00e1 que algo pode escapar de um buraco negro?<\/h2>\n<p><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2026\/09\/chto-proizojdyot-esli-vy-vojdyote-v-chyornuyu-dyru_6a967a30b42ea.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> Dada a for\u00e7a gravitacional t\u00e3o intensa que nem mesmo a luz consegue escapar, parece razo\u00e1vel e seguro supor que nada no universo poderia escapar de um buraco negro, a menos que fosse capaz de viajar mais r\u00e1pido que a velocidade da luz. A f\u00edsica nos diz que isso \u00e9, na realidade, imposs\u00edvel, exceto em casos te\u00f3ricos. Mas existem algumas coisas que podem resistir \u00e0 for\u00e7a gravitacional de um buraco negro: as part\u00edculas subat\u00f4micas.<\/p>\n<p> Buracos negros emitem jatos de plasma repletos de p\u00f3sitrons e el\u00e9trons. Esses jatos s\u00e3o expelidos do pr\u00f3prio buraco negro em dire\u00e7\u00e3o ao horizonte de eventos a velocidades pr\u00f3ximas \u00e0 da luz. L\u00e1, eles ricocheteiam violentamente e s\u00e3o ejetados para al\u00e9m do horizonte de eventos, de volta ao espa\u00e7o. Mas como diabos isso acontece?<\/p>\n<p> A teoria em voga \u00e9 que o buraco negro atrai todas essas part\u00edculas, algumas das quais s\u00e3o part\u00edculas de energia negativa. \u00c9 como um alimento com calorias negativas \u2014 um alimento que requer mais calorias para ser digerido do que as que voc\u00ea obt\u00e9m ao digeri-lo. Assim, o buraco negro se enche dessas part\u00edculas de energia negativa, que efetivamente drenam a energia do buraco negro, reduzindo sua for\u00e7a total e acelerando as pr\u00f3prias part\u00edculas. Enquanto est\u00e3o dentro do buraco negro, elas ganham energia, enquanto o buraco negro perde energia.<\/p>\n<p> Portanto, embora a maioria das subst\u00e2ncias nunca consiga escapar, existem circunst\u00e2ncias limitadas em que as part\u00edculas podem. E quanto a n\u00f3s? N\u00e3o temos essa sorte.<\/p>\n<p> Outros artigos que podem lhe interessar<\/p>","protected":false},"excerpt":{"rendered":"<p>De todos os lugares do universo para onde voc\u00ea poderia ir, um buraco negro provavelmente \u00e9 um dos \u00faltimos lugares onde voc\u00ea realmente gostaria de estar. Mesmo que\u2026<\/p>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-162750","post","type-post","status-publish","format-standard","hentry","category-interesnye-fakty"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/162750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=162750"}],"version-history":[{"count":1,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/162750\/revisions"}],"predecessor-version":[{"id":162757,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/162750\/revisions\/162757"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=162750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=162750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=162750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}