{"id":19139,"date":"2026-06-23T22:36:14","date_gmt":"2026-06-23T19:36:14","guid":{"rendered":"https:\/\/imgist.ru\/milli-alkok-rasskazala-chto-supergyorl-veroyatno-biseksualna-vo-vselennoj-dc\/"},"modified":"2026-08-24T14:00:04","modified_gmt":"2026-08-24T11:00:04","slug":"millie-alcock-revelou-que-a-supergirl-provavelmente-e-bissexual-no-universo-da-dc","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/milli-alkok-rasskazala-chto-supergyorl-veroyatno-biseksualna-vo-vselennoj-dc\/","title":{"rendered":"Millie Alcock revelou que a Supergirl provavelmente \u00e9 bissexual no universo da DC."},"content":{"rendered":"<p>A atriz Millie Alcock, conhecida por seu papel como Supergirl, abordou oficialmente a sexualidade de Kara Zor-El no novo Universo DC de James Gunn, afirmando que a personagem provavelmente \u00e9 bissexual. Supergirl \u00e9 o pr\u00f3ximo cap\u00edtulo do novo Universo DC e permitir\u00e1 que os f\u00e3s conhe\u00e7am melhor a vers\u00e3o da personagem interpretada por Alcock. Alcock fez uma breve apari\u00e7\u00e3o no final do filme do Superman de 2025, mas seu papel n\u00e3o foi suficientemente amplo para que o p\u00fablico aprendesse muito sobre ela. No entanto, isso est\u00e1 prestes a mudar.<\/p>\n<p> Em uma entrevista recente \u00e0 Associated Press (AP) durante a promo\u00e7\u00e3o do filme &quot;Supergirl&quot;, a estrela do filme, Millie Alcock, finalmente revelou aos f\u00e3s a orienta\u00e7\u00e3o sexual da protagonista do Universo DC. Alcock n\u00e3o hesitou em se pronunciar, demonstrando grande seguran\u00e7a em sua resposta.<\/p>\n<figure><figcaption> DC Studios<\/figcaption><\/figure>\n<p> Em particular, a atriz falou sobre o quanto <strong>O filme da Supergirl \u00e9 \u00f3timo.,<\/strong> porque ele <strong>\u00ab&quot;sem nenhum foco no homem&quot;\u00bb<\/strong> ou <strong>\u00ab&quot;sobre o amor&quot;\u00bb<\/strong> . Alcock parece estar argumentando essencialmente que o filme e Kara n\u00e3o precisam necessariamente de uma trama rom\u00e2ntica para serem envolventes, e que pode funcionar mesmo sem Kara estar em qualquer tipo de relacionamento.<\/p>\n<p> No entanto, Alcock afirmou ent\u00e3o que Supergirl <strong>\u00ab&quot;Provavelmente ser\u00e1 bissexual&quot;,<\/strong> indicando que acredita que Kara, no Universo Estendido da DC (DCEU), \u00e9 bissexual. A atriz n\u00e3o deu exemplos espec\u00edficos do porqu\u00ea de acreditar que Kara \u00e9 bissexual, mas sua resposta pareceu bastante confiante:<\/p>\n<blockquote>\n<p> \u00ab&quot;N\u00e3o foi bem assim. Mas em homenagem ao M\u00eas do Orgulho, quando recebo todas essas perguntas... N\u00e3o sei, acho que a beleza deste filme \u00e9 que ele n\u00e3o se centra em um homem. N\u00e3o se centra no amor, se \u00e9 que existe algum. Mas veremos. Realmente n\u00e3o sei. Mas n\u00e3o sei... Ela provavelmente dir\u00e1 sim para as duas perguntas.&quot;.<\/p>\n<\/blockquote>\n<p> Com base na campanha promocional do filme e na adapta\u00e7\u00e3o dos quadrinhos, \u00e9 prov\u00e1vel que Kara n\u00e3o tenha um relacionamento rom\u00e2ntico com ningu\u00e9m no filme, o que est\u00e1 de acordo com o que Alcock disse sobre Kara n\u00e3o precisar de um para que sua hist\u00f3ria e arco sejam envolventes.<\/p>\n<p> Em \u00faltima an\u00e1lise, Supergirl ser\u00e1 mais sobre o relacionamento de Kara com Krypto, sua jornada de autodescoberta e sua rela\u00e7\u00e3o plat\u00f4nica com Ruthie do que qualquer outra coisa.<\/p>\n<p> No entanto, parece que os f\u00e3s poder\u00e3o v\u00ea-la &quot;seguir os dois caminhos&quot; no futuro do Universo Estendido da DC (DCEU).<\/p>\n<h2> Os relacionamentos rom\u00e2nticos da Supergirl nos quadrinhos e nas telas.<\/h2>\n<p> Ao longo dos anos, a Supergirl teve v\u00e1rios relacionamentos rom\u00e2nticos s\u00e9rios, tanto em diversas hist\u00f3rias em quadrinhos quanto em outras m\u00eddias, como a s\u00e9rie de televis\u00e3o e o filme original da Supergirl.<\/p>\n<p> Vale ressaltar que todos os relacionamentos anteriores da Supergirl foram com homens, ent\u00e3o ela sempre foi apresentada como heterossexual. Portanto, se fosse revelado que ela \u00e9 bissexual no Universo DC, seria um momento significativo na hist\u00f3ria da DC, pois seria a primeira vez que a sexualidade de uma personagem seria explorada de uma maneira diferente do que foi no passado.<\/p>\n<figure><figcaption> DC Comics<\/figcaption><\/figure>\n<p> Quanto aos relacionamentos passados de Kara, ela teve alguns not\u00e1veis. Por exemplo, na s\u00e9rie de quadrinhos Terra-1, ela desenvolveu um relacionamento rom\u00e2ntico com seu cavalo, Cometa. No entanto, o romance s\u00f3 aconteceu quando ele estava em sua forma humana (onde se chamava &quot;Bronco&quot; Bill Starr), e Kara n\u00e3o fazia ideia de que ele era, na verdade, Cometa.<\/p>\n<p> Kara teve v\u00e1rios relacionamentos com Brainiac 5, um dos personagens principais da Legi\u00e3o dos Super-Her\u00f3is. Kara e Brainiac 5 viveram romances tanto nos quadrinhos quanto no Universo Animado da DC. Eles demonstraram forte qu\u00edmica em diversas obras, especialmente quando Kara fazia parte da Legi\u00e3o dos Super-Her\u00f3is ao lado de Brainiac.<\/p>\n<figure><figcaption> DC Comics<\/figcaption><\/figure>\n<p> Jimmy Olsen \u00e9 outro personagem com quem a Supergirl j\u00e1 se relacionou em diversos projetos. Especificamente, ela e Jimmy Olsen tiveram um envolvimento rom\u00e2ntico na s\u00e9rie Imaginary Tales Elseworlds, na s\u00e9rie Smallville, na s\u00e9rie Supergirl do Arrowverse e nos quadrinhos da Terra-Um. Kara e Jimmy sempre demonstraram uma qu\u00edmica incr\u00edvel ao longo dos anos e se mostraram um casal bastante compat\u00edvel.<\/p>\n<p> Os detalhes do relacionamento deles variavam dependendo do projeto e do formato, mas eles se conheciam muito bem.<\/p>\n<p> Nos quadrinhos, Kara tamb\u00e9m teve relacionamentos rom\u00e2nticos com personagens como Dick Malvern, Power Boy, Michael Harris, Ben Reubel e H&#039;el.<\/p>\n<p> No filme &quot;Supergirl&quot;, estrelado por Helen Slater, Kara se apaixona por um jardineiro chamado Ethan enquanto trabalha disfar\u00e7ada em um col\u00e9gio feminino sob o nome de Linda Lee. Eles iniciam um romance rel\u00e2mpago, mas acabam se separando.<\/p>\n<figure><figcaption> CW<\/figcaption><\/figure>\n<p> Al\u00e9m de Jimmy Olsen, Kara Danvers tamb\u00e9m teve relacionamentos rom\u00e2nticos com Adam Foster, Mon-El e William Day no Arrowverso.<\/p>","protected":false},"excerpt":{"rendered":"<p>A atriz Millie Alcock, que interpreta Kara Zor-El em Supergirl, abordou oficialmente a sexualidade da personagem no novo Universo DC de James Gunn, afirmando que ela provavelmente \u00e9 bissexual.<\/p>","protected":false},"author":1,"featured_media":19140,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-19139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/19139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=19139"}],"version-history":[{"count":4,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/19139\/revisions"}],"predecessor-version":[{"id":140150,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/19139\/revisions\/140150"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/19140"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=19139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=19139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=19139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}