{"id":2410,"date":"2026-05-30T22:12:44","date_gmt":"2026-05-30T19:12:44","guid":{"rendered":"https:\/\/imgist.ru\/dzhejmi-li-kertis-otdala-dan-pamyati-svoej-sestre-kelli-li-kertis-posle-ee-smerti-v-vozraste-69-let\/"},"modified":"2026-08-29T11:20:52","modified_gmt":"2026-08-29T08:20:52","slug":"jamie-lee-curtis-prestou-homenagem-a-sua-irma-kelly-lee-curtis-apos-a-sua-morte-aos-69-anos","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/dzhejmi-li-kertis-otdala-dan-pamyati-svoej-sestre-kelli-li-kertis-posle-ee-smerti-v-vozraste-69-let\/","title":{"rendered":"Jamie Lee Curtis prestou homenagem \u00e0 sua irm\u00e3, Kelly Lee Curtis, ap\u00f3s a sua morte aos 69 anos."},"content":{"rendered":"<p>Jamie Lee Curtis est\u00e1 de luto pela morte de sua irm\u00e3 mais velha, Kelly Lee Curtis.<\/p>\n<p> Kelly, a atriz e filha mais velha de Tony Curtis e Janet Leigh, faleceu no s\u00e1bado, 30 de maio, em sua casa na Calif\u00f3rnia. Ela tinha 69 anos. Jamie Lee Curtis anunciou a not\u00edcia em uma publica\u00e7\u00e3o no Instagram, escrevendo que sua irm\u00e3 morreu &quot;em paz&quot;, tanto em casa quanto ao ar livre.<\/p>\n<p> Segundo a revista PEOPLE, a causa da morte ainda n\u00e3o foi divulgada.<\/p>\n<h2> Jamie Lee Curtis chamou Kelly de sua &quot;primeira amiga&quot;. <\/h2>\n<p> Em seu obitu\u00e1rio, Curtis chamou Kelly de sua &quot;primeira amiga e confidente para toda a vida&quot;. Ela se lembrou da irm\u00e3 como uma mulher bonita, talentosa, segura de si, curiosa, elegante e generosa. <\/p>\n<p> Conforme relatado pelo TMZ, Curtis tamb\u00e9m compartilhou detalhes pessoais sobre a vida de Kelly, incluindo seu amor por tartarugas, m\u00fasica, natureza, viagens, compras em brech\u00f3s, fam\u00edlia e jogos de cartas.<\/p>\n<p> Curtis tamb\u00e9m lembrou dos biscoitos de Natal de Kelly e da b\u00ean\u00e7\u00e3o h\u00fangara que ela usava no final de suas mensagens. A publica\u00e7\u00e3o terminou com as palavras &quot;Isten Veled&quot;, que a revista PEOPLE traduz como &quot;Que Deus esteja com voc\u00ea&quot;.<\/p>\n<h2> Kelly Lee Curtis teve sua pr\u00f3pria carreira de atriz. <\/h2>\n<p> Imagem cedida por s_bukley\/Shutterstock.<\/p>\n<p> Kelly pertencia a uma das fam\u00edlias mais famosas de Hollywood, mas tamb\u00e9m trabalhava no cinema. A revista PEOPLE observou que ela estrelou em <em>filmes &quot;Vikings&quot;\u00ab<\/em> \u0438 <em>\u00ab&quot;Trocando de Lugares&quot;\u00bb<\/em> , neste \u00faltimo - juntamente com Jamie Lee Curtis.<\/p>\n<p> Segundo o E! News, os trabalhos de Kelly na televis\u00e3o incluem: <em>A s\u00e9rie Equalizador\u00ab<\/em> , <em>\u00ab&quot;Ca\u00e7ador&quot;\u00bb<\/em> , <em>\u00abAnimais de pel\u00facia de seda\u00bb<\/em> , <em>\u00abStar Trek: Deep Space Nine\u00bb<\/em> \u0438 <em>\u00abGuardi\u00e3o\u00bb<\/em> . <\/p>\n<p> Segundo a revista PEOPLE, ela tamb\u00e9m trabalhou nos bastidores como assistente de Jamie Lee Curtis em diversos projetos.<\/p>\n<h2> Ela era filha de Tony Curtis e Janet Leigh. <\/h2>\n<p> Imagem cedida por Alan Light, CC BY 2.0\/Wiki Commons.<\/p>\n<p> Kelly era a filha mais velha de Tony Curtis e Janet Leigh, dois atores cujas carreiras permanecem indissociavelmente ligadas ao cinema cl\u00e1ssico de Hollywood. Tony Curtis estrelou filmes como... <em>\u00abAlgumas pessoas gostam de comida quente.\u00bb<\/em> , e o papel de Janet Leigh em <em>\u00ab&quot;Psicose&quot;\u00bb<\/em> Tornou-se um dos filmes de terror mais famosos da hist\u00f3ria.<\/p>\n<p> Kelly era a \u00fanica irm\u00e3 de Jamie Lee Curtis. A revista PEOPLE noticiou que ela deixa o marido, Scott Morphy.<\/p>\n<p> Em sua homenagem, Kelly foi vista n\u00e3o apenas como parte de uma c\u00e9lebre dinastia de Hollywood, mas tamb\u00e9m como irm\u00e3, esposa, atriz e membro da fam\u00edlia. Em sua publica\u00e7\u00e3o, Jamie Lee Curtis descreveu sua perda pessoal atrav\u00e9s de detalhes de uma vida que ela conhecia bem.<\/p>","protected":false},"excerpt":{"rendered":"<p>Jamie Lee Curtis est\u00e1 de luto pela morte de sua irm\u00e3 mais velha, Kelly Lee Curtis. Kelly, a atriz e filha mais velha de Tony Curtis e Janet Leigh, faleceu em\u2026<\/p>","protected":false},"author":1,"featured_media":2411,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selebriti","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/2410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=2410"}],"version-history":[{"count":2,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/2410\/revisions"}],"predecessor-version":[{"id":145282,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/2410\/revisions\/145282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/2411"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=2410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=2410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=2410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}