{"id":4285,"date":"2026-06-01T05:09:56","date_gmt":"2026-06-01T02:09:56","guid":{"rendered":"https:\/\/imgist.ru\/gollivud-chtit-pamyat-merilin-monro-spustya-100-let-posle-eyo-rozhdeniya\/"},"modified":"2026-06-01T05:09:56","modified_gmt":"2026-06-01T02:09:56","slug":"hollywood-homenageia-a-memoria-de-marilyn-monroe-100-anos-apos-seu-nascimento","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/gollivud-chtit-pamyat-merilin-monro-spustya-100-let-posle-eyo-rozhdeniya\/","title":{"rendered":"Hollywood homenageia a mem\u00f3ria de Marilyn Monroe 100 anos ap\u00f3s seu nascimento."},"content":{"rendered":"<p>Uma s\u00e9rie de eventos especiais comemorativos do centen\u00e1rio do nascimento da estrela de cinema ter\u00e1 in\u00edcio na cidade natal de Marilyn Monroe, Hollywood, na segunda-feira.<\/p>\n<p> No hist\u00f3rico Teatro Chin\u00eas, onde as impress\u00f5es das m\u00e3os de Marilyn Monroe est\u00e3o imortalizadas ao lado das de sua colega de elenco em Os Homens Preferem as Loiras (1953), Jane Russell, os f\u00e3s planejam cantar &quot;Parab\u00e9ns a Voc\u00ea&quot; \u2014 ecoando sua famosa e sensual serenata para o presidente John F. Kennedy.<\/p>\n<p> Cem rosas e um bolo ser\u00e3o depositados no local, um s\u00edmbolo da era de ouro de Hollywood e um destino tur\u00edstico popular.<\/p>\n<p> No domingo, come\u00e7aram os eventos dedicados \u00e0 mem\u00f3ria da lend\u00e1ria filha de Hollywood: o Museu da Academia inaugurou uma exposi\u00e7\u00e3o, &quot;Marilyn Monroe: \u00cdcone de Hollywood&quot;, dedicada \u00e0 sua carreira cinematogr\u00e1fica e \u00e0 sua vida tragicamente interrompida.<\/p>\n<p> Ap\u00f3s se tornar uma superestrela na d\u00e9cada de 1950, a atriz e modelo morreu de overdose em sua casa em Brentwood, em agosto de 1962, aos 36 anos.<\/p>\n<p> Ao longo do m\u00eas, o Museu da Academia apresentar\u00e1 exibi\u00e7\u00f5es especiais de sua extensa filmografia, incluindo &quot;The Asphalt Jungle&quot; (1950), &quot;Niagara&quot; (1953), &quot;The Seven Year Itch&quot; (1955), &quot;Some Like It Hot&quot; (1959) e &quot;The Misfits&quot; (1961).<\/p>\n<p> A exposi\u00e7\u00e3o, que estar\u00e1 em cartaz at\u00e9 fevereiro de 2027, apresenta centenas de pe\u00e7as originais, algumas das quais raramente s\u00e3o exibidas ao p\u00fablico, como o famoso vestido rosa que Marilyn Monroe usou durante sua ic\u00f4nica apresenta\u00e7\u00e3o de &quot;Diamonds Are a Girl&#039;s Best Friend&quot; no filme Os Homens Preferem as Loiras.<\/p>\n<p> No final desta semana, dia 4 de junho, a Julien&#039;s Auctions leiloar\u00e1 quase 200 itens relacionados a Marilyn Monroe como parte de sua venda especial &quot;100 Anos de Marilyn&quot;.<\/p>\n<p> A exposi\u00e7\u00e3o inclui fotografias in\u00e9ditas, um roteiro com anota\u00e7\u00f5es para seu trabalho final, um curta-metragem inacabado, Something&#039;s Got to Give, e itens pessoais como receitas manuscritas e seu batom Elizabeth Arden.<\/p>\n<p> \u2014 Criador de Imagens \u2014<\/p>\n<p> Nascida em Los Angeles em 1\u00ba de junho de 1926, Marilyn Monroe teve uma inf\u00e2ncia dif\u00edcil, passando de um orfanato para outro e sendo colocada em lares adotivos. Ela se casou pela primeira vez aos 16 anos.<\/p>\n<p> Seu primeiro contato com o mundo do entretenimento aconteceu em 1944, quando trabalhava em uma f\u00e1brica e um fot\u00f3grafo foi at\u00e9 l\u00e1 para tirar fotos de mulheres trabalhando nas linhas de produ\u00e7\u00e3o durante a Segunda Guerra Mundial.<\/p>\n<p> Logo depois, ela iniciou sua carreira de modelo, divorciou-se do marido e tomou uma decis\u00e3o que mudaria sua vida: pintou seus cabelos castanhos de loiro platinado.<\/p>\n<p> Ela assinou seu primeiro contrato com a Fox e, aos 30 anos, j\u00e1 havia se consolidado como uma estrela global.<\/p>\n<p> Nos bastidores, Monroe fundou sua pr\u00f3pria produtora, frequentou o prestigiado Actors Studio na cidade de Nova York e at\u00e9 desafiou os est\u00fadios de cinema.<\/p>\n<p> Na d\u00e9cada de 1950, enquanto estava sob contrato com a 20th Century Fox, ela recusou um papel na adapta\u00e7\u00e3o cinematogr\u00e1fica do musical &quot;The Girl in Pink Tights&quot;, considerando o roteiro med\u00edocre e seu sal\u00e1rio \u2014 um ter\u00e7o do de seu colega de elenco Frank Sinatra \u2014 injusto.<\/p>\n<p> Mais de meio s\u00e9culo antes do movimento #MeToo abalar a ind\u00fastria global do entretenimento, Monroe denunciou os &quot;lobos&quot; de Hollywood que se aproveitavam do talento feminino.<\/p>\n<p> pr\/des\/md<\/p>","protected":false},"excerpt":{"rendered":"<p>Uma s\u00e9rie de eventos especiais comemorativos do centen\u00e1rio do nascimento da estrela de cinema come\u00e7a nesta segunda-feira em Hollywood, cidade natal de Marilyn Monroe. No hist\u00f3rico Teatro Chin\u00eas, onde as impress\u00f5es de suas m\u00e3os\u2026<\/p>","protected":false},"author":1,"featured_media":4286,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-4285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/4285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=4285"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/4285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/4286"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=4285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=4285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=4285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}