{"id":6140,"date":"2026-06-02T00:21:25","date_gmt":"2026-06-01T21:21:25","guid":{"rendered":"https:\/\/imgist.ru\/blogersha-osparivaet-shtraf-posle-togo-kak-policzejskij-zayavil-chto-ona-polzovalas-telefonom-ne-derzha-ego-v-ruke\/"},"modified":"2026-08-29T11:52:03","modified_gmt":"2026-08-29T08:52:03","slug":"uma-blogueira-esta-contestando-uma-multa-depois-que-um-policial-alegou-que-ela-usou-o-celular-sem-segura-lo-na-mao","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/blogersha-osparivaet-shtraf-posle-togo-kak-policzejskij-zayavil-chto-ona-polzovalas-telefonom-ne-derzha-ego-v-ruke\/","title":{"rendered":"Uma blogueira est\u00e1 contestando uma multa aplicada ap\u00f3s um policial alegar que ela estava usando o celular sem segur\u00e1-lo na m\u00e3o."},"content":{"rendered":"<p>Uma multa por dire\u00e7\u00e3o distra\u00edda aplicada a uma influenciadora da Fl\u00f3rida se transformou em um esc\u00e2ndalo viral na internet depois que imagens da c\u00e2mera corporal parecem contradizer a explica\u00e7\u00e3o de um policial sobre a abordagem.<\/p>\n<p> Katie, uma atleta com defici\u00eancia e criadora de conte\u00fado para redes sociais conhecida por sua conta no Instagram, Slightlyoff.balance, compartilhou recentemente um v\u00eddeo de uma abordagem policial na Fl\u00f3rida em fevereiro, ap\u00f3s ser multada por supostamente usar o celular enquanto dirigia.<\/p>\n<p> Uma policial do condado de Palm Beach afirmou ter visto Katie segurando o celular na &quot;m\u00e3o direita&quot; enquanto dirigia na North Dixie Highway. O problema, por\u00e9m, \u00e9 que Katie n\u00e3o tem m\u00e3o direita. O v\u00eddeo da c\u00e2mera corporal viralizou depois que Katie publicou trechos da abordagem policial no TikTok e no Instagram.<\/p>\n<p> O v\u00eddeo mostra um agente do xerife se aproximando do carro e dizendo a Katie que a viu usando o celular com a m\u00e3o direita. Katie ent\u00e3o levanta o bra\u00e7o direito, que termina logo abaixo do cotovelo, e questiona o depoimento do policial.<\/p>\n<p> LOJA COMPLETA: Compre suas marcas favoritas a qualquer hora, em qualquer lugar. Descubra as novidades. Compre. Colecione. Aproveite.<\/p>\n<p> Tentando amenizar a situa\u00e7\u00e3o constrangedora, Katie brincou com o policial e perguntou se eles poderiam simplesmente &quot;encerrar por hoje&quot;, mas a conversa continuou enquanto o policial perguntava repetidamente se ela havia usado o celular enquanto dirigia.<\/p>\n<p> Em outro momento da conversa, o policial teria pedido a Katie que levantasse a &quot;m\u00e3o para Deus&quot;, jurando que ela estava dizendo a verdade. Katie riu e levantou a m\u00e3o, ap\u00f3s o que o policial instruiu-a a usar a m\u00e3o esquerda.<\/p>\n<p> Apesar da confus\u00e3o durante a abordagem policial, Katie ainda recebeu uma multa de US$ 116 por dirigir distra\u00edda, de acordo com a lei da Fl\u00f3rida.<\/p>\n<p> Katie anunciou que se declarou inocente remotamente e que estava se preparando para contestar as acusa\u00e7\u00f5es no tribunal, em audi\u00eancia marcada para maio. Antes da audi\u00eancia, ela publicou imagens adicionais da c\u00e2mera corporal da abordagem policial, alimentando ainda mais a pol\u00eamica que viralizou.<\/p>\n<p> Segundo a CBS12, o relat\u00f3rio foi arquivado a pedido de um delegado do xerife antes de uma audi\u00eancia judicial agendada.<\/p>\n<p> Conhecida online por seu conte\u00fado sobre condicionamento f\u00edsico adaptado e vida com um bra\u00e7o s\u00f3, Katie conquistou um grande p\u00fablico atrav\u00e9s de v\u00eddeos que ela descreve como &quot;fazendo truques com um bra\u00e7o s\u00f3&quot;.<\/p>\n<p> A lei da Fl\u00f3rida que pro\u00edbe enviar mensagens de texto enquanto dirige impede que os motoristas digitem, leiam ou insiram informa\u00e7\u00f5es manualmente em um dispositivo sem fio enquanto operam um ve\u00edculo, embora existam exce\u00e7\u00f5es para navega\u00e7\u00e3o, comunica\u00e7\u00f5es de emerg\u00eancia e alguns usos de dispositivos m\u00e3os-livres.<\/p>\n<h3> Not\u00edcias relacionadas <\/h3>\n<p> Um homem da Fl\u00f3rida entrou com um processo de US$ 5 milh\u00f5es contra a Carnival Cruise Line por supostas queimaduras no deck da piscina. Um homem da Fl\u00f3rida foi preso por supostamente amea\u00e7ar uma modelo online em uma disputa sobre honor\u00e1rios por fotos. Veja Rick Ross exibindo seu luxuoso lago de carpas, deck de iate e muito mais em sua mans\u00e3o em Miami.<\/p>\n<h2> Not\u00edcias relacionadas<\/h2>\n<p> Zoran Mamdani est\u00e1 estabelecendo um novo precedente para autoridades eleitas ao lan\u00e7ar uma s\u00e9rie de transmiss\u00f5es ao vivo no Twitch.<\/p>\n<p> Tesouro de 10 mil d\u00f3lares encontrado em S\u00e3o Francisco: o que voc\u00ea precisa saber.<\/p>\n<p> LOJA COMPLETA: Compre suas marcas favoritas a qualquer hora, em qualquer lugar. Descubra as novidades. Compre. Colecione. Aproveite.<\/p>\n<p> Damos vida \u00e0 cultura. Aqui voc\u00ea encontra as \u00faltimas not\u00edcias do mundo do entretenimento, al\u00e9m do melhor conte\u00fado sobre m\u00fasica, cultura pop, t\u00eanis, estilo e s\u00e9ries originais.<\/p>","protected":false},"excerpt":{"rendered":"<p>Uma multa por dire\u00e7\u00e3o distra\u00edda aplicada a uma influenciadora da Fl\u00f3rida se transformou em um esc\u00e2ndalo viral na internet depois que imagens da c\u00e2mera corporal parecem contradizer a explica\u00e7\u00e3o\u2026<\/p>","protected":false},"author":1,"featured_media":6141,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6140","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selebriti","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/6140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=6140"}],"version-history":[{"count":3,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/6140\/revisions"}],"predecessor-version":[{"id":150044,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/6140\/revisions\/150044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/6141"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=6140"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=6140"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=6140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}