{"id":9156,"date":"2026-06-03T13:09:52","date_gmt":"2026-06-03T10:09:52","guid":{"rendered":"https:\/\/imgist.ru\/sidni-suini-sygraet-glavnuyu-rol-v-novoj-interpretaczii-legendy-o-sonnoj-loshhine\/"},"modified":"2026-06-03T13:09:52","modified_gmt":"2026-06-03T10:09:52","slug":"sidney-sweeney-estrelara-uma-nova-interpretacao-da-lenda-do-cavalo-adormecido","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/sidni-suini-sygraet-glavnuyu-rol-v-novoj-interpretaczii-legendy-o-sonnoj-loshhine\/","title":{"rendered":"Sydney Sweeney estrelar\u00e1 uma nova interpreta\u00e7\u00e3o de &quot;A Lenda do Cavaleiro Sem Cabe\u00e7a&quot;."},"content":{"rendered":"<p>Sydney Sweeney foi escalada para o papel principal em uma nova vers\u00e3o de &quot;A Lenda do Cavaleiro Sem Cabe\u00e7a&quot;. A atriz de Euphoria estrelar\u00e1 a adapta\u00e7\u00e3o cinematogr\u00e1fica do romance de estreia da roteirista Lindsay Anderson Beer, &quot;Hollow&quot;, com estreia prevista para o outono de 2027. Beer adaptar\u00e1 seu pr\u00f3prio romance para o cinema e dirigir\u00e1 o projeto.<\/p>\n<p> O romance \u00e9 uma ousada releitura do conto de Washington Irving de 1820, &quot;A Lenda do Cavaleiro Sem Cabe\u00e7a&quot;, narrada da perspectiva de Katrina Van Tassel, interpretada por Sweeney.<\/p>\n<p> Segundo o Deadline, Van Tassel interpreta um papel central em &quot;Hollow&quot;, um filme sobre um segredo perigoso e um sedutor tri\u00e2ngulo amoroso sobrenatural. A interpreta\u00e7\u00e3o moderna e conceitual combinar\u00e1 atmosfera g\u00f3tica, intriga psicol\u00f3gica e suspense er\u00f3tico.<\/p>\n<p> Al\u00e9m de estrelar o filme, Sweeney tamb\u00e9m produzir\u00e1 &quot;Hollow&quot; por meio de sua nova empresa, Honey Trap, anunciada no in\u00edcio desta semana. Esta adapta\u00e7\u00e3o ser\u00e1 o primeiro filme oficial da Honey Trap.<\/p>\n<p> A produtora de Margot Robbie, LuckyChap, tamb\u00e9m est\u00e1 produzindo em parceria com Beer para sua marca Lab Brew.<\/p>\n<p> Anteriormente, Bier escreveu e dirigiu o filme de 2023, Pet Sematary: Blood Ties, que marcou sua estreia na dire\u00e7\u00e3o, e escreveu a com\u00e9dia dram\u00e1tica adolescente de 2018, Sierra Burgess Is a Loser, uma vers\u00e3o moderna de Cyrano de Bergerac.<\/p>\n<p> A Lenda do Cavaleiro Sem Cabe\u00e7a conta a hist\u00f3ria de Ichabod Crane, que se muda para a tranquila vila rural de Sleepy Hollow e se apaixona por Van Tassel, filha do morador mais rico da cidade. Os habitantes acreditam na lenda do Cavaleiro Sem Cabe\u00e7a, que vaga pela regi\u00e3o \u00e0 noite.<\/p>\n<p> Este conto foi adaptado para o cinema in\u00fameras vezes, a come\u00e7ar pelo filme mudo de 1922, O Cavaleiro Sem Cabe\u00e7a. Talvez a vers\u00e3o mais famosa seja o filme de terror g\u00f3tico de Tim Burton, de 1999, estrelado por Johnny Depp como Crane e Christina Ricci como Van Tassel.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sydney Sweeney foi escalada para o papel principal em uma nova vers\u00e3o de &quot;A Lenda do Cavaleiro Sem Cabe\u00e7a&quot;. A atriz de &quot;Euphoria&quot; estrelar\u00e1 a adapta\u00e7\u00e3o cinematogr\u00e1fica do romance de estreia da roteirista Lindsay Anderson Beare.<\/p>","protected":false},"author":1,"featured_media":9157,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-9156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kinoindustriya","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/9156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=9156"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/9156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/9157"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=9156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=9156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=9156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}