{"id":9193,"date":"2026-06-03T13:19:28","date_gmt":"2026-06-03T10:19:28","guid":{"rendered":"https:\/\/imgist.ru\/kris-hemsvort-vspominaet-samyj-strashnyj-koshmar-lyubogo-otcza-v-aeroportu-vo-vremya-puteshestviya-s-detmi\/"},"modified":"2026-08-29T12:01:12","modified_gmt":"2026-08-29T09:01:12","slug":"chris-hemsworth-relembra-o-pior-pesadelo-de-qualquer-pai-ser-barrado-no-aeroporto-ao-viajar-com-os-filhos","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/kris-hemsvort-vspominaet-samyj-strashnyj-koshmar-lyubogo-otcza-v-aeroportu-vo-vremya-puteshestviya-s-detmi\/","title":{"rendered":"Chris Hemsworth relembra o pior pesadelo de todo pai ao viajar de avi\u00e3o com os filhos."},"content":{"rendered":"<h3>PRECISA SABER<\/h3>\n<ul>\n<li>\n<p> Em uma entrevista recente <em>Harper&#039;s Bazaar Ar\u00e1bia<\/em> Chris Hemsworth revelou o grande erro que cometeu enquanto era pai em um aeroporto.<\/p>\n<\/li>\n<li>\n<p> \u00ab&quot;Certa vez, cheguei ao aeroporto e estava com o passaporte da minha filha em vez do passaporte do meu filho&quot;, contou ele \u00e0 publica\u00e7\u00e3o, falando com sua esposa, Elsa Pataky.<\/p>\n<\/li>\n<li>\n<p> O astro da Marvel brincou: &quot;N\u00e3o funcionou&quot;, ent\u00e3o ele n\u00e3o p\u00f4de voar.<\/p>\n<\/li>\n<\/ul>\n<p> Chris Hemsworth cometeu uma vez um erro cl\u00e1ssico no aeroporto.<\/p>\n<p> Em uma entrevista <em>Harper&#039;s Bazaar Ar\u00e1bia,<\/em> Em uma publica\u00e7\u00e3o no Instagram na ter\u00e7a-feira, 2 de junho, Hemsworth, de 42 anos, e sua esposa, Elsa Pataky, de 49 anos, responderam a muitas perguntas sobre suas f\u00e9rias.<\/p>\n<p> Ao serem questionados sobre quem mais frequentemente esquece o passaporte, ambos apontaram um para o outro, ap\u00f3s o que o ator, <em>que interpretou Thor<\/em> , admitiu: \u00abUma vez eu estava no aeroporto e tinha o passaporte da minha filha em vez do do meu filho.\u00bb.<\/p>\n<p> \u00ab&quot;Eles at\u00e9 que se parecem um pouco&quot;, acrescentou ele, antes que a modelo e atriz Pataky insistisse: &quot;Mas n\u00e3o s\u00e3o&quot;.<\/p>\n<p> Hemsworth disse que falou para os funcion\u00e1rios do aeroporto: &quot;\u00c9 ela&quot;, mas eles perceberam automaticamente o seu erro.<\/p>\n<p> \u00abEles disseram: \u201e\u00c9 um menino\u201c\u00bb, relembra a estrela. <em>filme &quot;Opera\u00e7\u00e3o de Resgate&quot;<\/em> \u00bb&quot;Ent\u00e3o n\u00e3o funcionou.&quot;.<\/p>\n<p> Hemsworth e Pataky, que se casaram em 2010, t\u00eam tr\u00eas filhos: a filha India Rose, de 14 anos, e os g\u00eameos Sasha e Tristan, de 12 anos.<\/p>\n<p> <strong>N\u00e3o perca nenhuma novidade - inscreva-se!<\/strong> <strong>newsletter di\u00e1ria gratuita PEOPLE<\/strong> <strong>, Para ficar por dentro do melhor que a revista PEOPLE tem a oferecer, desde not\u00edcias sobre celebridades at\u00e9 hist\u00f3rias humanas inspiradoras.<\/strong><\/p>\n<p> Em entrevista concedida \u00e0 revista PEOPLE em fevereiro, o casal revelou o segredo de seu relacionamento duradouro. <\/p>\n<p> Chris Hemsworth e Elsa Pataky com seus filhos. Foto: Elsa Pataky\/Instagram<\/p>\n<p> \u00ab&quot;Elsa tem uma honestidade, uma luz guia de verdade. Posso mostrar algo para muitas outras pessoas, e elas podem dizer: &#039;Oh, \u00f3timo trabalho&#039;, mas Elsa me dir\u00e1 se estiver terr\u00edvel&quot;, disse Hemsworth.<\/p>\n<p> \u00ab&quot;Vou dizer para ele: &#039;Isso n\u00e3o tem gra\u00e7a. Isso n\u00e3o est\u00e1 funcionando&#039;&quot;, acrescentou Pataki na ocasi\u00e3o.<\/p>\n<p> Essa honestidade, que Hemsworth descreveu como &quot;avalia\u00e7\u00e3o cr\u00edtica&quot;, \u00e9 fundamental porque sua esposa &quot;sabe quem eu sou, e n\u00f3s sabemos do que cada um de n\u00f3s \u00e9 capaz&quot;.<\/p>\n<p> Hemsworth acrescentou: &quot;A honestidade de Elsa \u00e9 meu par\u00e2metro de sucesso. Levo isso em considera\u00e7\u00e3o quando trabalho em filmes, comerciais e tudo mais. Todos os outros podem me dizer uma coisa, mas sei que dela receberei a verdade absoluta.&quot;.<\/p>\n<p> \u00ab&quot;E \u00e0s vezes \u00e9 expresso de forma delicada para n\u00e3o me magoar, pelo que sou grata&quot;, brincou a estrela. <\/p>\n<p> Chris Hemsworth e Elsa Pataky. Foto: Jeff Spicer\/Getty<\/p>\n<p> Hemsworth e Pataky se conheceram em 2010 e se casaram naquele mesmo ano, na Austr\u00e1lia, no dia de Natal.<\/p>\n<p> Embora o casal esteja sob os holofotes devido \u00e0s suas carreiras, eles n\u00e3o escondem o desejo de proporcionar aos filhos uma cria\u00e7\u00e3o normal.<\/p>\n<p> \u00ab&quot;Quero que eles valorizem tudo&quot;, disse o ator da Marvel \u00e0 revista PEOPLE em 2017. &quot;Cresci em circunst\u00e2ncias muito humildes, mas meus pais foram meus verdadeiros her\u00f3is. Eles eram pessoas respeitosas e gentis, que constantemente me inspiravam, cuidavam de mim e demonstravam amor.&quot;.<\/p>\n<p> E Hemsworth espera incutir esses mesmos valores em seus filhos.<\/p>\n<p> \u00ab&quot;Quando eu era crian\u00e7a, t\u00ednhamos muito pouco dinheiro, e meus pais economizaram durante um ano inteiro para pagar apenas duas semanas de f\u00e9rias em um acampamento&quot;, disse ele na \u00e9poca.<\/p>\n<p> \u00ab&quot;Estamos em uma situa\u00e7\u00e3o financeira diferente, mas quero que eles saibam que essas coisas n\u00e3o v\u00eam f\u00e1cil. Elas exigem trabalho e n\u00e3o podem ser consideradas garantidas. O sucesso depende mais dos nossos valores e do tipo de pessoa que somos do que dos bens materiais que podemos adquirir&quot;, continuou o ator.<\/p>\n<p> Leia o artigo original na revista People.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c9 NECESS\u00c1RIO SABER: Em uma entrevista recente \u00e0 Harper&#039;s Bazaar Arabia, Chris Hemsworth revelou um grande erro que cometeu enquanto era pai no aeroporto. &quot;Certa vez...<\/p>","protected":false},"author":1,"featured_media":9194,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-9193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-selebriti","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/9193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=9193"}],"version-history":[{"count":2,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/9193\/revisions"}],"predecessor-version":[{"id":152911,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/9193\/revisions\/152911"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/9194"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=9193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=9193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=9193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}