{"id":98766,"date":"2018-01-23T23:03:57","date_gmt":"2018-01-23T20:03:57","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/?p=1686"},"modified":"2018-01-23T23:03:57","modified_gmt":"2018-01-23T20:03:57","slug":"12-motivos-reais-para-ir-a-academia","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/top-12-nastoyashhix-prichin-pojti-v-sportzal\/","title":{"rendered":"12 motivos reais para ir \u00e0 academia"},"content":{"rendered":"<p>Se voc\u00ea est\u00e1 procurando motivos para ir \u00e0 academia, provavelmente \u00e9 uma pessoa pregui\u00e7osa. Mas n\u00e3o se preocupe, ningu\u00e9m est\u00e1 te julgando. Todo mundo precisa de motiva\u00e7\u00e3o para qualquer empreitada. Mesmo que voc\u00ea n\u00e3o frequente a academia, n\u00e3o se preocupe, voc\u00ea n\u00e3o est\u00e1 sozinho. Cerca de 671 mil pessoas que t\u00eam matr\u00edculas em academias nunca as usam. Se voc\u00ea ainda est\u00e1 se perguntando como se motivar a ir \u00e0 academia, aqui est\u00e3o 12 motivos que devem te convencer de que \u00e9 a decis\u00e3o certa.<\/p>\n<p>Se esta lista n\u00e3o te convencer a ir \u00e0 academia, voc\u00ea est\u00e1 perdendo uma etapa muito importante da sua vida.<\/p>\n<h2>1. Uma boa maneira de aliviar o estresse<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1691\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-1.jpg\" alt=\"\" width=\"800\" height=\"533\" \/><\/p>\n<p>Voc\u00ea trabalha das 8h \u00e0s 17h e se sente sobrecarregado? Sua esposa ou namorada vive reclamando? Ir \u00e0 academia \u00e9 a melhor maneira de escapar da rotina e aliviar o estresse. Para muitos, a academia \u00e9 um ref\u00fagio, um espa\u00e7o pessoal para esquecer o dia a dia, focar em si mesmo e se dar algumas horas de liberdade.<\/p>\n<p>Ent\u00e3o, v\u00e1 para a academia, desligue o celular e fa\u00e7a um favor ao seu corpo e aos seus nervos. Ao entrar em forma, voc\u00ea mudar\u00e1 seus pensamentos e receber\u00e1 uma dose de bom humor. Depois de um dia \u00e1rduo de trabalho, voc\u00ea sair\u00e1 da academia se sentindo euf\u00f3rico e pronto para qualquer desafio. Todo o nervosismo e estresse acumulados durante o dia desaparecem sem deixar vest\u00edgios ap\u00f3s a academia, ou at\u00e9 mesmo se tornam irrelevantes. Muitas pessoas se distraem dos problemas cotidianos enquanto se exercitam, mas quando voltam a se concentrar em um problema antigo e insol\u00favel, de repente encontram uma solu\u00e7\u00e3o.<\/p>\n<p>Enquanto voc\u00ea perde peso e ganha massa muscular, esquecer\u00e1 o estresse para sempre e deixar\u00e1 de tomar sedativos em grandes quantidades.<\/p>\n<h2>2. Se voc\u00ea n\u00e3o tiver nada para fazer<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1696\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-6.jpg\" alt=\"\" width=\"764\" height=\"480\" \/><\/p>\n<p>Se voc\u00ea tem muito tempo livre e est\u00e1 se perguntando o que fazer com ele, por que n\u00e3o ir \u00e0 academia? Agora eu tenho uma ideia. A academia pode ser uma \u00f3tima v\u00e1lvula de escape. \u00c9 um lugar onde voc\u00ea pode ir e fazer um treino produtivo em vez de perder tempo no sof\u00e1 navegando nas redes sociais.<\/p>\n<p>Ir \u00e0 academia n\u00e3o s\u00f3 lhe permitir\u00e1 se divertir, como tamb\u00e9m o impedir\u00e1 de fazer coisas desnecess\u00e1rias.<\/p>\n<p>A academia pode facilmente se tornar uma barreira para o resto da sua vida di\u00e1ria. Voc\u00ea vai querer parar de beber e fumar, e vai considerar cada vez mais uma alimenta\u00e7\u00e3o saud\u00e1vel. Em outras palavras, voc\u00ea vai embarcar no &quot;trem da sa\u00fade&quot;, como alguns gostam de chamar. E uma vez que voc\u00ea entra nele, muitos n\u00e3o querem mais sair.<\/p>\n<h2>3. A capacidade de prolongar a sua vida<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1701\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-11.jpg\" alt=\"\" width=\"650\" height=\"389\" \/><\/p>\n<p>Todos os seres humanos s\u00e3o mortais, mas amam a vida e desejam permanecer aqui o m\u00e1ximo de tempo poss\u00edvel. Isso \u00e9 completamente natural, est\u00e1 enraizado em nosso DNA.<\/p>\n<p>Existe um pequeno segredo para viver uma vida longa e saud\u00e1vel: primeiro, voc\u00ea precisa ser saud\u00e1vel. Isso pode parecer \u00f3bvio, mas muitas vezes as pessoas ficam sentadas sem fazer nada, se perguntando por que suas vidas parecem estar escapando por entre seus dedos. Elas costumam pensar: &quot;Ah, vou come\u00e7ar a me alimentar bem na semana que vem&quot; ou &quot;Vou \u00e0 academia amanh\u00e3&quot;. Muitas pessoas acham que amanh\u00e3 \u00e9 outro dia.<\/p>\n<p>Isso n\u00e3o \u00e9 nada bom. Se voc\u00ea quer viver mais, fa\u00e7a exerc\u00edcios diariamente e alimente-se corretamente. Est\u00e1 na hora de come\u00e7ar, e qualquer outra desculpa que voc\u00ea possa ter \u00e9 um obst\u00e1culo. \u00c9 pura pregui\u00e7a!<\/p>\n<p>\u00ab&quot;Falta de tempo&quot; \u00e9 a desculpa mais comum. Sempre h\u00e1 tempo. Todo o resto s\u00e3o apenas desculpas. O amanh\u00e3 pode nunca chegar. Mas o hoje \u00e9 para aproveitar ao m\u00e1ximo.<\/p>\n<h2>4. Deixe seu corpo bonito e atraente.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1698 size-full\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-8.jpg\" alt=\"\" width=\"1000\" height=\"445\" \/><\/p>\n<p>Nove em cada dez pessoas que desejam ter um corpo bonito e atraente consideram esse o principal motivo para frequentar a academia. Ali\u00e1s, pode-se afirmar que a academia \u00e9 o que as motiva.<\/p>\n<p>Ser saud\u00e1vel \u00e9 sempre \u00f3timo. Faz bem para o corpo e \u00e9 fant\u00e1stico para a sa\u00fade em geral e para a longevidade. No entanto, ser saud\u00e1vel tamb\u00e9m significa ter um corpo bonito. Quem n\u00e3o quer um cara super atraente com tanquinho? N\u00e3o \u00e9 segredo que os humanos s\u00e3o instintivamente atra\u00eddos por pessoas saud\u00e1veis. Est\u00e1 no nosso DNA. Queremos nos reproduzir com outras pessoas saud\u00e1veis para que nossos filhos tenham uma chance maior de sobreviv\u00eancia. Parece estranho? Veja este v\u00eddeo sobre atra\u00e7\u00e3o sexual humana. \u00c9 interessante.<\/p>\n<p>Por mais bobo que pare\u00e7a, ter um corpo saud\u00e1vel pode te ajudar mais do que voc\u00ea imagina. Isso te dar\u00e1 confian\u00e7a. Melhorar\u00e1 sua vida social. Pode at\u00e9 te ajudar a conseguir um emprego! O Dr. Price conduziu um estudo sobre como pessoas mais saud\u00e1veis s\u00e3o estatisticamente mais bem-sucedidas do que aquelas que, em vez de se exercitarem, ficam deitadas no sof\u00e1 assistindo TV ou navegando na internet.<\/p>\n<p>Ent\u00e3o, caso voc\u00ea n\u00e3o esteja interessado na sua sa\u00fade, veja agora como ir \u00e0 academia pode te ajudar no trabalho! Quer conseguir um novo emprego? Talvez voc\u00ea deva perder alguns quilos primeiro.<\/p>\n<h2>5. \u00d3timo hobby<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1702\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-12.jpg\" alt=\"\" width=\"604\" height=\"404\" \/><\/p>\n<p>\u00c9 comum encontrarmos atletas que, sem nem perceber, transformaram o esporte em um hobby. Muitas pessoas t\u00eam um passatempo favorito. Algumas colecionam moedas, outras esquiam, outras simplesmente v\u00e3o \u00e0 sauna. A academia tamb\u00e9m \u00e9 um hobby, e um \u00f3timo hobby, diga-se de passagem.<\/p>\n<p>Se voc\u00ea encontrar algo que ame, persista. Fa\u00e7a disso seu hobby. A academia \u00e9 \u00f3tima para isso, porque h\u00e1 muito o que aprender e explorar. Voc\u00ea pode definir metas e alcan\u00e7\u00e1-las. \u00c9 uma daquelas coisas que podem facilmente viciar.<\/p>\n<p>Algumas pessoas dir\u00e3o que \u00e9 ruim ser viciado em qualquer coisa, mas se voc\u00ea perguntar a qualquer pessoa com um f\u00edsico excelente, ela ser\u00e1 a primeira a lhe dizer que a academia \u00e9 um \u00f3timo lugar, seja voc\u00ea viciado ou n\u00e3o. Na verdade, \u00e9 \u00f3timo mesmo.<\/p>\n<h2>6. Investir em si mesmo<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1697 size-large\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-7.jpg\" alt=\"\" width=\"1024\" height=\"633\" \/><\/p>\n<p>Certo, talvez voc\u00ea esteja com pouco dinheiro e pensando: &quot;Por que ir \u00e0 academia se posso me exercitar em casa?&quot; \u00d3timo, mas o que acontece quando chove ou neva? Voc\u00ea pretende sair para correr? Provavelmente n\u00e3o.<\/p>\n<p>Se voc\u00ea \u00e9 s\u00f3cio de uma academia, provavelmente n\u00e3o pode faltar a um treino, sen\u00e3o perder\u00e1 o dinheiro investido, o que ter\u00e1 um impacto negativo no seu or\u00e7amento. \u00c9 um fato. Se voc\u00ea n\u00e3o gosta de neve ou calor intenso, a academia \u00e9 o lugar perfeito para correr e se exercitar, independentemente do clima.<\/p>\n<p>Voc\u00ea deve encarar a academia como um investimento em si mesmo. Pode parecer estranho, mas isso ter\u00e1 um impacto positivo no seu bem-estar. N\u00e3o se preocupe com o custo. Voc\u00ea s\u00f3 tem um corpo e deve cuidar dele. Invista na sua longevidade. Voc\u00ea n\u00e3o vai se arrepender!<\/p>\n<h2>7. Melhorar suas habilidades f\u00edsicas<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1699\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-9.jpg\" alt=\"\" width=\"650\" height=\"413\" \/><\/p>\n<p>Muitas de nossas habilidades atl\u00e9ticas s\u00e3o gen\u00e9ticas, e tamb\u00e9m \u00e9 verdade que maior for\u00e7a f\u00edsica e resist\u00eancia s\u00e3o conquistadas na academia. Esses fatores est\u00e3o diretamente relacionados ao desempenho atl\u00e9tico geral, e isso \u00e9 um fato.<\/p>\n<p>Se voc\u00ea quer desenvolver um f\u00edsico atl\u00e9tico, n\u00e3o h\u00e1 lugar melhor para isso do que na academia. Seja para entrar no time de futebol, jogar futebol ou simplesmente melhorar seu condicionamento f\u00edsico geral, o levantamento de peso \u00e9 uma das suas melhores op\u00e7\u00f5es.<\/p>\n<h2>8. Isso ter\u00e1 um impacto positivo em sua vida pessoal.<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1695 size-large\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-5.jpg\" alt=\"\" width=\"1024\" height=\"682\" \/><\/p>\n<p>As pessoas adoram sexualidade \u2014 isso \u00e9 um fato. Gostamos de estar perto de pessoas atraentes; ficamos impressionados com elas e as respeitamos. Se voc\u00ea vai \u00e0 academia, est\u00e1 ajudando seu corpo a ficar mais atraente.<\/p>\n<p>Voc\u00ea se sentir\u00e1 mais confiante ao conversar com seu c\u00f4njuge, amigo ou colega usando uma roupa ajustada e elegante do que com seus jeans sem forma favoritos ou roupas largas que s\u00e3o feitas para esconder n\u00e3o apenas suas imperfei\u00e7\u00f5es, mas tamb\u00e9m seus melhores atributos.<\/p>\n<p>Voc\u00ea tamb\u00e9m ter\u00e1 mais energia para estar perto de pessoas. Sentir\u00e1 vontade de sair e socializar, em vez de ficar em casa. Exercitar-se nos d\u00e1 um corpo que pode nos ajudar a nos sentirmos atraentes, seja com um marido ou, se voc\u00ea for solteira, uma forma de encontrar uma alma g\u00eamea. Energia e coragem s\u00e3o qualidades valiosas em sua vida e podem lhe proporcionar ainda mais do que voc\u00ea imagina.<\/p>\n<h2>9. Para aumentar a autoestima<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1694 size-large\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-4.jpg\" alt=\"\" width=\"1024\" height=\"1024\" \/><\/p>\n<p>Se voc\u00ea vai sair de f\u00e9rias ou simplesmente quer dar in\u00edcio \u00e0 temporada de praia, o ideal \u00e9 usar um biqu\u00edni sexy, e n\u00e3o um mai\u00f4 que pare\u00e7a uma capa de chuva, para que voc\u00ea possa se esconder nele como um caracol dentro de uma concha.<\/p>\n<p>Ir \u00e0 academia pode ser um passo a mais para usar aquela cal\u00e7a jeans favorita que voc\u00ea n\u00e3o veste h\u00e1 mais de dois anos. O aumento da autoestima que voc\u00ea obt\u00e9m com a sua apar\u00eancia n\u00e3o deve ser subestimado.<\/p>\n<p>A confian\u00e7a est\u00e1 intrinsecamente ligada \u00e0 apar\u00eancia e, infelizmente, neste mundo, todos n\u00f3s nos comparamos e julgamos a n\u00f3s mesmos e aos outros pela nossa apar\u00eancia.<\/p>\n<p>Treinos regulares na academia ajudar\u00e3o voc\u00ea a sentir que pode aproveitar mais a vida em apenas algumas semanas, e voc\u00ea brilhar\u00e1 sob os holofotes gra\u00e7as \u00e0 sua beleza interior e exterior.<\/p>\n<h2>10. Descanso da fam\u00edlia, tempo pessoal<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1704\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-14.jpg\" alt=\"\" width=\"559\" height=\"366\" \/><\/p>\n<p>Muitas vezes acontece de, al\u00e9m do trabalho e da vida familiar, a rotina tomar conta de tudo e voc\u00ea se sentir sufocado. Voc\u00ea quer fazer algo produtivo, mas est\u00e1 girando como um esquilo num ciclo &quot;casa-trabalho-casa&quot;. Com uma rotina dessas, qualquer pessoa sensata simplesmente procuraria uma desculpa para sair de casa ou se esquivar do trabalho, s\u00f3 para respirar fundo e olhar para cima. Sua esposa est\u00e1 reclamando, as crian\u00e7as est\u00e3o pulando por a\u00ed, sua sogra est\u00e1 te enlouquecendo? Deixe tudo de lado e v\u00e1 para a academia. Sua mente vai clarear, seus pensamentos v\u00e3o se organizar. Seu marido come\u00e7ou a olhar para outra pessoa, ou seu namorado come\u00e7ou a sumir com os amigos \u00e0 noite sem voc\u00ea? Deixe tudo como est\u00e1, v\u00e1 para a academia. Voc\u00ea vai relaxar, sua mente vai clarear, sua respira\u00e7\u00e3o vai ficar mais f\u00e1cil e, em casa, voc\u00eas ter\u00e3o algo para conversar al\u00e9m de reclamar um do outro. Quem sabe, talvez com o tempo voc\u00eas comecem a ir \u00e0 academia juntos, e isso se torne n\u00e3o apenas um espa\u00e7o pessoal e uma fuga, mas uma nova tradi\u00e7\u00e3o rom\u00e2ntica em fam\u00edlia?<\/p>\n<h2>11. Trabalhando com um instrutor<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1692\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-2.jpg\" alt=\"\" width=\"770\" height=\"472\" \/><\/p>\n<p>Cada pessoa \u00e9 \u00fanica em sua personalidade, tipo f\u00edsico e estilo de vida. Programas de exerc\u00edcios padr\u00e3o n\u00e3o s\u00e3o adequados para todos. Algumas pessoas t\u00eam les\u00f5es, outras t\u00eam problemas de sa\u00fade que limitam sua capacidade de realizar todos os treinos, mas ainda assim querem ir \u00e0 academia, e algumas t\u00eam rea\u00e7\u00f5es \u00fanicas ao exerc\u00edcio. Mesmo aqueles que querem ir \u00e0 academia, mas n\u00e3o sabem o que fazer l\u00e1, tamb\u00e9m precisam de motiva\u00e7\u00e3o extra. Para todas essas pessoas, existe uma \u00f3tima solu\u00e7\u00e3o: trabalhar com um personal trainer. Sob a supervis\u00e3o dele, voc\u00ea pode ter certeza de que ele criar\u00e1 um programa de exerc\u00edcios personalizado, adaptado \u00e0s necessidades do seu corpo e aos resultados desejados. Embora o custo de uma sess\u00e3o com um personal trainer seja um pouco maior do que a mensalidade de uma aula individual, vale a pena. Voc\u00ea pode frequentar apenas algumas aulas at\u00e9 se sentir confort\u00e1vel com os exerc\u00edcios, mas ser\u00e1 muito mais eficaz do que ter receio de ir \u00e0 academia.<\/p>\n<h2>12. Um motivo para renovar seu guarda-roupa<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1703\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2018\/01\/%D1%81%D0%BF%D0%BE%D1%80%D1%82%D0%B7%D0%B0%D0%BB-13.jpg\" alt=\"\" width=\"659\" height=\"380\" \/><\/p>\n<p>Come\u00e7ar uma rotina na academia n\u00e3o se resume a simplesmente ir at\u00e9 l\u00e1; \u00e9 um ritual especial. Voc\u00ea pode pegar sua cal\u00e7a de moletom favorita, sua camiseta de sempre e um t\u00eanis velho do arm\u00e1rio e sair para malhar. Mas uma ida \u00e0 loja para comprar um novo agasalho e um par de t\u00eanis confort\u00e1veis n\u00e3o s\u00f3 aumentar\u00e1 sua autoestima, como tamb\u00e9m melhorar\u00e1 seu desempenho. O motivo pode parecer superficial, mas a autoestima \u00e9 algo positivo, e uma maneira de aument\u00e1-la \u00e9 comprando algo novo para si mesmo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Se voc\u00ea est\u00e1 procurando motivos para ir \u00e0 academia, provavelmente \u00e9 uma pessoa pregui\u00e7osa. Mas n\u00e3o se preocupe, ningu\u00e9m est\u00e1 te julgando. Todo mundo precisa de um pouco de...<\/p>","protected":false},"author":1,"featured_media":1691,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-98766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/98766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=98766"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/98766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/1691"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=98766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=98766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=98766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}