{"id":99108,"date":"2022-08-10T00:00:00","date_gmt":"2022-08-09T21:00:00","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni\/"},"modified":"2022-08-10T00:00:00","modified_gmt":"2022-08-09T21:00:00","slug":"10-maneiras-interessantes-de-procurar-vida-extraterrestre","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni\/","title":{"rendered":"10 maneiras interessantes de procurar vida extraterrestre"},"content":{"rendered":"<div readability=\"248.60633705303\">\n<p><span>Carl Sagan disse certa vez: &quot;Em algum lugar, algo incr\u00edvel est\u00e1 esperando para ser descoberto&quot;. \u00c9 esse desejo de conhecer o desconhecido que impulsiona a humanidade al\u00e9m das estrelas. Estendemos a m\u00e3o para al\u00e9m do nosso pr\u00f3prio mundo, rumo ao cosmos, para ver o que existe l\u00e1 fora. E o que descobrimos est\u00e1 literalmente al\u00e9m da nossa compreens\u00e3o. O telesc\u00f3pio.<\/span> <span>James Webb<\/span> <span>Enviaram imagens do universo que remontam a mais de 13 bilh\u00f5es de anos, quase \u00e0 sua pr\u00f3pria cria\u00e7\u00e3o.<\/span><\/p>\n<p> <span>J\u00e1 vimos milhares de gal\u00e1xias contendo bilh\u00f5es de estrelas e potencialmente centenas de bilh\u00f5es de mundos. Todos no espa\u00e7o, assim como n\u00f3s. E a pergunta permanece: existem outros seres como n\u00f3s entre eles? Existem outras pessoas l\u00e1 fora? Ou coisas que respiram, vivem e crescem? A busca continua e envolve mais m\u00e9todos do que voc\u00ea imagina.<\/span><\/p>\n<h2> <span>10. Monitoramento da luz das estrelas<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-70264\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_641077151b555.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>O vasto espa\u00e7o entre aqui e literalmente qualquer outro lugar torna a busca por vida extraterrestre um pouco mais desafiadora do que encontrar um par de meias perdidas. Em muitos casos, \u00e9 mais f\u00e1cil procurar n\u00e3o por extraterrestres em si, mas por sinais de que eles existem. \u00c9 por isso que come\u00e7amos a monitorar a luz das estrelas.<\/span><\/p>\n<p> <span>A luz de estrelas distantes \u00e9 frequentemente uma das poucas coisas que podemos ver de uma gal\u00e1xia distante. Mesmo com o Telesc\u00f3pio James Webb, n\u00e3o vamos conseguir espiar pelas janelas de casas alien\u00edgenas. Mas uma estrela pode nos dizer muito sobre um determinado sistema solar simplesmente analisando a luz que ela emite em nossa dire\u00e7\u00e3o.<\/span><\/p>\n<p> <span>A Starlight tamb\u00e9m busca sinais de tecnologia alien\u00edgena, n\u00e3o apenas seus mundos. Por exemplo, se houver uma esta\u00e7\u00e3o espacial gigantesca, ela projetar\u00e1 uma sombra, e tamb\u00e9m seremos capazes de ver a Starlight bloqueando a sombra. A ideia \u00e9 que uma ra\u00e7a suficientemente avan\u00e7ada criaria sistemas incr\u00edveis.<\/span> <span>feitos tecnol\u00f3gicos<\/span> <span>, como usinas de energia do tamanho de estrelas ou computadores que ocupam sistemas solares inteiros.<\/span><\/p>\n<p> <span>Estrelas como aquela distante<\/span> <span>A estrela de Boyajian,<\/span> <span>s\u00e3o propensas a escurecimento peri\u00f3dico, levando os cientistas a se perguntarem se existem megaestruturas alien\u00edgenas que poderiam interferir na transmiss\u00e3o de luz de l\u00e1 para c\u00e1.<\/span><\/p>\n<h2> <span>9. Rastreamento de bioassinaturas em atmosferas extraterrestres<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-64298\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_641077160baa6.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Os planetas passam em frente \u00e0s estrelas. Isso \u00e9 feito usando uma t\u00e9cnica chamada<\/span> <span>espectroscopia<\/span> <span>, Podemos analisar o espectro de luz emitido por uma estrela quando um planeta passa em frente a ela. Ocorrer\u00e1 uma mudan\u00e7a de cor, permitindo-nos ver o espectro do pr\u00f3prio planeta e dos gases que devem estar presentes em sua atmosfera para filtrar certas frequ\u00eancias de luz.<\/span><\/p>\n<p> <span>O metano \u00e9 um g\u00e1s produzido por seres vivos que conhecemos e que contribui para a vida. Se um planeta possui metano em sua atmosfera, ele pode ser um potencial portador de vida. Portanto, podemos analisar o espectro de luz, filtrar a luz n\u00e3o alterada da estrela e determinar quais gases est\u00e3o presentes na atmosfera do planeta e, potencialmente, se ele abriga vida.<\/span><\/p>\n<p> <span>Com milhares de exoplanetas j\u00e1 descobertos e, agora, gra\u00e7as ao telesc\u00f3pio Webb, dezenas de milhares mais no horizonte, haver\u00e1 muitas oportunidades para procurar vida. Restringir a busca significa procurar por coisas espec\u00edficas, como...<\/span> <span>bioassinaturas<\/span> <span>, sinais de que existe, ou pelo menos poderia existir, vida no planeta.<\/span><\/p>\n<p> <span>Buscamos na atmosfera gases como oxig\u00eanio e metano, subst\u00e2ncias que sabemos serem essenciais \u00e0 vida, pois est\u00e3o presentes em nossa pr\u00f3pria atmosfera e os seres vivos precisam delas ou as produzem. Embora o oxig\u00eanio seja uma escolha \u00f3bvia, n\u00e3o se trata de uma quest\u00e3o de tudo ou nada, especialmente porque sabemos que o oxig\u00eanio s\u00f3 existe na Terra h\u00e1 parte de sua hist\u00f3ria. Em vez disso, os cientistas identificaram milhares de compostos potenciais que<\/span> <span>pode indicar vida<\/span> <span>, que podemos procurar. Coisas como di\u00f3xido de carbono, mas n\u00e3o mon\u00f3xido de carbono, tamb\u00e9m s\u00e3o potenciais indicadores de vida, ou pelo menos de habitabilidade.<\/span><\/p>\n<h2> <span>8. Tecnoassinaturas em uma atmosfera alien\u00edgena<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-64299\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_64107716cffc4.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Vimos, ent\u00e3o, como as bioassinaturas e as tecnologias s\u00e3o alvos na busca por vida extraterrestre. Mas, com uma pequena modifica\u00e7\u00e3o nesses m\u00e9todos de busca, tamb\u00e9m podemos nos concentrar nas tecnoassinaturas.<\/span><\/p>\n<p> <span>O que descrevemos at\u00e9 agora \u00e9 uma busca por marcadores de vida ou pelo potencial para a vida. A busca por tecnoassinaturas \u00e9 uma busca por sinais de atividade industrial. Mais precisamente, polui\u00e7\u00e3o. Uma esp\u00e9cie capaz de construir \u00e9 capaz de poluir. Isso significa que podemos vasculhar a atmosfera.<\/span> <span>, Por exemplo,<\/span> <span>di\u00f3xido de nitrog\u00eanio<\/span> . <span>Embora provenha de fontes naturais, tamb\u00e9m prov\u00e9m da queima de combust\u00edveis.<\/span><\/p>\n<p> <span>Os pain\u00e9is solares s\u00e3o outra poss\u00edvel assinatura tecnol\u00f3gica que poder\u00edamos detectar. Como todo planeta precisa orbitar uma estrela para que a vida exista, \u00e9 razo\u00e1vel supor que esp\u00e9cies inteligentes aproveitariam a energia de seu sol da mesma forma que n\u00f3s. Os pain\u00e9is solares refletem muita luz, e essa luz teria um perfil espec\u00edfico.<\/span> <span>caracter\u00edstica espectral<\/span> <span>. Se encontrarmos isso, pode ser um sinal de vida.<\/span><\/p>\n<h2> <span>7. Sinais de r\u00e1dio<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-79309\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_64107717a7f2e.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>Uma das maneiras mais antigas e ainda populares de procurar vida extraterrestre \u00e9 buscando sinais de r\u00e1dio. Pesquisadores do Instituto de Tecnologia de Massachusetts (MIT) descobriram que...<\/span> em julho de 2023 <span>sinal repetitivo,<\/span> <span>Um sinal semelhante a uma batida card\u00edaca emanando de bilh\u00f5es de anos-luz da Terra. Sua localiza\u00e7\u00e3o exata ainda n\u00e3o foi determinada, mas est\u00e1 entre muitos sinais, alguns misteriosos e outros naturais, que descobrimos.<\/span> <span>ao longo dos anos<\/span> <span>.<\/span><\/p>\n<p> <span>Pouco antes desse sinal, cientistas chineses anunciaram que tamb\u00e9m haviam detectado um sinal alien\u00edgena, possivelmente de uma intelig\u00eancia extraterrestre, usando seus enormes telesc\u00f3pios.<\/span> <span>Telesc\u00f3pio Sky Eye<\/span> <span>.<\/span><\/p>\n<p> <span>O SETI, programa de busca por intelig\u00eancia extraterrestre, come\u00e7ou a procurar sinais de r\u00e1dio em 1960 com seu<\/span> <span>Projeto Ozma<\/span> <span>. Um dos maiores desafios desse m\u00e9todo \u00e9 a necessidade de restringir a \u00e1rea de busca na imensid\u00e3o do espa\u00e7o e o fato de existirem muitas fontes naturais de ondas de r\u00e1dio. Estrelas e muitos outros corpos celestes emitem radiofrequ\u00eancias, e precisam ser examinados e descartados durante a busca. A esperan\u00e7a \u00e9 encontrar, um dia, um sinal que seja mais do que apenas ru\u00eddo de fundo e que ofere\u00e7a uma indica\u00e7\u00e3o clara de inten\u00e7\u00e3o inteligente.<\/span><\/p>\n<h2> <span>6. Telesc\u00f3pios<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-66721\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_641077187c869.jpeg\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Talvez a maneira mais \u00f3bvia de encontrar planetas ainda esteja na vanguarda dos esfor\u00e7os. Usar um telesc\u00f3pio n\u00e3o \u00e9 t\u00e3o simples quanto parece, mas \u00e9 assim que obtemos aquelas imagens incr\u00edveis que telesc\u00f3pios como o Hubble e o Webb nos retornam. A parte mais dif\u00edcil \u00e9 saber onde procurar.<\/span><\/p>\n<p> <span>Existem muitos sinais reveladores nos quais voc\u00ea pode confiar para determinar para onde apontar seu telesc\u00f3pio. Um m\u00e9todo \u00e9<\/span> <span>m\u00e9todo de oscila\u00e7\u00e3o<\/span> <span>. Voc\u00ea encontra uma estrela distante e observa sua luz. Se a estrela parecer oscilar, significa que algo pode estar orbitando-a, ent\u00e3o voc\u00ea aponta seu telesc\u00f3pio para essa regi\u00e3o.<\/span><\/p>\n<p> <span>J\u00e1 enchemos o c\u00e9u<\/span><span>numerosos sat\u00e9lites<\/span> <span>e sondas que nos ajudar\u00e3o na busca. Webb e Hubble s\u00e3o duas delas, mas tamb\u00e9m h\u00e1 Spitzer, Kepler, Tess e Cheops, com muitas outras a caminho. A Ag\u00eancia Espacial Europeia planeja<\/span> <span>lan\u00e7amento PLATO<\/span> <span>Em 2025, com a capacidade de observar 1 milh\u00e3o de estrelas e procurar planetas ao seu redor.<\/span><\/p>\n<h2> <span>5. Comunica\u00e7\u00f5es qu\u00e2nticas<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-66724\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_6410771932c81.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>A pessoa comum n\u00e3o est\u00e1 muito familiarizada com a ideia de comunica\u00e7\u00e3o qu\u00e2ntica, mas ela interessa a quem busca vida extraterrestre. Sinais podem ser enviados atrav\u00e9s de gal\u00e1xias usando f\u00f3tons sem perda de informa\u00e7\u00e3o. Em vez de bits padr\u00e3o, como os que usamos em nossos computadores hoje, com seus 1s e 0s, a comunica\u00e7\u00e3o qu\u00e2ntica usa algo chamado qubits. As pessoas ainda est\u00e3o explorando essa ideia para desenvolver redes de comunica\u00e7\u00e3o seguras, que acreditamos que proporcionar\u00e3o seguran\u00e7a sem precedentes para uma poss\u00edvel vida.<\/span> <span>internet qu\u00e2ntica<\/span> <span>.<\/span><\/p>\n<p> <span>Embora ainda estejamos a come\u00e7ar a entender, a ideia \u00e9 que<\/span> <span>tipos mais complexos<\/span> <span>Ter\u00edamos dominado essa t\u00e9cnica e j\u00e1 poder\u00edamos us\u00e1-la. Isso tamb\u00e9m poderia explicar por que nossa busca por sinais \u00e9 t\u00e3o infrut\u00edfera. Procurar por sinais de r\u00e1dio no universo qu\u00e2ntico seria como tentar encontrar dinossauros em um zool\u00f3gico. Voc\u00ea simplesmente chega atrasado \u00e0 festa, e o que voc\u00ea procura j\u00e1 n\u00e3o existe. Mas se mudarmos o que procuramos, talvez comecemos a encontrar resultados melhores.<\/span><\/p>\n<h2> <span>4. Rob\u00f4s de busca - sondas<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-69690\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_6410771a05a1a.png\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Mais perto de casa, as luas de Saturno e Marte ainda est\u00e3o repletas de possibilidades. Embora ainda n\u00e3o tenhamos detectado sinais de vida, isso n\u00e3o significa que n\u00e3o tenhamos descoberto nada. E ferramentas de detec\u00e7\u00e3o mais eficazes aumentar\u00e3o nossas chances.<\/span><\/p>\n<p> <span>A NASA tem explorado a ideia de enviar sondas a luas como Europa e Enc\u00e9lado, que poderiam ser enviadas para baixo do gelo como o conhecemos, para procurar sinais de vida. A equipe<\/span> <span>rob\u00f4s<\/span> <span>Podem ser colocados em \u00e1gua l\u00edquida sob o gelo e deixados a nadar por toda parte para ver o que conseguem enxergar.<\/span><\/p>\n<p> <span>Esta ser\u00e1 apenas um tipo de sonda inteligente futura, capaz de pesquisar e determinar por si mesma se encontrou algo \u00fatil. Como os sinais do espa\u00e7o levam muito tempo para chegar \u00e0 Terra, eles podem<\/span> <span>usar IA<\/span> <span>Para auxiliar nas buscas e an\u00e1lises, reportando apenas quando acreditam ter encontrado algo relevante.<\/span><\/p>\n<h2> <span>3. Lentes gravitacionais<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-81486\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_6410771ab3f8f.jpeg\" alt=\"\" width=\"640\" height=\"360\"><\/p>\n<p> <span>Se voc\u00ea se lembra <em>\u00abJornada nas Estrelas IV\u00bb<\/em> (Aquele com as baleias), ent\u00e3o voc\u00ea talvez saiba que existe um precedente para objetos orbitando o Sol. E por mais fant\u00e1stico que esse filme possa parecer, h\u00e1 ci\u00eancia por tr\u00e1s da ideia de usar a gravidade do Sol para mover coisas. Chama-se lente gravitacional e pode nos ajudar a interceptar sinais alien\u00edgenas.<\/span><\/p>\n<p> <span>Se algo for grande o suficiente, sua for\u00e7a gravitacional pode at\u00e9 mesmo curvar a luz. Como resultado, tamb\u00e9m focaliza e amplifica essa luz. Pesquisadores argumentam que sinais de comunica\u00e7\u00e3o poderiam ser<\/span> <span>curvado e focado<\/span> <span>Da mesma forma. Isso significa que estrelas como o nosso Sol poderiam ser usadas como redes de sat\u00e9lites terrestres, transmitindo e repetindo sinais por toda a gal\u00e1xia. Se outra ra\u00e7a de seres estivesse usando estrelas dessa maneira, e n\u00f3s instal\u00e1ssemos um repetidor de sat\u00e9lites, poder\u00edamos interceptar as comunica\u00e7\u00f5es.<\/span><\/p>\n<p> <span>No entanto, a comunica\u00e7\u00e3o n\u00e3o \u00e9 tudo.<\/span> <span>Tamb\u00e9m est\u00e1 sendo estudado.<\/span> <span>influ\u00eancia<\/span> <span>sol para luz<\/span> . <span>Se posicionarmos uma espa\u00e7onave ou sat\u00e9lite de forma que sua luz seja refratada e ent\u00e3o focalizada pelo nosso Sol, poderemos obter uma vis\u00e3o muito mais n\u00edtida de mundos extraterrestres. O Sol se tornaria, efetivamente, um telesc\u00f3pio natural, ampliando nossa vis\u00e3o. Pelo menos um pesquisador acredita que o efeito seria impressionante \u2014 possivelmente atingindo uma resolu\u00e7\u00e3o de 20 quil\u00f4metros por pixel. N\u00edtido o suficiente para discernir continentes e at\u00e9 mesmo padr\u00f5es clim\u00e1ticos em outros mundos.<\/span><\/p>\n<h2> <span>2. Qu\u00edmica \u00famida<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-69692\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_6410771b8e309.png\" alt=\"\" width=\"640\" height=\"427\"><\/p>\n<p> <span>Por mais repulsivo que possa parecer, a qu\u00edmica \u00famida oferece a possibilidade de encontrar vida em outros mundos. Isso funciona em planetas mais pr\u00f3ximos da Terra, como Marte, e n\u00e3o em gal\u00e1xias distantes.<\/span><\/p>\n<p> <span>Usando algo chamado<\/span> <span>An\u00e1lise de amostras em Marte<\/span> <span>, O rover Curiosity, ou SAM, examinou o solo marciano em busca dos elementos b\u00e1sicos da vida. Isso inclui quaisquer compostos org\u00e2nicos que possam conter subst\u00e2ncias como oxig\u00eanio e nitrog\u00eanio. As amostras de solo s\u00e3o analisadas em tr\u00eas c\u00e2maras diferentes, onde podem ser expostas a<\/span> <span>diversos solventes<\/span> <span>, bem como em outras c\u00e2maras onde podiam ser secas. Como resultado, v\u00e1rias mol\u00e9culas org\u00e2nicas foram descobertas, as quais n\u00e3o teriam passado despercebidas durante uma an\u00e1lise convencional de amostras. Certamente n\u00e3o descobrimos vida, mas isso nos deu uma vis\u00e3o muito mais clara do que estava presente e certamente poder\u00e1 ser \u00fatil no futuro.<\/span><\/p>\n<p> <span>Essa t\u00e9cnica poderia ser aplicada novamente em outros locais, como nas luas de Saturno, como Tit\u00e3.<\/span><\/p>\n<h2> <span>1. Ondas de r\u00e1dio aurorais<\/span> <\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-75361\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-interesnyx-sposobov-poiska-inoplanetnoj-zhizni_6410771c986aa.jpeg\" alt=\"\" width=\"640\" height=\"426\"><\/p>\n<p> <span>Voc\u00ea j\u00e1 ouviu falar das ondas de r\u00e1dio emitidas pela aurora boreal? N\u00e3o \u00e9 um assunto que costuma surgir em conversas informais, mas \u00e9 de particular interesse na busca por vida extraterrestre.<\/span><\/p>\n<p> <span>Aqui na Terra, a aurora boreal ocorre quando part\u00edculas solares carregadas colidem com gases em nossa atmosfera. Isso acontece em ambos os polos, n\u00e3o apenas no norte. Na maioria das vezes, a aurora boreal \u00e9 verde, mas diferentes gases produzem cores diferentes. E a Terra n\u00e3o \u00e9 o \u00fanico planeta onde isso ocorre.<\/span><\/p>\n<p> <span>A aurora boreal produz ondas de r\u00e1dio, e esses sinais de r\u00e1dio podem nos fornecer informa\u00e7\u00f5es sobre o planeta de onde v\u00eam, incluindo seu campo magn\u00e9tico. Isso \u00e9 importante porque<\/span> <span>campo magn\u00e9tico<\/span> <span>Essencial para a vida em nosso planeta como a conhecemos. Nosso campo magn\u00e9tico mant\u00e9m nossa atmosfera est\u00e1vel, impedindo que part\u00edculas nocivas nos alcancem e destruam toda a vida na superf\u00edcie.<\/span><\/p>\n<p> <span>Se um exoplaneta for descoberto e apresentar auroras, poderemos analisar essas ondas de r\u00e1dio. Se elas indicarem um forte campo magn\u00e9tico, isso poder\u00e1 ser um forte ind\u00edcio de que o planeta \u00e9 habit\u00e1vel. Da mesma forma,<\/span> <span>os pr\u00f3prios sinais<\/span> <span>pode nos levar de volta a planetas que, de outra forma, poder\u00edamos perder.<\/span><\/p>\n<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>Carl Sagan disse certa vez: &quot;Em algum lugar, algo incr\u00edvel est\u00e1 esperando para ser descoberto.&quot; \u00c9 esse desejo de conhecer o desconhecido que impulsiona a humanidade al\u00e9m...<\/p>","protected":false},"author":1,"featured_media":12859,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-99108","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/99108","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=99108"}],"version-history":[{"count":0,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/99108\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/12859"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=99108"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=99108"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=99108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}