{"id":99158,"date":"2022-06-04T00:00:00","date_gmt":"2022-06-03T21:00:00","guid":{"rendered":"http:\/\/aleksawn.bget.ru\/10-ptic-s-uzhasayushhej-temnoj-storonoj\/"},"modified":"2026-08-24T13:32:07","modified_gmt":"2026-08-24T10:32:07","slug":"10-passaros-com-um-lado-sombrio-e-aterrorizante","status":"publish","type":"post","link":"https:\/\/imgist.ru\/pt\/10-ptic-s-uzhasayushhej-temnoj-storonoj\/","title":{"rendered":"10 p\u00e1ssaros com um lado sombrio e aterrorizante: p\u00e1ssaros chocantes"},"content":{"rendered":"<p>Ao longo da hist\u00f3ria, as aves t\u00eam sido s\u00edmbolos dos nossos ideais mais elevados. Dos p\u00e1ssaros canoros \u00e0s \u00e1guias majestosas, elas personificam a beleza da natureza, a devo\u00e7\u00e3o dos pais, a liberdade de esp\u00edrito\u2026 Mas ser\u00e1 que est\u00e3o t\u00e3o distantes assim dos nossos costumes mundanos e pr\u00e1ticos?<\/p>\n<p>Aqui est\u00e3o 10 aves e fatos chocantes sobre o lado sombrio de sua exist\u00eancia.<\/p>\n<h2>10. Ca\u00e7ador de parasitas<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-126230\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2022\/06\/eger-ptica.jpg\" alt=\"\" width=\"800\" height=\"574\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Ah, aquele ca\u00e7ador parasita! Sabe, quando o vi pela primeira vez, pensei imediatamente: que descaramento! Ele parece uma gaivota raivosa e exausta, s\u00f3 que com um brilho... predat\u00f3rio nos olhos. Ali\u00e1s, em alem\u00e3o, soa como &quot;ca\u00e7ador&quot; \u2014 e isso, diga-se de passagem, define perfeitamente a sua ess\u00eancia.<\/p>\n<p>Ele \u00e9 como um lobo solit\u00e1rio, embora \u00e0s vezes cace em bando. E seu nome \u00e9 revelador: &quot;parasita&quot;. Porque, imagine, ele rouba comida direto do ar! Voc\u00ea alcan\u00e7a algum coitado que provavelmente acabou de pescar um peixe saboroso e \u2013 bam! \u2013 o ca\u00e7ador parasita o arrebata de seu bico. Esse sim \u00e9 um verdadeiro pirata do ar, e que pirata ousado! Bem, como piratas, basicamente \u2013 eles passam a maior parte da vida sobre o mar, sobre aquelas extens\u00f5es infinitas e fervilhantes, circulando, amea\u00e7ando, for\u00e7ando os p\u00e1ssaros a se renderem. E \u00e9, honestamente, um pouco assustador.<\/p>\n<p>Li uma vez que eles preferem as partes mais agitadas do mar, supostamente porque l\u00e1 h\u00e1 mais presas. Pode ser verdade, mas acho que eles simplesmente gostam de desafiar a sorte, sabe, como pessoas que gostam de adrenalina.<\/p>\n<p>Eles v\u00eam para a costa, essencialmente, por um \u00fanico motivo: procriar, como se costuma dizer. Sabe, neg\u00f3cios. Na Europa, chamam-lhe skua-\u00e1rtica porque se reproduz na tundra, bem ao norte. E mesmo l\u00e1, em meio a essa beleza agreste, continua a ser uma verdadeira amea\u00e7a. N\u00e3o, falando s\u00e9rio, comer outras aves e os seus ovos... isso \u00e9 demais, na minha opini\u00e3o!<\/p>\n<p>E sabe de outra coisa? Dizem que seu grito soa como o choro de um beb\u00ea! Que reviravolta, n\u00e3o \u00e9? Imagine s\u00f3, uma ave t\u00e3o imponente, mas que emite um som como... como se estivesse chamando pela m\u00e3e. Que contraste terr\u00edvel, n\u00e3o \u00e9? N\u00e3o sei se j\u00e1 ouvi pessoalmente, mas parece convincente. Enfim, a ave-ca\u00e7adora-parasita definitivamente merece uma hist\u00f3ria s\u00f3 para ela. Que criatura!<\/p>\n<p>&nbsp;<\/p>\n<h2>9. Pelicano<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-66105\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-ptic-s-uzhasayushhej-temnoj-storonoj_64107b6934e72.jpeg\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Ah, os pelicanos! Que aves encantadoras... com seus p\u00e9s parecidos com os de um pato e pesco\u00e7os curvados como os de um flamingo, s\u00e3o simplesmente fascinantes. E sabe, eu me pergunto se n\u00e3o foi a cegonha que nos trouxe nossos beb\u00eas, como dizem nos contos de fadas? Bem, eles certamente t\u00eam o bico perfeito \u2013 voc\u00ea poderia pegar um rec\u00e9m-nascido agora mesmo! Brincadeirinha, \u00e9 claro... embora, falando s\u00e9rio, nunca, jamais deixe uma crian\u00e7a com um pelicano, ou qualquer outro animal que voc\u00ea ame! Vou te dizer por qu\u00ea.<\/p>\n<p>Imagine s\u00f3, essas criaturinhas fofas, quando estressadas ou com fome, se transformam em verdadeiros monstros! Bem, n\u00e3o exatamente monstros, claro, mas... come\u00e7am a agarrar tudo o que veem pela frente, engolindo qualquer um! Dizem que j\u00e1 pegaram gansinhos, filhotes de pinguim azarados, patos, pombos... at\u00e9 tartaruguinhas \u2013 uau! E, imagine, um chihuahua! Sim, n\u00e3o estou brincando!<\/p>\n<p>E assim, a pobre criatura acaba naquele bico enorme... e desce pela garganta, viva! Depois, se o pelicano estiver com muita fome, ele rasteja at\u00e9 o est\u00f4mago para pegar os restos... e se n\u00e3o, come\u00e7a com a colheita, as plantas, o que for! Imagine, uma esp\u00e9cie de &quot;bolsa de armazenamento&quot;! Sabe, em vez de enzimas, eles t\u00eam algum tipo de muco dentro para amolecer a presa. \u00c9 simplesmente assustador, se voc\u00ea parar para pensar!<\/p>\n<p>\u00c9 estranho, n\u00e3o \u00e9? Aves t\u00e3o graciosas, e ainda assim com uma dieta t\u00e3o... peculiar. Uma vez vi um pelicano no zool\u00f3gico, e o jeito que ele me olhou! Era como se estivesse pensando: &quot;Que pena se voc\u00ea...&quot;. Bem, claro, eu rapidamente me afastei. Mas mesmo assim, apesar disso, eles despertam em mim um deleite inexplic\u00e1vel. H\u00e1 uma beleza selvagem e imprevis\u00edvel neles, sabe? Como a pr\u00f3pria vida \u2014 \u00e0s vezes encanta com ternura, \u00e0s vezes aterroriza a ponto de causar arrepios. \u00c9 assim que os pelicanos s\u00e3o \u2014 parecem t\u00e3o doces, mas por dentro... s\u00e3o um mundo inteiro!<\/p>\n<p>&nbsp;<\/p>\n<h2>8. Casuar<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-126232\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2022\/06\/kazuar.jpg\" alt=\"\" width=\"800\" height=\"550\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Consegue imaginar? Austr\u00e1lia, sol, eucaliptos... e um casuar. Esta ave \u2014 bem, na verdade n\u00e3o \u00e9 bem uma ave, mais parecida com um dinossauro emplumado de casaco \u2014 desempenha um papel colossal no ecossistema, mesmo que n\u00e3o seja particularmente fofa. Sem ela, sabe, algumas plantas australianas simplesmente n\u00e3o cresceriam! Acontece que algumas sementes s\u00e3o t\u00e3o grandes que outros animais frug\u00edvoros nem conseguem engoli-las. Mas o sistema digestivo do casuar \u00e9 como uma f\u00e1brica de germina\u00e7\u00e3o de sementes, s\u00f3 que muito mais... especializada. Ent\u00e3o, de certa forma, devemos ser gratos, n\u00e3o \u00e9?<\/p>\n<p>Mas aqui, sabe, chegamos \u00e0 parte mais interessante. Porque o casuar \u00e9 possivelmente a ave mais perigosa do planeta. N\u00e3o estou brincando! Ele tem uma garra enorme em cada p\u00e9, como uma adaga \u2014 dez cent\u00edmetros de comprimento! E se ele decidir que voc\u00ea \u00e9 uma amea\u00e7a... bem, acredite, ele vai atacar como um raio. Ele simplesmente &quot;corta qualquer amea\u00e7a em potencial com um golpe r\u00e1pido&quot;, como dizem nos document\u00e1rios. E ele pode correr a at\u00e9 cinquenta quil\u00f4metros por hora! Honestamente, n\u00e3o consigo imaginar uma ave que corra t\u00e3o r\u00e1pido. E ele consegue pular! Quase dois metros de altura! Basicamente, \u00e9 como os velociraptors de Jurassic Park, s\u00f3 que com penas. At\u00e9 os casuares se assustam uns aos outros \u2014 uau!<\/p>\n<p>S\u00e3o criaturas essencialmente solit\u00e1rias. Romance definitivamente n\u00e3o \u00e9 o forte delas. Os machos se envolvem em brigas de ranger de dentes para mostrar quem manda, e as f\u00eameas... bem, elas conseguem faz\u00ea-los fugir com um simples olhar. Isso sim \u00e9 poder! E quando se comunicam, \u00e9 incr\u00edvel \u2014 sons de baixa frequ\u00eancia que voc\u00ea sente nos ossos. Como se o ch\u00e3o tremesse. N\u00e3o \u00e9 \u00e0 toa que j\u00e1 se sabe que elas matam pessoas. Consegue imaginar? Geralmente, elas apenas chutam ou pulam em cima de voc\u00ea, mas tamb\u00e9m podem bicar ou dar cabe\u00e7adas. Voc\u00ea acaba com, como se diz, &quot;ferimentos perfurantes, lacera\u00e7\u00f5es e ossos quebrados&quot;. N\u00e3o parece nada agrad\u00e1vel, n\u00e3o \u00e9?<\/p>\n<p>E sabe o que mais? Eles chegam a invadir casas! Bicam e chutam portas e janelas. \u00c0s vezes, acredite se quiser, at\u00e9 quebram vidros! Mas acontece que isso n\u00e3o \u00e9 agress\u00e3o. \u00c9 apenas uma demonstra\u00e7\u00e3o de &quot;vigil\u00e2ncia preventiva&quot;, como se estivessem se protegendo de uma poss\u00edvel amea\u00e7a. \u00c9 como se tivessem medo de si mesmos! \u00c9 simplesmente inacredit\u00e1vel!<\/p>\n<p>Ser\u00e1 que eles se sentem um pouco desconfort\u00e1veis com tanto poder? Talvez simplesmente n\u00e3o saibam o que fazer consigo mesmos? De qualquer forma, o casuar \u00e9 uma ave misteriosa, uma ave do terror, uma ave da salva\u00e7\u00e3o. E talvez uma ave que seja melhor observada de longe... bem de longe. Bem, fui ver se algu\u00e9m estava batendo na janela... talvez fosse um casuar fazendo uma visita. Brrr!<\/p>\n<p>&nbsp;<\/p>\n<h2>7. Cabe\u00e7a de Baleia<\/h2>\n<p>&nbsp;<\/p>\n<p>Meu Deus, a cegonha-bico-de-sapato! Essa esp\u00e9cie... \u00e9 simplesmente fascinante, sinceramente. Descobri sobre ela recentemente e estou completamente encantada. D\u00e1 para acreditar? Representa\u00e7\u00f5es dela j\u00e1 foram encontradas na arte eg\u00edpcia antiga! E agora, descobri que ela at\u00e9 inspirou os desenvolvedores de The Legend of Zelda \u2013 Loftwing, aquele personagem incr\u00edvel, \u00e9 a cara de uma cegonha-bico-de-sapato. Uau!<\/p>\n<p>A cegonha-bico-de-sapato n\u00e3o \u00e9 nenhuma boba, viu? Ela tem o tamanho de um homem, e sua envergadura \u00e9 de impressionantes dois metros e meio! Consegue imaginar o qu\u00e3o formid\u00e1vel ela \u00e9? Ela ca\u00e7a todo tipo de criatura: peixes gigantes, cobras, filhotes de crocodilo e at\u00e9 mesmo lagartos-monitores do Nilo! O mais interessante \u00e9 o seu bico. Ele \u00e9 curvado, como, sabe, uma esp\u00e9cie de sabot... \u00c9 por isso que os \u00e1rabes a chamam de &quot;abu markhub&quot; \u2014 &quot;pai do sapato&quot;. E esse &quot;sapato&quot; \u2014 com raz\u00e3o \u2014 \u00e9 uma arma poderosa! Dizem que ela morde a presa e... bem, voc\u00ea sabe, a decapita. \u00c9 aterrorizante, com certeza.<\/p>\n<p>Tamb\u00e9m me disseram isto: ele dispara como uma metralhadora quando cumprimenta outros bicos-de-sapato! Consegue imaginar o som disso? Mas sabe, o mais impressionante n\u00e3o s\u00e3o as suas habilidades de ca\u00e7a. \u00c9 a forma como ele trata os seus filhotes!<\/p>\n<p>Eu j\u00e1 tinha ouvido falar da crueldade do mundo natural, claro, mas quando assisti ao document\u00e1rio &quot;\u00c1frica&quot;, de David Attenborough, fiquei absolutamente chocada. As imagens eram de partir o cora\u00e7\u00e3o... A m\u00e3e voa para buscar \u00e1gua e o filhote mais velho, veja s\u00f3, decide zombar do mais novo. Ele simplesmente arranca suas penas com tanta ferocidade! O pobre filhote, que mal consegue se manter vivo, sofre esse tipo de abuso. E o pior \u00e9 que, quando a m\u00e3e retorna, ela n\u00e3o interv\u00e9m! Ela simplesmente ignora a v\u00edtima e, na pr\u00e1tica, encoraja o agressor. Que reviravolta! N\u00e3o \u00e9 de admirar que os filhotes de bico-de-sapato raramente sobrevivam \u2014 na melhor das hip\u00f3teses, apenas um.<\/p>\n<p>Percebi que at\u00e9 o mundo das aves tem suas pr\u00f3prias regras complexas e cru\u00e9is de sobreviv\u00eancia. E como tudo isso contrasta com a beleza majestosa, quase m\u00edtica, que vemos em pinturas antigas ou personagens de videogames. \u00c9 como se fossem duas faces completamente diferentes da mesma moeda. No geral, a cegonha-bico-de-sapato \u00e9 uma ave misteriosa, o que posso dizer? Um esp\u00e9cime muito incomum e, admito, um pouco assustador. Preciso ler mais sobre ela; provavelmente ainda h\u00e1 muito mais interessante para descobrir.<\/p>\n<h2>6. Cuco<\/h2>\n<p>Ah, o cuco! Seu canto \u00e9, claro, o primeiro pren\u00fancio da primavera; todos o ouvimos e nossos cora\u00e7\u00f5es se alegram. Mas voc\u00ea sabe, por tr\u00e1s desse trinado vibrante, esconde-se uma hist\u00f3ria... t\u00e3o astuta, at\u00e9 um pouco assustadora! Afinal, os cucos s\u00e3o, em ess\u00eancia, verdadeiros parasitas, s\u00f3 que em penas. Eles n\u00e3o se d\u00e3o ao trabalho de criar seus filhotes, mas simplesmente jogam seus ovos em ninhos de outros p\u00e1ssaros, na esperan\u00e7a de que os pais tolos criem seus filhotes como se fossem seus. Imagine a economia de energia que isso representa!<\/p>\n<p>\u00c0s vezes, \u00e9 realmente incr\u00edvel como eles fazem isso! Dizem que alguns cucos simplesmente deixam cair seus ovos no ninho de cima! Suas cascas s\u00e3o t\u00e3o grossas, como uma pequena bomba \u2014 bum! \u2014 e o ovo do outro p\u00e1ssaro se quebra. Parece descuidado, n\u00e3o \u00e9? Mas, na verdade, tudo \u00e9 planejado nos m\u00ednimos detalhes. Nada \u00e9 deixado ao acaso! Os cucos, como agentes experientes, por assim dizer, escolhem os ninhos com anteced\u00eancia.<\/p>\n<p>Eu sempre os imaginei escondidos nos arbustos, como espi\u00f5es, observando seus donos, calculando o momento em que poderiam p\u00f4r um ovo em seguran\u00e7a. E o mais interessante \u00e9 que os machos tamb\u00e9m participam! Em algumas esp\u00e9cies, eles at\u00e9 parecem gavi\u00f5es \u2013 t\u00e3o amea\u00e7adores. E o que eles fazem? Distraem seus hospedeiros, for\u00e7ando-os a lutar! Bem, apenas para criar caos e facilitar as coisas para a f\u00eamea. Isso sim \u00e9 trabalho em equipe!<\/p>\n<p>E n\u00e3o \u00e9 s\u00f3 isso! Os cucos, ao que parece, n\u00e3o se esquecem dos seus filhotes. Eles voltam para verificar como est\u00e3o. E se os donos, de repente, decidem &quot;isto n\u00e3o \u00e9 meu&quot; e tentam expulsar o filhote de cuco, a\u00ed \u00e9 que a coisa fica interessante! Dizem que o cuco-pintado-grande pode at\u00e9 se vingar! Matar os filhotes do dono. Igualzinho \u00e0 m\u00e1fia, sabe? \u00c9 esse tipo de extors\u00e3o que essas aves praticam.<\/p>\n<p>Mas, sabe, nem sempre \u00e9 preciso recorrer a medidas t\u00e3o dr\u00e1sticas. Os cucos s\u00e3o astutos, viu? Seus filhotes nascem mais cedo e mais fortes que os outros. E o que eles fazem? Simplesmente expulsam todos os outros do ninho! Literalmente, chutam-nos para fora! Consegue imaginar a luta pela sobreviv\u00eancia no mundo das aves?<\/p>\n<p>Ent\u00e3o voc\u00ea fica pensando: o cuco \u00e9 um personagem t\u00e3o interessante, se n\u00e3o o mais agrad\u00e1vel. \u00c9 assim que a vida na natureza \u00e9 \u2014 cheia de intrigas e surpresas. E agora, para mim, cada canto de cuco soa como a hist\u00f3ria de um pequeno, mas muito determinado, trapaceiro. O que voc\u00ea acha?<\/p>\n<h2>5. Rouxinol-pequeno-dos-cani\u00e7os<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81845\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-ptic-s-uzhasayushhej-temnoj-storonoj_64107b69ec74e.jpeg\" alt=\"\" width=\"640\" height=\"427\" \/><\/p>\n<p>Sabe, acabei de me deparar com uma hist\u00f3ria muito louca sobre toutinegras e rouxinol-pequeno-dos-cani\u00e7os! Imagine s\u00f3, as toutinegras, esses nossos cantores doces e melodiosos, s\u00e3o um verdadeiro deleite para os cucos, praticamente um almo\u00e7o gr\u00e1tis. Bem, isso \u00e9 compreens\u00edvel; os cucos s\u00e3o mestres do disfarce, mas mesmo assim!<\/p>\n<p>Mas os rouxinol-pequeno... essa \u00e9 uma hist\u00f3ria completamente diferente. A m\u00e3e parece totalmente alheia \u00e0 presen\u00e7a de intrusos em seu ninho! Imagine s\u00f3: um cuco nasce, come\u00e7a a crescer, e a pobre m\u00e3e continua a aliment\u00e1-lo, mesmo quando esse &quot;cuco&quot; j\u00e1 tem o dobro do seu tamanho! Simplesmente inacredit\u00e1vel! E, ainda mais estranho, ela parece n\u00e3o perceber quando os outros ovos s\u00e3o empurrados para fora do ninho. \u00c9 como se estivesse de olhos vendados!<\/p>\n<p>Mas n\u00e3o pense que isso significa que os rouxinol-dos-cani\u00e7os s\u00e3o est\u00fapidos ou confiantes demais. N\u00e3o, n\u00e3o, n\u00e3o! Eles t\u00eam seu pr\u00f3prio plano, muito astuto! Acontece que os machos de rouxinol-dos-cani\u00e7os geralmente constroem apenas um ninho, mesmo que tenham uma ninhada inteira de filhotes dentro. E \u00e9 a\u00ed que entram as f\u00eameas, conhecidas como &quot;parceiras do har\u00e9m inferior&quot;. Parece engra\u00e7ado, claro, mas a quest\u00e3o \u00e9 que elas destroem impiedosamente os ovos de seus rivais!<\/p>\n<p>Sinceramente, quase me engasguei com o caf\u00e9 quando li isso! Consegue imaginar o drama que se desenrola nesses humildes ninhos de junco? Os cientistas at\u00e9 testaram! Colocaram ovos artificiais de plasticina nos ninhos e monitoraram os rouxinol-pequeno-dos-cani\u00e7os \u2014 uau! Descobriu-se que, uma vez que uma &quot;amante&quot; destr\u00f3i os &quot;filhos&quot; de sua primeira esposa, ela, por assim dizer, constr\u00f3i uma &quot;carreira&quot; para si mesma e sobe na fila para obter apoio masculino.<\/p>\n<p>E n\u00e3o \u00e9 s\u00f3 isso! Novas f\u00eameas chegaram, aparentemente determinadas a lucrar com esse caos. Elas constroem ninhos bem ao lado do local do &quot;infantic\u00eddio&quot; para aumentar as chances de fisgar um macho. Exatamente como na vida real! Voc\u00ea entende a luta pela sobreviv\u00eancia que elas est\u00e3o enfrentando? \u00c9 engra\u00e7ado e assustador ao mesmo tempo, n\u00e3o \u00e9? Afinal, a natureza \u00e9 maravilhosa, e os conceitos de &quot;bem&quot; e &quot;mal&quot; s\u00e3o, de certa forma... indefinidos. Cada um simplesmente faz o que for preciso para sobreviver e gerar descendentes. \u00c0s vezes, para conseguir o que \u00e9 seu, voc\u00ea precisa... afastar um pouco o seu rival. Que fazer!<\/p>\n<h2>4. Pican\u00e7o<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81844\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-ptic-s-uzhasayushhej-temnoj-storonoj_64107b6acb22d.jpeg\" alt=\"\" width=\"640\" height=\"359\" \/><\/p>\n<p>Bem, o que posso dizer sobre o pican\u00e7o? Essa criatura, sabe, evoca sentimentos contradit\u00f3rios. Por um lado, imagine: pequeno, t\u00e3o fofo, com uma m\u00e1scara de guaxinim no rosto e aquele grito estridente e penetrante \u2013 igualzinho a uma pega, s\u00f3 que ainda mais nervoso.<\/p>\n<p>Com seu pequeno porte, m\u00e1scara semelhante \u00e0 de um guaxinim e chamado estridente e agudo, o pican\u00e7o \u00e9 inegavelmente fofo. Mas tamb\u00e9m \u00e9 uma ave de rapina \u2014 e um psicopata. Voc\u00ea j\u00e1 deve ter visto insetos \u2014 besouros, por exemplo \u2014 empalados em cercas de arame farpado. Essa n\u00e3o \u00e9 uma cena incomum. Na verdade, \u00e9 um sinal claro de que um pican\u00e7o (seja um adulto ou uma crian\u00e7a psicopata) est\u00e1 por perto.<\/p>\n<h2>3. Kea<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81843\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-ptic-s-uzhasayushhej-temnoj-storonoj_64107b6b8942d.jpeg\" alt=\"\" width=\"640\" height=\"382\" \/><\/p>\n<p>Este kea... ah, o kea! \u00c9 uma ave incrivelmente bela, um papagaio das montanhas, e, sabe, \u00e9 um verdadeiro tesouro para a Nova Zel\u00e2ndia. Consegue imaginar? Sua imagem estampa notas de banco, \u00e9 um her\u00f3i dos antigos mitos maori \u2014 como um personagem de conto de fadas! E at\u00e9 mesmo no movimento escoteiro da Nova Zel\u00e2ndia, se voc\u00ea tem entre cinco e oito anos, pode ser chamado de &quot;kea&quot; \u2014 uma associa\u00e7\u00e3o t\u00e3o doce, n\u00e3o \u00e9?<\/p>\n<p>Mas \u00e9 aqui que as coisas ficam interessantes e, francamente, um pouco assustadoras. Porque o kea tamb\u00e9m \u00e9 uma praga nacional. Sim, voc\u00ea leu certo. Essas aves, ao que parece, s\u00e3o verdadeiras arruaceiras! Sabe, elas sobem nas costas das ovelhas... e, bem, \u00e9 um verdadeiro pesadelo. Elas as devoram, arrancando seus lombos com seus bicos poderosos. Assustador, n\u00e3o \u00e9?<\/p>\n<p>Lembro-me de ter lido a hist\u00f3ria de um agricultor em 2009 que se queixava de ter perdido at\u00e9 trinta ovelhas em apenas alguns meses devido ao que ele chamava de &quot;ataques de kea&quot;. Imagine o qu\u00e3o atordoado ele ficou! E um dia, ele descobriu... bem, \u00e9 melhor n\u00e3o descrever, mas direi apenas que a cavidade intestinal estava aberta. Foi absolutamente aterrador.<\/p>\n<p>E eis o mais estranho: os neozelandeses est\u00e3o completamente confusos. Por um lado, o kea est\u00e1 sob a mais rigorosa prote\u00e7\u00e3o; n\u00e3o pode ser tocado! \u00c9 um tesouro nacional, como j\u00e1 disse. Mas, por outro lado, a carne de cordeiro \u00e9 a espinha dorsal da economia, seu principal produto de exporta\u00e7\u00e3o! Consegue imaginar quanto dinheiro essa ind\u00fastria movimenta? Ent\u00e3o, voc\u00eas est\u00e3o protegendo uma ave que est\u00e1 destruindo seus neg\u00f3cios.<\/p>\n<p>O governo est\u00e1, obviamente, tentando encontrar uma solu\u00e7\u00e3o. Atualmente, est\u00e3o emitindo licen\u00e7as para ca\u00e7ar keas, mas apenas se forem pegos em flagrante, por assim dizer. Consegue imaginar tentar pegar essa ave em pleno ato? \u00c9 como tentar pegar o vento dentro de um saco, sinceramente.<\/p>\n<p>Fico pensando se eles n\u00e3o deveriam tentar algo mais criativo? Tipo ensinar o kea a colher frutinhas ou algo assim. Ou talvez eles s\u00f3 precisem aceitar que o kea \u00e9 uma ave exc\u00eantrica, com suas peculiaridades e maus h\u00e1bitos. Afinal, quem entre n\u00f3s \u00e9 perfeito? At\u00e9 os tesouros nacionais mais belos podem, \u00e0s vezes, ser um verdadeiro inc\u00f4modo. Mas, sabe, mesmo com todos esses problemas, eu ainda acho o kea uma ave incrivelmente charmosa. S\u00f3... cuidado com as ovelhas!<\/p>\n<h2>2. Abutre-preto<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81841\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-ptic-s-uzhasayushhej-temnoj-storonoj_64107b6c80027.jpeg\" alt=\"\" width=\"640\" height=\"429\" \/><\/p>\n<p>Meu Deus, ou\u00e7am s\u00f3 o que eu descobri! Esses urubus... bem, eles s\u00e3o assustadores, simplesmente assustadores! Imaginem eles sobrevoando pr\u00e9dios abandonados como bruxas sinistras, s\u00f3 que completamente pretas. E eles perseguem perus, esses urubus-de-cabe\u00e7a-vermelha, sim, para roubar alguma coisa comest\u00edvel deles, sibilando como gatos raivosos. Mas acontece que \u00e9 s\u00f3 divers\u00e3o para eles!<\/p>\n<p>O verdadeiro pesadelo come\u00e7a nas fazendas do Kentucky. \u00c9 l\u00e1 que elas mostram sua verdadeira face. Os fazendeiros est\u00e3o em p\u00e2nico, francamente! Dizem que essas aves gostam de... voc\u00ea sabe, perturbar os bezerros rec\u00e9m-nascidos. Primeiro, elas pulam freneticamente para &quot;acalmar&quot; o bezerro, e ent\u00e3o... ent\u00e3o o pior acontece. Elas bicam os olhos, depois a l\u00edngua e, em seguida, tudo o que conseguem. E tudo isso em literalmente alguns minutos!<\/p>\n<p>E o pior \u00e9 que atacam as ovelhas quando est\u00e3o a dar \u00e0 luz! Consegue imaginar?! Como verdadeiros cirurgi\u00f5es, arrancam cuidadosamente a pele da m\u00e3e para se banquetearem com ela e com o cordeiro. \u00c9 simplesmente de arrepiar! Eu sei que a natureza \u00e9 cruel, mas isto\u2026 isto \u00e9 demais, para ser sincera.<\/p>\n<p>E aqui est\u00e1 a pior parte: n\u00e3o h\u00e1 nada que voc\u00ea possa fazer a respeito! A Lei do Tratado de Aves Migrat\u00f3rias, entende? Voc\u00ea n\u00e3o pode toc\u00e1-las sem permiss\u00e3o federal. Bem, a menos que voc\u00ea seja um g\u00eanio do direito e possa provar que elas n\u00e3o s\u00e3o apenas p\u00e1ssaros, mas a pr\u00f3pria personifica\u00e7\u00e3o do mal.<\/p>\n<p>Claro, elas t\u00eam sua utilidade \u2014 dizem que s\u00e3o muito boas em se alimentar de animais atropelados. Mas sabe, quando voc\u00ea pensa no bezerro e na ovelha\u2026 \u00e9 dif\u00edcil n\u00e3o pensar neles como algum tipo de mal que surgiu das trevas. Como se a pr\u00f3pria escurid\u00e3o tivesse se transformado em penas e bico. Simplesmente aterrorizante! Agora eu olho para os p\u00e1ssaros com apreens\u00e3o, para ser sincera. Eu nunca teria imaginado que criaturas aparentemente t\u00e3o inofensivas pudessem ser t\u00e3o\u2026 sedentas de sangue. O que voc\u00ea acha?<\/p>\n<h2>1. Pato<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-81840\" src=\"https:\/\/imgist.ru\/wp-content\/uploads\/2023\/03\/10-ptic-s-uzhasayushhej-temnoj-storonoj_64107b6d51c69.jpeg\" alt=\"\" width=\"640\" height=\"418\" \/><\/p>\n<p>Quem n\u00e3o ama patos? Essas criaturinhas fofas com seus grasnados inocentes e plumagem brilhante... Mas sabe de uma coisa? Existe um segredo sombrio, nada fofo, que poucas pessoas imaginam. E eu vou contar para voc\u00eas, ent\u00e3o preparem-se.<\/p>\n<p>O fato \u00e9 que os patos machos, esses marrecos, est\u00e3o entre as aves que possuem p\u00eanis. E n\u00e3o s\u00f3 isso, mas, imagine, eles est\u00e3o entre os 31 maiores! E, em rela\u00e7\u00e3o ao tamanho do corpo, s\u00e3o campe\u00f5es entre todos os vertebrados. Honestamente, \u00e9 simplesmente inacredit\u00e1vel! O pato-argentino, por exemplo, ostenta um p\u00eanis que \u00e9 dez cent\u00edmetros maior que o seu corpo! Isso \u00e9 pura fic\u00e7\u00e3o cient\u00edfica, n\u00e3o realidade.<\/p>\n<p>E n\u00e3o \u00e9 s\u00f3 isso! O mais interessante \u00e9 o formato. S\u00e3o torcidas... como um saca-rolhas! Como se algu\u00e9m tivesse projetado esse mecanismo especificamente para isso. Imagine um rabo de porco torcido, s\u00f3 que dez vezes mais apertado. E como posso descrever... \u00e9 como escolher um brinquedo sexual numa m\u00e1quina de venda autom\u00e1tica num bar alien\u00edgena maluco! Com ranhuras, \u00e1spero, at\u00e9 irregular! Bem, n\u00e3o sei o que voc\u00ea acha, mas acho que \u00e9 um pouco demais.<\/p>\n<p>E aqui reside o ponto crucial da quest\u00e3o. Todos esses refinamentos evolutivos, todas essas adapta\u00e7\u00f5es... Tudo isso, por mais estranho que pare\u00e7a, se desenvolveu... para o prazer da f\u00eamea. Sim, voc\u00ea leu certo. Para impedi-la de fugir. Consegue imaginar o dilema que isso representa para os machos? Afinal, a maioria das esp\u00e9cies de patos tem mais machos do que f\u00eameas. O que significa que nem todos eles conseguem satisfazer o afeto de uma f\u00eamea. Ent\u00e3o, o que eles fazem? Infelizmente, recorrem a... bem, digamos, m\u00e9todos n\u00e3o muito agrad\u00e1veis. Frequentemente, a a\u00e7\u00f5es coletivas muito cru\u00e9is e at\u00e9 mesmo mortais.<\/p>\n<p>Isso est\u00e1 t\u00e3o arraigado em sua natureza que o \u00f3rg\u00e3o reprodutor masculino literalmente evoluiu para... bem, para se travar no lugar. \u00c9 como uma esp\u00e9cie de corrida armamentista sexual! E, como \u00e9 t\u00edpico em qualquer corrida, o outro lado tem suas pr\u00f3prias defesas. Nas f\u00eameas, por exemplo, o \u00f3rg\u00e3o reprodutor pode ter uma espiral apontando na dire\u00e7\u00e3o oposta, ou &quot;bolsos laterais sem sa\u00edda&quot;, para, por assim dizer, interceptar espermatozoides indesejados.<\/p>\n<p>N\u00e3o sei quanto a voc\u00eas, mas eu estou chocada. Quem diria que por tr\u00e1s daqueles grasnados fofos e penas macias se escondia uma hist\u00f3ria t\u00e3o complexa, sombria e, francamente, assustadora? Agora terei que olhar para os patos no parque de outra forma... e, para ser sincera, ficar um pouco assustada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ao longo da hist\u00f3ria, as aves t\u00eam sido s\u00edmbolos dos nossos mais elevados ideais. Dos p\u00e1ssaros canoros \u00e0s \u00e1guias majestosas, elas personificam a beleza da natureza, a devo\u00e7\u00e3o dos pais, a liberdade do esp\u00edrito\u2026 Mas\u2026<\/p>","protected":false},"author":1,"featured_media":126235,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[],"class_list":["post-99158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interesnye-fakty","hvn-theme-has-thumbnail"],"_links":{"self":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/99158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/comments?post=99158"}],"version-history":[{"count":3,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/99158\/revisions"}],"predecessor-version":[{"id":138635,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/posts\/99158\/revisions\/138635"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media\/126235"}],"wp:attachment":[{"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/media?parent=99158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/categories?post=99158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/imgist.ru\/pt\/wp-json\/wp\/v2\/tags?post=99158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}